{"id":109,"date":"2021-08-17T13:02:14","date_gmt":"2021-08-17T13:02:14","guid":{"rendered":"https:\/\/websitedemos.net\/shoe-store-02\/?post_type=product&#038;p=109"},"modified":"2026-05-06T11:05:51","modified_gmt":"2026-05-06T11:05:51","slug":"product-name-7","status":"publish","type":"product","link":"https:\/\/websitedemos.net\/shoe-store-02\/product\/product-name-7\/","title":{"rendered":"Leather Sport Shoes"},"content":{"rendered":"<p>Lorem ipsum dolor sit amet, consectetur adipisicing elit, sed do eiusmod tempor incididunt ut labore. et dolore magna aliqua. Ut enim ad minim veniam, quis nostrud exercitation ullamco laboris nisi ut aliquip ex ea commodo consequat. Duis aute irure dolor in reprehenderit in voluptate velit esse cillum dolore eu fugiat nulla pariatur.<\/p>\n<p>Eiusmod tempor incididunt ut labore. et dolore magna aliqua. Ut enim ad minim veniam, quis nostrud exercitation ullamco laboris nisi ut aliquip ex ea commodo consequat. Duis aute irure dolor in reprehenderit in voluptate velit esse cillum dolore eu fugiat.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Limited Edition Color, Everest<\/p>\n","protected":false},"featured_media":349,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"site-sidebar-layout":"default","site-content-layout":"default","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}}},"product_brand":[],"product_cat":[38,32,30,36],"product_tag":[],"class_list":{"0":"post-109","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-heels","7":"product_cat-men","8":"product_cat-shoes","9":"product_cat-sneakers","10":"desktop-align-left","11":"tablet-align-left","12":"mobile-align-left","14":"first","15":"instock","16":"shipping-taxable","17":"purchasable","18":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Leather Sport Shoes - Shoe Store<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/websitedemos.net\/shoe-store-02\/product\/product-name-7\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Leather Sport Shoes - Shoe Store\" \/>\n<meta property=\"og:description\" content=\"Limited Edition Color, Everest\" \/>\n<meta property=\"og:url\" content=\"https:\/\/websitedemos.net\/shoe-store-02\/product\/product-name-7\/\" \/>\n<meta property=\"og:site_name\" content=\"Shoe Store\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-06T11:05:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/websitedemos.net\/shoe-store-02\/wp-content\/uploads\/sites\/930\/2021\/08\/shoe-09.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1290\" \/>\n\t<meta property=\"og:image:height\" content=\"1290\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/websitedemos.net\\\/shoe-store-02\\\/product\\\/product-name-7\\\/\",\"url\":\"https:\\\/\\\/websitedemos.net\\\/shoe-store-02\\\/product\\\/product-name-7\\\/\",\"name\":\"Leather Sport Shoes - Shoe Store\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/websitedemos.net\\\/shoe-store-02\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/websitedemos.net\\\/shoe-store-02\\\/product\\\/product-name-7\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/websitedemos.net\\\/shoe-store-02\\\/product\\\/product-name-7\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/websitedemos.net\\\/shoe-store-02\\\/wp-content\\\/uploads\\\/sites\\\/930\\\/2021\\\/08\\\/shoe-09.png\",\"datePublished\":\"2021-08-17T13:02:14+00:00\",\"dateModified\":\"2026-05-06T11:05:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/websitedemos.net\\\/shoe-store-02\\\/product\\\/product-name-7\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/websitedemos.net\\\/shoe-store-02\\\/product\\\/product-name-7\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/websitedemos.net\\\/shoe-store-02\\\/product\\\/product-name-7\\\/#primaryimage\",\"url\":\"https:\\\/\\\/websitedemos.net\\\/shoe-store-02\\\/wp-content\\\/uploads\\\/sites\\\/930\\\/2021\\\/08\\\/shoe-09.png\",\"contentUrl\":\"https:\\\/\\\/websitedemos.net\\\/shoe-store-02\\\/wp-content\\\/uploads\\\/sites\\\/930\\\/2021\\\/08\\\/shoe-09.png\",\"width\":1290,\"height\":1290},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/websitedemos.net\\\/shoe-store-02\\\/product\\\/product-name-7\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/websitedemos.net\\\/shoe-store-02\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/websitedemos.net\\\/shoe-store-02\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Leather Sport Shoes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/websitedemos.net\\\/shoe-store-02\\\/#website\",\"url\":\"https:\\\/\\\/websitedemos.net\\\/shoe-store-02\\\/\",\"name\":\"Shoe Store\",\"description\":\"Shoe Store Website\",\"publisher\":{\"@id\":\"https:\\\/\\\/websitedemos.net\\\/shoe-store-02\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/websitedemos.net\\\/shoe-store-02\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/websitedemos.net\\\/shoe-store-02\\\/#organization\",\"name\":\"Shoe Store\",\"url\":\"https:\\\/\\\/websitedemos.net\\\/shoe-store-02\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/websitedemos.net\\\/shoe-store-02\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/websitedemos.net\\\/shoe-store-02\\\/wp-content\\\/uploads\\\/sites\\\/930\\\/2021\\\/08\\\/logo-regular.png\",\"contentUrl\":\"https:\\\/\\\/websitedemos.net\\\/shoe-store-02\\\/wp-content\\\/uploads\\\/sites\\\/930\\\/2021\\\/08\\\/logo-regular.png\",\"width\":135,\"height\":15,\"caption\":\"Shoe Store\"},\"image\":{\"@id\":\"https:\\\/\\\/websitedemos.net\\\/shoe-store-02\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Leather Sport Shoes - Shoe Store","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/websitedemos.net\/shoe-store-02\/product\/product-name-7\/","og_locale":"en_US","og_type":"article","og_title":"Leather Sport Shoes - Shoe Store","og_description":"Limited Edition Color, Everest","og_url":"https:\/\/websitedemos.net\/shoe-store-02\/product\/product-name-7\/","og_site_name":"Shoe Store","article_modified_time":"2026-05-06T11:05:51+00:00","og_image":[{"width":1290,"height":1290,"url":"https:\/\/websitedemos.net\/shoe-store-02\/wp-content\/uploads\/sites\/930\/2021\/08\/shoe-09.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/websitedemos.net\/shoe-store-02\/product\/product-name-7\/","url":"https:\/\/websitedemos.net\/shoe-store-02\/product\/product-name-7\/","name":"Leather Sport Shoes - Shoe Store","isPartOf":{"@id":"https:\/\/websitedemos.net\/shoe-store-02\/#website"},"primaryImageOfPage":{"@id":"https:\/\/websitedemos.net\/shoe-store-02\/product\/product-name-7\/#primaryimage"},"image":{"@id":"https:\/\/websitedemos.net\/shoe-store-02\/product\/product-name-7\/#primaryimage"},"thumbnailUrl":"https:\/\/websitedemos.net\/shoe-store-02\/wp-content\/uploads\/sites\/930\/2021\/08\/shoe-09.png","datePublished":"2021-08-17T13:02:14+00:00","dateModified":"2026-05-06T11:05:51+00:00","breadcrumb":{"@id":"https:\/\/websitedemos.net\/shoe-store-02\/product\/product-name-7\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/websitedemos.net\/shoe-store-02\/product\/product-name-7\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/websitedemos.net\/shoe-store-02\/product\/product-name-7\/#primaryimage","url":"https:\/\/websitedemos.net\/shoe-store-02\/wp-content\/uploads\/sites\/930\/2021\/08\/shoe-09.png","contentUrl":"https:\/\/websitedemos.net\/shoe-store-02\/wp-content\/uploads\/sites\/930\/2021\/08\/shoe-09.png","width":1290,"height":1290},{"@type":"BreadcrumbList","@id":"https:\/\/websitedemos.net\/shoe-store-02\/product\/product-name-7\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/websitedemos.net\/shoe-store-02\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/websitedemos.net\/shoe-store-02\/shop\/"},{"@type":"ListItem","position":3,"name":"Leather Sport Shoes"}]},{"@type":"WebSite","@id":"https:\/\/websitedemos.net\/shoe-store-02\/#website","url":"https:\/\/websitedemos.net\/shoe-store-02\/","name":"Shoe Store","description":"Shoe Store Website","publisher":{"@id":"https:\/\/websitedemos.net\/shoe-store-02\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/websitedemos.net\/shoe-store-02\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/websitedemos.net\/shoe-store-02\/#organization","name":"Shoe Store","url":"https:\/\/websitedemos.net\/shoe-store-02\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/websitedemos.net\/shoe-store-02\/#\/schema\/logo\/image\/","url":"https:\/\/websitedemos.net\/shoe-store-02\/wp-content\/uploads\/sites\/930\/2021\/08\/logo-regular.png","contentUrl":"https:\/\/websitedemos.net\/shoe-store-02\/wp-content\/uploads\/sites\/930\/2021\/08\/logo-regular.png","width":135,"height":15,"caption":"Shoe Store"},"image":{"@id":"https:\/\/websitedemos.net\/shoe-store-02\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/websitedemos.net\/shoe-store-02\/wp-json\/wp\/v2\/product\/109","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/websitedemos.net\/shoe-store-02\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/websitedemos.net\/shoe-store-02\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/websitedemos.net\/shoe-store-02\/wp-json\/wp\/v2\/comments?post=109"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/websitedemos.net\/shoe-store-02\/wp-json\/wp\/v2\/media\/349"}],"wp:attachment":[{"href":"https:\/\/websitedemos.net\/shoe-store-02\/wp-json\/wp\/v2\/media?parent=109"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/websitedemos.net\/shoe-store-02\/wp-json\/wp\/v2\/product_brand?post=109"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/websitedemos.net\/shoe-store-02\/wp-json\/wp\/v2\/product_cat?post=109"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/websitedemos.net\/shoe-store-02\/wp-json\/wp\/v2\/product_tag?post=109"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}