{"id":7,"date":"2021-04-09T09:26:42","date_gmt":"2021-04-09T09:26:42","guid":{"rendered":"https:\/\/websitedemos.net\/luxury-hotel-04\/?page_id=7"},"modified":"2024-08-06T12:50:27","modified_gmt":"2024-08-06T12:50:27","slug":"home","status":"publish","type":"page","link":"https:\/\/websitedemos.net\/luxury-hotel-04\/","title":{"rendered":"Home"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"7\" class=\"elementor elementor-7\">\n\t\t\t\t<div class=\"elementor-element elementor-element-714eee0 e-con-full e-flex e-con e-parent\" data-id=\"714eee0\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-1062390 e-con-full e-flex e-con e-child\" data-id=\"1062390\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8ce63fd elementor-widget elementor-widget-heading\" data-id=\"8ce63fd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">Dive into Ultimate Luxury at<\/h6>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1eb2a50 elementor-widget elementor-widget-image-box\" data-id=\"1eb2a50\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><div class=\"elementor-image-box-content\"><h1 class=\"elementor-image-box-title\">The Caeser Grand<\/h1><p class=\"elementor-image-box-description\">Lorem ipsum dolor sit amet, consectetur adipiscing elit. Ut elit tellus, <br \/>luctus nec ullamcorper mattis, pulvinar dapibus leo.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8637ce2 elementor-widget elementor-widget-button\" data-id=\"8637ce2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Make A Reservation<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-19cc3d0 elementor-widget elementor-widget-image-carousel\" data-id=\"19cc3d0\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;none&quot;,&quot;slides_to_show_tablet&quot;:&quot;1&quot;,&quot;slides_to_show_mobile&quot;:&quot;1&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Image Carousel\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper swiper-image-stretch\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 of 4\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/websitedemos.net\/luxury-hotel-04\/wp-content\/uploads\/sites\/812\/2021\/04\/carousel-11-.jpg\" alt=\"carousel-11-\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 of 4\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/websitedemos.net\/luxury-hotel-04\/wp-content\/uploads\/sites\/812\/2021\/04\/carousel12-.jpg\" alt=\"carousel12-\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 of 4\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/websitedemos.net\/luxury-hotel-04\/wp-content\/uploads\/sites\/812\/2021\/04\/carousel13-.jpg\" alt=\"carousel13-\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 of 4\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/websitedemos.net\/luxury-hotel-04\/wp-content\/uploads\/sites\/812\/2021\/04\/carousel14-.jpg\" alt=\"carousel14-\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f4a45e5 e-flex e-con-boxed e-con e-parent\" data-id=\"f4a45e5\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-428a1ec e-con-full e-flex e-con e-child\" data-id=\"428a1ec\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-da2e9ad elementor-widget elementor-widget-heading\" data-id=\"da2e9ad\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">An Escape from Reality<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a8bfba6 elementor-widget elementor-widget-text-editor\" data-id=\"a8bfba6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tQuisque velit nisi, pretium ut lacinia in, elementum id enim. Curabitur non nulla sit amet nisl tempus convallis quis ac lectus. Lorem elit tellus, luctus nec ullamcorper mattis, pulvinar dapibus leo.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c4df2b6 elementor-view-framed elementor-shape-circle elementor-widget elementor-widget-icon\" data-id=\"c4df2b6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<a class=\"elementor-icon elementor-animation-grow\" href=\"#\">\n\t\t\t<i aria-hidden=\"true\" class=\"fas fa-play\"><\/i>\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7d08070 e-con-full e-flex e-con e-parent\" data-id=\"7d08070\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-92712f0 e-con-full e-flex e-con e-child\" data-id=\"92712f0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-df16266 elementor-widget elementor-widget-heading\" data-id=\"df16266\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"> Luxurious Services<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-cfccc70 e-con-full e-flex e-con e-child\" data-id=\"cfccc70\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-13716e0 e-con-full e-flex e-con e-child\" data-id=\"13716e0\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7c63934 elementor-widget elementor-widget-heading\" data-id=\"7c63934\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">In-room Dining<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b36a5fb e-con-full e-flex e-con e-child\" data-id=\"b36a5fb\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0c82358 elementor-widget elementor-widget-heading\" data-id=\"0c82358\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Private Pools<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c761caf e-con-full e-flex e-con e-child\" data-id=\"c761caf\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0a0a2f8 elementor-widget elementor-widget-heading\" data-id=\"0a0a2f8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Concierge Service<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-61ee7d5 e-con-full e-flex e-con e-child\" data-id=\"61ee7d5\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e08bef1 elementor-widget elementor-widget-heading\" data-id=\"e08bef1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">VIP Casino Entries<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a45f3d6 e-flex e-con-boxed e-con e-parent\" data-id=\"a45f3d6\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-b85241c e-con-full e-flex e-con e-child\" data-id=\"b85241c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-31e1165 elementor-widget elementor-widget-heading\" data-id=\"31e1165\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Every corner with a<br> Luxury Touch<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f72314f elementor-widget elementor-widget-text-editor\" data-id=\"f72314f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tLorem elit tellus, luctus nec ullamcorper mattis, pulvinar dapibus leo.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-847dde8 e-con-full e-flex e-con e-child\" data-id=\"847dde8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-c44ccd6 e-con-full e-flex e-con e-child\" data-id=\"c44ccd6\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-de309b3 elementor-widget elementor-widget-image\" data-id=\"de309b3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"414\" height=\"670\" src=\"https:\/\/websitedemos.net\/luxury-hotel-04\/wp-content\/uploads\/sites\/812\/2021\/04\/gallery-new-1.jpeg\" class=\"attachment-large size-large wp-image-671\" alt=\"\" srcset=\"https:\/\/websitedemos.net\/luxury-hotel-04\/wp-content\/uploads\/sites\/812\/2021\/04\/gallery-new-1.jpeg 414w, https:\/\/websitedemos.net\/luxury-hotel-04\/wp-content\/uploads\/sites\/812\/2021\/04\/gallery-new-1-185x300.jpeg 185w, https:\/\/websitedemos.net\/luxury-hotel-04\/wp-content\/uploads\/sites\/812\/2021\/04\/gallery-new-1-400x647.jpeg 400w\" sizes=\"(max-width: 414px) 100vw, 414px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-47cc48b elementor-widget elementor-widget-image\" data-id=\"47cc48b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"414\" height=\"360\" src=\"https:\/\/websitedemos.net\/luxury-hotel-04\/wp-content\/uploads\/sites\/812\/2021\/04\/gallery-new-7.jpeg\" class=\"attachment-large size-large wp-image-676\" alt=\"\" srcset=\"https:\/\/websitedemos.net\/luxury-hotel-04\/wp-content\/uploads\/sites\/812\/2021\/04\/gallery-new-7.jpeg 414w, https:\/\/websitedemos.net\/luxury-hotel-04\/wp-content\/uploads\/sites\/812\/2021\/04\/gallery-new-7-300x261.jpeg 300w, https:\/\/websitedemos.net\/luxury-hotel-04\/wp-content\/uploads\/sites\/812\/2021\/04\/gallery-new-7-400x348.jpeg 400w\" sizes=\"(max-width: 414px) 100vw, 414px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2030191 e-con-full e-flex e-con e-child\" data-id=\"2030191\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-29f66e6 elementor-widget elementor-widget-image\" data-id=\"29f66e6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"591\" height=\"692\" src=\"https:\/\/websitedemos.net\/luxury-hotel-04\/wp-content\/uploads\/sites\/812\/2021\/04\/gallery-new-4.jpeg\" class=\"attachment-large size-large wp-image-677\" alt=\"\" srcset=\"https:\/\/websitedemos.net\/luxury-hotel-04\/wp-content\/uploads\/sites\/812\/2021\/04\/gallery-new-4.jpeg 591w, https:\/\/websitedemos.net\/luxury-hotel-04\/wp-content\/uploads\/sites\/812\/2021\/04\/gallery-new-4-256x300.jpeg 256w, https:\/\/websitedemos.net\/luxury-hotel-04\/wp-content\/uploads\/sites\/812\/2021\/04\/gallery-new-4-400x468.jpeg 400w\" sizes=\"(max-width: 591px) 100vw, 591px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2da95c4 elementor-widget elementor-widget-image\" data-id=\"2da95c4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"867\" height=\"1135\" src=\"https:\/\/websitedemos.net\/luxury-hotel-04\/wp-content\/uploads\/sites\/812\/2021\/04\/gallery-15.jpeg\" class=\"attachment-full size-full wp-image-825\" alt=\"\" srcset=\"https:\/\/websitedemos.net\/luxury-hotel-04\/wp-content\/uploads\/sites\/812\/2021\/04\/gallery-15.jpeg 867w, https:\/\/websitedemos.net\/luxury-hotel-04\/wp-content\/uploads\/sites\/812\/2021\/04\/gallery-15-229x300.jpeg 229w, https:\/\/websitedemos.net\/luxury-hotel-04\/wp-content\/uploads\/sites\/812\/2021\/04\/gallery-15-782x1024.jpeg 782w, https:\/\/websitedemos.net\/luxury-hotel-04\/wp-content\/uploads\/sites\/812\/2021\/04\/gallery-15-768x1005.jpeg 768w, https:\/\/websitedemos.net\/luxury-hotel-04\/wp-content\/uploads\/sites\/812\/2021\/04\/gallery-15-400x524.jpeg 400w\" sizes=\"(max-width: 867px) 100vw, 867px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-459dfc8 e-con-full e-flex e-con e-child\" data-id=\"459dfc8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6209781 elementor-widget-mobile__width-initial elementor-widget elementor-widget-image\" data-id=\"6209781\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"414\" height=\"670\" src=\"https:\/\/websitedemos.net\/luxury-hotel-04\/wp-content\/uploads\/sites\/812\/2021\/04\/gallery-new-5.jpeg\" class=\"attachment-large size-large wp-image-674\" alt=\"\" srcset=\"https:\/\/websitedemos.net\/luxury-hotel-04\/wp-content\/uploads\/sites\/812\/2021\/04\/gallery-new-5.jpeg 414w, https:\/\/websitedemos.net\/luxury-hotel-04\/wp-content\/uploads\/sites\/812\/2021\/04\/gallery-new-5-185x300.jpeg 185w, https:\/\/websitedemos.net\/luxury-hotel-04\/wp-content\/uploads\/sites\/812\/2021\/04\/gallery-new-5-400x647.jpeg 400w\" sizes=\"(max-width: 414px) 100vw, 414px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8e3c895 elementor-widget-mobile__width-initial elementor-widget elementor-widget-image\" data-id=\"8e3c895\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"414\" height=\"360\" src=\"https:\/\/websitedemos.net\/luxury-hotel-04\/wp-content\/uploads\/sites\/812\/2021\/04\/gallery-6.png\" class=\"attachment-large size-large wp-image-214\" alt=\"\" srcset=\"https:\/\/websitedemos.net\/luxury-hotel-04\/wp-content\/uploads\/sites\/812\/2021\/04\/gallery-6.png 414w, https:\/\/websitedemos.net\/luxury-hotel-04\/wp-content\/uploads\/sites\/812\/2021\/04\/gallery-6-300x261.png 300w, https:\/\/websitedemos.net\/luxury-hotel-04\/wp-content\/uploads\/sites\/812\/2021\/04\/gallery-6-400x348.png 400w\" sizes=\"(max-width: 414px) 100vw, 414px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7eb1b32 e-flex e-con-boxed e-con e-parent\" data-id=\"7eb1b32\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-8c62acb e-con-full e-flex e-con e-child\" data-id=\"8c62acb\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-d646544 e-con-full e-flex e-con e-child\" data-id=\"d646544\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-97ab379 e-con-full e-flex e-con e-child\" data-id=\"97ab379\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ff14b57 elementor-widget elementor-widget-heading\" data-id=\"ff14b57\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">Luxury Privileges<\/h6>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b89395a elementor-widget elementor-widget-heading\" data-id=\"b89395a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Membership Benefits<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-294ca8d elementor-widget elementor-widget-text-editor\" data-id=\"294ca8d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tLorem ipsum dolor sit amet, consectetur adipiscing elit. Ut elit tellus, luctus nec ullamcorper mattis, pulvinar dapibus leo.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b1524e4 e-con-full e-flex e-con e-child\" data-id=\"b1524e4\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c8065ca elementor-widget elementor-widget-heading\" data-id=\"c8065ca\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">World-class Stay Benefits<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4b2f766 elementor-widget elementor-widget-text-editor\" data-id=\"4b2f766\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tLorem ipsum dolor sit amet, consec tetur adipiscing. Ut elit tellus, luctus nec nullam corper, pulvinar dapibus leo.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1225fb2 e-con-full e-flex e-con e-child\" data-id=\"1225fb2\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d0c4671 elementor-widget elementor-widget-image\" data-id=\"d0c4671\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/websitedemos.net\/luxury-hotel-04\/wp-content\/uploads\/sites\/812\/2021\/04\/world-class1-300x300.jpg\" class=\"attachment-medium size-medium wp-image-1091\" alt=\"\" srcset=\"https:\/\/websitedemos.net\/luxury-hotel-04\/wp-content\/uploads\/sites\/812\/2021\/04\/world-class1-300x300.jpg 300w, https:\/\/websitedemos.net\/luxury-hotel-04\/wp-content\/uploads\/sites\/812\/2021\/04\/world-class1-150x150.jpg 150w, https:\/\/websitedemos.net\/luxury-hotel-04\/wp-content\/uploads\/sites\/812\/2021\/04\/world-class1-400x400.jpg 400w, https:\/\/websitedemos.net\/luxury-hotel-04\/wp-content\/uploads\/sites\/812\/2021\/04\/world-class1.jpg 427w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-fa19ba7 e-con-full e-flex e-con e-child\" data-id=\"fa19ba7\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-3d23f22 e-con-full e-flex e-con e-child\" data-id=\"3d23f22\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-05755b8 elementor-widget elementor-widget-image\" data-id=\"05755b8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/websitedemos.net\/luxury-hotel-04\/wp-content\/uploads\/sites\/812\/2021\/04\/casino-11-300x300.jpg\" class=\"attachment-medium size-medium wp-image-1087\" alt=\"\" srcset=\"https:\/\/websitedemos.net\/luxury-hotel-04\/wp-content\/uploads\/sites\/812\/2021\/04\/casino-11-300x300.jpg 300w, https:\/\/websitedemos.net\/luxury-hotel-04\/wp-content\/uploads\/sites\/812\/2021\/04\/casino-11-150x150.jpg 150w, https:\/\/websitedemos.net\/luxury-hotel-04\/wp-content\/uploads\/sites\/812\/2021\/04\/casino-11-400x400.jpg 400w, https:\/\/websitedemos.net\/luxury-hotel-04\/wp-content\/uploads\/sites\/812\/2021\/04\/casino-11.jpg 640w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4693b4f e-con-full e-flex e-con e-child\" data-id=\"4693b4f\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a12dafc elementor-widget elementor-widget-heading\" data-id=\"a12dafc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Exclusive Casino Benefits<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-81780ec elementor-widget elementor-widget-text-editor\" data-id=\"81780ec\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tLorem ipsum dolor sit amet, consec tetur adipiscing. Ut elit tellus, luctus nec nullam corper, pulvinar dapibus leo.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b005f72 e-con-full e-flex e-con e-child\" data-id=\"b005f72\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1740e04 elementor-widget elementor-widget-image\" data-id=\"1740e04\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/websitedemos.net\/luxury-hotel-04\/wp-content\/uploads\/sites\/812\/2021\/04\/350x350-3-300x300.png\" class=\"attachment-medium size-medium wp-image-192\" alt=\"\" srcset=\"https:\/\/websitedemos.net\/luxury-hotel-04\/wp-content\/uploads\/sites\/812\/2021\/04\/350x350-3-300x300.png 300w, https:\/\/websitedemos.net\/luxury-hotel-04\/wp-content\/uploads\/sites\/812\/2021\/04\/350x350-3-150x150.png 150w, https:\/\/websitedemos.net\/luxury-hotel-04\/wp-content\/uploads\/sites\/812\/2021\/04\/350x350-3.png 350w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3b812d3 e-con-full e-flex e-con e-child\" data-id=\"3b812d3\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6d87d08 elementor-widget elementor-widget-heading\" data-id=\"6d87d08\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Exclusive Lifestyle Voucher<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5bcca61 elementor-widget elementor-widget-text-editor\" data-id=\"5bcca61\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tLorem ipsum dolor sit amet, consec tetur adipiscing. Ut elit tellus, luctus nec nullam corper, pulvinar dapibus leo.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-598928d e-con-full e-flex e-con e-child\" data-id=\"598928d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-47f9cdf e-con-full e-flex e-con e-child\" data-id=\"47f9cdf\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2853383 elementor-widget elementor-widget-heading\" data-id=\"2853383\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Complementary<br> Wine Bottle <\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7698123 elementor-widget elementor-widget-text-editor\" data-id=\"7698123\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tLorem ipsum dolor sit amet, consec tetur adipiscing. Ut elit tellus, luctus nec nullam corper, pulvinar dapibus leo.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6872806 e-con-full e-flex e-con e-child\" data-id=\"6872806\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-10dcd41 elementor-widget elementor-widget-image\" data-id=\"10dcd41\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/websitedemos.net\/luxury-hotel-04\/wp-content\/uploads\/sites\/812\/2021\/04\/wine-bottle-300x300.jpg\" class=\"attachment-medium size-medium wp-image-1095\" alt=\"\" srcset=\"https:\/\/websitedemos.net\/luxury-hotel-04\/wp-content\/uploads\/sites\/812\/2021\/04\/wine-bottle-300x300.jpg 300w, https:\/\/websitedemos.net\/luxury-hotel-04\/wp-content\/uploads\/sites\/812\/2021\/04\/wine-bottle-150x150.jpg 150w, https:\/\/websitedemos.net\/luxury-hotel-04\/wp-content\/uploads\/sites\/812\/2021\/04\/wine-bottle-400x400.jpg 400w, https:\/\/websitedemos.net\/luxury-hotel-04\/wp-content\/uploads\/sites\/812\/2021\/04\/wine-bottle.jpg 640w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7613f61 e-con-full e-flex e-con e-child\" data-id=\"7613f61\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-504f666 elementor-widget elementor-widget-heading\" data-id=\"504f666\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\"> More Benefits<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3413d42 elementor-widget elementor-widget-text-editor\" data-id=\"3413d42\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tQuisque velit nisi, pretium ut lacinia in, elementum id enim. Curabitur non nulla sit amet nisl tempus convallis quis ac lectus.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-747e002 elementor-tablet-align-center elementor-mobile-align-left elementor-widget elementor-widget-button\" data-id=\"747e002\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Become a Member<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d0d1ab1 e-flex e-con-boxed e-con e-parent\" data-id=\"d0d1ab1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-c3afb67 e-con-full e-flex e-con e-child\" data-id=\"c3afb67\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3f3e405 elementor-widget elementor-widget-heading\" data-id=\"3f3e405\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Ideal Venue For Any Event<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c3d4407 elementor-widget elementor-widget-text-editor\" data-id=\"c3d4407\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tQuisque velit nisi, pretium ut lacinia in, elementum id enim.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e420b23 e-con-full e-flex e-con e-child\" data-id=\"e420b23\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-6d05509 e-con-full e-flex e-con e-child\" data-id=\"6d05509\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8ff67a0 elementor-widget elementor-widget-image\" data-id=\"8ff67a0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"452\" height=\"333\" src=\"https:\/\/websitedemos.net\/luxury-hotel-04\/wp-content\/uploads\/sites\/812\/2021\/04\/event-1.png\" class=\"attachment-large size-large wp-image-243\" alt=\"\" srcset=\"https:\/\/websitedemos.net\/luxury-hotel-04\/wp-content\/uploads\/sites\/812\/2021\/04\/event-1.png 452w, https:\/\/websitedemos.net\/luxury-hotel-04\/wp-content\/uploads\/sites\/812\/2021\/04\/event-1-300x221.png 300w, https:\/\/websitedemos.net\/luxury-hotel-04\/wp-content\/uploads\/sites\/812\/2021\/04\/event-1-400x295.png 400w\" sizes=\"(max-width: 452px) 100vw, 452px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7d54893 elementor-widget elementor-widget-image-box\" data-id=\"7d54893\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><div class=\"elementor-image-box-content\"><h4 class=\"elementor-image-box-title\">Weddings<\/h4><p class=\"elementor-image-box-description\">Lorem ipsum dolor sit amet, consectetur adipiscing elit. Ut elit tellus, luctus nec ullamcorper mattis, pulvinar dapibus leo.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-aea64ab e-con-full e-flex e-con e-child\" data-id=\"aea64ab\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f929a45 elementor-widget elementor-widget-image-box\" data-id=\"f929a45\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><div class=\"elementor-image-box-content\"><h4 class=\"elementor-image-box-title\">Parties<\/h4><p class=\"elementor-image-box-description\">Lorem ipsum dolor sit amet, consectetur adipiscing elit. Ut elit tellus, luctus nec ullamcorper mattis, pulvinar dapibus leo.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-784e7a5 elementor-widget elementor-widget-image\" data-id=\"784e7a5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"452\" height=\"333\" src=\"https:\/\/websitedemos.net\/luxury-hotel-04\/wp-content\/uploads\/sites\/812\/2021\/04\/event-2.png\" class=\"attachment-large size-large wp-image-245\" alt=\"\" srcset=\"https:\/\/websitedemos.net\/luxury-hotel-04\/wp-content\/uploads\/sites\/812\/2021\/04\/event-2.png 452w, https:\/\/websitedemos.net\/luxury-hotel-04\/wp-content\/uploads\/sites\/812\/2021\/04\/event-2-300x221.png 300w, https:\/\/websitedemos.net\/luxury-hotel-04\/wp-content\/uploads\/sites\/812\/2021\/04\/event-2-400x295.png 400w\" sizes=\"(max-width: 452px) 100vw, 452px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2f92c95 e-con-full e-flex e-con e-child\" data-id=\"2f92c95\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-110b108 elementor-widget elementor-widget-image\" data-id=\"110b108\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"452\" height=\"333\" src=\"https:\/\/websitedemos.net\/luxury-hotel-04\/wp-content\/uploads\/sites\/812\/2021\/04\/conference-1.jpg\" class=\"attachment-large size-large wp-image-1101\" alt=\"\" srcset=\"https:\/\/websitedemos.net\/luxury-hotel-04\/wp-content\/uploads\/sites\/812\/2021\/04\/conference-1.jpg 452w, https:\/\/websitedemos.net\/luxury-hotel-04\/wp-content\/uploads\/sites\/812\/2021\/04\/conference-1-300x221.jpg 300w, https:\/\/websitedemos.net\/luxury-hotel-04\/wp-content\/uploads\/sites\/812\/2021\/04\/conference-1-400x295.jpg 400w\" sizes=\"(max-width: 452px) 100vw, 452px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ae815d2 elementor-widget elementor-widget-image-box\" data-id=\"ae815d2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><div class=\"elementor-image-box-content\"><h4 class=\"elementor-image-box-title\">Conference<\/h4><p class=\"elementor-image-box-description\">Lorem ipsum dolor sit amet, consectetur adipiscing elit. Ut elit tellus, luctus nec ullamcorper mattis, pulvinar dapibus leo.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7af717b e-flex e-con-boxed e-con e-parent\" data-id=\"7af717b\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-3541771 e-con-full e-flex e-con e-child\" data-id=\"3541771\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-125deeb elementor-widget elementor-widget-heading\" data-id=\"125deeb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Your search for True Luxury ends here<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cf4e79d elementor-widget elementor-widget-text-editor\" data-id=\"cf4e79d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tLorem ipsum dolor sit amet, consectetur adipiscing elit. Ut elit tellus, luctus nec ullamcorper mattis, pulvinar dapibus leo.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9afc588 e-con-full e-flex e-con e-child\" data-id=\"9afc588\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-46ff7a2 elementor-align-right elementor-tablet-align-center elementor-widget elementor-widget-button\" data-id=\"46ff7a2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Book Now<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Dive into Ultimate Luxury at The Caeser Grand Lorem ipsum dolor sit amet, consectetur adipiscing elit. Ut elit tellus, luctus nec ullamcorper mattis, pulvinar dapibus leo. Make A Reservation An Escape from Reality Quisque velit nisi, pretium ut lacinia in, elementum id enim. Curabitur non nulla sit amet nisl tempus convallis quis ac lectus. Lorem [&hellip;]<\/p>\n","protected":false},"author":156,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"site-sidebar-layout":"no-sidebar","site-content-layout":"page-builder","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"disabled","ast-featured-img":"disabled","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"enabled","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-7","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Home - Luxury Hotel<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/websitedemos.net\/luxury-hotel-04\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Home - Luxury Hotel\" \/>\n<meta property=\"og:description\" content=\"Dive into Ultimate Luxury at The Caeser Grand Lorem ipsum dolor sit amet, consectetur adipiscing elit. Ut elit tellus, luctus nec ullamcorper mattis, pulvinar dapibus leo. Make A Reservation An Escape from Reality Quisque velit nisi, pretium ut lacinia in, elementum id enim. Curabitur non nulla sit amet nisl tempus convallis quis ac lectus. Lorem [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/websitedemos.net\/luxury-hotel-04\/\" \/>\n<meta property=\"og:site_name\" content=\"Luxury Hotel\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-06T12:50:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/websitedemos.net\/luxury-hotel-04\/wp-content\/uploads\/sites\/812\/2021\/04\/carousel-11-.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/websitedemos.net\\\/luxury-hotel-04\\\/\",\"url\":\"https:\\\/\\\/websitedemos.net\\\/luxury-hotel-04\\\/\",\"name\":\"Home - Luxury Hotel\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/websitedemos.net\\\/luxury-hotel-04\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/websitedemos.net\\\/luxury-hotel-04\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/websitedemos.net\\\/luxury-hotel-04\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/websitedemos.net\\\/luxury-hotel-04\\\/wp-content\\\/uploads\\\/sites\\\/812\\\/2021\\\/04\\\/carousel-11-.jpg\",\"datePublished\":\"2021-04-09T09:26:42+00:00\",\"dateModified\":\"2024-08-06T12:50:27+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/websitedemos.net\\\/luxury-hotel-04\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/websitedemos.net\\\/luxury-hotel-04\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/websitedemos.net\\\/luxury-hotel-04\\\/#primaryimage\",\"url\":\"https:\\\/\\\/websitedemos.net\\\/luxury-hotel-04\\\/wp-content\\\/uploads\\\/sites\\\/812\\\/2021\\\/04\\\/carousel-11-.jpg\",\"contentUrl\":\"https:\\\/\\\/websitedemos.net\\\/luxury-hotel-04\\\/wp-content\\\/uploads\\\/sites\\\/812\\\/2021\\\/04\\\/carousel-11-.jpg\",\"width\":1920,\"height\":790},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/websitedemos.net\\\/luxury-hotel-04\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/websitedemos.net\\\/luxury-hotel-04\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Home\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/websitedemos.net\\\/luxury-hotel-04\\\/#website\",\"url\":\"https:\\\/\\\/websitedemos.net\\\/luxury-hotel-04\\\/\",\"name\":\"Luxury Hotel\",\"description\":\"Just another Astra Starter Templates site\",\"publisher\":{\"@id\":\"https:\\\/\\\/websitedemos.net\\\/luxury-hotel-04\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/websitedemos.net\\\/luxury-hotel-04\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/websitedemos.net\\\/luxury-hotel-04\\\/#organization\",\"name\":\"Luxury Hotel\",\"url\":\"https:\\\/\\\/websitedemos.net\\\/luxury-hotel-04\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/websitedemos.net\\\/luxury-hotel-04\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/websitedemos.net\\\/luxury-hotel-04\\\/wp-content\\\/uploads\\\/sites\\\/812\\\/2021\\\/06\\\/logo.svg\",\"contentUrl\":\"https:\\\/\\\/websitedemos.net\\\/luxury-hotel-04\\\/wp-content\\\/uploads\\\/sites\\\/812\\\/2021\\\/06\\\/logo.svg\",\"width\":250,\"height\":91,\"caption\":\"Luxury Hotel\"},\"image\":{\"@id\":\"https:\\\/\\\/websitedemos.net\\\/luxury-hotel-04\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Home - Luxury Hotel","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/websitedemos.net\/luxury-hotel-04\/","og_locale":"en_US","og_type":"article","og_title":"Home - Luxury Hotel","og_description":"Dive into Ultimate Luxury at The Caeser Grand Lorem ipsum dolor sit amet, consectetur adipiscing elit. Ut elit tellus, luctus nec ullamcorper mattis, pulvinar dapibus leo. Make A Reservation An Escape from Reality Quisque velit nisi, pretium ut lacinia in, elementum id enim. Curabitur non nulla sit amet nisl tempus convallis quis ac lectus. Lorem [&hellip;]","og_url":"https:\/\/websitedemos.net\/luxury-hotel-04\/","og_site_name":"Luxury Hotel","article_modified_time":"2024-08-06T12:50:27+00:00","og_image":[{"url":"https:\/\/websitedemos.net\/luxury-hotel-04\/wp-content\/uploads\/sites\/812\/2021\/04\/carousel-11-.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/websitedemos.net\/luxury-hotel-04\/","url":"https:\/\/websitedemos.net\/luxury-hotel-04\/","name":"Home - Luxury Hotel","isPartOf":{"@id":"https:\/\/websitedemos.net\/luxury-hotel-04\/#website"},"primaryImageOfPage":{"@id":"https:\/\/websitedemos.net\/luxury-hotel-04\/#primaryimage"},"image":{"@id":"https:\/\/websitedemos.net\/luxury-hotel-04\/#primaryimage"},"thumbnailUrl":"https:\/\/websitedemos.net\/luxury-hotel-04\/wp-content\/uploads\/sites\/812\/2021\/04\/carousel-11-.jpg","datePublished":"2021-04-09T09:26:42+00:00","dateModified":"2024-08-06T12:50:27+00:00","breadcrumb":{"@id":"https:\/\/websitedemos.net\/luxury-hotel-04\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/websitedemos.net\/luxury-hotel-04\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/websitedemos.net\/luxury-hotel-04\/#primaryimage","url":"https:\/\/websitedemos.net\/luxury-hotel-04\/wp-content\/uploads\/sites\/812\/2021\/04\/carousel-11-.jpg","contentUrl":"https:\/\/websitedemos.net\/luxury-hotel-04\/wp-content\/uploads\/sites\/812\/2021\/04\/carousel-11-.jpg","width":1920,"height":790},{"@type":"BreadcrumbList","@id":"https:\/\/websitedemos.net\/luxury-hotel-04\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/websitedemos.net\/luxury-hotel-04\/"},{"@type":"ListItem","position":2,"name":"Home"}]},{"@type":"WebSite","@id":"https:\/\/websitedemos.net\/luxury-hotel-04\/#website","url":"https:\/\/websitedemos.net\/luxury-hotel-04\/","name":"Luxury Hotel","description":"Just another Astra Starter Templates site","publisher":{"@id":"https:\/\/websitedemos.net\/luxury-hotel-04\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/websitedemos.net\/luxury-hotel-04\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/websitedemos.net\/luxury-hotel-04\/#organization","name":"Luxury Hotel","url":"https:\/\/websitedemos.net\/luxury-hotel-04\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/websitedemos.net\/luxury-hotel-04\/#\/schema\/logo\/image\/","url":"https:\/\/websitedemos.net\/luxury-hotel-04\/wp-content\/uploads\/sites\/812\/2021\/06\/logo.svg","contentUrl":"https:\/\/websitedemos.net\/luxury-hotel-04\/wp-content\/uploads\/sites\/812\/2021\/06\/logo.svg","width":250,"height":91,"caption":"Luxury Hotel"},"image":{"@id":"https:\/\/websitedemos.net\/luxury-hotel-04\/#\/schema\/logo\/image\/"}}]}},"post-meta":{"site-post-title":"disabled","site-sidebar-layout":"no-sidebar","site-content-layout":"page-builder","ast-featured-img":"disabled","ast-breadcrumbs-content":"disabled","theme-transparent-header-meta":"enabled","_yoast_wpseo_estimated-reading-time-minutes":"6","_elementor_edit_mode":"builder","_elementor_template_type":"wp-page","_elementor_version":"3.23.3","_astra_content_layout_flag":"disabled","ast-title-bar-display":"disabled","_wp_page_template":"default","_elementor_data":"[{\"id\":\"714eee0\",\"elType\":\"container\",\"settings\":{\"content_width\":\"full\",\"flex_gap\":{\"size\":0,\"column\":\"0\",\"row\":\"0\",\"unit\":\"px\"},\"overflow\":\"hidden\",\"padding\":{\"unit\":\"px\",\"top\":\"250\",\"right\":\"0\",\"bottom\":\"120\",\"left\":\"250\",\"isLinked\":\"\"},\"margin_tablet\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":\"1\"},\"margin_mobile\":{\"unit\":\"px\",\"top\":\"0\",\"right\":0,\"bottom\":\"0\",\"left\":0,\"isLinked\":\"\"},\"padding_tablet\":{\"unit\":\"px\",\"top\":\"180\",\"right\":\"0\",\"bottom\":\"50\",\"left\":\"50\",\"isLinked\":\"\"},\"padding_mobile\":{\"unit\":\"px\",\"top\":\"120\",\"right\":\"30\",\"bottom\":\"60\",\"left\":\"30\",\"isLinked\":\"\"},\"custom_height\":{\"unit\":\"vh\",\"size\":100,\"sizes\":[]},\"background_position\":\"center center\",\"background_attachment\":\"fixed\",\"background_repeat\":\"no-repeat\",\"background_size\":\"cover\",\"background_overlay_color_b\":\"\",\"background_overlay_gradient_angle\":{\"unit\":\"deg\",\"size\":0,\"sizes\":[]},\"background_overlay_opacity\":{\"unit\":\"px\",\"size\":0.4,\"sizes\":[]},\"background_background\":\"gradient\",\"background_color\":\"#1D264500\",\"background_gradient_angle\":{\"unit\":\"deg\",\"size\":310,\"sizes\":[]},\"background_overlay_background\":\"classic\",\"background_overlay_color\":\"#000000\",\"__globals__\":{\"background_color_b\":\"globals\\\/colors?id=astglobalcolor7\"},\"flex_direction\":\"row\",\"flex_align_items\":\"stretch\"},\"elements\":[{\"id\":\"1062390\",\"elType\":\"container\",\"settings\":{\"_column_size\":\"100\",\"margin_tablet\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":\"\"},\"padding_tablet\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":\"\"},\"content_width\":\"full\",\"padding\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":false}},\"elements\":[{\"id\":\"8ce63fd\",\"elType\":\"widget\",\"settings\":{\"title\":\"Dive into Ultimate Luxury at\",\"header_size\":\"h6\",\"content_width\":\"full\"},\"elements\":[],\"widgetType\":\"heading\"},{\"id\":\"1eb2a50\",\"elType\":\"widget\",\"settings\":{\"image\":{\"url\":\"\",\"id\":\"\"},\"title_text\":\"The Caeser Grand\",\"description_text\":\"Lorem ipsum dolor sit amet, consectetur adipiscing elit. Ut elit tellus, <br\\\/>luctus nec ullamcorper mattis, pulvinar dapibus leo.\",\"title_size\":\"h1\",\"text_align\":\"left\",\"_margin\":{\"unit\":\"%\",\"top\":\"\",\"right\":\"\",\"bottom\":\"\",\"left\":\"\",\"isLinked\":true},\"content_width\":\"full\"},\"elements\":[],\"widgetType\":\"image-box\"},{\"id\":\"8637ce2\",\"elType\":\"widget\",\"settings\":{\"text\":\"Make A Reservation\",\"border_width\":{\"unit\":\"px\",\"top\":\"1\",\"right\":\"1\",\"bottom\":\"1\",\"left\":\"1\",\"isLinked\":\"1\"},\"_element_custom_width\":{\"unit\":\"px\",\"size\":\"240\",\"sizes\":[]},\"_element_vertical_align\":\"center\",\"_margin\":{\"unit\":\"px\",\"top\":\"30\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":false},\"icon_indent\":{\"unit\":\"px\",\"size\":0,\"sizes\":[]},\"_margin_tablet\":{\"unit\":\"px\",\"top\":\"15\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":false},\"content_width\":\"full\"},\"elements\":[],\"widgetType\":\"button\"},{\"id\":\"19cc3d0\",\"elType\":\"widget\",\"settings\":{\"carousel\":[{\"id\":\"1328\",\"url\":\"https:\\\/\\\/websitedemos.net\\\/luxury-hotel-04\\\/wp-content\\\/uploads\\\/sites\\\/812\\\/2021\\\/04\\\/carousel-11-.jpg\"},{\"id\":\"1329\",\"url\":\"https:\\\/\\\/websitedemos.net\\\/luxury-hotel-04\\\/wp-content\\\/uploads\\\/sites\\\/812\\\/2021\\\/04\\\/carousel12-.jpg\"},{\"id\":\"1330\",\"url\":\"https:\\\/\\\/websitedemos.net\\\/luxury-hotel-04\\\/wp-content\\\/uploads\\\/sites\\\/812\\\/2021\\\/04\\\/carousel13-.jpg\"},{\"id\":\"1331\",\"url\":\"https:\\\/\\\/websitedemos.net\\\/luxury-hotel-04\\\/wp-content\\\/uploads\\\/sites\\\/812\\\/2021\\\/04\\\/carousel14-.jpg\"}],\"thumbnail_size\":\"full\",\"thumbnail_custom_dimension\":{\"width\":\"1500\",\"height\":\"847\"},\"slides_to_show\":\"1\",\"image_stretch\":\"yes\",\"navigation\":\"none\",\"_margin\":{\"unit\":\"px\",\"top\":\"100\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":\"\"},\"_padding\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":\"\"},\"image_border_radius\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":\"\"},\"slides_to_show_tablet\":\"1\",\"slides_to_show_mobile\":\"1\",\"_margin_mobile\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":\"\"},\"_padding_tablet\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":\"\"},\"_padding_mobile\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":\"\"},\"_margin_tablet\":{\"unit\":\"px\",\"top\":\"50\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":false},\"content_width\":\"full\"},\"elements\":[],\"widgetType\":\"image-carousel\"}],\"isInner\":true}],\"isInner\":false},{\"id\":\"f4a45e5\",\"elType\":\"container\",\"settings\":{\"padding\":{\"unit\":\"px\",\"top\":\"100\",\"right\":\"0\",\"bottom\":\"100\",\"left\":\"0\",\"isLinked\":false},\"margin_mobile\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":\"\"},\"padding_mobile\":{\"unit\":\"px\",\"top\":\"20\",\"right\":\"20\",\"bottom\":\"20\",\"left\":\"20\",\"isLinked\":true},\"flex_gap\":{\"size\":0,\"column\":\"0\",\"row\":\"0\",\"unit\":\"px\"},\"padding_tablet\":{\"unit\":\"px\",\"top\":\"50\",\"right\":\"50\",\"bottom\":\"50\",\"left\":\"50\",\"isLinked\":true},\"background_background\":\"classic\",\"background_image\":{\"url\":\"https:\\\/\\\/websitedemos.net\\\/luxury-hotel-04\\\/wp-content\\\/uploads\\\/sites\\\/812\\\/2021\\\/06\\\/facilities-list-bg.jpg\",\"id\":1599},\"background_position\":\"center center\",\"background_attachment\":\"fixed\",\"background_repeat\":\"no-repeat\",\"background_size\":\"cover\",\"background_overlay_background\":\"classic\",\"margin\":{\"unit\":\"px\",\"top\":\"0\",\"right\":0,\"bottom\":\"0\",\"left\":0,\"isLinked\":false},\"__globals__\":{\"background_overlay_color\":\"globals\\\/colors?id=astglobalcolor7\"},\"flex_direction\":\"row\",\"flex_align_items\":\"stretch\"},\"elements\":[{\"id\":\"428a1ec\",\"elType\":\"container\",\"settings\":{\"_column_size\":\"100\",\"padding_mobile\":{\"unit\":\"px\",\"top\":\"40\",\"right\":\"20\",\"bottom\":\"40\",\"left\":\"20\",\"isLinked\":false},\"margin\":{\"unit\":\"%\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":true},\"padding\":{\"unit\":\"%\",\"top\":\"8\",\"right\":\"35\",\"bottom\":\"8\",\"left\":\"8\",\"isLinked\":false},\"flex_justify_content\":\"center\",\"background_background\":\"classic\",\"background_position\":\"center center\",\"background_attachment\":\"fixed\",\"background_repeat\":\"no-repeat\",\"background_size\":\"cover\",\"background_overlay_background\":\"classic\",\"border_radius\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":\"\"},\"margin_mobile\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":\"\"},\"z_index\":\"1\",\"padding_tablet\":{\"unit\":\"px\",\"top\":\"50\",\"right\":\"50\",\"bottom\":\"50\",\"left\":\"50\",\"isLinked\":true},\"background_overlay_opacity\":{\"unit\":\"px\",\"size\":0.8,\"sizes\":[]},\"border_border\":\"solid\",\"border_width\":{\"unit\":\"px\",\"top\":\"1\",\"right\":\"1\",\"bottom\":\"1\",\"left\":\"1\",\"isLinked\":true},\"border_color\":\"#353232\",\"__globals__\":{\"background_overlay_color\":\"globals\\\/colors?id=astglobalcolor4\"},\"content_width\":\"full\"},\"elements\":[{\"id\":\"da2e9ad\",\"elType\":\"widget\",\"settings\":{\"title\":\"An Escape from Reality\",\"align\":\"left\",\"__globals__\":{\"title_color\":\"globals\\\/colors?id=astglobalcolor0\"},\"content_width\":\"full\"},\"elements\":[],\"widgetType\":\"heading\"},{\"id\":\"a8bfba6\",\"elType\":\"widget\",\"settings\":{\"editor\":\"Quisque velit nisi, pretium ut lacinia in, elementum id enim. Curabitur non nulla sit amet nisl tempus convallis quis ac lectus. Lorem elit tellus, luctus nec ullamcorper mattis, pulvinar dapibus leo.\",\"text_columns\":\"1\",\"column_gap\":{\"unit\":\"px\",\"size\":\"0\",\"sizes\":[]},\"_padding_mobile\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"25\",\"left\":\"0\",\"isLinked\":\"\"},\"typography_typography\":\"custom\",\"typography_font_size_mobile\":{\"unit\":\"px\",\"size\":13,\"sizes\":[]},\"content_width\":\"full\"},\"elements\":[],\"widgetType\":\"text-editor\"},{\"id\":\"c4df2b6\",\"elType\":\"widget\",\"settings\":{\"selected_icon\":{\"value\":\"fas fa-play\",\"library\":\"fa-solid\"},\"view\":\"framed\",\"size\":{\"unit\":\"px\",\"size\":25,\"sizes\":[]},\"icon_padding\":{\"unit\":\"px\",\"size\":20,\"sizes\":[]},\"border_width\":{\"unit\":\"px\",\"top\":\"2\",\"right\":\"2\",\"bottom\":\"2\",\"left\":\"2\",\"isLinked\":true},\"_margin\":{\"unit\":\"px\",\"top\":\"50\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":false},\"link\":{\"url\":\"#\",\"is_external\":\"\",\"nofollow\":\"\",\"custom_attributes\":\"\"},\"hover_animation\":\"grow\",\"size_tablet\":{\"unit\":\"px\",\"size\":15,\"sizes\":[]},\"align\":\"\",\"size_mobile\":{\"unit\":\"px\",\"size\":13,\"sizes\":[]},\"_margin_tablet\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":false},\"_padding_tablet\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":false},\"__globals__\":{\"primary_color\":\"globals\\\/colors?id=astglobalcolor0\",\"hover_primary_color\":\"globals\\\/colors?id=astglobalcolor1\"},\"content_width\":\"full\"},\"elements\":[],\"widgetType\":\"icon\"}],\"isInner\":true}],\"isInner\":false},{\"id\":\"7d08070\",\"elType\":\"container\",\"settings\":{\"flex_gap\":{\"size\":0,\"column\":\"0\",\"row\":\"0\",\"unit\":\"px\"},\"padding\":{\"unit\":\"px\",\"top\":\"120\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":\"\"},\"custom_height\":{\"unit\":\"vh\",\"size\":\"100\",\"sizes\":[]},\"padding_tablet\":{\"unit\":\"px\",\"top\":\"50\",\"right\":\"50\",\"bottom\":\"50\",\"left\":\"50\",\"isLinked\":true},\"padding_mobile\":{\"unit\":\"px\",\"top\":\"50\",\"right\":\"0\",\"bottom\":\"50\",\"left\":\"0\",\"isLinked\":\"\"},\"content_width\":\"full\",\"flex_direction\":\"row\",\"flex_align_items\":\"stretch\"},\"elements\":[{\"id\":\"92712f0\",\"elType\":\"container\",\"settings\":{\"_column_size\":\"100\",\"padding_mobile\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"25\",\"bottom\":\"0\",\"left\":\"25\",\"isLinked\":\"\"},\"content_width\":\"full\",\"padding\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":false}},\"elements\":[{\"id\":\"df16266\",\"elType\":\"widget\",\"settings\":{\"title\":\" Luxurious Services\",\"align\":\"center\",\"align_mobile\":\"left\",\"_padding\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":true},\"align_tablet\":\"center\",\"_margin_tablet\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":false},\"_padding_tablet\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":false},\"content_width\":\"full\"},\"elements\":[],\"widgetType\":\"heading\"},{\"id\":\"cfccc70\",\"elType\":\"container\",\"settings\":{\"flex_gap\":{\"size\":0,\"column\":\"0\",\"row\":\"0\",\"unit\":\"px\"},\"structure\":\"40\",\"padding_tablet\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":false},\"padding_mobile\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":\"\"},\"content_width\":\"full\",\"margin\":{\"unit\":\"px\",\"top\":\"50\",\"right\":0,\"bottom\":\"0\",\"left\":0,\"isLinked\":false},\"margin_tablet\":{\"unit\":\"px\",\"top\":\"20\",\"right\":0,\"bottom\":\"0\",\"left\":0,\"isLinked\":false},\"padding\":{\"unit\":\"%\",\"top\":\"0\",\"right\":\"10\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":false},\"flex_direction\":\"row\",\"flex_align_items\":\"stretch\",\"flex_wrap_tablet\":\"wrap\"},\"elements\":[{\"id\":\"13716e0\",\"elType\":\"container\",\"settings\":{\"_column_size\":25,\"flex_justify_content\":\"flex-end\",\"flex_gap\":{\"size\":\"10\",\"column\":\"10\",\"row\":\"10\",\"unit\":\"px\"},\"background_background\":\"classic\",\"box_shadow_box_shadow\":{\"horizontal\":\"0\",\"vertical\":\"0\",\"blur\":\"45\",\"spread\":\"0\",\"color\":\"#FFFFFF\"},\"margin\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":\"1\"},\"padding\":{\"unit\":\"px\",\"top\":\"400\",\"right\":\"50\",\"bottom\":\"50\",\"left\":\"50\",\"isLinked\":\"\"},\"background_hover_background\":\"classic\",\"background_hover_color\":\"#C0925F\",\"background_hover_transition\":{\"unit\":\"px\",\"size\":\"1.3\",\"sizes\":[]},\"border_width\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"2\",\"bottom\":\"2\",\"left\":\"0\",\"isLinked\":\"\"},\"z_index\":\"1\",\"background_image\":{\"url\":\"https:\\\/\\\/websitedemos.net\\\/luxury-hotel-04\\\/wp-content\\\/uploads\\\/sites\\\/812\\\/2021\\\/04\\\/world-class1.jpg\",\"id\":1091,\"alt\":\"\",\"source\":\"library\"},\"background_position\":\"center center\",\"background_attachment\":\"scroll\",\"background_repeat\":\"no-repeat\",\"background_size\":\"cover\",\"background_overlay_background\":\"gradient\",\"background_overlay_hover_background\":\"classic\",\"background_overlay_hover_color\":\"#000000\",\"background_overlay_hover_opacity\":{\"unit\":\"px\",\"size\":\"0.29\",\"sizes\":[]},\"border_radius\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":\"\"},\"width\":{\"size\":null,\"unit\":\"%\"},\"width_tablet\":{\"size\":50,\"unit\":\"%\"},\"background_overlay_color_b\":\"#FFFFFF00\",\"background_overlay_gradient_angle\":{\"unit\":\"deg\",\"size\":75,\"sizes\":[]},\"background_overlay_color_stop\":{\"unit\":\"%\",\"size\":15,\"sizes\":[]},\"background_overlay_opacity\":{\"unit\":\"px\",\"size\":0.7,\"sizes\":[]},\"padding_tablet\":{\"unit\":\"px\",\"top\":\"130\",\"right\":\"30\",\"bottom\":\"30\",\"left\":\"30\",\"isLinked\":false},\"__globals__\":{\"background_overlay_color\":\"globals\\\/colors?id=astglobalcolor7\"},\"content_width\":\"full\"},\"elements\":[{\"id\":\"7c63934\",\"elType\":\"widget\",\"settings\":{\"title\":\"In-room Dining\",\"header_size\":\"h5\",\"align\":\"left\",\"title_color\":\"#FFFFFF\",\"align_mobile\":\"left\",\"_margin_mobile\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":\"1\"},\"_padding_mobile\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"25\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":\"\"},\"content_width\":\"full\"},\"elements\":[],\"widgetType\":\"heading\"}],\"isInner\":true},{\"id\":\"b36a5fb\",\"elType\":\"container\",\"settings\":{\"_column_size\":25,\"flex_justify_content\":\"flex-end\",\"flex_gap\":{\"size\":\"10\",\"column\":\"10\",\"row\":\"10\",\"unit\":\"px\"},\"background_background\":\"classic\",\"box_shadow_box_shadow\":{\"horizontal\":\"0\",\"vertical\":\"0\",\"blur\":\"45\",\"spread\":\"0\",\"color\":\"#FFFFFF\"},\"margin\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":\"1\"},\"padding\":{\"unit\":\"px\",\"top\":\"400\",\"right\":\"50\",\"bottom\":\"50\",\"left\":\"50\",\"isLinked\":\"\"},\"background_hover_background\":\"classic\",\"background_hover_color\":\"#C0925F\",\"background_hover_transition\":{\"unit\":\"px\",\"size\":\"1.3\",\"sizes\":[]},\"border_width\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"2\",\"bottom\":\"2\",\"left\":\"0\",\"isLinked\":\"\"},\"z_index\":\"1\",\"background_image\":{\"url\":\"https:\\\/\\\/websitedemos.net\\\/luxury-hotel-04\\\/wp-content\\\/uploads\\\/sites\\\/812\\\/2021\\\/06\\\/facilities-list-bg.jpg\",\"id\":1599,\"alt\":\"\",\"source\":\"library\"},\"background_position\":\"center center\",\"background_attachment\":\"scroll\",\"background_repeat\":\"no-repeat\",\"background_size\":\"cover\",\"background_overlay_background\":\"gradient\",\"background_overlay_hover_background\":\"classic\",\"background_overlay_hover_color\":\"#000000\",\"background_overlay_hover_opacity\":{\"unit\":\"px\",\"size\":\"0.29\",\"sizes\":[]},\"border_radius\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":\"\"},\"width\":{\"size\":null,\"unit\":\"%\"},\"width_tablet\":{\"size\":50,\"unit\":\"%\"},\"background_overlay_color_b\":\"#FFFFFF00\",\"background_overlay_gradient_angle\":{\"unit\":\"deg\",\"size\":75,\"sizes\":[]},\"background_overlay_color_stop\":{\"unit\":\"%\",\"size\":15,\"sizes\":[]},\"background_overlay_opacity\":{\"unit\":\"px\",\"size\":0.7,\"sizes\":[]},\"padding_tablet\":{\"unit\":\"px\",\"top\":\"130\",\"right\":\"30\",\"bottom\":\"30\",\"left\":\"30\",\"isLinked\":false},\"__globals__\":{\"background_overlay_color\":\"globals\\\/colors?id=astglobalcolor7\",\"background_overlay_hover_color\":\"globals\\\/colors?id=astglobalcolor4\"},\"content_width\":\"full\"},\"elements\":[{\"id\":\"0c82358\",\"elType\":\"widget\",\"settings\":{\"title\":\"Private Pools\",\"header_size\":\"h5\",\"align\":\"left\",\"title_color\":\"#FFFFFF\",\"content_width\":\"full\"},\"elements\":[],\"widgetType\":\"heading\"}],\"isInner\":true},{\"id\":\"c761caf\",\"elType\":\"container\",\"settings\":{\"_column_size\":25,\"flex_justify_content\":\"flex-end\",\"flex_gap\":{\"size\":\"10\",\"column\":\"10\",\"row\":\"10\",\"unit\":\"px\"},\"background_background\":\"classic\",\"margin\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":\"1\"},\"padding\":{\"unit\":\"px\",\"top\":\"400\",\"right\":\"50\",\"bottom\":\"50\",\"left\":\"50\",\"isLinked\":\"\"},\"z_index\":\"1\",\"background_hover_background\":\"classic\",\"background_hover_color\":\"#C0925F\",\"border_width\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"2\",\"bottom\":\"2\",\"left\":\"0\",\"isLinked\":\"\"},\"box_shadow_box_shadow\":{\"horizontal\":\"0\",\"vertical\":\"0\",\"blur\":\"45\",\"spread\":\"0\",\"color\":\"#FFFFFF\"},\"background_image\":{\"url\":\"https:\\\/\\\/websitedemos.net\\\/luxury-hotel-04\\\/wp-content\\\/uploads\\\/sites\\\/812\\\/2021\\\/04\\\/Concierge.jpg\",\"id\":1009,\"alt\":\"\",\"source\":\"library\"},\"background_position\":\"center center\",\"background_attachment\":\"scroll\",\"background_repeat\":\"no-repeat\",\"background_size\":\"cover\",\"background_hover_transition\":{\"unit\":\"px\",\"size\":\"1.3\",\"sizes\":[]},\"background_overlay_background\":\"gradient\",\"background_overlay_hover_background\":\"classic\",\"background_overlay_hover_color\":\"#000000\",\"background_overlay_hover_opacity\":{\"unit\":\"px\",\"size\":\"0.29\",\"sizes\":[]},\"border_radius\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":\"\"},\"width\":{\"size\":null,\"unit\":\"%\"},\"width_tablet\":{\"size\":50,\"unit\":\"%\"},\"background_overlay_color_b\":\"#FFFFFF00\",\"background_overlay_gradient_angle\":{\"unit\":\"deg\",\"size\":75,\"sizes\":[]},\"background_overlay_color_stop\":{\"unit\":\"%\",\"size\":15,\"sizes\":[]},\"background_overlay_opacity\":{\"unit\":\"px\",\"size\":0.7,\"sizes\":[]},\"padding_tablet\":{\"unit\":\"px\",\"top\":\"130\",\"right\":\"30\",\"bottom\":\"30\",\"left\":\"30\",\"isLinked\":false},\"__globals__\":{\"background_overlay_color\":\"globals\\\/colors?id=astglobalcolor7\"},\"content_width\":\"full\"},\"elements\":[{\"id\":\"0a0a2f8\",\"elType\":\"widget\",\"settings\":{\"title\":\"Concierge Service\",\"header_size\":\"h5\",\"align\":\"left\",\"title_color\":\"#FFFFFF\",\"content_width\":\"full\"},\"elements\":[],\"widgetType\":\"heading\"}],\"isInner\":true},{\"id\":\"61ee7d5\",\"elType\":\"container\",\"settings\":{\"_column_size\":25,\"flex_justify_content\":\"flex-end\",\"flex_gap\":{\"size\":\"10\",\"column\":\"10\",\"row\":\"10\",\"unit\":\"px\"},\"background_background\":\"classic\",\"margin\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":\"1\"},\"padding\":{\"unit\":\"px\",\"top\":\"400\",\"right\":\"50\",\"bottom\":\"50\",\"left\":\"50\",\"isLinked\":\"\"},\"z_index\":\"1\",\"background_hover_background\":\"classic\",\"background_hover_color\":\"#C0925F\",\"border_width\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"2\",\"bottom\":\"2\",\"left\":\"0\",\"isLinked\":\"\"},\"box_shadow_box_shadow\":{\"horizontal\":\"0\",\"vertical\":\"0\",\"blur\":\"45\",\"spread\":\"0\",\"color\":\"#FFFFFF\"},\"background_image\":{\"url\":\"https:\\\/\\\/websitedemos.net\\\/luxury-hotel-04\\\/wp-content\\\/uploads\\\/sites\\\/812\\\/2021\\\/04\\\/games.jpg\",\"id\":958,\"alt\":\"\",\"source\":\"library\"},\"background_position\":\"center center\",\"background_attachment\":\"scroll\",\"background_repeat\":\"no-repeat\",\"background_size\":\"cover\",\"background_hover_transition\":{\"unit\":\"px\",\"size\":\"1.3\",\"sizes\":[]},\"background_overlay_background\":\"gradient\",\"background_overlay_hover_background\":\"classic\",\"background_overlay_hover_color\":\"#000000\",\"background_overlay_hover_opacity\":{\"unit\":\"px\",\"size\":\"0.29\",\"sizes\":[]},\"border_radius\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":\"\"},\"width\":{\"size\":null,\"unit\":\"%\"},\"width_tablet\":{\"size\":50,\"unit\":\"%\"},\"background_overlay_color_b\":\"#FFFFFF00\",\"background_overlay_gradient_angle\":{\"unit\":\"deg\",\"size\":75,\"sizes\":[]},\"background_overlay_color_stop\":{\"unit\":\"%\",\"size\":15,\"sizes\":[]},\"background_overlay_opacity\":{\"unit\":\"px\",\"size\":0.7,\"sizes\":[]},\"padding_tablet\":{\"unit\":\"px\",\"top\":\"130\",\"right\":\"30\",\"bottom\":\"30\",\"left\":\"30\",\"isLinked\":false},\"__globals__\":{\"background_overlay_color\":\"globals\\\/colors?id=astglobalcolor7\"},\"content_width\":\"full\"},\"elements\":[{\"id\":\"e08bef1\",\"elType\":\"widget\",\"settings\":{\"title\":\"VIP Casino Entries\",\"header_size\":\"h5\",\"align\":\"left\",\"title_color\":\"#FFFFFF\",\"content_width\":\"full\"},\"elements\":[],\"widgetType\":\"heading\"}],\"isInner\":true}],\"isInner\":true}],\"isInner\":true}],\"isInner\":false},{\"id\":\"a45f3d6\",\"elType\":\"container\",\"settings\":{\"flex_gap\":{\"size\":0,\"column\":\"0\",\"row\":\"0\",\"unit\":\"px\"},\"custom_height\":{\"unit\":\"vh\",\"size\":\"100\",\"sizes\":[]},\"overflow\":\"hidden\",\"padding\":{\"unit\":\"px\",\"top\":\"120\",\"right\":\"0\",\"bottom\":\"120\",\"left\":\"0\",\"isLinked\":\"\"},\"margin_tablet\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":\"\"},\"padding_tablet\":{\"unit\":\"px\",\"top\":\"50\",\"right\":\"50\",\"bottom\":\"50\",\"left\":\"50\",\"isLinked\":true},\"padding_mobile\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"20\",\"bottom\":\"50\",\"left\":\"20\",\"isLinked\":\"\"},\"flex_direction\":\"row\",\"flex_align_items\":\"stretch\"},\"elements\":[{\"id\":\"b85241c\",\"elType\":\"container\",\"settings\":{\"_column_size\":\"100\",\"margin_tablet\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":false},\"padding_tablet\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":false},\"padding_mobile\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":true},\"content_width\":\"full\",\"padding\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":false}},\"elements\":[{\"id\":\"31e1165\",\"elType\":\"widget\",\"settings\":{\"title\":\"Every corner with a<br> Luxury Touch\",\"header_size\":\"h3\",\"align\":\"center\",\"align_mobile\":\"left\",\"content_width\":\"full\"},\"elements\":[],\"widgetType\":\"heading\"},{\"id\":\"f72314f\",\"elType\":\"widget\",\"settings\":{\"editor\":\"Lorem elit tellus, luctus nec ullamcorper mattis, pulvinar dapibus leo.\",\"align\":\"center\",\"align_mobile\":\"left\",\"_margin\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":false},\"content_width\":\"full\"},\"elements\":[],\"widgetType\":\"text-editor\"},{\"id\":\"847dde8\",\"elType\":\"container\",\"settings\":{\"structure\":\"30\",\"padding\":{\"unit\":\"px\",\"top\":\"50\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":\"\"},\"margin_mobile\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":\"\"},\"padding_tablet\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":true},\"padding_mobile\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":\"\"},\"margin_tablet\":{\"unit\":\"px\",\"top\":\"0\",\"right\":0,\"bottom\":\"0\",\"left\":0,\"isLinked\":false},\"flex_direction\":\"row\",\"flex_align_items\":\"stretch\",\"flex_gap\":{\"size\":0,\"column\":\"0\",\"row\":\"0\",\"unit\":\"px\"},\"content_width\":\"full\"},\"elements\":[{\"id\":\"c44ccd6\",\"elType\":\"container\",\"settings\":{\"_column_size\":\"33\",\"width_mobile\":{\"size\":50,\"unit\":\"%\"},\"content_width\":\"full\",\"width\":{\"unit\":\"%\",\"size\":33.33,\"sizes\":[]},\"padding\":{\"unit\":\"px\",\"top\":\"10\",\"right\":\"10\",\"bottom\":\"10\",\"left\":\"10\",\"isLinked\":true}},\"elements\":[{\"id\":\"de309b3\",\"elType\":\"widget\",\"settings\":{\"image\":{\"url\":\"https:\\\/\\\/websitedemos.net\\\/luxury-hotel-04\\\/wp-content\\\/uploads\\\/sites\\\/812\\\/2021\\\/04\\\/gallery-new-1.jpeg\",\"id\":\"671\"},\"background_hover_transition\":{\"unit\":\"px\",\"size\":\"0.9\",\"sizes\":[]},\"width_mobile\":{\"unit\":\"%\",\"size\":100,\"sizes\":[]},\"content_width\":\"full\"},\"elements\":[],\"widgetType\":\"image\"},{\"id\":\"47cc48b\",\"elType\":\"widget\",\"settings\":{\"image\":{\"url\":\"https:\\\/\\\/websitedemos.net\\\/luxury-hotel-04\\\/wp-content\\\/uploads\\\/sites\\\/812\\\/2021\\\/04\\\/gallery-new-7.jpeg\",\"id\":\"676\"},\"background_hover_transition\":{\"unit\":\"px\",\"size\":\"0.9\",\"sizes\":[]},\"width_mobile\":{\"unit\":\"%\",\"size\":100,\"sizes\":[]},\"content_width\":\"full\"},\"elements\":[],\"widgetType\":\"image\"}],\"isInner\":true},{\"id\":\"2030191\",\"elType\":\"container\",\"settings\":{\"_column_size\":\"33\",\"width_mobile\":{\"size\":50,\"unit\":\"%\"},\"content_width\":\"full\",\"width\":{\"unit\":\"%\",\"size\":33.33,\"sizes\":[]},\"padding\":{\"unit\":\"px\",\"top\":\"10\",\"right\":\"10\",\"bottom\":\"10\",\"left\":\"10\",\"isLinked\":true}},\"elements\":[{\"id\":\"29f66e6\",\"elType\":\"widget\",\"settings\":{\"image\":{\"url\":\"https:\\\/\\\/websitedemos.net\\\/luxury-hotel-04\\\/wp-content\\\/uploads\\\/sites\\\/812\\\/2021\\\/04\\\/gallery-new-4.jpeg\",\"id\":\"677\"},\"background_hover_transition\":{\"unit\":\"px\",\"size\":\"0.9\",\"sizes\":[]},\"width_mobile\":{\"unit\":\"%\",\"size\":100,\"sizes\":[]},\"content_width\":\"full\"},\"elements\":[],\"widgetType\":\"image\"},{\"id\":\"2da95c4\",\"elType\":\"widget\",\"settings\":{\"image\":{\"url\":\"https:\\\/\\\/websitedemos.net\\\/luxury-hotel-04\\\/wp-content\\\/uploads\\\/sites\\\/812\\\/2021\\\/04\\\/gallery-15.jpeg\",\"id\":\"825\"},\"background_hover_transition\":{\"unit\":\"px\",\"size\":\"0.9\",\"sizes\":[]},\"image_size\":\"full\",\"space\":{\"unit\":\"px\",\"size\":\"\",\"sizes\":[]},\"height\":{\"unit\":\"vh\",\"size\":\"\",\"sizes\":[]},\"width_mobile\":{\"unit\":\"%\",\"size\":100,\"sizes\":[]},\"content_width\":\"full\"},\"elements\":[],\"widgetType\":\"image\"}],\"isInner\":true},{\"id\":\"459dfc8\",\"elType\":\"container\",\"settings\":{\"_column_size\":\"33\",\"align_mobile\":\"space-between\",\"content_width\":\"full\",\"width\":{\"unit\":\"%\",\"size\":33.33,\"sizes\":[]},\"flex_direction_mobile\":\"row\",\"flex_gap_mobile\":{\"column\":\"18\",\"row\":\"0\",\"isLinked\":false,\"unit\":\"px\",\"size\":18},\"padding\":{\"unit\":\"px\",\"top\":\"10\",\"right\":\"10\",\"bottom\":\"10\",\"left\":\"10\",\"isLinked\":true}},\"elements\":[{\"id\":\"6209781\",\"elType\":\"widget\",\"settings\":{\"image\":{\"url\":\"https:\\\/\\\/websitedemos.net\\\/luxury-hotel-04\\\/wp-content\\\/uploads\\\/sites\\\/812\\\/2021\\\/04\\\/gallery-new-5.jpeg\",\"id\":\"674\"},\"background_hover_transition\":{\"unit\":\"px\",\"size\":\"0.9\",\"sizes\":[]},\"width_mobile\":{\"unit\":\"%\",\"size\":100,\"sizes\":[]},\"_element_width_mobile\":\"initial\",\"_element_custom_width_mobile\":{\"unit\":\"%\",\"size\":47,\"sizes\":[]},\"content_width\":\"full\"},\"elements\":[],\"widgetType\":\"image\"},{\"id\":\"8e3c895\",\"elType\":\"widget\",\"settings\":{\"image\":{\"url\":\"https:\\\/\\\/websitedemos.net\\\/luxury-hotel-04\\\/wp-content\\\/uploads\\\/sites\\\/812\\\/2021\\\/04\\\/gallery-6.png\",\"id\":\"214\"},\"background_hover_transition\":{\"unit\":\"px\",\"size\":\"0.9\",\"sizes\":[]},\"width_mobile\":{\"unit\":\"%\",\"size\":100,\"sizes\":[]},\"_element_width_mobile\":\"initial\",\"_element_custom_width_mobile\":{\"unit\":\"%\",\"size\":47,\"sizes\":[]},\"content_width\":\"full\"},\"elements\":[],\"widgetType\":\"image\"}],\"isInner\":true}],\"isInner\":true}],\"isInner\":true}],\"isInner\":false},{\"id\":\"7eb1b32\",\"elType\":\"container\",\"settings\":{\"flex_gap\":{\"size\":0,\"column\":\"0\",\"row\":\"0\",\"unit\":\"px\"},\"background_background\":\"classic\",\"padding\":{\"unit\":\"px\",\"top\":\"50\",\"right\":\"0\",\"bottom\":\"120\",\"left\":\"0\",\"isLinked\":\"\"},\"custom_height\":{\"unit\":\"px\",\"size\":\"\",\"sizes\":[]},\"background_image\":{\"url\":\"https:\\\/\\\/websitedemos.net\\\/luxury-hotel-04\\\/wp-content\\\/uploads\\\/sites\\\/812\\\/2021\\\/06\\\/contact-us-hero-bg.jpg\",\"id\":1562},\"background_position\":\"center center\",\"background_attachment\":\"fixed\",\"background_repeat\":\"no-repeat\",\"background_size\":\"cover\",\"background_overlay_background\":\"gradient\",\"background_overlay_opacity\":{\"unit\":\"px\",\"size\":1,\"sizes\":[]},\"padding_mobile\":{\"unit\":\"px\",\"top\":\"70\",\"right\":\"0\",\"bottom\":\"50\",\"left\":\"0\",\"isLinked\":\"\"},\"background_overlay_color_b_stop\":{\"unit\":\"%\",\"size\":25,\"sizes\":[]},\"padding_tablet\":{\"unit\":\"px\",\"top\":\"50\",\"right\":\"50\",\"bottom\":\"50\",\"left\":\"50\",\"isLinked\":false},\"__globals__\":{\"background_overlay_color\":\"globals\\\/colors?id=astglobalcolor4\",\"background_overlay_color_b\":\"globals\\\/colors?id=astglobalcolor4\"},\"flex_direction\":\"row\",\"flex_align_items\":\"stretch\"},\"elements\":[{\"id\":\"8c62acb\",\"elType\":\"container\",\"settings\":{\"_column_size\":\"100\",\"padding_mobile\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"25\",\"bottom\":\"0\",\"left\":\"25\",\"isLinked\":\"\"},\"margin\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":false},\"padding\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":false},\"content_width\":\"full\",\"flex_gap\":{\"column\":\"0\",\"row\":\"0\",\"isLinked\":false,\"unit\":\"px\",\"size\":0}},\"elements\":[{\"id\":\"d646544\",\"elType\":\"container\",\"settings\":{\"flex_gap\":{\"size\":0,\"column\":\"0\",\"row\":\"0\",\"unit\":\"px\"},\"structure\":\"32\",\"padding\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":\"\"},\"padding_tablet\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":true},\"padding_mobile\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":\"\"},\"margin\":{\"unit\":\"px\",\"top\":\"0\",\"right\":0,\"bottom\":\"0\",\"left\":0,\"isLinked\":false},\"margin_mobile\":{\"unit\":\"px\",\"top\":\"0\",\"right\":0,\"bottom\":\"0\",\"left\":0,\"isLinked\":false},\"flex_direction\":\"row\",\"flex_align_items\":\"stretch\",\"content_width\":\"full\",\"flex_wrap_tablet\":\"wrap\"},\"elements\":[{\"id\":\"97ab379\",\"elType\":\"container\",\"settings\":{\"_column_size\":\"50\",\"flex_justify_content\":\"center\",\"padding\":{\"unit\":\"px\",\"top\":\"30\",\"right\":\"30\",\"bottom\":\"30\",\"left\":\"0\",\"isLinked\":false},\"width_tablet\":{\"size\":100,\"unit\":\"%\"},\"padding_tablet\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"50\",\"bottom\":\"50\",\"left\":\"50\",\"isLinked\":false},\"margin_mobile\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"30\",\"left\":\"0\",\"isLinked\":false},\"padding_mobile\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":true},\"content_width\":\"full\",\"width\":{\"unit\":\"%\",\"size\":50,\"sizes\":[]}},\"elements\":[{\"id\":\"ff14b57\",\"elType\":\"widget\",\"settings\":{\"title\":\"Luxury Privileges\",\"header_size\":\"h6\",\"align\":\"left\",\"typography_font_size\":{\"unit\":\"px\",\"size\":\"20\",\"sizes\":[]},\"typography_font_weight\":\"500\",\"align_tablet\":\"center\",\"align_mobile\":\"left\",\"content_width\":\"full\"},\"elements\":[],\"widgetType\":\"heading\"},{\"id\":\"b89395a\",\"elType\":\"widget\",\"settings\":{\"title\":\"Membership Benefits\",\"align\":\"left\",\"align_tablet\":\"center\",\"align_mobile\":\"left\",\"_margin\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":false},\"_padding\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":false},\"__globals__\":{\"title_color\":\"globals\\\/colors?id=astglobalcolor0\"},\"content_width\":\"full\"},\"elements\":[],\"widgetType\":\"heading\"},{\"id\":\"294ca8d\",\"elType\":\"widget\",\"settings\":{\"_padding\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"50\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":\"\"},\"editor\":\"Lorem ipsum dolor sit amet, consectetur adipiscing elit. Ut elit tellus, luctus nec ullamcorper mattis, pulvinar dapibus leo.\",\"align_tablet\":\"center\",\"_margin_tablet\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":false},\"_padding_tablet\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":false},\"align_mobile\":\"left\",\"content_width\":\"full\"},\"elements\":[],\"widgetType\":\"text-editor\"}],\"isInner\":true},{\"id\":\"b1524e4\",\"elType\":\"container\",\"settings\":{\"_column_size\":\"25\",\"flex_justify_content\":\"center\",\"flex_gap\":{\"size\":30,\"column\":\"30\",\"row\":\"30\",\"unit\":\"px\"},\"background_background\":\"classic\",\"margin\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":\"\"},\"padding\":{\"unit\":\"px\",\"top\":\"30\",\"right\":\"30\",\"bottom\":\"30\",\"left\":\"30\",\"isLinked\":true},\"width_tablet\":{\"size\":50,\"unit\":\"%\"},\"padding_tablet\":{\"unit\":\"px\",\"top\":\"40\",\"right\":\"40\",\"bottom\":\"40\",\"left\":\"40\",\"isLinked\":true},\"padding_mobile\":{\"unit\":\"px\",\"top\":\"25\",\"right\":\"25\",\"bottom\":\"25\",\"left\":\"25\",\"isLinked\":true},\"flex_gap_mobile\":{\"size\":10,\"column\":\"10\",\"row\":\"10\",\"unit\":\"px\"},\"content_width\":\"full\",\"width\":{\"unit\":\"%\",\"size\":25,\"sizes\":[]}},\"elements\":[{\"id\":\"c8065ca\",\"elType\":\"widget\",\"settings\":{\"title\":\"World-class Stay Benefits\",\"header_size\":\"h5\",\"align\":\"left\",\"_padding\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":\"\"},\"content_width\":\"full\"},\"elements\":[],\"widgetType\":\"heading\"},{\"id\":\"4b2f766\",\"elType\":\"widget\",\"settings\":{\"editor\":\"Lorem ipsum dolor sit amet, consec tetur adipiscing. Ut elit tellus, luctus nec nullam corper, pulvinar dapibus leo.\",\"_padding\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":\"\"},\"_margin_mobile\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":false},\"_padding_mobile\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":false},\"content_width\":\"full\"},\"elements\":[],\"widgetType\":\"text-editor\"}],\"isInner\":true},{\"id\":\"1225fb2\",\"elType\":\"container\",\"settings\":{\"_column_size\":\"25\",\"width_tablet\":{\"size\":50,\"unit\":\"%\"},\"content_width\":\"full\",\"width\":{\"unit\":\"%\",\"size\":25,\"sizes\":[]},\"min_height_mobile\":{\"unit\":\"px\",\"size\":375,\"sizes\":[]},\"padding\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":false}},\"elements\":[{\"id\":\"d0c4671\",\"elType\":\"widget\",\"settings\":{\"image\":{\"url\":\"https:\\\/\\\/websitedemos.net\\\/luxury-hotel-04\\\/wp-content\\\/uploads\\\/sites\\\/812\\\/2021\\\/04\\\/world-class1.jpg\",\"id\":\"1091\"},\"image_size\":\"medium\",\"width_tablet\":{\"unit\":\"%\",\"size\":100,\"sizes\":[]},\"content_width\":\"full\"},\"elements\":[],\"widgetType\":\"image\"}],\"isInner\":true}],\"isInner\":true},{\"id\":\"fa19ba7\",\"elType\":\"container\",\"settings\":{\"flex_gap\":{\"size\":0,\"column\":\"0\",\"row\":\"0\",\"unit\":\"px\"},\"structure\":\"40\",\"padding\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":\"\"},\"padding_mobile\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":\"\"},\"reverse_order_mobile\":\"reverse-mobile\",\"flex_direction\":\"row\",\"flex_align_items\":\"stretch\",\"content_width\":\"full\",\"flex_direction_mobile\":\"column-reverse\",\"flex_wrap_tablet\":\"wrap\",\"flex_wrap_mobile\":\"wrap\"},\"elements\":[{\"id\":\"3d23f22\",\"elType\":\"container\",\"settings\":{\"_column_size\":\"25\",\"width_tablet\":{\"size\":50,\"unit\":\"%\"},\"content_width\":\"full\",\"width\":{\"unit\":\"%\",\"size\":25,\"sizes\":[]},\"padding\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":false}},\"elements\":[{\"id\":\"05755b8\",\"elType\":\"widget\",\"settings\":{\"image\":{\"url\":\"https:\\\/\\\/websitedemos.net\\\/luxury-hotel-04\\\/wp-content\\\/uploads\\\/sites\\\/812\\\/2021\\\/04\\\/casino-11.jpg\",\"id\":\"1087\"},\"image_size\":\"medium\",\"width_tablet\":{\"unit\":\"%\",\"size\":100,\"sizes\":[]},\"content_width\":\"full\"},\"elements\":[],\"widgetType\":\"image\"}],\"isInner\":true},{\"id\":\"4693b4f\",\"elType\":\"container\",\"settings\":{\"_column_size\":\"25\",\"flex_justify_content\":\"center\",\"flex_gap\":{\"size\":30,\"column\":\"30\",\"row\":\"30\",\"unit\":\"px\"},\"background_background\":\"classic\",\"margin\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":\"\"},\"padding\":{\"unit\":\"px\",\"top\":\"30\",\"right\":\"30\",\"bottom\":\"30\",\"left\":\"30\",\"isLinked\":true},\"width_tablet\":{\"size\":50,\"unit\":\"%\"},\"padding_tablet\":{\"unit\":\"px\",\"top\":\"40\",\"right\":\"40\",\"bottom\":\"40\",\"left\":\"40\",\"isLinked\":true},\"padding_mobile\":{\"unit\":\"px\",\"top\":\"25\",\"right\":\"25\",\"bottom\":\"25\",\"left\":\"25\",\"isLinked\":true},\"flex_gap_mobile\":{\"size\":10,\"column\":\"10\",\"row\":\"10\",\"unit\":\"px\"},\"content_width\":\"full\",\"width\":{\"unit\":\"%\",\"size\":25,\"sizes\":[]},\"margin_mobile\":{\"unit\":\"px\",\"top\":\"75\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":false}},\"elements\":[{\"id\":\"a12dafc\",\"elType\":\"widget\",\"settings\":{\"title\":\"Exclusive Casino Benefits\",\"header_size\":\"h5\",\"align\":\"left\",\"_padding\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":\"\"},\"content_width\":\"full\"},\"elements\":[],\"widgetType\":\"heading\"},{\"id\":\"81780ec\",\"elType\":\"widget\",\"settings\":{\"editor\":\"Lorem ipsum dolor sit amet, consec tetur adipiscing. Ut elit tellus, luctus nec nullam corper, pulvinar dapibus leo.\",\"_padding\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":\"\"},\"_margin_mobile\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":false},\"_padding_mobile\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":false},\"content_width\":\"full\"},\"elements\":[],\"widgetType\":\"text-editor\"}],\"isInner\":true},{\"id\":\"b005f72\",\"elType\":\"container\",\"settings\":{\"_column_size\":\"25\",\"flex_justify_content\":\"center\",\"flex_gap\":{\"size\":\"3\",\"column\":\"3\",\"row\":\"3\",\"unit\":\"px\"},\"padding_mobile\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":\"\"},\"width_tablet\":{\"size\":50,\"unit\":\"%\"},\"margin_mobile\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":false},\"content_width\":\"full\",\"width\":{\"unit\":\"%\",\"size\":25,\"sizes\":[]},\"padding\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":false}},\"elements\":[{\"id\":\"1740e04\",\"elType\":\"widget\",\"settings\":{\"image\":{\"url\":\"https:\\\/\\\/websitedemos.net\\\/luxury-hotel-04\\\/wp-content\\\/uploads\\\/sites\\\/812\\\/2021\\\/04\\\/350x350-3.png\",\"id\":\"192\"},\"image_size\":\"medium\",\"width_tablet\":{\"unit\":\"%\",\"size\":100,\"sizes\":[]},\"content_width\":\"full\"},\"elements\":[],\"widgetType\":\"image\"}],\"isInner\":true},{\"id\":\"3b812d3\",\"elType\":\"container\",\"settings\":{\"_column_size\":\"25\",\"flex_justify_content\":\"center\",\"flex_gap\":{\"size\":30,\"column\":\"30\",\"row\":\"30\",\"unit\":\"px\"},\"background_background\":\"classic\",\"margin\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":\"\"},\"padding\":{\"unit\":\"px\",\"top\":\"30\",\"right\":\"30\",\"bottom\":\"30\",\"left\":\"30\",\"isLinked\":true},\"width_tablet\":{\"size\":50,\"unit\":\"%\"},\"padding_tablet\":{\"unit\":\"px\",\"top\":\"40\",\"right\":\"40\",\"bottom\":\"40\",\"left\":\"40\",\"isLinked\":true},\"padding_mobile\":{\"unit\":\"px\",\"top\":\"25\",\"right\":\"25\",\"bottom\":\"25\",\"left\":\"25\",\"isLinked\":true},\"flex_gap_mobile\":{\"size\":10,\"column\":\"10\",\"row\":\"10\",\"unit\":\"px\"},\"content_width\":\"full\",\"width\":{\"unit\":\"%\",\"size\":25,\"sizes\":[]}},\"elements\":[{\"id\":\"6d87d08\",\"elType\":\"widget\",\"settings\":{\"title\":\"Exclusive Lifestyle Voucher\",\"header_size\":\"h5\",\"align\":\"left\",\"_padding\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":\"\"},\"content_width\":\"full\"},\"elements\":[],\"widgetType\":\"heading\"},{\"id\":\"5bcca61\",\"elType\":\"widget\",\"settings\":{\"editor\":\"Lorem ipsum dolor sit amet, consec tetur adipiscing. Ut elit tellus, luctus nec nullam corper, pulvinar dapibus leo.\",\"_padding\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":\"\"},\"_margin_mobile\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":false},\"_padding_mobile\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":false},\"content_width\":\"full\"},\"elements\":[],\"widgetType\":\"text-editor\"}],\"isInner\":true}],\"isInner\":true},{\"id\":\"598928d\",\"elType\":\"container\",\"settings\":{\"flex_gap\":{\"size\":0,\"column\":\"0\",\"row\":\"0\",\"unit\":\"px\"},\"structure\":\"31\",\"padding\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":\"\"},\"padding_mobile\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":\"\"},\"margin_mobile\":{\"unit\":\"px\",\"top\":\"0\",\"right\":0,\"bottom\":\"0\",\"left\":0,\"isLinked\":false},\"flex_direction\":\"row\",\"flex_align_items\":\"stretch\",\"content_width\":\"full\",\"flex_wrap_tablet\":\"wrap\"},\"elements\":[{\"id\":\"47f9cdf\",\"elType\":\"container\",\"settings\":{\"_column_size\":\"25\",\"flex_justify_content\":\"center\",\"flex_gap\":{\"size\":30,\"column\":\"30\",\"row\":\"30\",\"unit\":\"px\"},\"background_background\":\"classic\",\"margin\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":\"\"},\"padding\":{\"unit\":\"px\",\"top\":\"30\",\"right\":\"30\",\"bottom\":\"30\",\"left\":\"30\",\"isLinked\":true},\"width_tablet\":{\"size\":50,\"unit\":\"%\"},\"padding_tablet\":{\"unit\":\"px\",\"top\":\"40\",\"right\":\"40\",\"bottom\":\"40\",\"left\":\"40\",\"isLinked\":true},\"padding_mobile\":{\"unit\":\"px\",\"top\":\"25\",\"right\":\"25\",\"bottom\":\"25\",\"left\":\"25\",\"isLinked\":true},\"flex_gap_mobile\":{\"size\":10,\"column\":\"10\",\"row\":\"10\",\"unit\":\"px\"},\"content_width\":\"full\",\"width\":{\"unit\":\"%\",\"size\":25,\"sizes\":[]},\"margin_mobile\":{\"unit\":\"px\",\"top\":\"75\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":false}},\"elements\":[{\"id\":\"2853383\",\"elType\":\"widget\",\"settings\":{\"title\":\"Complementary<br> Wine Bottle \",\"header_size\":\"h5\",\"align\":\"left\",\"_padding\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":\"\"},\"content_width\":\"full\"},\"elements\":[],\"widgetType\":\"heading\"},{\"id\":\"7698123\",\"elType\":\"widget\",\"settings\":{\"editor\":\"Lorem ipsum dolor sit amet, consec tetur adipiscing. Ut elit tellus, luctus nec nullam corper, pulvinar dapibus leo.\",\"_padding\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":\"\"},\"_margin_mobile\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":false},\"_padding_mobile\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":false},\"content_width\":\"full\"},\"elements\":[],\"widgetType\":\"text-editor\"}],\"isInner\":true},{\"id\":\"6872806\",\"elType\":\"container\",\"settings\":{\"_column_size\":\"25\",\"width_tablet\":{\"size\":50,\"unit\":\"%\"},\"content_width\":\"full\",\"width\":{\"unit\":\"%\",\"size\":25,\"sizes\":[]},\"padding\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":false}},\"elements\":[{\"id\":\"10dcd41\",\"elType\":\"widget\",\"settings\":{\"image\":{\"url\":\"https:\\\/\\\/websitedemos.net\\\/luxury-hotel-04\\\/wp-content\\\/uploads\\\/sites\\\/812\\\/2021\\\/04\\\/wine-bottle.jpg\",\"id\":\"1095\"},\"image_size\":\"medium\",\"width_tablet\":{\"unit\":\"%\",\"size\":100,\"sizes\":[]},\"content_width\":\"full\"},\"elements\":[],\"widgetType\":\"image\"}],\"isInner\":true},{\"id\":\"7613f61\",\"elType\":\"container\",\"settings\":{\"_column_size\":\"50\",\"flex_justify_content\":\"center\",\"background_background\":\"classic\",\"margin\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":\"\"},\"padding\":{\"unit\":\"px\",\"top\":\"30\",\"right\":\"0\",\"bottom\":\"30\",\"left\":\"30\",\"isLinked\":false},\"padding_mobile\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":false},\"width_tablet\":{\"size\":100,\"unit\":\"%\"},\"padding_tablet\":{\"unit\":\"px\",\"top\":\"50\",\"right\":\"50\",\"bottom\":\"50\",\"left\":\"50\",\"isLinked\":false},\"margin_mobile\":{\"unit\":\"px\",\"top\":\"107\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":false},\"content_width\":\"full\",\"width\":{\"unit\":\"%\",\"size\":50,\"sizes\":[]}},\"elements\":[{\"id\":\"504f666\",\"elType\":\"widget\",\"settings\":{\"title\":\" More Benefits\",\"header_size\":\"h4\",\"align\":\"left\",\"align_tablet\":\"center\",\"align_mobile\":\"left\",\"__globals__\":{\"title_color\":\"globals\\\/colors?id=astglobalcolor0\"},\"content_width\":\"full\"},\"elements\":[],\"widgetType\":\"heading\"},{\"id\":\"3413d42\",\"elType\":\"widget\",\"settings\":{\"editor\":\"Quisque velit nisi, pretium ut lacinia in, elementum id enim. Curabitur non nulla sit amet nisl tempus convallis quis ac lectus.\",\"_padding\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"50\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":\"\"},\"align_tablet\":\"center\",\"_margin_tablet\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":false},\"_padding_tablet\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":false},\"align_mobile\":\"left\",\"content_width\":\"full\"},\"elements\":[],\"widgetType\":\"text-editor\"},{\"id\":\"747e002\",\"elType\":\"widget\",\"settings\":{\"text\":\"Become a Member\",\"_padding\":{\"unit\":\"px\",\"top\":\"15\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":\"\"},\"background_background\":\"\",\"button_background_hover_background\":\"\",\"align_tablet\":\"center\",\"_margin_tablet\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":false},\"_padding_tablet\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":false},\"align_mobile\":\"left\",\"content_width\":\"full\"},\"elements\":[],\"widgetType\":\"button\"}],\"isInner\":true}],\"isInner\":true}],\"isInner\":true}],\"isInner\":false},{\"id\":\"d0d1ab1\",\"elType\":\"container\",\"settings\":{\"flex_gap\":{\"size\":0,\"column\":\"0\",\"row\":\"0\",\"unit\":\"px\"},\"padding\":{\"unit\":\"px\",\"top\":\"120\",\"right\":\"0\",\"bottom\":\"80\",\"left\":\"0\",\"isLinked\":\"\"},\"padding_mobile\":{\"unit\":\"px\",\"top\":\"50\",\"right\":\"25\",\"bottom\":\"50\",\"left\":\"25\",\"isLinked\":\"\"},\"boxed_width\":{\"unit\":\"px\",\"size\":1200,\"sizes\":[]},\"custom_height\":{\"unit\":\"px\",\"size\":\"\",\"sizes\":[]},\"flex_align_items\":\"stretch\",\"padding_tablet\":{\"unit\":\"px\",\"top\":\"50\",\"right\":\"20\",\"bottom\":\"50\",\"left\":\"20\",\"isLinked\":false},\"flex_direction\":\"row\"},\"elements\":[{\"id\":\"c3afb67\",\"elType\":\"container\",\"settings\":{\"_column_size\":\"100\",\"padding_mobile\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":\"\"},\"content_width\":\"full\",\"padding\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":false}},\"elements\":[{\"id\":\"3f3e405\",\"elType\":\"widget\",\"settings\":{\"title\":\"Ideal Venue For Any Event\",\"header_size\":\"h3\",\"align\":\"center\",\"align_mobile\":\"left\",\"content_width\":\"full\"},\"elements\":[],\"widgetType\":\"heading\"},{\"id\":\"c3d4407\",\"elType\":\"widget\",\"settings\":{\"editor\":\"Quisque velit nisi, pretium ut lacinia in, elementum id enim.\",\"align\":\"center\",\"align_mobile\":\"left\",\"content_width\":\"full\"},\"elements\":[],\"widgetType\":\"text-editor\"},{\"id\":\"e420b23\",\"elType\":\"container\",\"settings\":{\"flex_gap\":{\"size\":0,\"column\":\"0\",\"row\":\"0\",\"unit\":\"px\"},\"structure\":\"30\",\"padding\":{\"unit\":\"px\",\"top\":\"50\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":\"\"},\"padding_mobile\":{\"unit\":\"px\",\"top\":\"35\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":\"\"},\"padding_tablet\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":false},\"flex_direction\":\"row\",\"flex_align_items\":\"stretch\",\"content_width\":\"full\"},\"elements\":[{\"id\":\"6d05509\",\"elType\":\"container\",\"settings\":{\"_column_size\":\"33\",\"flex_gap\":{\"size\":0,\"column\":\"0\",\"row\":\"0\",\"unit\":\"px\"},\"background_color\":\"#FFFFFF\",\"margin\":{\"unit\":\"px\",\"top\":\"15\",\"right\":\"15\",\"bottom\":\"15\",\"left\":\"15\",\"isLinked\":true},\"box_shadow_box_shadow\":{\"horizontal\":0,\"vertical\":0,\"blur\":15,\"spread\":0,\"color\":\"rgba(0, 0, 0, 0.1)\"},\"margin_tablet\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":false},\"padding_tablet\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":false},\"content_width\":\"full\",\"width\":{\"unit\":\"%\",\"size\":33.33,\"sizes\":[]},\"padding\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":false}},\"elements\":[{\"id\":\"8ff67a0\",\"elType\":\"widget\",\"settings\":{\"image\":{\"url\":\"https:\\\/\\\/websitedemos.net\\\/luxury-hotel-04\\\/wp-content\\\/uploads\\\/sites\\\/812\\\/2021\\\/04\\\/event-1.png\",\"id\":\"243\"},\"content_width\":\"full\"},\"elements\":[],\"widgetType\":\"image\"},{\"id\":\"7d54893\",\"elType\":\"widget\",\"settings\":{\"image\":{\"url\":\"\",\"id\":\"\"},\"title_text\":\"Weddings\",\"description_text\":\"Lorem ipsum dolor sit amet, consectetur adipiscing elit. Ut elit tellus, luctus nec ullamcorper mattis, pulvinar dapibus leo.\",\"title_size\":\"h4\",\"_padding\":{\"unit\":\"px\",\"top\":\"55\",\"right\":\"25\",\"bottom\":\"55\",\"left\":\"25\",\"isLinked\":false},\"_padding_tablet\":{\"unit\":\"px\",\"top\":\"25\",\"right\":\"25\",\"bottom\":\"25\",\"left\":\"25\",\"isLinked\":true},\"description_typography_typography\":\"custom\",\"description_typography_font_size_tablet\":{\"unit\":\"px\",\"size\":13,\"sizes\":[]},\"__globals__\":{\"title_color\":\"globals\\\/colors?id=astglobalcolor0\"},\"content_width\":\"full\"},\"elements\":[],\"widgetType\":\"image-box\"}],\"isInner\":true},{\"id\":\"aea64ab\",\"elType\":\"container\",\"settings\":{\"_column_size\":\"33\",\"background_color\":\"#FFFFFF\",\"flex_gap\":{\"size\":0,\"column\":\"0\",\"row\":\"0\",\"unit\":\"px\"},\"margin\":{\"unit\":\"px\",\"top\":\"15\",\"right\":\"15\",\"bottom\":\"15\",\"left\":\"15\",\"isLinked\":true},\"box_shadow_box_shadow\":{\"horizontal\":0,\"vertical\":0,\"blur\":15,\"spread\":0,\"color\":\"rgba(0, 0, 0, 0.1)\"},\"margin_tablet\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":false},\"padding_tablet\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":false},\"content_width\":\"full\",\"width\":{\"unit\":\"%\",\"size\":33.33,\"sizes\":[]},\"padding\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":false}},\"elements\":[{\"id\":\"f929a45\",\"elType\":\"widget\",\"settings\":{\"image\":{\"url\":\"\",\"id\":\"\"},\"title_text\":\"Parties\",\"description_text\":\"Lorem ipsum dolor sit amet, consectetur adipiscing elit. Ut elit tellus, luctus nec ullamcorper mattis, pulvinar dapibus leo.\",\"title_size\":\"h4\",\"_padding\":{\"unit\":\"px\",\"top\":\"55\",\"right\":\"25\",\"bottom\":\"55\",\"left\":\"25\",\"isLinked\":false},\"_padding_tablet\":{\"unit\":\"px\",\"top\":\"25\",\"right\":\"25\",\"bottom\":\"25\",\"left\":\"25\",\"isLinked\":true},\"description_typography_typography\":\"custom\",\"description_typography_font_size_tablet\":{\"unit\":\"px\",\"size\":13,\"sizes\":[]},\"__globals__\":{\"title_color\":\"globals\\\/colors?id=astglobalcolor0\"},\"content_width\":\"full\"},\"elements\":[],\"widgetType\":\"image-box\"},{\"id\":\"784e7a5\",\"elType\":\"widget\",\"settings\":{\"image\":{\"url\":\"https:\\\/\\\/websitedemos.net\\\/luxury-hotel-04\\\/wp-content\\\/uploads\\\/sites\\\/812\\\/2021\\\/04\\\/event-2.png\",\"id\":\"245\"},\"_margin\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":false},\"_padding\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":false},\"content_width\":\"full\"},\"elements\":[],\"widgetType\":\"image\"}],\"isInner\":true},{\"id\":\"2f92c95\",\"elType\":\"container\",\"settings\":{\"_column_size\":\"33\",\"flex_gap\":{\"size\":0,\"column\":\"0\",\"row\":\"0\",\"unit\":\"px\"},\"background_color\":\"#FFFFFF\",\"margin\":{\"unit\":\"px\",\"top\":\"15\",\"right\":\"15\",\"bottom\":\"15\",\"left\":\"15\",\"isLinked\":true},\"box_shadow_box_shadow\":{\"horizontal\":0,\"vertical\":0,\"blur\":15,\"spread\":0,\"color\":\"rgba(0, 0, 0, 0.1)\"},\"margin_tablet\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":false},\"padding_tablet\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":false},\"content_width\":\"full\",\"width\":{\"unit\":\"%\",\"size\":33.33,\"sizes\":[]},\"padding\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":false}},\"elements\":[{\"id\":\"110b108\",\"elType\":\"widget\",\"settings\":{\"image\":{\"url\":\"https:\\\/\\\/websitedemos.net\\\/luxury-hotel-04\\\/wp-content\\\/uploads\\\/sites\\\/812\\\/2021\\\/04\\\/conference-1.jpg\",\"id\":\"1101\"},\"content_width\":\"full\"},\"elements\":[],\"widgetType\":\"image\"},{\"id\":\"ae815d2\",\"elType\":\"widget\",\"settings\":{\"image\":{\"url\":\"\",\"id\":\"\"},\"title_text\":\"Conference\",\"description_text\":\"Lorem ipsum dolor sit amet, consectetur adipiscing elit. Ut elit tellus, luctus nec ullamcorper mattis, pulvinar dapibus leo.\",\"title_size\":\"h4\",\"_padding\":{\"unit\":\"px\",\"top\":\"55\",\"right\":\"25\",\"bottom\":\"55\",\"left\":\"25\",\"isLinked\":false},\"_padding_tablet\":{\"unit\":\"px\",\"top\":\"25\",\"right\":\"25\",\"bottom\":\"25\",\"left\":\"25\",\"isLinked\":true},\"description_typography_typography\":\"custom\",\"description_typography_font_size_tablet\":{\"unit\":\"px\",\"size\":13,\"sizes\":[]},\"__globals__\":{\"title_color\":\"globals\\\/colors?id=astglobalcolor0\"},\"content_width\":\"full\"},\"elements\":[],\"widgetType\":\"image-box\"}],\"isInner\":true}],\"isInner\":true}],\"isInner\":true}],\"isInner\":false},{\"id\":\"7af717b\",\"elType\":\"container\",\"settings\":{\"flex_gap\":{\"size\":0,\"column\":\"0\",\"row\":\"0\",\"unit\":\"px\"},\"background_background\":\"classic\",\"background_image\":{\"url\":\"https:\\\/\\\/websitedemos.net\\\/luxury-hotel-04\\\/wp-content\\\/uploads\\\/sites\\\/812\\\/2021\\\/06\\\/hotel-cta-bg-1.jpg\",\"id\":1671},\"background_position\":\"bottom center\",\"background_attachment\":\"fixed\",\"background_repeat\":\"no-repeat\",\"background_size\":\"cover\",\"background_overlay_background\":\"gradient\",\"background_overlay_opacity\":{\"unit\":\"px\",\"size\":1,\"sizes\":[]},\"padding\":{\"unit\":\"px\",\"top\":\"140\",\"right\":\"0\",\"bottom\":\"200\",\"left\":\"0\",\"isLinked\":\"\"},\"structure\":\"22\",\"padding_tablet\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"50\",\"bottom\":\"50\",\"left\":\"50\",\"isLinked\":false},\"boxed_width\":{\"unit\":\"px\",\"size\":970,\"sizes\":[]},\"content_position\":\"middle\",\"padding_mobile\":{\"unit\":\"px\",\"top\":\"50\",\"right\":\"25\",\"bottom\":\"50\",\"left\":\"25\",\"isLinked\":false},\"__globals__\":{\"background_overlay_color\":\"globals\\\/colors?id=astglobalcolor4\",\"background_overlay_color_b\":\"globals\\\/colors?id=astglobalcolor4\"},\"flex_direction\":\"row\",\"flex_align_items\":\"stretch\",\"flex_wrap_tablet\":\"wrap\"},\"elements\":[{\"id\":\"3541771\",\"elType\":\"container\",\"settings\":{\"_column_size\":66,\"flex_gap\":{\"size\":40,\"column\":\"40\",\"row\":\"40\",\"unit\":\"px\"},\"padding_mobile\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":true},\"margin\":{\"unit\":\"%\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":false},\"width\":{\"size\":70,\"unit\":\"%\"},\"width_tablet\":{\"size\":100,\"unit\":\"%\"},\"flex_gap_mobile\":{\"size\":20,\"column\":\"20\",\"row\":\"20\",\"unit\":\"px\"},\"content_width\":\"full\",\"padding\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":false}},\"elements\":[{\"id\":\"125deeb\",\"elType\":\"widget\",\"settings\":{\"title\":\"Your search for True Luxury ends here\",\"align_mobile\":\"center\",\"align_tablet\":\"center\",\"__globals__\":{\"title_color\":\"globals\\\/colors?id=astglobalcolor0\"},\"content_width\":\"full\"},\"elements\":[],\"widgetType\":\"heading\"},{\"id\":\"cf4e79d\",\"elType\":\"widget\",\"settings\":{\"editor\":\"Lorem ipsum dolor sit amet, consectetur adipiscing elit. Ut elit tellus, luctus nec ullamcorper mattis, pulvinar dapibus leo.\",\"align_mobile\":\"center\",\"_padding_mobile\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":\"\"},\"_margin\":{\"unit\":\"%\",\"top\":\"0\",\"right\":\"10\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":false},\"typography_typography\":\"custom\",\"typography_font_size\":{\"unit\":\"px\",\"size\":18,\"sizes\":[]},\"align_tablet\":\"center\",\"typography_font_size_tablet\":{\"unit\":\"px\",\"size\":15,\"sizes\":[]},\"_margin_tablet\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":false},\"_padding_tablet\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":false},\"content_width\":\"full\"},\"elements\":[],\"widgetType\":\"text-editor\"}],\"isInner\":true},{\"id\":\"9afc588\",\"elType\":\"container\",\"settings\":{\"_column_size\":33,\"flex_gap\":{\"size\":40,\"column\":\"40\",\"row\":\"40\",\"unit\":\"px\"},\"padding_mobile\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":true},\"margin\":{\"unit\":\"%\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":true},\"width\":{\"size\":29.333,\"unit\":\"%\"},\"width_tablet\":{\"size\":100,\"unit\":\"%\"},\"content_width\":\"full\",\"flex_justify_content\":\"center\",\"padding\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":false}},\"elements\":[{\"id\":\"46ff7a2\",\"elType\":\"widget\",\"settings\":{\"text\":\"Book Now\",\"_padding\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":true},\"align\":\"right\",\"align_tablet\":\"center\",\"_margin\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":true},\"_margin_tablet\":{\"unit\":\"px\",\"top\":\"50\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":false},\"content_width\":\"full\"},\"elements\":[],\"widgetType\":\"button\"}],\"isInner\":true}],\"isInner\":false}]","_yoast_wpseo_content_score":"90","astra-main-page-id":"57196","ast_self_id_57196":"1","skip_page":"","dynamic_page":"","_elementor_page_settings":"a:53:{s:22:\"astra_sites_main_color\";s:25:\"var(--ast-global-color-0)\";s:30:\"astra_sites_heading_base_color\";s:25:\"var(--ast-global-color-2)\";s:22:\"astra_sites_link_color\";s:25:\"var(--ast-global-color-3)\";s:28:\"astra_sites_link_hover_color\";s:25:\"var(--ast-global-color-1)\";s:22:\"astra_sites_text_color\";s:25:\"var(--ast-global-color-3)\";s:27:\"astra_sites_body_typography\";s:6:\"custom\";s:26:\"astra_sites_body_font_size\";a:2:{s:4:\"unit\";s:2:\"px\";s:4:\"size\";i:15;}s:33:\"astra_sites_body_font_size_tablet\";a:2:{s:4:\"unit\";s:2:\"px\";s:4:\"size\";i:15;}s:33:\"astra_sites_body_font_size_mobile\";a:2:{s:4:\"unit\";s:2:\"px\";s:4:\"size\";i:14;}s:28:\"astra_sites_body_line_height\";a:2:{s:4:\"unit\";s:2:\"em\";s:4:\"size\";d:1.7;}s:28:\"astra_sites_body_font_family\";s:7:\"Poppins\";s:28:\"astra_sites_body_font_weight\";s:3:\"400\";s:32:\"astra_sites_heading_1_typography\";s:6:\"custom\";s:31:\"astra_sites_heading_1_font_size\";a:2:{s:4:\"unit\";s:2:\"px\";s:4:\"size\";i:84;}s:38:\"astra_sites_heading_1_font_size_tablet\";a:2:{s:4:\"unit\";s:2:\"px\";s:4:\"size\";i:54;}s:38:\"astra_sites_heading_1_font_size_mobile\";a:2:{s:4:\"unit\";s:2:\"px\";s:4:\"size\";i:42;}s:33:\"astra_sites_heading_1_line_height\";a:2:{s:4:\"unit\";s:2:\"em\";s:4:\"size\";d:1;}s:39:\"astra_sites_default_heading_font_family\";s:25:\"'DM Serif Display', serif\";s:33:\"astra_sites_heading_1_font_family\";s:18:\"'DM Serif Display'\";s:33:\"astra_sites_heading_1_font_weight\";s:6:\"normal\";s:32:\"astra_sites_heading_2_typography\";s:6:\"custom\";s:31:\"astra_sites_heading_2_font_size\";a:2:{s:4:\"unit\";s:2:\"px\";s:4:\"size\";i:62;}s:38:\"astra_sites_heading_2_font_size_tablet\";a:2:{s:4:\"unit\";s:2:\"px\";s:4:\"size\";i:38;}s:38:\"astra_sites_heading_2_font_size_mobile\";a:2:{s:4:\"unit\";s:2:\"px\";s:4:\"size\";i:30;}s:33:\"astra_sites_heading_2_line_height\";a:2:{s:4:\"unit\";s:2:\"em\";s:4:\"size\";d:1;}s:33:\"astra_sites_heading_2_font_family\";s:18:\"'DM Serif Display'\";s:33:\"astra_sites_heading_2_font_weight\";s:6:\"normal\";s:32:\"astra_sites_heading_3_typography\";s:6:\"custom\";s:31:\"astra_sites_heading_3_font_size\";a:2:{s:4:\"unit\";s:2:\"px\";s:4:\"size\";i:52;}s:38:\"astra_sites_heading_3_font_size_tablet\";a:2:{s:4:\"unit\";s:2:\"px\";s:4:\"size\";i:32;}s:38:\"astra_sites_heading_3_font_size_mobile\";a:2:{s:4:\"unit\";s:2:\"px\";s:4:\"size\";i:26;}s:33:\"astra_sites_heading_3_line_height\";a:2:{s:4:\"unit\";s:2:\"em\";s:4:\"size\";d:1;}s:33:\"astra_sites_heading_3_font_family\";s:18:\"'DM Serif Display'\";s:33:\"astra_sites_heading_3_font_weight\";s:6:\"normal\";s:32:\"astra_sites_heading_4_typography\";s:6:\"custom\";s:31:\"astra_sites_heading_4_font_size\";a:2:{s:4:\"unit\";s:2:\"px\";s:4:\"size\";i:32;}s:38:\"astra_sites_heading_4_font_size_tablet\";a:2:{s:4:\"unit\";s:2:\"px\";s:4:\"size\";i:28;}s:38:\"astra_sites_heading_4_font_size_mobile\";a:2:{s:4:\"unit\";s:2:\"px\";s:4:\"size\";i:22;}s:33:\"astra_sites_heading_4_font_family\";s:18:\"'DM Serif Display'\";s:33:\"astra_sites_heading_4_font_weight\";s:3:\"400\";s:32:\"astra_sites_heading_5_typography\";s:6:\"custom\";s:31:\"astra_sites_heading_5_font_size\";a:2:{s:4:\"unit\";s:2:\"px\";s:4:\"size\";i:22;}s:38:\"astra_sites_heading_5_font_size_tablet\";a:2:{s:4:\"unit\";s:2:\"px\";s:4:\"size\";i:22;}s:38:\"astra_sites_heading_5_font_size_mobile\";a:2:{s:4:\"unit\";s:2:\"px\";s:4:\"size\";i:18;}s:33:\"astra_sites_heading_5_font_family\";s:18:\"'DM Serif Display'\";s:33:\"astra_sites_heading_5_font_weight\";s:3:\"400\";s:32:\"astra_sites_heading_6_typography\";s:6:\"custom\";s:31:\"astra_sites_heading_6_font_size\";a:2:{s:4:\"unit\";s:2:\"px\";s:4:\"size\";i:18;}s:38:\"astra_sites_heading_6_font_size_tablet\";a:2:{s:4:\"unit\";s:2:\"px\";s:4:\"size\";i:18;}s:38:\"astra_sites_heading_6_font_size_mobile\";a:2:{s:4:\"unit\";s:2:\"px\";s:4:\"size\";i:15;}s:33:\"astra_sites_heading_6_font_family\";s:18:\"'DM Serif Display'\";s:33:\"astra_sites_heading_6_font_weight\";s:3:\"400\";s:31:\"astra_sites_page_setting_enable\";s:0:\"\";}","_elementor_data_bckp":"[{\"id\":\"9494263\",\"elType\":\"section\",\"settings\":{\"layout\":\"full_width\",\"gap\":\"no\",\"overflow\":\"hidden\",\"padding\":{\"unit\":\"px\",\"top\":\"250\",\"right\":\"0\",\"bottom\":\"120\",\"left\":\"250\",\"isLinked\":\"\"},\"margin_tablet\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":\"1\"},\"margin_mobile\":{\"unit\":\"px\",\"top\":\"0\",\"right\":0,\"bottom\":\"0\",\"left\":0,\"isLinked\":\"\"},\"padding_tablet\":{\"unit\":\"px\",\"top\":\"180\",\"right\":\"0\",\"bottom\":\"50\",\"left\":\"50\",\"isLinked\":\"\"},\"padding_mobile\":{\"unit\":\"px\",\"top\":\"120\",\"right\":\"30\",\"bottom\":\"60\",\"left\":\"30\",\"isLinked\":\"\"},\"custom_height\":{\"unit\":\"vh\",\"size\":100,\"sizes\":[]},\"background_position\":\"center center\",\"background_attachment\":\"fixed\",\"background_repeat\":\"no-repeat\",\"background_size\":\"cover\",\"background_overlay_color_b\":\"\",\"background_overlay_gradient_angle\":{\"unit\":\"deg\",\"size\":0,\"sizes\":[]},\"background_overlay_opacity\":{\"unit\":\"px\",\"size\":0.4,\"sizes\":[]},\"background_background\":\"gradient\",\"background_color\":\"#1D264500\",\"background_color_b\":\"#012047\",\"background_gradient_angle\":{\"unit\":\"deg\",\"size\":310,\"sizes\":[]},\"background_overlay_background\":\"classic\",\"background_overlay_color\":\"#000000\"},\"elements\":[{\"id\":\"92fb0ec\",\"elType\":\"column\",\"settings\":{\"_column_size\":\"100\",\"margin_tablet\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":\"\"},\"padding_tablet\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":\"\"}},\"elements\":[{\"id\":\"c557ad9\",\"elType\":\"widget\",\"settings\":{\"title\":\"Dive into Ultimate Luxury at\",\"header_size\":\"h6\"},\"elements\":[],\"widgetType\":\"heading\"},{\"id\":\"152a6c6\",\"elType\":\"widget\",\"settings\":{\"image\":{\"url\":\"\",\"id\":\"\"},\"title_text\":\"The Caeser Grand\",\"description_text\":\"Lorem ipsum dolor sit amet, consectetur adipiscing elit. Ut elit tellus, <br\\\/>luctus nec ullamcorper mattis, pulvinar dapibus leo.\",\"title_size\":\"h1\",\"text_align\":\"left\",\"_margin\":{\"unit\":\"%\",\"top\":\"\",\"right\":\"\",\"bottom\":\"\",\"left\":\"\",\"isLinked\":true}},\"elements\":[],\"widgetType\":\"image-box\"},{\"id\":\"3ca54ab\",\"elType\":\"widget\",\"settings\":{\"text\":\"Make A Reservation\",\"border_width\":{\"unit\":\"px\",\"top\":\"1\",\"right\":\"1\",\"bottom\":\"1\",\"left\":\"1\",\"isLinked\":\"1\"},\"_element_custom_width\":{\"unit\":\"px\",\"size\":\"240\",\"sizes\":[]},\"_element_vertical_align\":\"center\",\"_margin\":{\"unit\":\"px\",\"top\":\"30\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":false},\"icon_indent\":{\"unit\":\"px\",\"size\":0,\"sizes\":[]},\"_margin_tablet\":{\"unit\":\"px\",\"top\":\"15\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":false}},\"elements\":[],\"widgetType\":\"button\"},{\"id\":\"a840635\",\"elType\":\"widget\",\"settings\":{\"carousel\":[{\"id\":\"1328\",\"url\":\"https:\\\/\\\/websitedemos.net\\\/luxury-hotel-04\\\/wp-content\\\/uploads\\\/sites\\\/812\\\/2021\\\/04\\\/carousel-11-.jpg\"},{\"id\":\"1329\",\"url\":\"https:\\\/\\\/websitedemos.net\\\/luxury-hotel-04\\\/wp-content\\\/uploads\\\/sites\\\/812\\\/2021\\\/04\\\/carousel12-.jpg\"},{\"id\":\"1330\",\"url\":\"https:\\\/\\\/websitedemos.net\\\/luxury-hotel-04\\\/wp-content\\\/uploads\\\/sites\\\/812\\\/2021\\\/04\\\/carousel13-.jpg\"},{\"id\":\"1331\",\"url\":\"https:\\\/\\\/websitedemos.net\\\/luxury-hotel-04\\\/wp-content\\\/uploads\\\/sites\\\/812\\\/2021\\\/04\\\/carousel14-.jpg\"}],\"thumbnail_size\":\"full\",\"thumbnail_custom_dimension\":{\"width\":\"1500\",\"height\":\"847\"},\"slides_to_show\":\"1\",\"image_stretch\":\"yes\",\"navigation\":\"none\",\"_margin\":{\"unit\":\"px\",\"top\":\"100\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":\"\"},\"_padding\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":\"\"},\"image_border_radius\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":\"\"},\"slides_to_show_tablet\":\"1\",\"slides_to_show_mobile\":\"1\",\"_margin_mobile\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":\"\"},\"_padding_tablet\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":\"\"},\"_padding_mobile\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":\"\"},\"_margin_tablet\":{\"unit\":\"px\",\"top\":\"50\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":false}},\"elements\":[],\"widgetType\":\"image-carousel\"}],\"isInner\":\"\"}],\"isInner\":\"\"},{\"id\":\"5892a85\",\"elType\":\"section\",\"settings\":{\"padding\":{\"unit\":\"px\",\"top\":\"100\",\"right\":\"0\",\"bottom\":\"100\",\"left\":\"0\",\"isLinked\":false},\"margin_mobile\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":\"\"},\"padding_mobile\":{\"unit\":\"px\",\"top\":\"20\",\"right\":\"20\",\"bottom\":\"20\",\"left\":\"20\",\"isLinked\":true},\"gap\":\"no\",\"padding_tablet\":{\"unit\":\"px\",\"top\":\"50\",\"right\":\"50\",\"bottom\":\"50\",\"left\":\"50\",\"isLinked\":true},\"background_background\":\"classic\",\"background_image\":{\"url\":\"https:\\\/\\\/websitedemos.net\\\/luxury-hotel-04\\\/wp-content\\\/uploads\\\/sites\\\/812\\\/2021\\\/06\\\/facilities-list-bg.jpg\",\"id\":1599},\"background_position\":\"center center\",\"background_attachment\":\"fixed\",\"background_repeat\":\"no-repeat\",\"background_size\":\"cover\",\"background_overlay_background\":\"classic\",\"background_overlay_color\":\"#000000\",\"margin\":{\"unit\":\"px\",\"top\":\"0\",\"right\":0,\"bottom\":\"0\",\"left\":0,\"isLinked\":false}},\"elements\":[{\"id\":\"3603b1b\",\"elType\":\"column\",\"settings\":{\"_column_size\":\"100\",\"padding_mobile\":{\"unit\":\"px\",\"top\":\"40\",\"right\":\"20\",\"bottom\":\"40\",\"left\":\"20\",\"isLinked\":false},\"margin\":{\"unit\":\"%\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":true},\"padding\":{\"unit\":\"%\",\"top\":\"8\",\"right\":\"35\",\"bottom\":\"8\",\"left\":\"8\",\"isLinked\":false},\"content_position\":\"center\",\"background_background\":\"classic\",\"background_position\":\"center center\",\"background_attachment\":\"fixed\",\"background_repeat\":\"no-repeat\",\"background_size\":\"cover\",\"background_overlay_background\":\"classic\",\"border_radius\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":\"\"},\"margin_mobile\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":\"\"},\"z_index\":\"1\",\"padding_tablet\":{\"unit\":\"px\",\"top\":\"50\",\"right\":\"50\",\"bottom\":\"50\",\"left\":\"50\",\"isLinked\":true},\"background_overlay_opacity\":{\"unit\":\"px\",\"size\":0.8,\"sizes\":[]},\"border_border\":\"solid\",\"border_width\":{\"unit\":\"px\",\"top\":\"1\",\"right\":\"1\",\"bottom\":\"1\",\"left\":\"1\",\"isLinked\":true},\"border_color\":\"#353232\",\"__globals__\":{\"background_overlay_color\":\"globals\\\/colors?id=astraheadingcolor\"}},\"elements\":[{\"id\":\"8b40fe7\",\"elType\":\"widget\",\"settings\":{\"title\":\"An Escape from Reality\",\"align\":\"left\",\"__globals__\":{\"title_color\":\"globals\\\/colors?id=astratextcolor\"}},\"elements\":[],\"widgetType\":\"heading\"},{\"id\":\"372c646\",\"elType\":\"widget\",\"settings\":{\"editor\":\"Quisque velit nisi, pretium ut lacinia in, elementum id enim. Curabitur non nulla sit amet nisl tempus convallis quis ac lectus. Lorem elit tellus, luctus nec ullamcorper mattis, pulvinar dapibus leo.\",\"text_columns\":\"1\",\"column_gap\":{\"unit\":\"px\",\"size\":\"0\",\"sizes\":[]},\"_padding_mobile\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"25\",\"left\":\"0\",\"isLinked\":\"\"},\"typography_typography\":\"custom\",\"typography_font_size_mobile\":{\"unit\":\"px\",\"size\":13,\"sizes\":[]}},\"elements\":[],\"widgetType\":\"text-editor\"},{\"id\":\"6d81618\",\"elType\":\"widget\",\"settings\":{\"selected_icon\":{\"value\":\"fas fa-play\",\"library\":\"fa-solid\"},\"view\":\"framed\",\"size\":{\"unit\":\"px\",\"size\":25,\"sizes\":[]},\"icon_padding\":{\"unit\":\"px\",\"size\":20,\"sizes\":[]},\"border_width\":{\"unit\":\"px\",\"top\":\"2\",\"right\":\"2\",\"bottom\":\"2\",\"left\":\"2\",\"isLinked\":true},\"_margin\":{\"unit\":\"px\",\"top\":\"50\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":false},\"link\":{\"url\":\"#\",\"is_external\":\"\",\"nofollow\":\"\",\"custom_attributes\":\"\"},\"hover_animation\":\"grow\",\"size_tablet\":{\"unit\":\"px\",\"size\":15,\"sizes\":[]},\"align\":\"\",\"size_mobile\":{\"unit\":\"px\",\"size\":13,\"sizes\":[]},\"_margin_tablet\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":false},\"_padding_tablet\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":false},\"__globals__\":{\"primary_color\":\"globals\\\/colors?id=astratextcolor\",\"hover_primary_color\":\"globals\\\/colors?id=astrathemecolor\"}},\"elements\":[],\"widgetType\":\"icon\"}],\"isInner\":\"\"}],\"isInner\":\"\"},{\"id\":\"44e303f\",\"elType\":\"section\",\"settings\":{\"gap\":\"no\",\"padding\":{\"unit\":\"px\",\"top\":\"120\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":\"\"},\"custom_height\":{\"unit\":\"vh\",\"size\":\"100\",\"sizes\":[]},\"padding_tablet\":{\"unit\":\"px\",\"top\":\"50\",\"right\":\"50\",\"bottom\":\"50\",\"left\":\"50\",\"isLinked\":true},\"padding_mobile\":{\"unit\":\"px\",\"top\":\"50\",\"right\":\"0\",\"bottom\":\"50\",\"left\":\"0\",\"isLinked\":\"\"},\"layout\":\"full_width\"},\"elements\":[{\"id\":\"c543bb0\",\"elType\":\"column\",\"settings\":{\"_column_size\":\"100\",\"padding_mobile\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"25\",\"bottom\":\"0\",\"left\":\"25\",\"isLinked\":\"\"}},\"elements\":[{\"id\":\"2952b97\",\"elType\":\"widget\",\"settings\":{\"title\":\" Luxurious Services\",\"align\":\"center\",\"align_mobile\":\"left\",\"_padding\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":true},\"align_tablet\":\"center\",\"_margin_tablet\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":false},\"_padding_tablet\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":false}},\"elements\":[],\"widgetType\":\"heading\"},{\"id\":\"9429e4f\",\"elType\":\"section\",\"settings\":{\"gap\":\"no\",\"structure\":\"40\",\"padding_tablet\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":false},\"padding_mobile\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":\"\"},\"layout\":\"full_width\",\"margin\":{\"unit\":\"px\",\"top\":\"50\",\"right\":0,\"bottom\":\"0\",\"left\":0,\"isLinked\":false},\"margin_tablet\":{\"unit\":\"px\",\"top\":\"20\",\"right\":0,\"bottom\":\"0\",\"left\":0,\"isLinked\":false},\"padding\":{\"unit\":\"%\",\"top\":\"0\",\"right\":\"10\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":false}},\"elements\":[{\"id\":\"b890484\",\"elType\":\"column\",\"settings\":{\"_column_size\":25,\"content_position\":\"bottom\",\"space_between_widgets\":\"10\",\"background_background\":\"classic\",\"box_shadow_box_shadow\":{\"horizontal\":\"0\",\"vertical\":\"0\",\"blur\":\"45\",\"spread\":\"0\",\"color\":\"#FFFFFF\"},\"margin\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":\"1\"},\"padding\":{\"unit\":\"px\",\"top\":\"400\",\"right\":\"50\",\"bottom\":\"50\",\"left\":\"50\",\"isLinked\":\"\"},\"background_hover_background\":\"classic\",\"background_hover_color\":\"#C0925F\",\"background_hover_transition\":{\"unit\":\"px\",\"size\":\"1.3\",\"sizes\":[]},\"border_width\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"2\",\"bottom\":\"2\",\"left\":\"0\",\"isLinked\":\"\"},\"z_index\":\"1\",\"background_image\":{\"url\":\"https:\\\/\\\/websitedemos.net\\\/luxury-hotel-04\\\/wp-content\\\/uploads\\\/sites\\\/812\\\/2021\\\/04\\\/room-service.jpg\",\"id\":\"956\"},\"background_position\":\"center center\",\"background_attachment\":\"scroll\",\"background_repeat\":\"no-repeat\",\"background_size\":\"cover\",\"background_overlay_background\":\"gradient\",\"background_overlay_color\":\"#121314\",\"background_overlay_hover_background\":\"classic\",\"background_overlay_hover_color\":\"#000000\",\"background_overlay_hover_opacity\":{\"unit\":\"px\",\"size\":\"0.29\",\"sizes\":[]},\"border_radius\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":\"\"},\"_inline_size\":null,\"_inline_size_tablet\":50,\"background_overlay_color_b\":\"#FFFFFF00\",\"background_overlay_gradient_angle\":{\"unit\":\"deg\",\"size\":75,\"sizes\":[]},\"background_overlay_color_stop\":{\"unit\":\"%\",\"size\":15,\"sizes\":[]},\"background_overlay_opacity\":{\"unit\":\"px\",\"size\":0.7,\"sizes\":[]},\"padding_tablet\":{\"unit\":\"px\",\"top\":\"130\",\"right\":\"30\",\"bottom\":\"30\",\"left\":\"30\",\"isLinked\":false}},\"elements\":[{\"id\":\"9bed0b6\",\"elType\":\"widget\",\"settings\":{\"title\":\"In-room Dining\",\"header_size\":\"h5\",\"align\":\"left\",\"title_color\":\"#FFFFFF\",\"align_mobile\":\"left\",\"_margin_mobile\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":\"1\"},\"_padding_mobile\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"25\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":\"\"}},\"elements\":[],\"widgetType\":\"heading\"}],\"isInner\":\"1\"},{\"id\":\"32c9522\",\"elType\":\"column\",\"settings\":{\"_column_size\":25,\"content_position\":\"bottom\",\"space_between_widgets\":\"10\",\"background_background\":\"classic\",\"box_shadow_box_shadow\":{\"horizontal\":\"0\",\"vertical\":\"0\",\"blur\":\"45\",\"spread\":\"0\",\"color\":\"#FFFFFF\"},\"margin\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":\"1\"},\"padding\":{\"unit\":\"px\",\"top\":\"400\",\"right\":\"50\",\"bottom\":\"50\",\"left\":\"50\",\"isLinked\":\"\"},\"background_hover_background\":\"classic\",\"background_hover_color\":\"#C0925F\",\"background_hover_transition\":{\"unit\":\"px\",\"size\":\"1.3\",\"sizes\":[]},\"border_width\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"2\",\"bottom\":\"2\",\"left\":\"0\",\"isLinked\":\"\"},\"z_index\":\"1\",\"background_image\":{\"url\":\"https:\\\/\\\/websitedemos.net\\\/luxury-hotel-04\\\/wp-content\\\/uploads\\\/sites\\\/812\\\/2021\\\/07\\\/hotel-pool.jpg\",\"id\":1836},\"background_position\":\"center center\",\"background_attachment\":\"scroll\",\"background_repeat\":\"no-repeat\",\"background_size\":\"cover\",\"background_overlay_background\":\"gradient\",\"background_overlay_color\":\"#121314\",\"background_overlay_hover_background\":\"classic\",\"background_overlay_hover_color\":\"#000000\",\"background_overlay_hover_opacity\":{\"unit\":\"px\",\"size\":\"0.29\",\"sizes\":[]},\"border_radius\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":\"\"},\"_inline_size\":null,\"_inline_size_tablet\":50,\"background_overlay_color_b\":\"#FFFFFF00\",\"background_overlay_gradient_angle\":{\"unit\":\"deg\",\"size\":75,\"sizes\":[]},\"background_overlay_color_stop\":{\"unit\":\"%\",\"size\":15,\"sizes\":[]},\"background_overlay_opacity\":{\"unit\":\"px\",\"size\":0.7,\"sizes\":[]},\"padding_tablet\":{\"unit\":\"px\",\"top\":\"130\",\"right\":\"30\",\"bottom\":\"30\",\"left\":\"30\",\"isLinked\":false}},\"elements\":[{\"id\":\"9794a27\",\"elType\":\"widget\",\"settings\":{\"title\":\"Private Pools\",\"header_size\":\"h5\",\"align\":\"left\",\"title_color\":\"#FFFFFF\"},\"elements\":[],\"widgetType\":\"heading\"}],\"isInner\":true},{\"id\":\"d57eace\",\"elType\":\"column\",\"settings\":{\"_column_size\":25,\"content_position\":\"bottom\",\"space_between_widgets\":\"10\",\"background_background\":\"classic\",\"margin\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":\"1\"},\"padding\":{\"unit\":\"px\",\"top\":\"400\",\"right\":\"50\",\"bottom\":\"50\",\"left\":\"50\",\"isLinked\":\"\"},\"z_index\":\"1\",\"background_hover_background\":\"classic\",\"background_hover_color\":\"#C0925F\",\"border_width\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"2\",\"bottom\":\"2\",\"left\":\"0\",\"isLinked\":\"\"},\"box_shadow_box_shadow\":{\"horizontal\":\"0\",\"vertical\":\"0\",\"blur\":\"45\",\"spread\":\"0\",\"color\":\"#FFFFFF\"},\"background_image\":{\"url\":\"https:\\\/\\\/websitedemos.net\\\/luxury-hotel-04\\\/wp-content\\\/uploads\\\/sites\\\/812\\\/2021\\\/04\\\/Concierge.jpg\",\"id\":1009},\"background_position\":\"center center\",\"background_attachment\":\"scroll\",\"background_repeat\":\"no-repeat\",\"background_size\":\"cover\",\"background_hover_transition\":{\"unit\":\"px\",\"size\":\"1.3\",\"sizes\":[]},\"background_overlay_background\":\"gradient\",\"background_overlay_color\":\"#121314\",\"background_overlay_hover_background\":\"classic\",\"background_overlay_hover_color\":\"#000000\",\"background_overlay_hover_opacity\":{\"unit\":\"px\",\"size\":\"0.29\",\"sizes\":[]},\"border_radius\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":\"\"},\"_inline_size\":null,\"_inline_size_tablet\":50,\"background_overlay_color_b\":\"#FFFFFF00\",\"background_overlay_gradient_angle\":{\"unit\":\"deg\",\"size\":75,\"sizes\":[]},\"background_overlay_color_stop\":{\"unit\":\"%\",\"size\":15,\"sizes\":[]},\"background_overlay_opacity\":{\"unit\":\"px\",\"size\":0.7,\"sizes\":[]},\"padding_tablet\":{\"unit\":\"px\",\"top\":\"130\",\"right\":\"30\",\"bottom\":\"30\",\"left\":\"30\",\"isLinked\":false}},\"elements\":[{\"id\":\"020eec8\",\"elType\":\"widget\",\"settings\":{\"title\":\"Concierge Service\",\"header_size\":\"h5\",\"align\":\"left\",\"title_color\":\"#FFFFFF\"},\"elements\":[],\"widgetType\":\"heading\"}],\"isInner\":\"1\"},{\"id\":\"64370d6\",\"elType\":\"column\",\"settings\":{\"_column_size\":25,\"content_position\":\"bottom\",\"space_between_widgets\":\"10\",\"background_background\":\"classic\",\"margin\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":\"1\"},\"padding\":{\"unit\":\"px\",\"top\":\"400\",\"right\":\"50\",\"bottom\":\"50\",\"left\":\"50\",\"isLinked\":\"\"},\"z_index\":\"1\",\"background_hover_background\":\"classic\",\"background_hover_color\":\"#C0925F\",\"border_width\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"2\",\"bottom\":\"2\",\"left\":\"0\",\"isLinked\":\"\"},\"box_shadow_box_shadow\":{\"horizontal\":\"0\",\"vertical\":\"0\",\"blur\":\"45\",\"spread\":\"0\",\"color\":\"#FFFFFF\"},\"background_image\":{\"url\":\"https:\\\/\\\/websitedemos.net\\\/luxury-hotel-04\\\/wp-content\\\/uploads\\\/sites\\\/812\\\/2021\\\/04\\\/games.jpg\",\"id\":958},\"background_position\":\"center center\",\"background_attachment\":\"scroll\",\"background_repeat\":\"no-repeat\",\"background_size\":\"cover\",\"background_hover_transition\":{\"unit\":\"px\",\"size\":\"1.3\",\"sizes\":[]},\"background_overlay_background\":\"gradient\",\"background_overlay_color\":\"#121314\",\"background_overlay_hover_background\":\"classic\",\"background_overlay_hover_color\":\"#000000\",\"background_overlay_hover_opacity\":{\"unit\":\"px\",\"size\":\"0.29\",\"sizes\":[]},\"border_radius\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":\"\"},\"_inline_size\":null,\"_inline_size_tablet\":50,\"background_overlay_color_b\":\"#FFFFFF00\",\"background_overlay_gradient_angle\":{\"unit\":\"deg\",\"size\":75,\"sizes\":[]},\"background_overlay_color_stop\":{\"unit\":\"%\",\"size\":15,\"sizes\":[]},\"background_overlay_opacity\":{\"unit\":\"px\",\"size\":0.7,\"sizes\":[]},\"padding_tablet\":{\"unit\":\"px\",\"top\":\"130\",\"right\":\"30\",\"bottom\":\"30\",\"left\":\"30\",\"isLinked\":false}},\"elements\":[{\"id\":\"64f72e0\",\"elType\":\"widget\",\"settings\":{\"title\":\"VIP Casino Entries\",\"header_size\":\"h5\",\"align\":\"left\",\"title_color\":\"#FFFFFF\"},\"elements\":[],\"widgetType\":\"heading\"}],\"isInner\":true}],\"isInner\":\"1\"}],\"isInner\":\"\"}],\"isInner\":\"\"},{\"id\":\"1f30b13\",\"elType\":\"section\",\"settings\":{\"gap\":\"no\",\"custom_height\":{\"unit\":\"vh\",\"size\":\"100\",\"sizes\":[]},\"overflow\":\"hidden\",\"padding\":{\"unit\":\"px\",\"top\":\"120\",\"right\":\"0\",\"bottom\":\"120\",\"left\":\"0\",\"isLinked\":\"\"},\"margin_tablet\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":\"\"},\"padding_tablet\":{\"unit\":\"px\",\"top\":\"50\",\"right\":\"50\",\"bottom\":\"50\",\"left\":\"50\",\"isLinked\":true},\"padding_mobile\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"20\",\"bottom\":\"50\",\"left\":\"20\",\"isLinked\":\"\"}},\"elements\":[{\"id\":\"ec69b6e\",\"elType\":\"column\",\"settings\":{\"_column_size\":\"100\",\"margin_tablet\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":false},\"padding_tablet\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":false},\"padding_mobile\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":true}},\"elements\":[{\"id\":\"99fea7b\",\"elType\":\"widget\",\"settings\":{\"title\":\"Every corner with a<br> Luxury Touch\",\"header_size\":\"h3\",\"align\":\"center\",\"align_mobile\":\"left\"},\"elements\":[],\"widgetType\":\"heading\"},{\"id\":\"26df9a8\",\"elType\":\"widget\",\"settings\":{\"editor\":\"Lorem elit tellus, luctus nec ullamcorper mattis, pulvinar dapibus leo.\",\"align\":\"center\",\"align_mobile\":\"left\",\"_margin\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":false}},\"elements\":[],\"widgetType\":\"text-editor\"},{\"id\":\"8fe0606\",\"elType\":\"section\",\"settings\":{\"structure\":\"30\",\"padding\":{\"unit\":\"px\",\"top\":\"50\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":\"\"},\"margin_mobile\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":\"\"},\"padding_tablet\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":true},\"padding_mobile\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":\"\"},\"margin_tablet\":{\"unit\":\"px\",\"top\":\"0\",\"right\":0,\"bottom\":\"0\",\"left\":0,\"isLinked\":false}},\"elements\":[{\"id\":\"1110f17\",\"elType\":\"column\",\"settings\":{\"_column_size\":\"33\",\"_inline_size_mobile\":50},\"elements\":[{\"id\":\"796d717\",\"elType\":\"widget\",\"settings\":{\"image\":{\"url\":\"https:\\\/\\\/websitedemos.net\\\/luxury-hotel-04\\\/wp-content\\\/uploads\\\/sites\\\/812\\\/2021\\\/04\\\/gallery-new-1.jpeg\",\"id\":\"671\"},\"background_hover_transition\":{\"unit\":\"px\",\"size\":\"0.9\",\"sizes\":[]},\"width_mobile\":{\"unit\":\"%\",\"size\":100,\"sizes\":[]}},\"elements\":[],\"widgetType\":\"image\"},{\"id\":\"bc3f872\",\"elType\":\"widget\",\"settings\":{\"image\":{\"url\":\"https:\\\/\\\/websitedemos.net\\\/luxury-hotel-04\\\/wp-content\\\/uploads\\\/sites\\\/812\\\/2021\\\/04\\\/gallery-new-7.jpeg\",\"id\":\"676\"},\"background_hover_transition\":{\"unit\":\"px\",\"size\":\"0.9\",\"sizes\":[]},\"width_mobile\":{\"unit\":\"%\",\"size\":100,\"sizes\":[]}},\"elements\":[],\"widgetType\":\"image\"}],\"isInner\":\"1\"},{\"id\":\"f5d706d\",\"elType\":\"column\",\"settings\":{\"_column_size\":\"33\",\"_inline_size_mobile\":50},\"elements\":[{\"id\":\"3e30089\",\"elType\":\"widget\",\"settings\":{\"image\":{\"url\":\"https:\\\/\\\/websitedemos.net\\\/luxury-hotel-04\\\/wp-content\\\/uploads\\\/sites\\\/812\\\/2021\\\/04\\\/gallery-new-4.jpeg\",\"id\":\"677\"},\"background_hover_transition\":{\"unit\":\"px\",\"size\":\"0.9\",\"sizes\":[]},\"width_mobile\":{\"unit\":\"%\",\"size\":100,\"sizes\":[]}},\"elements\":[],\"widgetType\":\"image\"},{\"id\":\"1ba086f\",\"elType\":\"widget\",\"settings\":{\"image\":{\"url\":\"https:\\\/\\\/websitedemos.net\\\/luxury-hotel-04\\\/wp-content\\\/uploads\\\/sites\\\/812\\\/2021\\\/04\\\/gallery-15.jpeg\",\"id\":\"825\"},\"background_hover_transition\":{\"unit\":\"px\",\"size\":\"0.9\",\"sizes\":[]},\"image_size\":\"full\",\"space\":{\"unit\":\"px\",\"size\":\"\",\"sizes\":[]},\"height\":{\"unit\":\"vh\",\"size\":\"\",\"sizes\":[]},\"width_mobile\":{\"unit\":\"%\",\"size\":100,\"sizes\":[]}},\"elements\":[],\"widgetType\":\"image\"}],\"isInner\":\"1\"},{\"id\":\"6935ec6\",\"elType\":\"column\",\"settings\":{\"_column_size\":\"33\",\"align_mobile\":\"space-between\"},\"elements\":[{\"id\":\"09b40b8\",\"elType\":\"widget\",\"settings\":{\"image\":{\"url\":\"https:\\\/\\\/websitedemos.net\\\/luxury-hotel-04\\\/wp-content\\\/uploads\\\/sites\\\/812\\\/2021\\\/04\\\/gallery-new-5.jpeg\",\"id\":\"674\"},\"background_hover_transition\":{\"unit\":\"px\",\"size\":\"0.9\",\"sizes\":[]},\"width_mobile\":{\"unit\":\"%\",\"size\":100,\"sizes\":[]},\"_element_width_mobile\":\"initial\",\"_element_custom_width_mobile\":{\"unit\":\"%\",\"size\":47,\"sizes\":[]}},\"elements\":[],\"widgetType\":\"image\"},{\"id\":\"0340dd0\",\"elType\":\"widget\",\"settings\":{\"image\":{\"url\":\"https:\\\/\\\/websitedemos.net\\\/luxury-hotel-04\\\/wp-content\\\/uploads\\\/sites\\\/812\\\/2021\\\/04\\\/gallery-6.png\",\"id\":\"214\"},\"background_hover_transition\":{\"unit\":\"px\",\"size\":\"0.9\",\"sizes\":[]},\"width_mobile\":{\"unit\":\"%\",\"size\":100,\"sizes\":[]},\"_element_width_mobile\":\"initial\",\"_element_custom_width_mobile\":{\"unit\":\"%\",\"size\":47,\"sizes\":[]}},\"elements\":[],\"widgetType\":\"image\"}],\"isInner\":\"1\"}],\"isInner\":\"1\"}],\"isInner\":\"\"}],\"isInner\":\"\"},{\"id\":\"b43f964\",\"elType\":\"section\",\"settings\":{\"gap\":\"no\",\"background_background\":\"classic\",\"padding\":{\"unit\":\"px\",\"top\":\"50\",\"right\":\"0\",\"bottom\":\"120\",\"left\":\"0\",\"isLinked\":\"\"},\"custom_height\":{\"unit\":\"px\",\"size\":\"\",\"sizes\":[]},\"background_image\":{\"url\":\"https:\\\/\\\/websitedemos.net\\\/luxury-hotel-04\\\/wp-content\\\/uploads\\\/sites\\\/812\\\/2021\\\/06\\\/contact-us-hero-bg.jpg\",\"id\":1562},\"background_position\":\"center center\",\"background_attachment\":\"fixed\",\"background_repeat\":\"no-repeat\",\"background_size\":\"cover\",\"background_overlay_background\":\"gradient\",\"background_overlay_opacity\":{\"unit\":\"px\",\"size\":1,\"sizes\":[]},\"padding_mobile\":{\"unit\":\"px\",\"top\":\"50\",\"right\":\"0\",\"bottom\":\"50\",\"left\":\"0\",\"isLinked\":\"\"},\"background_overlay_color_b\":\"#121314CC\",\"background_overlay_color_b_stop\":{\"unit\":\"%\",\"size\":25,\"sizes\":[]},\"padding_tablet\":{\"unit\":\"px\",\"top\":\"50\",\"right\":\"50\",\"bottom\":\"50\",\"left\":\"50\",\"isLinked\":false},\"__globals__\":{\"background_overlay_color\":\"globals\\\/colors?id=astraheadingcolor\"}},\"elements\":[{\"id\":\"cfb75bc\",\"elType\":\"column\",\"settings\":{\"_column_size\":\"100\",\"padding_mobile\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"25\",\"bottom\":\"0\",\"left\":\"25\",\"isLinked\":\"\"},\"margin\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":false},\"padding\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":false}},\"elements\":[{\"id\":\"38de57f\",\"elType\":\"section\",\"settings\":{\"gap\":\"no\",\"structure\":\"32\",\"padding\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":\"\"},\"padding_tablet\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":true},\"padding_mobile\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":\"\"},\"margin\":{\"unit\":\"px\",\"top\":\"0\",\"right\":0,\"bottom\":\"0\",\"left\":0,\"isLinked\":false},\"margin_mobile\":{\"unit\":\"px\",\"top\":\"0\",\"right\":0,\"bottom\":\"0\",\"left\":0,\"isLinked\":false}},\"elements\":[{\"id\":\"bafa471\",\"elType\":\"column\",\"settings\":{\"_column_size\":\"50\",\"content_position\":\"center\",\"padding\":{\"unit\":\"px\",\"top\":\"30\",\"right\":\"30\",\"bottom\":\"30\",\"left\":\"0\",\"isLinked\":false},\"_inline_size_tablet\":100,\"padding_tablet\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"50\",\"bottom\":\"50\",\"left\":\"50\",\"isLinked\":false},\"margin_mobile\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"30\",\"left\":\"0\",\"isLinked\":false},\"padding_mobile\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":true}},\"elements\":[{\"id\":\"c084bbd\",\"elType\":\"widget\",\"settings\":{\"title\":\"Luxury Privileges\",\"header_size\":\"h6\",\"align\":\"left\",\"typography_font_size\":{\"unit\":\"px\",\"size\":\"20\",\"sizes\":[]},\"typography_font_weight\":\"500\",\"align_tablet\":\"center\",\"align_mobile\":\"left\"},\"elements\":[],\"widgetType\":\"heading\"},{\"id\":\"f6056e3\",\"elType\":\"widget\",\"settings\":{\"title\":\"Membership Benefits\",\"align\":\"left\",\"align_tablet\":\"center\",\"align_mobile\":\"left\",\"_margin\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":false},\"_padding\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":false},\"__globals__\":{\"title_color\":\"globals\\\/colors?id=astratextcolor\"}},\"elements\":[],\"widgetType\":\"heading\"},{\"id\":\"9e7be88\",\"elType\":\"widget\",\"settings\":{\"_padding\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"50\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":\"\"},\"editor\":\"Lorem ipsum dolor sit amet, consectetur adipiscing elit. Ut elit tellus, luctus nec ullamcorper mattis, pulvinar dapibus leo.\",\"align_tablet\":\"center\",\"_margin_tablet\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":false},\"_padding_tablet\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":false},\"align_mobile\":\"left\"},\"elements\":[],\"widgetType\":\"text-editor\"}],\"isInner\":\"1\"},{\"id\":\"a5ccee4\",\"elType\":\"column\",\"settings\":{\"_column_size\":\"25\",\"content_position\":\"center\",\"space_between_widgets\":30,\"background_background\":\"classic\",\"background_color\":\"#121314\",\"margin\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":\"\"},\"padding\":{\"unit\":\"px\",\"top\":\"30\",\"right\":\"30\",\"bottom\":\"30\",\"left\":\"30\",\"isLinked\":true},\"_inline_size_tablet\":50,\"padding_tablet\":{\"unit\":\"px\",\"top\":\"40\",\"right\":\"40\",\"bottom\":\"40\",\"left\":\"40\",\"isLinked\":true},\"padding_mobile\":{\"unit\":\"px\",\"top\":\"25\",\"right\":\"25\",\"bottom\":\"25\",\"left\":\"25\",\"isLinked\":true},\"space_between_widgets_mobile\":10},\"elements\":[{\"id\":\"3dbe085\",\"elType\":\"widget\",\"settings\":{\"title\":\"World-class Stay Benefits\",\"header_size\":\"h5\",\"align\":\"left\",\"_padding\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":\"\"}},\"elements\":[],\"widgetType\":\"heading\"},{\"id\":\"46e2928\",\"elType\":\"widget\",\"settings\":{\"editor\":\"Lorem ipsum dolor sit amet, consec tetur adipiscing. Ut elit tellus, luctus nec nullam corper, pulvinar dapibus leo.\",\"_padding\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":\"\"},\"_margin_mobile\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":false},\"_padding_mobile\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":false}},\"elements\":[],\"widgetType\":\"text-editor\"}],\"isInner\":\"1\"},{\"id\":\"48634c1\",\"elType\":\"column\",\"settings\":{\"_column_size\":\"25\",\"_inline_size_tablet\":50},\"elements\":[{\"id\":\"0808af0\",\"elType\":\"widget\",\"settings\":{\"image\":{\"url\":\"https:\\\/\\\/websitedemos.net\\\/luxury-hotel-04\\\/wp-content\\\/uploads\\\/sites\\\/812\\\/2021\\\/04\\\/world-class1.jpg\",\"id\":\"1091\"},\"image_size\":\"medium\",\"width_tablet\":{\"unit\":\"%\",\"size\":100,\"sizes\":[]}},\"elements\":[],\"widgetType\":\"image\"}],\"isInner\":\"1\"}],\"isInner\":\"1\"},{\"id\":\"72788a7\",\"elType\":\"section\",\"settings\":{\"gap\":\"no\",\"structure\":\"40\",\"padding\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":\"\"},\"padding_mobile\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":\"\"},\"reverse_order_mobile\":\"reverse-mobile\"},\"elements\":[{\"id\":\"03e50d8\",\"elType\":\"column\",\"settings\":{\"_column_size\":\"25\",\"_inline_size_tablet\":50},\"elements\":[{\"id\":\"92d51dc\",\"elType\":\"widget\",\"settings\":{\"image\":{\"url\":\"https:\\\/\\\/websitedemos.net\\\/luxury-hotel-04\\\/wp-content\\\/uploads\\\/sites\\\/812\\\/2021\\\/04\\\/casino-11.jpg\",\"id\":\"1087\"},\"image_size\":\"medium\",\"width_tablet\":{\"unit\":\"%\",\"size\":100,\"sizes\":[]}},\"elements\":[],\"widgetType\":\"image\"}],\"isInner\":\"1\"},{\"id\":\"69ebf5f\",\"elType\":\"column\",\"settings\":{\"_column_size\":\"25\",\"content_position\":\"center\",\"space_between_widgets\":30,\"background_background\":\"classic\",\"background_color\":\"#080809\",\"margin\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":\"\"},\"padding\":{\"unit\":\"px\",\"top\":\"30\",\"right\":\"30\",\"bottom\":\"30\",\"left\":\"30\",\"isLinked\":true},\"_inline_size_tablet\":50,\"padding_tablet\":{\"unit\":\"px\",\"top\":\"40\",\"right\":\"40\",\"bottom\":\"40\",\"left\":\"40\",\"isLinked\":true},\"padding_mobile\":{\"unit\":\"px\",\"top\":\"25\",\"right\":\"25\",\"bottom\":\"25\",\"left\":\"25\",\"isLinked\":true},\"space_between_widgets_mobile\":10},\"elements\":[{\"id\":\"c305487\",\"elType\":\"widget\",\"settings\":{\"title\":\"Exclusive Casino Benefits\",\"header_size\":\"h5\",\"align\":\"left\",\"_padding\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":\"\"}},\"elements\":[],\"widgetType\":\"heading\"},{\"id\":\"e136809\",\"elType\":\"widget\",\"settings\":{\"editor\":\"Lorem ipsum dolor sit amet, consec tetur adipiscing. Ut elit tellus, luctus nec nullam corper, pulvinar dapibus leo.\",\"_padding\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":\"\"},\"_margin_mobile\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":false},\"_padding_mobile\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":false}},\"elements\":[],\"widgetType\":\"text-editor\"}],\"isInner\":\"1\"},{\"id\":\"958d637\",\"elType\":\"column\",\"settings\":{\"_column_size\":\"25\",\"content_position\":\"center\",\"space_between_widgets\":\"3\",\"padding_mobile\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":\"\"},\"_inline_size_tablet\":50,\"margin_mobile\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":false}},\"elements\":[{\"id\":\"1fcafc8\",\"elType\":\"widget\",\"settings\":{\"image\":{\"url\":\"https:\\\/\\\/websitedemos.net\\\/luxury-hotel-04\\\/wp-content\\\/uploads\\\/sites\\\/812\\\/2021\\\/04\\\/350x350-3.png\",\"id\":\"192\"},\"image_size\":\"medium\",\"width_tablet\":{\"unit\":\"%\",\"size\":100,\"sizes\":[]}},\"elements\":[],\"widgetType\":\"image\"}],\"isInner\":\"1\"},{\"id\":\"3ba3f56\",\"elType\":\"column\",\"settings\":{\"_column_size\":\"25\",\"content_position\":\"center\",\"space_between_widgets\":30,\"background_background\":\"classic\",\"background_color\":\"#121314\",\"margin\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":\"\"},\"padding\":{\"unit\":\"px\",\"top\":\"30\",\"right\":\"30\",\"bottom\":\"30\",\"left\":\"30\",\"isLinked\":true},\"_inline_size_tablet\":50,\"padding_tablet\":{\"unit\":\"px\",\"top\":\"40\",\"right\":\"40\",\"bottom\":\"40\",\"left\":\"40\",\"isLinked\":true},\"padding_mobile\":{\"unit\":\"px\",\"top\":\"25\",\"right\":\"25\",\"bottom\":\"25\",\"left\":\"25\",\"isLinked\":true},\"space_between_widgets_mobile\":10},\"elements\":[{\"id\":\"80bb014\",\"elType\":\"widget\",\"settings\":{\"title\":\"Exclusive Lifestyle Voucher\",\"header_size\":\"h5\",\"align\":\"left\",\"_padding\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":\"\"}},\"elements\":[],\"widgetType\":\"heading\"},{\"id\":\"3c7cdd0\",\"elType\":\"widget\",\"settings\":{\"editor\":\"Lorem ipsum dolor sit amet, consec tetur adipiscing. Ut elit tellus, luctus nec nullam corper, pulvinar dapibus leo.\",\"_padding\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":\"\"},\"_margin_mobile\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":false},\"_padding_mobile\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":false}},\"elements\":[],\"widgetType\":\"text-editor\"}],\"isInner\":\"1\"}],\"isInner\":\"1\"},{\"id\":\"070f618\",\"elType\":\"section\",\"settings\":{\"gap\":\"no\",\"structure\":\"31\",\"padding\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":\"\"},\"padding_mobile\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":\"\"},\"margin_mobile\":{\"unit\":\"px\",\"top\":\"0\",\"right\":0,\"bottom\":\"0\",\"left\":0,\"isLinked\":false}},\"elements\":[{\"id\":\"339ed69\",\"elType\":\"column\",\"settings\":{\"_column_size\":\"25\",\"content_position\":\"center\",\"space_between_widgets\":30,\"background_background\":\"classic\",\"background_color\":\"#080809\",\"margin\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":\"\"},\"padding\":{\"unit\":\"px\",\"top\":\"30\",\"right\":\"30\",\"bottom\":\"30\",\"left\":\"30\",\"isLinked\":true},\"_inline_size_tablet\":50,\"padding_tablet\":{\"unit\":\"px\",\"top\":\"40\",\"right\":\"40\",\"bottom\":\"40\",\"left\":\"40\",\"isLinked\":true},\"padding_mobile\":{\"unit\":\"px\",\"top\":\"25\",\"right\":\"25\",\"bottom\":\"25\",\"left\":\"25\",\"isLinked\":true},\"space_between_widgets_mobile\":10},\"elements\":[{\"id\":\"6543a0c\",\"elType\":\"widget\",\"settings\":{\"title\":\"Complementary<br> Wine Bottle \",\"header_size\":\"h5\",\"align\":\"left\",\"_padding\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":\"\"}},\"elements\":[],\"widgetType\":\"heading\"},{\"id\":\"08dcee1\",\"elType\":\"widget\",\"settings\":{\"editor\":\"Lorem ipsum dolor sit amet, consec tetur adipiscing. Ut elit tellus, luctus nec nullam corper, pulvinar dapibus leo.\",\"_padding\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":\"\"},\"_margin_mobile\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":false},\"_padding_mobile\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":false}},\"elements\":[],\"widgetType\":\"text-editor\"}],\"isInner\":\"1\"},{\"id\":\"60ca7c4\",\"elType\":\"column\",\"settings\":{\"_column_size\":\"25\",\"_inline_size_tablet\":50},\"elements\":[{\"id\":\"4bb5e05\",\"elType\":\"widget\",\"settings\":{\"image\":{\"url\":\"https:\\\/\\\/websitedemos.net\\\/luxury-hotel-04\\\/wp-content\\\/uploads\\\/sites\\\/812\\\/2021\\\/04\\\/wine-bottle.jpg\",\"id\":\"1095\"},\"image_size\":\"medium\",\"width_tablet\":{\"unit\":\"%\",\"size\":100,\"sizes\":[]}},\"elements\":[],\"widgetType\":\"image\"}],\"isInner\":\"1\"},{\"id\":\"42498ad\",\"elType\":\"column\",\"settings\":{\"_column_size\":\"50\",\"content_position\":\"center\",\"background_background\":\"classic\",\"margin\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":\"\"},\"padding\":{\"unit\":\"px\",\"top\":\"30\",\"right\":\"0\",\"bottom\":\"30\",\"left\":\"30\",\"isLinked\":false},\"padding_mobile\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":false},\"_inline_size_tablet\":100,\"padding_tablet\":{\"unit\":\"px\",\"top\":\"50\",\"right\":\"50\",\"bottom\":\"50\",\"left\":\"50\",\"isLinked\":false},\"margin_mobile\":{\"unit\":\"px\",\"top\":\"30\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":false}},\"elements\":[{\"id\":\"410009b\",\"elType\":\"widget\",\"settings\":{\"title\":\" More Benefits\",\"header_size\":\"h4\",\"align\":\"left\",\"align_tablet\":\"center\",\"align_mobile\":\"left\",\"__globals__\":{\"title_color\":\"globals\\\/colors?id=astratextcolor\"}},\"elements\":[],\"widgetType\":\"heading\"},{\"id\":\"64450bd\",\"elType\":\"widget\",\"settings\":{\"editor\":\"Quisque velit nisi, pretium ut lacinia in, elementum id enim. Curabitur non nulla sit amet nisl tempus convallis quis ac lectus.\",\"_padding\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"50\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":\"\"},\"align_tablet\":\"center\",\"_margin_tablet\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":false},\"_padding_tablet\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":false},\"align_mobile\":\"left\"},\"elements\":[],\"widgetType\":\"text-editor\"},{\"id\":\"6c15209\",\"elType\":\"widget\",\"settings\":{\"text\":\"Become a Member\",\"_padding\":{\"unit\":\"px\",\"top\":\"15\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":\"\"},\"background_background\":\"\",\"button_background_hover_background\":\"\",\"align_tablet\":\"center\",\"_margin_tablet\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":false},\"_padding_tablet\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":false},\"align_mobile\":\"left\"},\"elements\":[],\"widgetType\":\"button\"}],\"isInner\":\"1\"}],\"isInner\":\"1\"}],\"isInner\":\"\"}],\"isInner\":\"\"},{\"id\":\"d4e6cd8\",\"elType\":\"section\",\"settings\":{\"gap\":\"no\",\"padding\":{\"unit\":\"px\",\"top\":\"120\",\"right\":\"0\",\"bottom\":\"80\",\"left\":\"0\",\"isLinked\":\"\"},\"padding_mobile\":{\"unit\":\"px\",\"top\":\"50\",\"right\":\"25\",\"bottom\":\"50\",\"left\":\"25\",\"isLinked\":\"\"},\"content_width\":{\"unit\":\"px\",\"size\":1200,\"sizes\":[]},\"custom_height\":{\"unit\":\"px\",\"size\":\"\",\"sizes\":[]},\"column_position\":\"stretch\",\"padding_tablet\":{\"unit\":\"px\",\"top\":\"50\",\"right\":\"20\",\"bottom\":\"50\",\"left\":\"20\",\"isLinked\":false}},\"elements\":[{\"id\":\"50621e2\",\"elType\":\"column\",\"settings\":{\"_column_size\":\"100\",\"padding_mobile\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":\"\"}},\"elements\":[{\"id\":\"e942a14\",\"elType\":\"widget\",\"settings\":{\"title\":\"Ideal Venue For Any Event\",\"header_size\":\"h3\",\"align\":\"center\",\"align_mobile\":\"left\"},\"elements\":[],\"widgetType\":\"heading\"},{\"id\":\"043c6de\",\"elType\":\"widget\",\"settings\":{\"editor\":\"Quisque velit nisi, pretium ut lacinia in, elementum id enim.\",\"align\":\"center\",\"align_mobile\":\"left\"},\"elements\":[],\"widgetType\":\"text-editor\"},{\"id\":\"53f2dd7\",\"elType\":\"section\",\"settings\":{\"gap\":\"no\",\"structure\":\"30\",\"padding\":{\"unit\":\"px\",\"top\":\"50\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":\"\"},\"padding_mobile\":{\"unit\":\"px\",\"top\":\"35\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":\"\"},\"padding_tablet\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":false}},\"elements\":[{\"id\":\"881ee3b\",\"elType\":\"column\",\"settings\":{\"_column_size\":\"33\",\"space_between_widgets\":0,\"background_color\":\"#FFFFFF\",\"margin\":{\"unit\":\"px\",\"top\":\"15\",\"right\":\"15\",\"bottom\":\"15\",\"left\":\"15\",\"isLinked\":true},\"box_shadow_box_shadow\":{\"horizontal\":0,\"vertical\":0,\"blur\":15,\"spread\":0,\"color\":\"rgba(0, 0, 0, 0.1)\"},\"margin_tablet\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":false},\"padding_tablet\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":false}},\"elements\":[{\"id\":\"6041157\",\"elType\":\"widget\",\"settings\":{\"image\":{\"url\":\"https:\\\/\\\/websitedemos.net\\\/luxury-hotel-04\\\/wp-content\\\/uploads\\\/sites\\\/812\\\/2021\\\/04\\\/event-1.png\",\"id\":\"243\"}},\"elements\":[],\"widgetType\":\"image\"},{\"id\":\"b77fb40\",\"elType\":\"widget\",\"settings\":{\"image\":{\"url\":\"\",\"id\":\"\"},\"title_text\":\"Weddings\",\"description_text\":\"Lorem ipsum dolor sit amet, consectetur adipiscing elit. Ut elit tellus, luctus nec ullamcorper mattis, pulvinar dapibus leo.\",\"title_size\":\"h4\",\"_padding\":{\"unit\":\"px\",\"top\":\"55\",\"right\":\"25\",\"bottom\":\"55\",\"left\":\"25\",\"isLinked\":false},\"_padding_tablet\":{\"unit\":\"px\",\"top\":\"25\",\"right\":\"25\",\"bottom\":\"25\",\"left\":\"25\",\"isLinked\":true},\"description_typography_typography\":\"custom\",\"description_typography_font_size_tablet\":{\"unit\":\"px\",\"size\":13,\"sizes\":[]},\"__globals__\":{\"title_color\":\"globals\\\/colors?id=astratextcolor\"}},\"elements\":[],\"widgetType\":\"image-box\"}],\"isInner\":\"1\"},{\"id\":\"7917a12\",\"elType\":\"column\",\"settings\":{\"_column_size\":\"33\",\"background_color\":\"#FFFFFF\",\"space_between_widgets\":0,\"margin\":{\"unit\":\"px\",\"top\":\"15\",\"right\":\"15\",\"bottom\":\"15\",\"left\":\"15\",\"isLinked\":true},\"box_shadow_box_shadow\":{\"horizontal\":0,\"vertical\":0,\"blur\":15,\"spread\":0,\"color\":\"rgba(0, 0, 0, 0.1)\"},\"margin_tablet\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":false},\"padding_tablet\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":false}},\"elements\":[{\"id\":\"87be951\",\"elType\":\"widget\",\"settings\":{\"image\":{\"url\":\"\",\"id\":\"\"},\"title_text\":\"Parties\",\"description_text\":\"Lorem ipsum dolor sit amet, consectetur adipiscing elit. Ut elit tellus, luctus nec ullamcorper mattis, pulvinar dapibus leo.\",\"title_size\":\"h4\",\"_padding\":{\"unit\":\"px\",\"top\":\"55\",\"right\":\"25\",\"bottom\":\"55\",\"left\":\"25\",\"isLinked\":false},\"_padding_tablet\":{\"unit\":\"px\",\"top\":\"25\",\"right\":\"25\",\"bottom\":\"25\",\"left\":\"25\",\"isLinked\":true},\"description_typography_typography\":\"custom\",\"description_typography_font_size_tablet\":{\"unit\":\"px\",\"size\":13,\"sizes\":[]},\"__globals__\":{\"title_color\":\"globals\\\/colors?id=astratextcolor\"}},\"elements\":[],\"widgetType\":\"image-box\"},{\"id\":\"72a84c1\",\"elType\":\"widget\",\"settings\":{\"image\":{\"url\":\"https:\\\/\\\/websitedemos.net\\\/luxury-hotel-04\\\/wp-content\\\/uploads\\\/sites\\\/812\\\/2021\\\/04\\\/event-2.png\",\"id\":\"245\"},\"_margin\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":false},\"_padding\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":false}},\"elements\":[],\"widgetType\":\"image\"}],\"isInner\":\"1\"},{\"id\":\"f870d46\",\"elType\":\"column\",\"settings\":{\"_column_size\":\"33\",\"space_between_widgets\":0,\"background_color\":\"#FFFFFF\",\"margin\":{\"unit\":\"px\",\"top\":\"15\",\"right\":\"15\",\"bottom\":\"15\",\"left\":\"15\",\"isLinked\":true},\"box_shadow_box_shadow\":{\"horizontal\":0,\"vertical\":0,\"blur\":15,\"spread\":0,\"color\":\"rgba(0, 0, 0, 0.1)\"},\"margin_tablet\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":false},\"padding_tablet\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":false}},\"elements\":[{\"id\":\"9ac7f1b\",\"elType\":\"widget\",\"settings\":{\"image\":{\"url\":\"https:\\\/\\\/websitedemos.net\\\/luxury-hotel-04\\\/wp-content\\\/uploads\\\/sites\\\/812\\\/2021\\\/04\\\/conference-1.jpg\",\"id\":\"1101\"}},\"elements\":[],\"widgetType\":\"image\"},{\"id\":\"cbc216a\",\"elType\":\"widget\",\"settings\":{\"image\":{\"url\":\"\",\"id\":\"\"},\"title_text\":\"Conference\",\"description_text\":\"Lorem ipsum dolor sit amet, consectetur adipiscing elit. Ut elit tellus, luctus nec ullamcorper mattis, pulvinar dapibus leo.\",\"title_size\":\"h4\",\"_padding\":{\"unit\":\"px\",\"top\":\"55\",\"right\":\"25\",\"bottom\":\"55\",\"left\":\"25\",\"isLinked\":false},\"_padding_tablet\":{\"unit\":\"px\",\"top\":\"25\",\"right\":\"25\",\"bottom\":\"25\",\"left\":\"25\",\"isLinked\":true},\"description_typography_typography\":\"custom\",\"description_typography_font_size_tablet\":{\"unit\":\"px\",\"size\":13,\"sizes\":[]},\"__globals__\":{\"title_color\":\"globals\\\/colors?id=astratextcolor\"}},\"elements\":[],\"widgetType\":\"image-box\"}],\"isInner\":\"1\"}],\"isInner\":\"1\"}],\"isInner\":\"\"}],\"isInner\":\"\"},{\"id\":\"d31a6a6\",\"elType\":\"section\",\"settings\":{\"gap\":\"no\",\"background_background\":\"classic\",\"background_image\":{\"url\":\"https:\\\/\\\/websitedemos.net\\\/luxury-hotel-04\\\/wp-content\\\/uploads\\\/sites\\\/812\\\/2021\\\/06\\\/hotel-cta-bg-1.jpg\",\"id\":1671},\"background_position\":\"bottom center\",\"background_attachment\":\"fixed\",\"background_repeat\":\"no-repeat\",\"background_size\":\"cover\",\"background_overlay_background\":\"gradient\",\"background_overlay_opacity\":{\"unit\":\"px\",\"size\":1,\"sizes\":[]},\"padding\":{\"unit\":\"px\",\"top\":\"140\",\"right\":\"0\",\"bottom\":\"200\",\"left\":\"0\",\"isLinked\":\"\"},\"background_overlay_color_b\":\"#000000BD\",\"structure\":\"22\",\"padding_tablet\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"50\",\"bottom\":\"50\",\"left\":\"50\",\"isLinked\":false},\"content_width\":{\"unit\":\"px\",\"size\":970,\"sizes\":[]},\"content_position\":\"middle\",\"padding_mobile\":{\"unit\":\"px\",\"top\":\"50\",\"right\":\"25\",\"bottom\":\"50\",\"left\":\"25\",\"isLinked\":false},\"__globals__\":{\"background_overlay_color\":\"globals\\\/colors?id=astraheadingcolor\"}},\"elements\":[{\"id\":\"7526b88\",\"elType\":\"column\",\"settings\":{\"_column_size\":66,\"space_between_widgets\":40,\"padding_mobile\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":true},\"margin\":{\"unit\":\"%\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":false},\"_inline_size\":70,\"_inline_size_tablet\":100,\"space_between_widgets_mobile\":20},\"elements\":[{\"id\":\"29e190a\",\"elType\":\"widget\",\"settings\":{\"title\":\"Your search for True Luxury ends here\",\"align_mobile\":\"center\",\"align_tablet\":\"center\",\"__globals__\":{\"title_color\":\"globals\\\/colors?id=astratextcolor\"}},\"elements\":[],\"widgetType\":\"heading\"},{\"id\":\"454a7bd\",\"elType\":\"widget\",\"settings\":{\"editor\":\"Lorem ipsum dolor sit amet, consectetur adipiscing elit. Ut elit tellus, luctus nec ullamcorper mattis, pulvinar dapibus leo.\",\"align_mobile\":\"center\",\"_padding_mobile\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":\"\"},\"_margin\":{\"unit\":\"%\",\"top\":\"0\",\"right\":\"10\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":false},\"typography_typography\":\"custom\",\"typography_font_size\":{\"unit\":\"px\",\"size\":18,\"sizes\":[]},\"align_tablet\":\"center\",\"typography_font_size_tablet\":{\"unit\":\"px\",\"size\":15,\"sizes\":[]},\"_margin_tablet\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":false},\"_padding_tablet\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":false}},\"elements\":[],\"widgetType\":\"text-editor\"}],\"isInner\":\"\"},{\"id\":\"1db09e8\",\"elType\":\"column\",\"settings\":{\"_column_size\":33,\"space_between_widgets\":40,\"padding_mobile\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":true},\"margin\":{\"unit\":\"%\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":true},\"_inline_size\":29.333,\"_inline_size_tablet\":100},\"elements\":[{\"id\":\"0fe22ef\",\"elType\":\"widget\",\"settings\":{\"text\":\"Book Now\",\"_padding\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":true},\"align\":\"right\",\"align_tablet\":\"center\",\"_margin\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":true},\"_margin_tablet\":{\"unit\":\"px\",\"top\":\"50\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":false}},\"elements\":[],\"widgetType\":\"button\"}],\"isInner\":false}],\"isInner\":\"\"}]","_elementor_controls_usage":"a:9:{s:7:\"heading\";a:3:{s:5:\"count\";i:17;s:15:\"control_percent\";i:1;s:8:\"controls\";a:3:{s:7:\"content\";a:1:{s:13:\"section_title\";a:5:{s:5:\"title\";i:17;s:11:\"header_size\";i:13;s:5:\"align\";i:15;s:12:\"align_mobile\";i:8;s:12:\"align_tablet\";i:5;}}s:8:\"advanced\";a:1:{s:14:\"_section_style\";a:6:{s:8:\"_padding\";i:6;s:14:\"_margin_tablet\";i:1;s:15:\"_padding_tablet\";i:1;s:14:\"_margin_mobile\";i:1;s:15:\"_padding_mobile\";i:1;s:7:\"_margin\";i:1;}}s:5:\"style\";a:1:{s:19:\"section_title_style\";a:3:{s:11:\"title_color\";i:4;s:20:\"typography_font_size\";i:1;s:22:\"typography_font_weight\";i:1;}}}}s:9:\"image-box\";a:3:{s:5:\"count\";i:4;s:15:\"control_percent\";i:2;s:8:\"controls\";a:3:{s:7:\"content\";a:1:{s:13:\"section_image\";a:4:{s:5:\"image\";i:4;s:10:\"title_text\";i:4;s:16:\"description_text\";i:1;s:10:\"title_size\";i:4;}}s:5:\"style\";a:1:{s:21:\"section_style_content\";a:3:{s:10:\"text_align\";i:1;s:33:\"description_typography_typography\";i:3;s:39:\"description_typography_font_size_tablet\";i:3;}}s:8:\"advanced\";a:1:{s:14:\"_section_style\";a:3:{s:7:\"_margin\";i:1;s:8:\"_padding\";i:3;s:15:\"_padding_tablet\";i:3;}}}}s:6:\"button\";a:3:{s:5:\"count\";i:3;s:15:\"control_percent\";i:2;s:8:\"controls\";a:3:{s:7:\"content\";a:1:{s:14:\"section_button\";a:5:{s:4:\"text\";i:3;s:11:\"icon_indent\";i:1;s:12:\"align_tablet\";i:2;s:12:\"align_mobile\";i:1;s:5:\"align\";i:1;}}s:5:\"style\";a:1:{s:13:\"section_style\";a:3:{s:12:\"border_width\";i:1;s:21:\"background_background\";i:1;s:34:\"button_background_hover_background\";i:1;}}s:8:\"advanced\";a:2:{s:17:\"_section_position\";a:2:{s:21:\"_element_custom_width\";i:1;s:23:\"_element_vertical_align\";i:1;}s:14:\"_section_style\";a:4:{s:7:\"_margin\";i:2;s:14:\"_margin_tablet\";i:3;s:8:\"_padding\";i:2;s:15:\"_padding_tablet\";i:1;}}}}s:14:\"image-carousel\";a:3:{s:5:\"count\";i:1;s:15:\"control_percent\";i:5;s:8:\"controls\";a:3:{s:7:\"content\";a:1:{s:22:\"section_image_carousel\";a:8:{s:8:\"carousel\";i:1;s:14:\"thumbnail_size\";i:1;s:26:\"thumbnail_custom_dimension\";i:1;s:14:\"slides_to_show\";i:1;s:13:\"image_stretch\";i:1;s:10:\"navigation\";i:1;s:21:\"slides_to_show_tablet\";i:1;s:21:\"slides_to_show_mobile\";i:1;}}s:8:\"advanced\";a:1:{s:14:\"_section_style\";a:6:{s:7:\"_margin\";i:1;s:8:\"_padding\";i:1;s:14:\"_margin_mobile\";i:1;s:15:\"_padding_tablet\";i:1;s:15:\"_padding_mobile\";i:1;s:14:\"_margin_tablet\";i:1;}}s:5:\"style\";a:1:{s:19:\"section_style_image\";a:1:{s:19:\"image_border_radius\";i:1;}}}}s:6:\"column\";a:3:{s:5:\"count\";i:28;s:15:\"control_percent\";i:2;s:8:\"controls\";a:3:{s:8:\"advanced\";a:1:{s:16:\"section_advanced\";a:7:{s:13:\"margin_tablet\";i:5;s:14:\"padding_tablet\";i:16;s:14:\"padding_mobile\";i:14;s:6:\"margin\";i:16;s:7:\"padding\";i:12;s:13:\"margin_mobile\";i:4;s:7:\"z_index\";i:5;}}s:6:\"layout\";a:1:{s:6:\"layout\";a:7:{s:16:\"content_position\";i:12;s:21:\"space_between_widgets\";i:14;s:12:\"_inline_size\";i:6;s:19:\"_inline_size_tablet\";i:16;s:19:\"_inline_size_mobile\";i:2;s:12:\"align_mobile\";i:1;s:28:\"space_between_widgets_mobile\";i:5;}}s:5:\"style\";a:3:{s:13:\"section_style\";a:10:{s:21:\"background_background\";i:10;s:19:\"background_position\";i:5;s:21:\"background_attachment\";i:5;s:17:\"background_repeat\";i:5;s:15:\"background_size\";i:5;s:27:\"background_hover_background\";i:4;s:22:\"background_hover_color\";i:4;s:27:\"background_hover_transition\";i:4;s:16:\"background_image\";i:4;s:16:\"background_color\";i:3;}s:26:\"section_background_overlay\";a:8:{s:29:\"background_overlay_background\";i:5;s:26:\"background_overlay_opacity\";i:5;s:35:\"background_overlay_hover_background\";i:4;s:30:\"background_overlay_hover_color\";i:4;s:32:\"background_overlay_hover_opacity\";i:4;s:26:\"background_overlay_color_b\";i:4;s:33:\"background_overlay_gradient_angle\";i:4;s:29:\"background_overlay_color_stop\";i:4;}s:14:\"section_border\";a:5:{s:13:\"border_radius\";i:5;s:13:\"border_border\";i:1;s:12:\"border_width\";i:5;s:12:\"border_color\";i:1;s:21:\"box_shadow_box_shadow\";i:7;}}}}s:7:\"section\";a:3:{s:5:\"count\";i:13;s:15:\"control_percent\";i:4;s:8:\"controls\";a:3:{s:6:\"layout\";a:2:{s:14:\"section_layout\";a:7:{s:6:\"layout\";i:3;s:3:\"gap\";i:12;s:8:\"overflow\";i:2;s:13:\"custom_height\";i:5;s:13:\"content_width\";i:2;s:15:\"column_position\";i:1;s:16:\"content_position\";i:1;}s:17:\"section_structure\";a:1:{s:9:\"structure\";i:7;}}s:8:\"advanced\";a:2:{s:16:\"section_advanced\";a:6:{s:7:\"padding\";i:13;s:13:\"margin_tablet\";i:4;s:13:\"margin_mobile\";i:5;s:14:\"padding_tablet\";i:11;s:14:\"padding_mobile\";i:13;s:6:\"margin\";i:3;}s:19:\"_section_responsive\";a:1:{s:20:\"reverse_order_mobile\";i:1;}}s:5:\"style\";a:2:{s:18:\"section_background\";a:8:{s:19:\"background_position\";i:4;s:21:\"background_attachment\";i:4;s:17:\"background_repeat\";i:4;s:15:\"background_size\";i:4;s:21:\"background_background\";i:4;s:16:\"background_color\";i:1;s:25:\"background_gradient_angle\";i:1;s:16:\"background_image\";i:3;}s:26:\"section_background_overlay\";a:6:{s:26:\"background_overlay_color_b\";i:1;s:33:\"background_overlay_gradient_angle\";i:1;s:26:\"background_overlay_opacity\";i:3;s:29:\"background_overlay_background\";i:4;s:24:\"background_overlay_color\";i:1;s:31:\"background_overlay_color_b_stop\";i:1;}}}}s:11:\"text-editor\";a:3:{s:5:\"count\";i:10;s:15:\"control_percent\";i:4;s:8:\"controls\";a:3:{s:7:\"content\";a:1:{s:14:\"section_editor\";a:3:{s:6:\"editor\";i:10;s:12:\"text_columns\";i:1;s:10:\"column_gap\";i:1;}}s:8:\"advanced\";a:1:{s:14:\"_section_style\";a:6:{s:15:\"_padding_mobile\";i:6;s:7:\"_margin\";i:2;s:8:\"_padding\";i:6;s:14:\"_margin_tablet\";i:3;s:15:\"_padding_tablet\";i:3;s:14:\"_margin_mobile\";i:4;}}s:5:\"style\";a:1:{s:13:\"section_style\";a:7:{s:21:\"typography_typography\";i:2;s:27:\"typography_font_size_mobile\";i:1;s:5:\"align\";i:2;s:12:\"align_mobile\";i:5;s:12:\"align_tablet\";i:3;s:20:\"typography_font_size\";i:1;s:27:\"typography_font_size_tablet\";i:1;}}}}s:4:\"icon\";a:3:{s:5:\"count\";i:1;s:15:\"control_percent\";i:5;s:8:\"controls\";a:3:{s:7:\"content\";a:1:{s:12:\"section_icon\";a:4:{s:13:\"selected_icon\";i:1;s:4:\"view\";i:1;s:4:\"link\";i:1;s:5:\"align\";i:1;}}s:5:\"style\";a:1:{s:18:\"section_style_icon\";a:6:{s:4:\"size\";i:1;s:12:\"icon_padding\";i:1;s:12:\"border_width\";i:1;s:15:\"hover_animation\";i:1;s:11:\"size_tablet\";i:1;s:11:\"size_mobile\";i:1;}}s:8:\"advanced\";a:1:{s:14:\"_section_style\";a:3:{s:7:\"_margin\";i:1;s:14:\"_margin_tablet\";i:1;s:15:\"_padding_tablet\";i:1;}}}}s:5:\"image\";a:3:{s:5:\"count\";i:13;s:15:\"control_percent\";i:0;s:8:\"controls\";a:3:{s:7:\"content\";a:1:{s:13:\"section_image\";a:2:{s:5:\"image\";i:13;s:10:\"image_size\";i:5;}}s:5:\"style\";a:1:{s:19:\"section_style_image\";a:5:{s:27:\"background_hover_transition\";i:6;s:12:\"width_mobile\";i:6;s:5:\"space\";i:1;s:6:\"height\";i:1;s:12:\"width_tablet\";i:4;}}s:8:\"advanced\";a:2:{s:17:\"_section_position\";a:2:{s:21:\"_element_width_mobile\";i:2;s:28:\"_element_custom_width_mobile\";i:2;}s:14:\"_section_style\";a:2:{s:7:\"_margin\";i:1;s:8:\"_padding\";i:1;}}}}}","_uag_page_assets":"a:9:{s:3:\"css\";s:0:\"\";s:2:\"js\";s:0:\"\";s:18:\"current_block_list\";a:0:{}s:8:\"uag_flag\";b:0;s:11:\"uag_version\";s:10:\"1726573559\";s:6:\"gfonts\";a:0:{}s:10:\"gfonts_url\";s:0:\"\";s:12:\"gfonts_files\";a:0:{}s:14:\"uag_faq_layout\";b:0;}","_elementor_page_assets":"a:2:{s:6:\"styles\";a:6:{i:0;s:14:\"widget-heading\";i:1;s:16:\"widget-image-box\";i:2;s:8:\"e-swiper\";i:3;s:21:\"widget-image-carousel\";i:4;s:16:\"e-animation-grow\";i:5;s:12:\"widget-image\";}s:7:\"scripts\";a:2:{i:0;s:18:\"elementor-frontend\";i:1;s:6:\"swiper\";}}","_elementor_css":"a:6:{s:4:\"time\";i:1781100988;s:5:\"fonts\";a:0:{}s:5:\"icons\";a:2:{i:0;s:0:\"\";i:1;s:8:\"fa-solid\";}s:20:\"dynamic_elements_ids\";a:0:{}s:6:\"status\";s:4:\"file\";i:0;s:0:\"\";}","_elementor_element_cache":"{\"timeout\":1784205292,\"value\":{\"content\":\"<div class=\\\"elementor-element elementor-element-714eee0 e-con-full e-flex e-con e-parent\\\" data-id=\\\"714eee0\\\" data-element_type=\\\"container\\\" data-e-type=\\\"container\\\" data-settings=\\\"{&quot;background_background&quot;:&quot;gradient&quot;}\\\">\\n\\t\\t<div class=\\\"elementor-element elementor-element-1062390 e-con-full e-flex e-con e-child\\\" data-id=\\\"1062390\\\" data-element_type=\\\"container\\\" data-e-type=\\\"container\\\">\\n\\t\\t\\t\\t<div class=\\\"elementor-element elementor-element-8ce63fd elementor-widget elementor-widget-heading\\\" data-id=\\\"8ce63fd\\\" data-element_type=\\\"widget\\\" data-e-type=\\\"widget\\\" data-widget_type=\\\"heading.default\\\">\\n\\t\\t\\t\\t<div class=\\\"elementor-widget-container\\\">\\n\\t\\t\\t\\t\\t<h6 class=\\\"elementor-heading-title elementor-size-default\\\">Dive into Ultimate Luxury at<\\\/h6>\\t\\t\\t\\t<\\\/div>\\n\\t\\t\\t\\t<\\\/div>\\n\\t\\t\\t\\t<div class=\\\"elementor-element elementor-element-1eb2a50 elementor-widget elementor-widget-image-box\\\" data-id=\\\"1eb2a50\\\" data-element_type=\\\"widget\\\" data-e-type=\\\"widget\\\" data-widget_type=\\\"image-box.default\\\">\\n\\t\\t\\t\\t<div class=\\\"elementor-widget-container\\\">\\n\\t\\t\\t\\t\\t<div class=\\\"elementor-image-box-wrapper\\\"><div class=\\\"elementor-image-box-content\\\"><h1 class=\\\"elementor-image-box-title\\\">The Caeser Grand<\\\/h1><p class=\\\"elementor-image-box-description\\\">Lorem ipsum dolor sit amet, consectetur adipiscing elit. Ut elit tellus, <br \\\/>luctus nec ullamcorper mattis, pulvinar dapibus leo.<\\\/p><\\\/div><\\\/div>\\t\\t\\t\\t<\\\/div>\\n\\t\\t\\t\\t<\\\/div>\\n\\t\\t\\t\\t<div class=\\\"elementor-element elementor-element-8637ce2 elementor-widget elementor-widget-button\\\" data-id=\\\"8637ce2\\\" data-element_type=\\\"widget\\\" data-e-type=\\\"widget\\\" data-widget_type=\\\"button.default\\\">\\n\\t\\t\\t\\t<div class=\\\"elementor-widget-container\\\">\\n\\t\\t\\t\\t\\t\\t\\t\\t\\t<div class=\\\"elementor-button-wrapper\\\">\\n\\t\\t\\t\\t\\t<a class=\\\"elementor-button elementor-button-link elementor-size-sm\\\" href=\\\"#\\\">\\n\\t\\t\\t\\t\\t\\t<span class=\\\"elementor-button-content-wrapper\\\">\\n\\t\\t\\t\\t\\t\\t\\t\\t\\t<span class=\\\"elementor-button-text\\\">Make A Reservation<\\\/span>\\n\\t\\t\\t\\t\\t<\\\/span>\\n\\t\\t\\t\\t\\t<\\\/a>\\n\\t\\t\\t\\t<\\\/div>\\n\\t\\t\\t\\t\\t\\t\\t\\t<\\\/div>\\n\\t\\t\\t\\t<\\\/div>\\n\\t\\t\\t\\t<div class=\\\"elementor-element elementor-element-19cc3d0 elementor-widget elementor-widget-image-carousel\\\" data-id=\\\"19cc3d0\\\" data-element_type=\\\"widget\\\" data-e-type=\\\"widget\\\" data-settings=\\\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;none&quot;,&quot;slides_to_show_tablet&quot;:&quot;1&quot;,&quot;slides_to_show_mobile&quot;:&quot;1&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\\\" data-widget_type=\\\"image-carousel.default\\\">\\n\\t\\t\\t\\t<div class=\\\"elementor-widget-container\\\">\\n\\t\\t\\t\\t\\t\\t\\t<div class=\\\"elementor-image-carousel-wrapper swiper\\\" role=\\\"region\\\" aria-roledescription=\\\"carousel\\\" aria-label=\\\"Image Carousel\\\" dir=\\\"ltr\\\">\\n\\t\\t\\t<div class=\\\"elementor-image-carousel swiper-wrapper swiper-image-stretch\\\" aria-live=\\\"off\\\">\\n\\t\\t\\t\\t\\t\\t\\t\\t<div class=\\\"swiper-slide\\\" role=\\\"group\\\" aria-roledescription=\\\"slide\\\" aria-label=\\\"1 of 4\\\"><figure class=\\\"swiper-slide-inner\\\"><img class=\\\"swiper-slide-image\\\" src=\\\"https:\\\/\\\/websitedemos.net\\\/luxury-hotel-04\\\/wp-content\\\/uploads\\\/sites\\\/812\\\/2021\\\/04\\\/carousel-11-.jpg\\\" alt=\\\"carousel-11-\\\" \\\/><\\\/figure><\\\/div><div class=\\\"swiper-slide\\\" role=\\\"group\\\" aria-roledescription=\\\"slide\\\" aria-label=\\\"2 of 4\\\"><figure class=\\\"swiper-slide-inner\\\"><img class=\\\"swiper-slide-image\\\" src=\\\"https:\\\/\\\/websitedemos.net\\\/luxury-hotel-04\\\/wp-content\\\/uploads\\\/sites\\\/812\\\/2021\\\/04\\\/carousel12-.jpg\\\" alt=\\\"carousel12-\\\" \\\/><\\\/figure><\\\/div><div class=\\\"swiper-slide\\\" role=\\\"group\\\" aria-roledescription=\\\"slide\\\" aria-label=\\\"3 of 4\\\"><figure class=\\\"swiper-slide-inner\\\"><img class=\\\"swiper-slide-image\\\" src=\\\"https:\\\/\\\/websitedemos.net\\\/luxury-hotel-04\\\/wp-content\\\/uploads\\\/sites\\\/812\\\/2021\\\/04\\\/carousel13-.jpg\\\" alt=\\\"carousel13-\\\" \\\/><\\\/figure><\\\/div><div class=\\\"swiper-slide\\\" role=\\\"group\\\" aria-roledescription=\\\"slide\\\" aria-label=\\\"4 of 4\\\"><figure class=\\\"swiper-slide-inner\\\"><img class=\\\"swiper-slide-image\\\" src=\\\"https:\\\/\\\/websitedemos.net\\\/luxury-hotel-04\\\/wp-content\\\/uploads\\\/sites\\\/812\\\/2021\\\/04\\\/carousel14-.jpg\\\" alt=\\\"carousel14-\\\" \\\/><\\\/figure><\\\/div>\\t\\t\\t<\\\/div>\\n\\t\\t\\t\\t\\t\\t\\t\\n\\t\\t\\t\\t\\t\\t\\t\\t\\t<\\\/div>\\n\\t\\t\\t\\t\\t\\t<\\\/div>\\n\\t\\t\\t\\t<\\\/div>\\n\\t\\t\\t\\t<\\\/div>\\n\\t\\t\\t\\t<\\\/div>\\n\\t\\t<div class=\\\"elementor-element elementor-element-f4a45e5 e-flex e-con-boxed e-con e-parent\\\" data-id=\\\"f4a45e5\\\" data-element_type=\\\"container\\\" data-e-type=\\\"container\\\" data-settings=\\\"{&quot;background_background&quot;:&quot;classic&quot;}\\\">\\n\\t\\t\\t\\t\\t<div class=\\\"e-con-inner\\\">\\n\\t\\t<div class=\\\"elementor-element elementor-element-428a1ec e-con-full e-flex e-con e-child\\\" data-id=\\\"428a1ec\\\" data-element_type=\\\"container\\\" data-e-type=\\\"container\\\" data-settings=\\\"{&quot;background_background&quot;:&quot;classic&quot;}\\\">\\n\\t\\t\\t\\t<div class=\\\"elementor-element elementor-element-da2e9ad elementor-widget elementor-widget-heading\\\" data-id=\\\"da2e9ad\\\" data-element_type=\\\"widget\\\" data-e-type=\\\"widget\\\" data-widget_type=\\\"heading.default\\\">\\n\\t\\t\\t\\t<div class=\\\"elementor-widget-container\\\">\\n\\t\\t\\t\\t\\t<h2 class=\\\"elementor-heading-title elementor-size-default\\\">An Escape from Reality<\\\/h2>\\t\\t\\t\\t<\\\/div>\\n\\t\\t\\t\\t<\\\/div>\\n\\t\\t[elementor-element k=\\\"f19e676918bba936d6bd7c5c78a50cb4\\\" data=\\\"eyJpZCI6ImE4YmZiYTYiLCJlbFR5cGUiOiJ3aWRnZXQiLCJzZXR0aW5ncyI6eyJlZGl0b3IiOiJRdWlzcXVlIHZlbGl0IG5pc2ksIHByZXRpdW0gdXQgbGFjaW5pYSBpbiwgZWxlbWVudHVtIGlkIGVuaW0uIEN1cmFiaXR1ciBub24gbnVsbGEgc2l0IGFtZXQgbmlzbCB0ZW1wdXMgY29udmFsbGlzIHF1aXMgYWMgbGVjdHVzLiBMb3JlbSBlbGl0IHRlbGx1cywgbHVjdHVzIG5lYyB1bGxhbWNvcnBlciBtYXR0aXMsIHB1bHZpbmFyIGRhcGlidXMgbGVvLiIsInRleHRfY29sdW1ucyI6IjEiLCJjb2x1bW5fZ2FwIjp7InVuaXQiOiJweCIsInNpemUiOiIwIiwic2l6ZXMiOltdfSwiX3BhZGRpbmdfbW9iaWxlIjp7InVuaXQiOiJweCIsInRvcCI6IjAiLCJyaWdodCI6IjAiLCJib3R0b20iOiIyNSIsImxlZnQiOiIwIiwiaXNMaW5rZWQiOiIifSwidHlwb2dyYXBoeV90eXBvZ3JhcGh5IjoiY3VzdG9tIiwidHlwb2dyYXBoeV9mb250X3NpemVfbW9iaWxlIjp7InVuaXQiOiJweCIsInNpemUiOjEzLCJzaXplcyI6W119LCJjb250ZW50X3dpZHRoIjoiZnVsbCJ9LCJlbGVtZW50cyI6W10sIndpZGdldFR5cGUiOiJ0ZXh0LWVkaXRvciJ9\\\"]\\t\\t<div class=\\\"elementor-element elementor-element-c4df2b6 elementor-view-framed elementor-shape-circle elementor-widget elementor-widget-icon\\\" data-id=\\\"c4df2b6\\\" data-element_type=\\\"widget\\\" data-e-type=\\\"widget\\\" data-widget_type=\\\"icon.default\\\">\\n\\t\\t\\t\\t<div class=\\\"elementor-widget-container\\\">\\n\\t\\t\\t\\t\\t\\t\\t<div class=\\\"elementor-icon-wrapper\\\">\\n\\t\\t\\t<a class=\\\"elementor-icon elementor-animation-grow\\\" href=\\\"#\\\">\\n\\t\\t\\t<i aria-hidden=\\\"true\\\" class=\\\"fas fa-play\\\"><\\\/i>\\t\\t\\t<\\\/a>\\n\\t\\t<\\\/div>\\n\\t\\t\\t\\t\\t\\t<\\\/div>\\n\\t\\t\\t\\t<\\\/div>\\n\\t\\t\\t\\t<\\\/div>\\n\\t\\t\\t\\t\\t<\\\/div>\\n\\t\\t\\t\\t<\\\/div>\\n\\t\\t<div class=\\\"elementor-element elementor-element-7d08070 e-con-full e-flex e-con e-parent\\\" data-id=\\\"7d08070\\\" data-element_type=\\\"container\\\" data-e-type=\\\"container\\\">\\n\\t\\t<div class=\\\"elementor-element elementor-element-92712f0 e-con-full e-flex e-con e-child\\\" data-id=\\\"92712f0\\\" data-element_type=\\\"container\\\" data-e-type=\\\"container\\\">\\n\\t\\t\\t\\t<div class=\\\"elementor-element elementor-element-df16266 elementor-widget elementor-widget-heading\\\" data-id=\\\"df16266\\\" data-element_type=\\\"widget\\\" data-e-type=\\\"widget\\\" data-widget_type=\\\"heading.default\\\">\\n\\t\\t\\t\\t<div class=\\\"elementor-widget-container\\\">\\n\\t\\t\\t\\t\\t<h2 class=\\\"elementor-heading-title elementor-size-default\\\"> Luxurious Services<\\\/h2>\\t\\t\\t\\t<\\\/div>\\n\\t\\t\\t\\t<\\\/div>\\n\\t\\t<div class=\\\"elementor-element elementor-element-cfccc70 e-con-full e-flex e-con e-child\\\" data-id=\\\"cfccc70\\\" data-element_type=\\\"container\\\" data-e-type=\\\"container\\\">\\n\\t\\t<div class=\\\"elementor-element elementor-element-13716e0 e-con-full e-flex e-con e-child\\\" data-id=\\\"13716e0\\\" data-element_type=\\\"container\\\" data-e-type=\\\"container\\\" data-settings=\\\"{&quot;background_background&quot;:&quot;classic&quot;}\\\">\\n\\t\\t\\t\\t<div class=\\\"elementor-element elementor-element-7c63934 elementor-widget elementor-widget-heading\\\" data-id=\\\"7c63934\\\" data-element_type=\\\"widget\\\" data-e-type=\\\"widget\\\" data-widget_type=\\\"heading.default\\\">\\n\\t\\t\\t\\t<div class=\\\"elementor-widget-container\\\">\\n\\t\\t\\t\\t\\t<h5 class=\\\"elementor-heading-title elementor-size-default\\\">In-room Dining<\\\/h5>\\t\\t\\t\\t<\\\/div>\\n\\t\\t\\t\\t<\\\/div>\\n\\t\\t\\t\\t<\\\/div>\\n\\t\\t<div class=\\\"elementor-element elementor-element-b36a5fb e-con-full e-flex e-con e-child\\\" data-id=\\\"b36a5fb\\\" data-element_type=\\\"container\\\" data-e-type=\\\"container\\\" data-settings=\\\"{&quot;background_background&quot;:&quot;classic&quot;}\\\">\\n\\t\\t\\t\\t<div class=\\\"elementor-element elementor-element-0c82358 elementor-widget elementor-widget-heading\\\" data-id=\\\"0c82358\\\" data-element_type=\\\"widget\\\" data-e-type=\\\"widget\\\" data-widget_type=\\\"heading.default\\\">\\n\\t\\t\\t\\t<div class=\\\"elementor-widget-container\\\">\\n\\t\\t\\t\\t\\t<h5 class=\\\"elementor-heading-title elementor-size-default\\\">Private Pools<\\\/h5>\\t\\t\\t\\t<\\\/div>\\n\\t\\t\\t\\t<\\\/div>\\n\\t\\t\\t\\t<\\\/div>\\n\\t\\t<div class=\\\"elementor-element elementor-element-c761caf e-con-full e-flex e-con e-child\\\" data-id=\\\"c761caf\\\" data-element_type=\\\"container\\\" data-e-type=\\\"container\\\" data-settings=\\\"{&quot;background_background&quot;:&quot;classic&quot;}\\\">\\n\\t\\t\\t\\t<div class=\\\"elementor-element elementor-element-0a0a2f8 elementor-widget elementor-widget-heading\\\" data-id=\\\"0a0a2f8\\\" data-element_type=\\\"widget\\\" data-e-type=\\\"widget\\\" data-widget_type=\\\"heading.default\\\">\\n\\t\\t\\t\\t<div class=\\\"elementor-widget-container\\\">\\n\\t\\t\\t\\t\\t<h5 class=\\\"elementor-heading-title elementor-size-default\\\">Concierge Service<\\\/h5>\\t\\t\\t\\t<\\\/div>\\n\\t\\t\\t\\t<\\\/div>\\n\\t\\t\\t\\t<\\\/div>\\n\\t\\t<div class=\\\"elementor-element elementor-element-61ee7d5 e-con-full e-flex e-con e-child\\\" data-id=\\\"61ee7d5\\\" data-element_type=\\\"container\\\" data-e-type=\\\"container\\\" data-settings=\\\"{&quot;background_background&quot;:&quot;classic&quot;}\\\">\\n\\t\\t\\t\\t<div class=\\\"elementor-element elementor-element-e08bef1 elementor-widget elementor-widget-heading\\\" data-id=\\\"e08bef1\\\" data-element_type=\\\"widget\\\" data-e-type=\\\"widget\\\" data-widget_type=\\\"heading.default\\\">\\n\\t\\t\\t\\t<div class=\\\"elementor-widget-container\\\">\\n\\t\\t\\t\\t\\t<h5 class=\\\"elementor-heading-title elementor-size-default\\\">VIP Casino Entries<\\\/h5>\\t\\t\\t\\t<\\\/div>\\n\\t\\t\\t\\t<\\\/div>\\n\\t\\t\\t\\t<\\\/div>\\n\\t\\t\\t\\t<\\\/div>\\n\\t\\t\\t\\t<\\\/div>\\n\\t\\t\\t\\t<\\\/div>\\n\\t\\t<div class=\\\"elementor-element elementor-element-a45f3d6 e-flex e-con-boxed e-con e-parent\\\" data-id=\\\"a45f3d6\\\" data-element_type=\\\"container\\\" data-e-type=\\\"container\\\">\\n\\t\\t\\t\\t\\t<div class=\\\"e-con-inner\\\">\\n\\t\\t<div class=\\\"elementor-element elementor-element-b85241c e-con-full e-flex e-con e-child\\\" data-id=\\\"b85241c\\\" data-element_type=\\\"container\\\" data-e-type=\\\"container\\\">\\n\\t\\t\\t\\t<div class=\\\"elementor-element elementor-element-31e1165 elementor-widget elementor-widget-heading\\\" data-id=\\\"31e1165\\\" data-element_type=\\\"widget\\\" data-e-type=\\\"widget\\\" data-widget_type=\\\"heading.default\\\">\\n\\t\\t\\t\\t<div class=\\\"elementor-widget-container\\\">\\n\\t\\t\\t\\t\\t<h3 class=\\\"elementor-heading-title elementor-size-default\\\">Every corner with a<br> Luxury Touch<\\\/h3>\\t\\t\\t\\t<\\\/div>\\n\\t\\t\\t\\t<\\\/div>\\n\\t\\t[elementor-element k=\\\"f19e676918bba936d6bd7c5c78a50cb4\\\" data=\\\"eyJpZCI6ImY3MjMxNGYiLCJlbFR5cGUiOiJ3aWRnZXQiLCJzZXR0aW5ncyI6eyJlZGl0b3IiOiJMb3JlbSBlbGl0IHRlbGx1cywgbHVjdHVzIG5lYyB1bGxhbWNvcnBlciBtYXR0aXMsIHB1bHZpbmFyIGRhcGlidXMgbGVvLiIsImFsaWduIjoiY2VudGVyIiwiYWxpZ25fbW9iaWxlIjoibGVmdCIsIl9tYXJnaW4iOnsidW5pdCI6InB4IiwidG9wIjoiMCIsInJpZ2h0IjoiMCIsImJvdHRvbSI6IjAiLCJsZWZ0IjoiMCIsImlzTGlua2VkIjpmYWxzZX0sImNvbnRlbnRfd2lkdGgiOiJmdWxsIn0sImVsZW1lbnRzIjpbXSwid2lkZ2V0VHlwZSI6InRleHQtZWRpdG9yIn0=\\\"]<div class=\\\"elementor-element elementor-element-847dde8 e-con-full e-flex e-con e-child\\\" data-id=\\\"847dde8\\\" data-element_type=\\\"container\\\" data-e-type=\\\"container\\\">\\n\\t\\t<div class=\\\"elementor-element elementor-element-c44ccd6 e-con-full e-flex e-con e-child\\\" data-id=\\\"c44ccd6\\\" data-element_type=\\\"container\\\" data-e-type=\\\"container\\\">\\n\\t\\t\\t\\t<div class=\\\"elementor-element elementor-element-de309b3 elementor-widget elementor-widget-image\\\" data-id=\\\"de309b3\\\" data-element_type=\\\"widget\\\" data-e-type=\\\"widget\\\" data-widget_type=\\\"image.default\\\">\\n\\t\\t\\t\\t<div class=\\\"elementor-widget-container\\\">\\n\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t<img width=\\\"414\\\" height=\\\"670\\\" src=\\\"https:\\\/\\\/websitedemos.net\\\/luxury-hotel-04\\\/wp-content\\\/uploads\\\/sites\\\/812\\\/2021\\\/04\\\/gallery-new-1.jpeg\\\" class=\\\"attachment-large size-large wp-image-671\\\" alt=\\\"\\\" srcset=\\\"https:\\\/\\\/websitedemos.net\\\/luxury-hotel-04\\\/wp-content\\\/uploads\\\/sites\\\/812\\\/2021\\\/04\\\/gallery-new-1.jpeg 414w, https:\\\/\\\/websitedemos.net\\\/luxury-hotel-04\\\/wp-content\\\/uploads\\\/sites\\\/812\\\/2021\\\/04\\\/gallery-new-1-185x300.jpeg 185w, https:\\\/\\\/websitedemos.net\\\/luxury-hotel-04\\\/wp-content\\\/uploads\\\/sites\\\/812\\\/2021\\\/04\\\/gallery-new-1-400x647.jpeg 400w\\\" sizes=\\\"(max-width: 414px) 100vw, 414px\\\" \\\/>\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t<\\\/div>\\n\\t\\t\\t\\t<\\\/div>\\n\\t\\t\\t\\t<div class=\\\"elementor-element elementor-element-47cc48b elementor-widget elementor-widget-image\\\" data-id=\\\"47cc48b\\\" data-element_type=\\\"widget\\\" data-e-type=\\\"widget\\\" data-widget_type=\\\"image.default\\\">\\n\\t\\t\\t\\t<div class=\\\"elementor-widget-container\\\">\\n\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t<img width=\\\"414\\\" height=\\\"360\\\" src=\\\"https:\\\/\\\/websitedemos.net\\\/luxury-hotel-04\\\/wp-content\\\/uploads\\\/sites\\\/812\\\/2021\\\/04\\\/gallery-new-7.jpeg\\\" class=\\\"attachment-large size-large wp-image-676\\\" alt=\\\"\\\" srcset=\\\"https:\\\/\\\/websitedemos.net\\\/luxury-hotel-04\\\/wp-content\\\/uploads\\\/sites\\\/812\\\/2021\\\/04\\\/gallery-new-7.jpeg 414w, https:\\\/\\\/websitedemos.net\\\/luxury-hotel-04\\\/wp-content\\\/uploads\\\/sites\\\/812\\\/2021\\\/04\\\/gallery-new-7-300x261.jpeg 300w, https:\\\/\\\/websitedemos.net\\\/luxury-hotel-04\\\/wp-content\\\/uploads\\\/sites\\\/812\\\/2021\\\/04\\\/gallery-new-7-400x348.jpeg 400w\\\" sizes=\\\"(max-width: 414px) 100vw, 414px\\\" \\\/>\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t<\\\/div>\\n\\t\\t\\t\\t<\\\/div>\\n\\t\\t\\t\\t<\\\/div>\\n\\t\\t<div class=\\\"elementor-element elementor-element-2030191 e-con-full e-flex e-con e-child\\\" data-id=\\\"2030191\\\" data-element_type=\\\"container\\\" data-e-type=\\\"container\\\">\\n\\t\\t\\t\\t<div class=\\\"elementor-element elementor-element-29f66e6 elementor-widget elementor-widget-image\\\" data-id=\\\"29f66e6\\\" data-element_type=\\\"widget\\\" data-e-type=\\\"widget\\\" data-widget_type=\\\"image.default\\\">\\n\\t\\t\\t\\t<div class=\\\"elementor-widget-container\\\">\\n\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t<img width=\\\"591\\\" height=\\\"692\\\" src=\\\"https:\\\/\\\/websitedemos.net\\\/luxury-hotel-04\\\/wp-content\\\/uploads\\\/sites\\\/812\\\/2021\\\/04\\\/gallery-new-4.jpeg\\\" class=\\\"attachment-large size-large wp-image-677\\\" alt=\\\"\\\" srcset=\\\"https:\\\/\\\/websitedemos.net\\\/luxury-hotel-04\\\/wp-content\\\/uploads\\\/sites\\\/812\\\/2021\\\/04\\\/gallery-new-4.jpeg 591w, https:\\\/\\\/websitedemos.net\\\/luxury-hotel-04\\\/wp-content\\\/uploads\\\/sites\\\/812\\\/2021\\\/04\\\/gallery-new-4-256x300.jpeg 256w, https:\\\/\\\/websitedemos.net\\\/luxury-hotel-04\\\/wp-content\\\/uploads\\\/sites\\\/812\\\/2021\\\/04\\\/gallery-new-4-400x468.jpeg 400w\\\" sizes=\\\"(max-width: 591px) 100vw, 591px\\\" \\\/>\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t<\\\/div>\\n\\t\\t\\t\\t<\\\/div>\\n\\t\\t\\t\\t<div class=\\\"elementor-element elementor-element-2da95c4 elementor-widget elementor-widget-image\\\" data-id=\\\"2da95c4\\\" data-element_type=\\\"widget\\\" data-e-type=\\\"widget\\\" data-widget_type=\\\"image.default\\\">\\n\\t\\t\\t\\t<div class=\\\"elementor-widget-container\\\">\\n\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t<img width=\\\"867\\\" height=\\\"1135\\\" src=\\\"https:\\\/\\\/websitedemos.net\\\/luxury-hotel-04\\\/wp-content\\\/uploads\\\/sites\\\/812\\\/2021\\\/04\\\/gallery-15.jpeg\\\" class=\\\"attachment-full size-full wp-image-825\\\" alt=\\\"\\\" srcset=\\\"https:\\\/\\\/websitedemos.net\\\/luxury-hotel-04\\\/wp-content\\\/uploads\\\/sites\\\/812\\\/2021\\\/04\\\/gallery-15.jpeg 867w, https:\\\/\\\/websitedemos.net\\\/luxury-hotel-04\\\/wp-content\\\/uploads\\\/sites\\\/812\\\/2021\\\/04\\\/gallery-15-229x300.jpeg 229w, https:\\\/\\\/websitedemos.net\\\/luxury-hotel-04\\\/wp-content\\\/uploads\\\/sites\\\/812\\\/2021\\\/04\\\/gallery-15-782x1024.jpeg 782w, https:\\\/\\\/websitedemos.net\\\/luxury-hotel-04\\\/wp-content\\\/uploads\\\/sites\\\/812\\\/2021\\\/04\\\/gallery-15-768x1005.jpeg 768w, https:\\\/\\\/websitedemos.net\\\/luxury-hotel-04\\\/wp-content\\\/uploads\\\/sites\\\/812\\\/2021\\\/04\\\/gallery-15-400x524.jpeg 400w\\\" sizes=\\\"(max-width: 867px) 100vw, 867px\\\" \\\/>\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t<\\\/div>\\n\\t\\t\\t\\t<\\\/div>\\n\\t\\t\\t\\t<\\\/div>\\n\\t\\t<div class=\\\"elementor-element elementor-element-459dfc8 e-con-full e-flex e-con e-child\\\" data-id=\\\"459dfc8\\\" data-element_type=\\\"container\\\" data-e-type=\\\"container\\\">\\n\\t\\t\\t\\t<div class=\\\"elementor-element elementor-element-6209781 elementor-widget-mobile__width-initial elementor-widget elementor-widget-image\\\" data-id=\\\"6209781\\\" data-element_type=\\\"widget\\\" data-e-type=\\\"widget\\\" data-widget_type=\\\"image.default\\\">\\n\\t\\t\\t\\t<div class=\\\"elementor-widget-container\\\">\\n\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t<img width=\\\"414\\\" height=\\\"670\\\" src=\\\"https:\\\/\\\/websitedemos.net\\\/luxury-hotel-04\\\/wp-content\\\/uploads\\\/sites\\\/812\\\/2021\\\/04\\\/gallery-new-5.jpeg\\\" class=\\\"attachment-large size-large wp-image-674\\\" alt=\\\"\\\" srcset=\\\"https:\\\/\\\/websitedemos.net\\\/luxury-hotel-04\\\/wp-content\\\/uploads\\\/sites\\\/812\\\/2021\\\/04\\\/gallery-new-5.jpeg 414w, https:\\\/\\\/websitedemos.net\\\/luxury-hotel-04\\\/wp-content\\\/uploads\\\/sites\\\/812\\\/2021\\\/04\\\/gallery-new-5-185x300.jpeg 185w, https:\\\/\\\/websitedemos.net\\\/luxury-hotel-04\\\/wp-content\\\/uploads\\\/sites\\\/812\\\/2021\\\/04\\\/gallery-new-5-400x647.jpeg 400w\\\" sizes=\\\"(max-width: 414px) 100vw, 414px\\\" \\\/>\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t<\\\/div>\\n\\t\\t\\t\\t<\\\/div>\\n\\t\\t\\t\\t<div class=\\\"elementor-element elementor-element-8e3c895 elementor-widget-mobile__width-initial elementor-widget elementor-widget-image\\\" data-id=\\\"8e3c895\\\" data-element_type=\\\"widget\\\" data-e-type=\\\"widget\\\" data-widget_type=\\\"image.default\\\">\\n\\t\\t\\t\\t<div class=\\\"elementor-widget-container\\\">\\n\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t<img width=\\\"414\\\" height=\\\"360\\\" src=\\\"https:\\\/\\\/websitedemos.net\\\/luxury-hotel-04\\\/wp-content\\\/uploads\\\/sites\\\/812\\\/2021\\\/04\\\/gallery-6.png\\\" class=\\\"attachment-large size-large wp-image-214\\\" alt=\\\"\\\" srcset=\\\"https:\\\/\\\/websitedemos.net\\\/luxury-hotel-04\\\/wp-content\\\/uploads\\\/sites\\\/812\\\/2021\\\/04\\\/gallery-6.png 414w, https:\\\/\\\/websitedemos.net\\\/luxury-hotel-04\\\/wp-content\\\/uploads\\\/sites\\\/812\\\/2021\\\/04\\\/gallery-6-300x261.png 300w, https:\\\/\\\/websitedemos.net\\\/luxury-hotel-04\\\/wp-content\\\/uploads\\\/sites\\\/812\\\/2021\\\/04\\\/gallery-6-400x348.png 400w\\\" sizes=\\\"(max-width: 414px) 100vw, 414px\\\" \\\/>\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t<\\\/div>\\n\\t\\t\\t\\t<\\\/div>\\n\\t\\t\\t\\t<\\\/div>\\n\\t\\t\\t\\t<\\\/div>\\n\\t\\t\\t\\t<\\\/div>\\n\\t\\t\\t\\t\\t<\\\/div>\\n\\t\\t\\t\\t<\\\/div>\\n\\t\\t<div class=\\\"elementor-element elementor-element-7eb1b32 e-flex e-con-boxed e-con e-parent\\\" data-id=\\\"7eb1b32\\\" data-element_type=\\\"container\\\" data-e-type=\\\"container\\\" data-settings=\\\"{&quot;background_background&quot;:&quot;classic&quot;}\\\">\\n\\t\\t\\t\\t\\t<div class=\\\"e-con-inner\\\">\\n\\t\\t<div class=\\\"elementor-element elementor-element-8c62acb e-con-full e-flex e-con e-child\\\" data-id=\\\"8c62acb\\\" data-element_type=\\\"container\\\" data-e-type=\\\"container\\\">\\n\\t\\t<div class=\\\"elementor-element elementor-element-d646544 e-con-full e-flex e-con e-child\\\" data-id=\\\"d646544\\\" data-element_type=\\\"container\\\" data-e-type=\\\"container\\\">\\n\\t\\t<div class=\\\"elementor-element elementor-element-97ab379 e-con-full e-flex e-con e-child\\\" data-id=\\\"97ab379\\\" data-element_type=\\\"container\\\" data-e-type=\\\"container\\\">\\n\\t\\t\\t\\t<div class=\\\"elementor-element elementor-element-ff14b57 elementor-widget elementor-widget-heading\\\" data-id=\\\"ff14b57\\\" data-element_type=\\\"widget\\\" data-e-type=\\\"widget\\\" data-widget_type=\\\"heading.default\\\">\\n\\t\\t\\t\\t<div class=\\\"elementor-widget-container\\\">\\n\\t\\t\\t\\t\\t<h6 class=\\\"elementor-heading-title elementor-size-default\\\">Luxury Privileges<\\\/h6>\\t\\t\\t\\t<\\\/div>\\n\\t\\t\\t\\t<\\\/div>\\n\\t\\t\\t\\t<div class=\\\"elementor-element elementor-element-b89395a elementor-widget elementor-widget-heading\\\" data-id=\\\"b89395a\\\" data-element_type=\\\"widget\\\" data-e-type=\\\"widget\\\" data-widget_type=\\\"heading.default\\\">\\n\\t\\t\\t\\t<div class=\\\"elementor-widget-container\\\">\\n\\t\\t\\t\\t\\t<h2 class=\\\"elementor-heading-title elementor-size-default\\\">Membership Benefits<\\\/h2>\\t\\t\\t\\t<\\\/div>\\n\\t\\t\\t\\t<\\\/div>\\n\\t\\t[elementor-element k=\\\"f19e676918bba936d6bd7c5c78a50cb4\\\" data=\\\"eyJpZCI6IjI5NGNhOGQiLCJlbFR5cGUiOiJ3aWRnZXQiLCJzZXR0aW5ncyI6eyJfcGFkZGluZyI6eyJ1bml0IjoicHgiLCJ0b3AiOiIwIiwicmlnaHQiOiI1MCIsImJvdHRvbSI6IjAiLCJsZWZ0IjoiMCIsImlzTGlua2VkIjoiIn0sImVkaXRvciI6IkxvcmVtIGlwc3VtIGRvbG9yIHNpdCBhbWV0LCBjb25zZWN0ZXR1ciBhZGlwaXNjaW5nIGVsaXQuIFV0IGVsaXQgdGVsbHVzLCBsdWN0dXMgbmVjIHVsbGFtY29ycGVyIG1hdHRpcywgcHVsdmluYXIgZGFwaWJ1cyBsZW8uIiwiYWxpZ25fdGFibGV0IjoiY2VudGVyIiwiX21hcmdpbl90YWJsZXQiOnsidW5pdCI6InB4IiwidG9wIjoiMCIsInJpZ2h0IjoiMCIsImJvdHRvbSI6IjAiLCJsZWZ0IjoiMCIsImlzTGlua2VkIjpmYWxzZX0sIl9wYWRkaW5nX3RhYmxldCI6eyJ1bml0IjoicHgiLCJ0b3AiOiIwIiwicmlnaHQiOiIwIiwiYm90dG9tIjoiMCIsImxlZnQiOiIwIiwiaXNMaW5rZWQiOmZhbHNlfSwiYWxpZ25fbW9iaWxlIjoibGVmdCIsImNvbnRlbnRfd2lkdGgiOiJmdWxsIn0sImVsZW1lbnRzIjpbXSwid2lkZ2V0VHlwZSI6InRleHQtZWRpdG9yIn0=\\\"]\\t\\t<\\\/div>\\n\\t\\t<div class=\\\"elementor-element elementor-element-b1524e4 e-con-full e-flex e-con e-child\\\" data-id=\\\"b1524e4\\\" data-element_type=\\\"container\\\" data-e-type=\\\"container\\\" data-settings=\\\"{&quot;background_background&quot;:&quot;classic&quot;}\\\">\\n\\t\\t\\t\\t<div class=\\\"elementor-element elementor-element-c8065ca elementor-widget elementor-widget-heading\\\" data-id=\\\"c8065ca\\\" data-element_type=\\\"widget\\\" data-e-type=\\\"widget\\\" data-widget_type=\\\"heading.default\\\">\\n\\t\\t\\t\\t<div class=\\\"elementor-widget-container\\\">\\n\\t\\t\\t\\t\\t<h5 class=\\\"elementor-heading-title elementor-size-default\\\">World-class Stay Benefits<\\\/h5>\\t\\t\\t\\t<\\\/div>\\n\\t\\t\\t\\t<\\\/div>\\n\\t\\t[elementor-element k=\\\"f19e676918bba936d6bd7c5c78a50cb4\\\" data=\\\"eyJpZCI6IjRiMmY3NjYiLCJlbFR5cGUiOiJ3aWRnZXQiLCJzZXR0aW5ncyI6eyJlZGl0b3IiOiJMb3JlbSBpcHN1bSBkb2xvciBzaXQgYW1ldCwgY29uc2VjIHRldHVyIGFkaXBpc2NpbmcuIFV0IGVsaXQgdGVsbHVzLCBsdWN0dXMgbmVjIG51bGxhbSBjb3JwZXIsIHB1bHZpbmFyIGRhcGlidXMgbGVvLiIsIl9wYWRkaW5nIjp7InVuaXQiOiJweCIsInRvcCI6IjAiLCJyaWdodCI6IjAiLCJib3R0b20iOiIwIiwibGVmdCI6IjAiLCJpc0xpbmtlZCI6IiJ9LCJfbWFyZ2luX21vYmlsZSI6eyJ1bml0IjoicHgiLCJ0b3AiOiIwIiwicmlnaHQiOiIwIiwiYm90dG9tIjoiMCIsImxlZnQiOiIwIiwiaXNMaW5rZWQiOmZhbHNlfSwiX3BhZGRpbmdfbW9iaWxlIjp7InVuaXQiOiJweCIsInRvcCI6IjAiLCJyaWdodCI6IjAiLCJib3R0b20iOiIwIiwibGVmdCI6IjAiLCJpc0xpbmtlZCI6ZmFsc2V9LCJjb250ZW50X3dpZHRoIjoiZnVsbCJ9LCJlbGVtZW50cyI6W10sIndpZGdldFR5cGUiOiJ0ZXh0LWVkaXRvciJ9\\\"]\\t\\t<\\\/div>\\n\\t\\t<div class=\\\"elementor-element elementor-element-1225fb2 e-con-full e-flex e-con e-child\\\" data-id=\\\"1225fb2\\\" data-element_type=\\\"container\\\" data-e-type=\\\"container\\\">\\n\\t\\t\\t\\t<div class=\\\"elementor-element elementor-element-d0c4671 elementor-widget elementor-widget-image\\\" data-id=\\\"d0c4671\\\" data-element_type=\\\"widget\\\" data-e-type=\\\"widget\\\" data-widget_type=\\\"image.default\\\">\\n\\t\\t\\t\\t<div class=\\\"elementor-widget-container\\\">\\n\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t<img width=\\\"300\\\" height=\\\"300\\\" src=\\\"https:\\\/\\\/websitedemos.net\\\/luxury-hotel-04\\\/wp-content\\\/uploads\\\/sites\\\/812\\\/2021\\\/04\\\/world-class1-300x300.jpg\\\" class=\\\"attachment-medium size-medium wp-image-1091\\\" alt=\\\"\\\" srcset=\\\"https:\\\/\\\/websitedemos.net\\\/luxury-hotel-04\\\/wp-content\\\/uploads\\\/sites\\\/812\\\/2021\\\/04\\\/world-class1-300x300.jpg 300w, https:\\\/\\\/websitedemos.net\\\/luxury-hotel-04\\\/wp-content\\\/uploads\\\/sites\\\/812\\\/2021\\\/04\\\/world-class1-150x150.jpg 150w, https:\\\/\\\/websitedemos.net\\\/luxury-hotel-04\\\/wp-content\\\/uploads\\\/sites\\\/812\\\/2021\\\/04\\\/world-class1-400x400.jpg 400w, https:\\\/\\\/websitedemos.net\\\/luxury-hotel-04\\\/wp-content\\\/uploads\\\/sites\\\/812\\\/2021\\\/04\\\/world-class1.jpg 427w\\\" sizes=\\\"(max-width: 300px) 100vw, 300px\\\" \\\/>\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t<\\\/div>\\n\\t\\t\\t\\t<\\\/div>\\n\\t\\t\\t\\t<\\\/div>\\n\\t\\t\\t\\t<\\\/div>\\n\\t\\t<div class=\\\"elementor-element elementor-element-fa19ba7 e-con-full e-flex e-con e-child\\\" data-id=\\\"fa19ba7\\\" data-element_type=\\\"container\\\" data-e-type=\\\"container\\\">\\n\\t\\t<div class=\\\"elementor-element elementor-element-3d23f22 e-con-full e-flex e-con e-child\\\" data-id=\\\"3d23f22\\\" data-element_type=\\\"container\\\" data-e-type=\\\"container\\\">\\n\\t\\t\\t\\t<div class=\\\"elementor-element elementor-element-05755b8 elementor-widget elementor-widget-image\\\" data-id=\\\"05755b8\\\" data-element_type=\\\"widget\\\" data-e-type=\\\"widget\\\" data-widget_type=\\\"image.default\\\">\\n\\t\\t\\t\\t<div class=\\\"elementor-widget-container\\\">\\n\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t<img width=\\\"300\\\" height=\\\"300\\\" src=\\\"https:\\\/\\\/websitedemos.net\\\/luxury-hotel-04\\\/wp-content\\\/uploads\\\/sites\\\/812\\\/2021\\\/04\\\/casino-11-300x300.jpg\\\" class=\\\"attachment-medium size-medium wp-image-1087\\\" alt=\\\"\\\" srcset=\\\"https:\\\/\\\/websitedemos.net\\\/luxury-hotel-04\\\/wp-content\\\/uploads\\\/sites\\\/812\\\/2021\\\/04\\\/casino-11-300x300.jpg 300w, https:\\\/\\\/websitedemos.net\\\/luxury-hotel-04\\\/wp-content\\\/uploads\\\/sites\\\/812\\\/2021\\\/04\\\/casino-11-150x150.jpg 150w, https:\\\/\\\/websitedemos.net\\\/luxury-hotel-04\\\/wp-content\\\/uploads\\\/sites\\\/812\\\/2021\\\/04\\\/casino-11-400x400.jpg 400w, https:\\\/\\\/websitedemos.net\\\/luxury-hotel-04\\\/wp-content\\\/uploads\\\/sites\\\/812\\\/2021\\\/04\\\/casino-11.jpg 640w\\\" sizes=\\\"(max-width: 300px) 100vw, 300px\\\" \\\/>\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t<\\\/div>\\n\\t\\t\\t\\t<\\\/div>\\n\\t\\t\\t\\t<\\\/div>\\n\\t\\t<div class=\\\"elementor-element elementor-element-4693b4f e-con-full e-flex e-con e-child\\\" data-id=\\\"4693b4f\\\" data-element_type=\\\"container\\\" data-e-type=\\\"container\\\" data-settings=\\\"{&quot;background_background&quot;:&quot;classic&quot;}\\\">\\n\\t\\t\\t\\t<div class=\\\"elementor-element elementor-element-a12dafc elementor-widget elementor-widget-heading\\\" data-id=\\\"a12dafc\\\" data-element_type=\\\"widget\\\" data-e-type=\\\"widget\\\" data-widget_type=\\\"heading.default\\\">\\n\\t\\t\\t\\t<div class=\\\"elementor-widget-container\\\">\\n\\t\\t\\t\\t\\t<h5 class=\\\"elementor-heading-title elementor-size-default\\\">Exclusive Casino Benefits<\\\/h5>\\t\\t\\t\\t<\\\/div>\\n\\t\\t\\t\\t<\\\/div>\\n\\t\\t[elementor-element k=\\\"f19e676918bba936d6bd7c5c78a50cb4\\\" data=\\\"eyJpZCI6IjgxNzgwZWMiLCJlbFR5cGUiOiJ3aWRnZXQiLCJzZXR0aW5ncyI6eyJlZGl0b3IiOiJMb3JlbSBpcHN1bSBkb2xvciBzaXQgYW1ldCwgY29uc2VjIHRldHVyIGFkaXBpc2NpbmcuIFV0IGVsaXQgdGVsbHVzLCBsdWN0dXMgbmVjIG51bGxhbSBjb3JwZXIsIHB1bHZpbmFyIGRhcGlidXMgbGVvLiIsIl9wYWRkaW5nIjp7InVuaXQiOiJweCIsInRvcCI6IjAiLCJyaWdodCI6IjAiLCJib3R0b20iOiIwIiwibGVmdCI6IjAiLCJpc0xpbmtlZCI6IiJ9LCJfbWFyZ2luX21vYmlsZSI6eyJ1bml0IjoicHgiLCJ0b3AiOiIwIiwicmlnaHQiOiIwIiwiYm90dG9tIjoiMCIsImxlZnQiOiIwIiwiaXNMaW5rZWQiOmZhbHNlfSwiX3BhZGRpbmdfbW9iaWxlIjp7InVuaXQiOiJweCIsInRvcCI6IjAiLCJyaWdodCI6IjAiLCJib3R0b20iOiIwIiwibGVmdCI6IjAiLCJpc0xpbmtlZCI6ZmFsc2V9LCJjb250ZW50X3dpZHRoIjoiZnVsbCJ9LCJlbGVtZW50cyI6W10sIndpZGdldFR5cGUiOiJ0ZXh0LWVkaXRvciJ9\\\"]\\t\\t<\\\/div>\\n\\t\\t<div class=\\\"elementor-element elementor-element-b005f72 e-con-full e-flex e-con e-child\\\" data-id=\\\"b005f72\\\" data-element_type=\\\"container\\\" data-e-type=\\\"container\\\">\\n\\t\\t\\t\\t<div class=\\\"elementor-element elementor-element-1740e04 elementor-widget elementor-widget-image\\\" data-id=\\\"1740e04\\\" data-element_type=\\\"widget\\\" data-e-type=\\\"widget\\\" data-widget_type=\\\"image.default\\\">\\n\\t\\t\\t\\t<div class=\\\"elementor-widget-container\\\">\\n\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t<img width=\\\"300\\\" height=\\\"300\\\" src=\\\"https:\\\/\\\/websitedemos.net\\\/luxury-hotel-04\\\/wp-content\\\/uploads\\\/sites\\\/812\\\/2021\\\/04\\\/350x350-3-300x300.png\\\" class=\\\"attachment-medium size-medium wp-image-192\\\" alt=\\\"\\\" srcset=\\\"https:\\\/\\\/websitedemos.net\\\/luxury-hotel-04\\\/wp-content\\\/uploads\\\/sites\\\/812\\\/2021\\\/04\\\/350x350-3-300x300.png 300w, https:\\\/\\\/websitedemos.net\\\/luxury-hotel-04\\\/wp-content\\\/uploads\\\/sites\\\/812\\\/2021\\\/04\\\/350x350-3-150x150.png 150w, https:\\\/\\\/websitedemos.net\\\/luxury-hotel-04\\\/wp-content\\\/uploads\\\/sites\\\/812\\\/2021\\\/04\\\/350x350-3.png 350w\\\" sizes=\\\"(max-width: 300px) 100vw, 300px\\\" \\\/>\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t<\\\/div>\\n\\t\\t\\t\\t<\\\/div>\\n\\t\\t\\t\\t<\\\/div>\\n\\t\\t<div class=\\\"elementor-element elementor-element-3b812d3 e-con-full e-flex e-con e-child\\\" data-id=\\\"3b812d3\\\" data-element_type=\\\"container\\\" data-e-type=\\\"container\\\" data-settings=\\\"{&quot;background_background&quot;:&quot;classic&quot;}\\\">\\n\\t\\t\\t\\t<div class=\\\"elementor-element elementor-element-6d87d08 elementor-widget elementor-widget-heading\\\" data-id=\\\"6d87d08\\\" data-element_type=\\\"widget\\\" data-e-type=\\\"widget\\\" data-widget_type=\\\"heading.default\\\">\\n\\t\\t\\t\\t<div class=\\\"elementor-widget-container\\\">\\n\\t\\t\\t\\t\\t<h5 class=\\\"elementor-heading-title elementor-size-default\\\">Exclusive Lifestyle Voucher<\\\/h5>\\t\\t\\t\\t<\\\/div>\\n\\t\\t\\t\\t<\\\/div>\\n\\t\\t[elementor-element k=\\\"f19e676918bba936d6bd7c5c78a50cb4\\\" data=\\\"eyJpZCI6IjViY2NhNjEiLCJlbFR5cGUiOiJ3aWRnZXQiLCJzZXR0aW5ncyI6eyJlZGl0b3IiOiJMb3JlbSBpcHN1bSBkb2xvciBzaXQgYW1ldCwgY29uc2VjIHRldHVyIGFkaXBpc2NpbmcuIFV0IGVsaXQgdGVsbHVzLCBsdWN0dXMgbmVjIG51bGxhbSBjb3JwZXIsIHB1bHZpbmFyIGRhcGlidXMgbGVvLiIsIl9wYWRkaW5nIjp7InVuaXQiOiJweCIsInRvcCI6IjAiLCJyaWdodCI6IjAiLCJib3R0b20iOiIwIiwibGVmdCI6IjAiLCJpc0xpbmtlZCI6IiJ9LCJfbWFyZ2luX21vYmlsZSI6eyJ1bml0IjoicHgiLCJ0b3AiOiIwIiwicmlnaHQiOiIwIiwiYm90dG9tIjoiMCIsImxlZnQiOiIwIiwiaXNMaW5rZWQiOmZhbHNlfSwiX3BhZGRpbmdfbW9iaWxlIjp7InVuaXQiOiJweCIsInRvcCI6IjAiLCJyaWdodCI6IjAiLCJib3R0b20iOiIwIiwibGVmdCI6IjAiLCJpc0xpbmtlZCI6ZmFsc2V9LCJjb250ZW50X3dpZHRoIjoiZnVsbCJ9LCJlbGVtZW50cyI6W10sIndpZGdldFR5cGUiOiJ0ZXh0LWVkaXRvciJ9\\\"]\\t\\t<\\\/div>\\n\\t\\t\\t\\t<\\\/div>\\n\\t\\t<div class=\\\"elementor-element elementor-element-598928d e-con-full e-flex e-con e-child\\\" data-id=\\\"598928d\\\" data-element_type=\\\"container\\\" data-e-type=\\\"container\\\">\\n\\t\\t<div class=\\\"elementor-element elementor-element-47f9cdf e-con-full e-flex e-con e-child\\\" data-id=\\\"47f9cdf\\\" data-element_type=\\\"container\\\" data-e-type=\\\"container\\\" data-settings=\\\"{&quot;background_background&quot;:&quot;classic&quot;}\\\">\\n\\t\\t\\t\\t<div class=\\\"elementor-element elementor-element-2853383 elementor-widget elementor-widget-heading\\\" data-id=\\\"2853383\\\" data-element_type=\\\"widget\\\" data-e-type=\\\"widget\\\" data-widget_type=\\\"heading.default\\\">\\n\\t\\t\\t\\t<div class=\\\"elementor-widget-container\\\">\\n\\t\\t\\t\\t\\t<h5 class=\\\"elementor-heading-title elementor-size-default\\\">Complementary<br> Wine Bottle <\\\/h5>\\t\\t\\t\\t<\\\/div>\\n\\t\\t\\t\\t<\\\/div>\\n\\t\\t[elementor-element k=\\\"f19e676918bba936d6bd7c5c78a50cb4\\\" data=\\\"eyJpZCI6Ijc2OTgxMjMiLCJlbFR5cGUiOiJ3aWRnZXQiLCJzZXR0aW5ncyI6eyJlZGl0b3IiOiJMb3JlbSBpcHN1bSBkb2xvciBzaXQgYW1ldCwgY29uc2VjIHRldHVyIGFkaXBpc2NpbmcuIFV0IGVsaXQgdGVsbHVzLCBsdWN0dXMgbmVjIG51bGxhbSBjb3JwZXIsIHB1bHZpbmFyIGRhcGlidXMgbGVvLiIsIl9wYWRkaW5nIjp7InVuaXQiOiJweCIsInRvcCI6IjAiLCJyaWdodCI6IjAiLCJib3R0b20iOiIwIiwibGVmdCI6IjAiLCJpc0xpbmtlZCI6IiJ9LCJfbWFyZ2luX21vYmlsZSI6eyJ1bml0IjoicHgiLCJ0b3AiOiIwIiwicmlnaHQiOiIwIiwiYm90dG9tIjoiMCIsImxlZnQiOiIwIiwiaXNMaW5rZWQiOmZhbHNlfSwiX3BhZGRpbmdfbW9iaWxlIjp7InVuaXQiOiJweCIsInRvcCI6IjAiLCJyaWdodCI6IjAiLCJib3R0b20iOiIwIiwibGVmdCI6IjAiLCJpc0xpbmtlZCI6ZmFsc2V9LCJjb250ZW50X3dpZHRoIjoiZnVsbCJ9LCJlbGVtZW50cyI6W10sIndpZGdldFR5cGUiOiJ0ZXh0LWVkaXRvciJ9\\\"]\\t\\t<\\\/div>\\n\\t\\t<div class=\\\"elementor-element elementor-element-6872806 e-con-full e-flex e-con e-child\\\" data-id=\\\"6872806\\\" data-element_type=\\\"container\\\" data-e-type=\\\"container\\\">\\n\\t\\t\\t\\t<div class=\\\"elementor-element elementor-element-10dcd41 elementor-widget elementor-widget-image\\\" data-id=\\\"10dcd41\\\" data-element_type=\\\"widget\\\" data-e-type=\\\"widget\\\" data-widget_type=\\\"image.default\\\">\\n\\t\\t\\t\\t<div class=\\\"elementor-widget-container\\\">\\n\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t<img width=\\\"300\\\" height=\\\"300\\\" src=\\\"https:\\\/\\\/websitedemos.net\\\/luxury-hotel-04\\\/wp-content\\\/uploads\\\/sites\\\/812\\\/2021\\\/04\\\/wine-bottle-300x300.jpg\\\" class=\\\"attachment-medium size-medium wp-image-1095\\\" alt=\\\"\\\" srcset=\\\"https:\\\/\\\/websitedemos.net\\\/luxury-hotel-04\\\/wp-content\\\/uploads\\\/sites\\\/812\\\/2021\\\/04\\\/wine-bottle-300x300.jpg 300w, https:\\\/\\\/websitedemos.net\\\/luxury-hotel-04\\\/wp-content\\\/uploads\\\/sites\\\/812\\\/2021\\\/04\\\/wine-bottle-150x150.jpg 150w, https:\\\/\\\/websitedemos.net\\\/luxury-hotel-04\\\/wp-content\\\/uploads\\\/sites\\\/812\\\/2021\\\/04\\\/wine-bottle-400x400.jpg 400w, https:\\\/\\\/websitedemos.net\\\/luxury-hotel-04\\\/wp-content\\\/uploads\\\/sites\\\/812\\\/2021\\\/04\\\/wine-bottle.jpg 640w\\\" sizes=\\\"(max-width: 300px) 100vw, 300px\\\" \\\/>\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t<\\\/div>\\n\\t\\t\\t\\t<\\\/div>\\n\\t\\t\\t\\t<\\\/div>\\n\\t\\t<div class=\\\"elementor-element elementor-element-7613f61 e-con-full e-flex e-con e-child\\\" data-id=\\\"7613f61\\\" data-element_type=\\\"container\\\" data-e-type=\\\"container\\\" data-settings=\\\"{&quot;background_background&quot;:&quot;classic&quot;}\\\">\\n\\t\\t\\t\\t<div class=\\\"elementor-element elementor-element-504f666 elementor-widget elementor-widget-heading\\\" data-id=\\\"504f666\\\" data-element_type=\\\"widget\\\" data-e-type=\\\"widget\\\" data-widget_type=\\\"heading.default\\\">\\n\\t\\t\\t\\t<div class=\\\"elementor-widget-container\\\">\\n\\t\\t\\t\\t\\t<h4 class=\\\"elementor-heading-title elementor-size-default\\\"> More Benefits<\\\/h4>\\t\\t\\t\\t<\\\/div>\\n\\t\\t\\t\\t<\\\/div>\\n\\t\\t[elementor-element k=\\\"f19e676918bba936d6bd7c5c78a50cb4\\\" data=\\\"eyJpZCI6IjM0MTNkNDIiLCJlbFR5cGUiOiJ3aWRnZXQiLCJzZXR0aW5ncyI6eyJlZGl0b3IiOiJRdWlzcXVlIHZlbGl0IG5pc2ksIHByZXRpdW0gdXQgbGFjaW5pYSBpbiwgZWxlbWVudHVtIGlkIGVuaW0uIEN1cmFiaXR1ciBub24gbnVsbGEgc2l0IGFtZXQgbmlzbCB0ZW1wdXMgY29udmFsbGlzIHF1aXMgYWMgbGVjdHVzLiIsIl9wYWRkaW5nIjp7InVuaXQiOiJweCIsInRvcCI6IjAiLCJyaWdodCI6IjUwIiwiYm90dG9tIjoiMCIsImxlZnQiOiIwIiwiaXNMaW5rZWQiOiIifSwiYWxpZ25fdGFibGV0IjoiY2VudGVyIiwiX21hcmdpbl90YWJsZXQiOnsidW5pdCI6InB4IiwidG9wIjoiMCIsInJpZ2h0IjoiMCIsImJvdHRvbSI6IjAiLCJsZWZ0IjoiMCIsImlzTGlua2VkIjpmYWxzZX0sIl9wYWRkaW5nX3RhYmxldCI6eyJ1bml0IjoicHgiLCJ0b3AiOiIwIiwicmlnaHQiOiIwIiwiYm90dG9tIjoiMCIsImxlZnQiOiIwIiwiaXNMaW5rZWQiOmZhbHNlfSwiYWxpZ25fbW9iaWxlIjoibGVmdCIsImNvbnRlbnRfd2lkdGgiOiJmdWxsIn0sImVsZW1lbnRzIjpbXSwid2lkZ2V0VHlwZSI6InRleHQtZWRpdG9yIn0=\\\"]\\t\\t<div class=\\\"elementor-element elementor-element-747e002 elementor-tablet-align-center elementor-mobile-align-left elementor-widget elementor-widget-button\\\" data-id=\\\"747e002\\\" data-element_type=\\\"widget\\\" data-e-type=\\\"widget\\\" data-widget_type=\\\"button.default\\\">\\n\\t\\t\\t\\t<div class=\\\"elementor-widget-container\\\">\\n\\t\\t\\t\\t\\t\\t\\t\\t\\t<div class=\\\"elementor-button-wrapper\\\">\\n\\t\\t\\t\\t\\t<a class=\\\"elementor-button elementor-button-link elementor-size-sm\\\" href=\\\"#\\\">\\n\\t\\t\\t\\t\\t\\t<span class=\\\"elementor-button-content-wrapper\\\">\\n\\t\\t\\t\\t\\t\\t\\t\\t\\t<span class=\\\"elementor-button-text\\\">Become a Member<\\\/span>\\n\\t\\t\\t\\t\\t<\\\/span>\\n\\t\\t\\t\\t\\t<\\\/a>\\n\\t\\t\\t\\t<\\\/div>\\n\\t\\t\\t\\t\\t\\t\\t\\t<\\\/div>\\n\\t\\t\\t\\t<\\\/div>\\n\\t\\t\\t\\t<\\\/div>\\n\\t\\t\\t\\t<\\\/div>\\n\\t\\t\\t\\t<\\\/div>\\n\\t\\t\\t\\t\\t<\\\/div>\\n\\t\\t\\t\\t<\\\/div>\\n\\t\\t<div class=\\\"elementor-element elementor-element-d0d1ab1 e-flex e-con-boxed e-con e-parent\\\" data-id=\\\"d0d1ab1\\\" data-element_type=\\\"container\\\" data-e-type=\\\"container\\\">\\n\\t\\t\\t\\t\\t<div class=\\\"e-con-inner\\\">\\n\\t\\t<div class=\\\"elementor-element elementor-element-c3afb67 e-con-full e-flex e-con e-child\\\" data-id=\\\"c3afb67\\\" data-element_type=\\\"container\\\" data-e-type=\\\"container\\\">\\n\\t\\t\\t\\t<div class=\\\"elementor-element elementor-element-3f3e405 elementor-widget elementor-widget-heading\\\" data-id=\\\"3f3e405\\\" data-element_type=\\\"widget\\\" data-e-type=\\\"widget\\\" data-widget_type=\\\"heading.default\\\">\\n\\t\\t\\t\\t<div class=\\\"elementor-widget-container\\\">\\n\\t\\t\\t\\t\\t<h3 class=\\\"elementor-heading-title elementor-size-default\\\">Ideal Venue For Any Event<\\\/h3>\\t\\t\\t\\t<\\\/div>\\n\\t\\t\\t\\t<\\\/div>\\n\\t\\t[elementor-element k=\\\"f19e676918bba936d6bd7c5c78a50cb4\\\" data=\\\"eyJpZCI6ImMzZDQ0MDciLCJlbFR5cGUiOiJ3aWRnZXQiLCJzZXR0aW5ncyI6eyJlZGl0b3IiOiJRdWlzcXVlIHZlbGl0IG5pc2ksIHByZXRpdW0gdXQgbGFjaW5pYSBpbiwgZWxlbWVudHVtIGlkIGVuaW0uIiwiYWxpZ24iOiJjZW50ZXIiLCJhbGlnbl9tb2JpbGUiOiJsZWZ0IiwiY29udGVudF93aWR0aCI6ImZ1bGwifSwiZWxlbWVudHMiOltdLCJ3aWRnZXRUeXBlIjoidGV4dC1lZGl0b3IifQ==\\\"]<div class=\\\"elementor-element elementor-element-e420b23 e-con-full e-flex e-con e-child\\\" data-id=\\\"e420b23\\\" data-element_type=\\\"container\\\" data-e-type=\\\"container\\\">\\n\\t\\t<div class=\\\"elementor-element elementor-element-6d05509 e-con-full e-flex e-con e-child\\\" data-id=\\\"6d05509\\\" data-element_type=\\\"container\\\" data-e-type=\\\"container\\\">\\n\\t\\t\\t\\t<div class=\\\"elementor-element elementor-element-8ff67a0 elementor-widget elementor-widget-image\\\" data-id=\\\"8ff67a0\\\" data-element_type=\\\"widget\\\" data-e-type=\\\"widget\\\" data-widget_type=\\\"image.default\\\">\\n\\t\\t\\t\\t<div class=\\\"elementor-widget-container\\\">\\n\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t<img width=\\\"452\\\" height=\\\"333\\\" src=\\\"https:\\\/\\\/websitedemos.net\\\/luxury-hotel-04\\\/wp-content\\\/uploads\\\/sites\\\/812\\\/2021\\\/04\\\/event-1.png\\\" class=\\\"attachment-large size-large wp-image-243\\\" alt=\\\"\\\" srcset=\\\"https:\\\/\\\/websitedemos.net\\\/luxury-hotel-04\\\/wp-content\\\/uploads\\\/sites\\\/812\\\/2021\\\/04\\\/event-1.png 452w, https:\\\/\\\/websitedemos.net\\\/luxury-hotel-04\\\/wp-content\\\/uploads\\\/sites\\\/812\\\/2021\\\/04\\\/event-1-300x221.png 300w, https:\\\/\\\/websitedemos.net\\\/luxury-hotel-04\\\/wp-content\\\/uploads\\\/sites\\\/812\\\/2021\\\/04\\\/event-1-400x295.png 400w\\\" sizes=\\\"(max-width: 452px) 100vw, 452px\\\" \\\/>\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t<\\\/div>\\n\\t\\t\\t\\t<\\\/div>\\n\\t\\t\\t\\t<div class=\\\"elementor-element elementor-element-7d54893 elementor-widget elementor-widget-image-box\\\" data-id=\\\"7d54893\\\" data-element_type=\\\"widget\\\" data-e-type=\\\"widget\\\" data-widget_type=\\\"image-box.default\\\">\\n\\t\\t\\t\\t<div class=\\\"elementor-widget-container\\\">\\n\\t\\t\\t\\t\\t<div class=\\\"elementor-image-box-wrapper\\\"><div class=\\\"elementor-image-box-content\\\"><h4 class=\\\"elementor-image-box-title\\\">Weddings<\\\/h4><p class=\\\"elementor-image-box-description\\\">Lorem ipsum dolor sit amet, consectetur adipiscing elit. Ut elit tellus, luctus nec ullamcorper mattis, pulvinar dapibus leo.<\\\/p><\\\/div><\\\/div>\\t\\t\\t\\t<\\\/div>\\n\\t\\t\\t\\t<\\\/div>\\n\\t\\t\\t\\t<\\\/div>\\n\\t\\t<div class=\\\"elementor-element elementor-element-aea64ab e-con-full e-flex e-con e-child\\\" data-id=\\\"aea64ab\\\" data-element_type=\\\"container\\\" data-e-type=\\\"container\\\">\\n\\t\\t\\t\\t<div class=\\\"elementor-element elementor-element-f929a45 elementor-widget elementor-widget-image-box\\\" data-id=\\\"f929a45\\\" data-element_type=\\\"widget\\\" data-e-type=\\\"widget\\\" data-widget_type=\\\"image-box.default\\\">\\n\\t\\t\\t\\t<div class=\\\"elementor-widget-container\\\">\\n\\t\\t\\t\\t\\t<div class=\\\"elementor-image-box-wrapper\\\"><div class=\\\"elementor-image-box-content\\\"><h4 class=\\\"elementor-image-box-title\\\">Parties<\\\/h4><p class=\\\"elementor-image-box-description\\\">Lorem ipsum dolor sit amet, consectetur adipiscing elit. Ut elit tellus, luctus nec ullamcorper mattis, pulvinar dapibus leo.<\\\/p><\\\/div><\\\/div>\\t\\t\\t\\t<\\\/div>\\n\\t\\t\\t\\t<\\\/div>\\n\\t\\t\\t\\t<div class=\\\"elementor-element elementor-element-784e7a5 elementor-widget elementor-widget-image\\\" data-id=\\\"784e7a5\\\" data-element_type=\\\"widget\\\" data-e-type=\\\"widget\\\" data-widget_type=\\\"image.default\\\">\\n\\t\\t\\t\\t<div class=\\\"elementor-widget-container\\\">\\n\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t<img width=\\\"452\\\" height=\\\"333\\\" src=\\\"https:\\\/\\\/websitedemos.net\\\/luxury-hotel-04\\\/wp-content\\\/uploads\\\/sites\\\/812\\\/2021\\\/04\\\/event-2.png\\\" class=\\\"attachment-large size-large wp-image-245\\\" alt=\\\"\\\" srcset=\\\"https:\\\/\\\/websitedemos.net\\\/luxury-hotel-04\\\/wp-content\\\/uploads\\\/sites\\\/812\\\/2021\\\/04\\\/event-2.png 452w, https:\\\/\\\/websitedemos.net\\\/luxury-hotel-04\\\/wp-content\\\/uploads\\\/sites\\\/812\\\/2021\\\/04\\\/event-2-300x221.png 300w, https:\\\/\\\/websitedemos.net\\\/luxury-hotel-04\\\/wp-content\\\/uploads\\\/sites\\\/812\\\/2021\\\/04\\\/event-2-400x295.png 400w\\\" sizes=\\\"(max-width: 452px) 100vw, 452px\\\" \\\/>\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t<\\\/div>\\n\\t\\t\\t\\t<\\\/div>\\n\\t\\t\\t\\t<\\\/div>\\n\\t\\t<div class=\\\"elementor-element elementor-element-2f92c95 e-con-full e-flex e-con e-child\\\" data-id=\\\"2f92c95\\\" data-element_type=\\\"container\\\" data-e-type=\\\"container\\\">\\n\\t\\t\\t\\t<div class=\\\"elementor-element elementor-element-110b108 elementor-widget elementor-widget-image\\\" data-id=\\\"110b108\\\" data-element_type=\\\"widget\\\" data-e-type=\\\"widget\\\" data-widget_type=\\\"image.default\\\">\\n\\t\\t\\t\\t<div class=\\\"elementor-widget-container\\\">\\n\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t<img width=\\\"452\\\" height=\\\"333\\\" src=\\\"https:\\\/\\\/websitedemos.net\\\/luxury-hotel-04\\\/wp-content\\\/uploads\\\/sites\\\/812\\\/2021\\\/04\\\/conference-1.jpg\\\" class=\\\"attachment-large size-large wp-image-1101\\\" alt=\\\"\\\" srcset=\\\"https:\\\/\\\/websitedemos.net\\\/luxury-hotel-04\\\/wp-content\\\/uploads\\\/sites\\\/812\\\/2021\\\/04\\\/conference-1.jpg 452w, https:\\\/\\\/websitedemos.net\\\/luxury-hotel-04\\\/wp-content\\\/uploads\\\/sites\\\/812\\\/2021\\\/04\\\/conference-1-300x221.jpg 300w, https:\\\/\\\/websitedemos.net\\\/luxury-hotel-04\\\/wp-content\\\/uploads\\\/sites\\\/812\\\/2021\\\/04\\\/conference-1-400x295.jpg 400w\\\" sizes=\\\"(max-width: 452px) 100vw, 452px\\\" \\\/>\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t\\t<\\\/div>\\n\\t\\t\\t\\t<\\\/div>\\n\\t\\t\\t\\t<div class=\\\"elementor-element elementor-element-ae815d2 elementor-widget elementor-widget-image-box\\\" data-id=\\\"ae815d2\\\" data-element_type=\\\"widget\\\" data-e-type=\\\"widget\\\" data-widget_type=\\\"image-box.default\\\">\\n\\t\\t\\t\\t<div class=\\\"elementor-widget-container\\\">\\n\\t\\t\\t\\t\\t<div class=\\\"elementor-image-box-wrapper\\\"><div class=\\\"elementor-image-box-content\\\"><h4 class=\\\"elementor-image-box-title\\\">Conference<\\\/h4><p class=\\\"elementor-image-box-description\\\">Lorem ipsum dolor sit amet, consectetur adipiscing elit. Ut elit tellus, luctus nec ullamcorper mattis, pulvinar dapibus leo.<\\\/p><\\\/div><\\\/div>\\t\\t\\t\\t<\\\/div>\\n\\t\\t\\t\\t<\\\/div>\\n\\t\\t\\t\\t<\\\/div>\\n\\t\\t\\t\\t<\\\/div>\\n\\t\\t\\t\\t<\\\/div>\\n\\t\\t\\t\\t\\t<\\\/div>\\n\\t\\t\\t\\t<\\\/div>\\n\\t\\t<div class=\\\"elementor-element elementor-element-7af717b e-flex e-con-boxed e-con e-parent\\\" data-id=\\\"7af717b\\\" data-element_type=\\\"container\\\" data-e-type=\\\"container\\\" data-settings=\\\"{&quot;background_background&quot;:&quot;classic&quot;}\\\">\\n\\t\\t\\t\\t\\t<div class=\\\"e-con-inner\\\">\\n\\t\\t<div class=\\\"elementor-element elementor-element-3541771 e-con-full e-flex e-con e-child\\\" data-id=\\\"3541771\\\" data-element_type=\\\"container\\\" data-e-type=\\\"container\\\">\\n\\t\\t\\t\\t<div class=\\\"elementor-element elementor-element-125deeb elementor-widget elementor-widget-heading\\\" data-id=\\\"125deeb\\\" data-element_type=\\\"widget\\\" data-e-type=\\\"widget\\\" data-widget_type=\\\"heading.default\\\">\\n\\t\\t\\t\\t<div class=\\\"elementor-widget-container\\\">\\n\\t\\t\\t\\t\\t<h2 class=\\\"elementor-heading-title elementor-size-default\\\">Your search for True Luxury ends here<\\\/h2>\\t\\t\\t\\t<\\\/div>\\n\\t\\t\\t\\t<\\\/div>\\n\\t\\t[elementor-element k=\\\"f19e676918bba936d6bd7c5c78a50cb4\\\" data=\\\"eyJpZCI6ImNmNGU3OWQiLCJlbFR5cGUiOiJ3aWRnZXQiLCJzZXR0aW5ncyI6eyJlZGl0b3IiOiJMb3JlbSBpcHN1bSBkb2xvciBzaXQgYW1ldCwgY29uc2VjdGV0dXIgYWRpcGlzY2luZyBlbGl0LiBVdCBlbGl0IHRlbGx1cywgbHVjdHVzIG5lYyB1bGxhbWNvcnBlciBtYXR0aXMsIHB1bHZpbmFyIGRhcGlidXMgbGVvLiIsImFsaWduX21vYmlsZSI6ImNlbnRlciIsIl9wYWRkaW5nX21vYmlsZSI6eyJ1bml0IjoicHgiLCJ0b3AiOiIwIiwicmlnaHQiOiIwIiwiYm90dG9tIjoiMCIsImxlZnQiOiIwIiwiaXNMaW5rZWQiOiIifSwiX21hcmdpbiI6eyJ1bml0IjoiJSIsInRvcCI6IjAiLCJyaWdodCI6IjEwIiwiYm90dG9tIjoiMCIsImxlZnQiOiIwIiwiaXNMaW5rZWQiOmZhbHNlfSwidHlwb2dyYXBoeV90eXBvZ3JhcGh5IjoiY3VzdG9tIiwidHlwb2dyYXBoeV9mb250X3NpemUiOnsidW5pdCI6InB4Iiwic2l6ZSI6MTgsInNpemVzIjpbXX0sImFsaWduX3RhYmxldCI6ImNlbnRlciIsInR5cG9ncmFwaHlfZm9udF9zaXplX3RhYmxldCI6eyJ1bml0IjoicHgiLCJzaXplIjoxNSwic2l6ZXMiOltdfSwiX21hcmdpbl90YWJsZXQiOnsidW5pdCI6InB4IiwidG9wIjoiMCIsInJpZ2h0IjoiMCIsImJvdHRvbSI6IjAiLCJsZWZ0IjoiMCIsImlzTGlua2VkIjpmYWxzZX0sIl9wYWRkaW5nX3RhYmxldCI6eyJ1bml0IjoicHgiLCJ0b3AiOiIwIiwicmlnaHQiOiIwIiwiYm90dG9tIjoiMCIsImxlZnQiOiIwIiwiaXNMaW5rZWQiOmZhbHNlfSwiY29udGVudF93aWR0aCI6ImZ1bGwifSwiZWxlbWVudHMiOltdLCJ3aWRnZXRUeXBlIjoidGV4dC1lZGl0b3IifQ==\\\"]\\t\\t<\\\/div>\\n\\t\\t<div class=\\\"elementor-element elementor-element-9afc588 e-con-full e-flex e-con e-child\\\" data-id=\\\"9afc588\\\" data-element_type=\\\"container\\\" data-e-type=\\\"container\\\">\\n\\t\\t\\t\\t<div class=\\\"elementor-element elementor-element-46ff7a2 elementor-align-right elementor-tablet-align-center elementor-widget elementor-widget-button\\\" data-id=\\\"46ff7a2\\\" data-element_type=\\\"widget\\\" data-e-type=\\\"widget\\\" data-widget_type=\\\"button.default\\\">\\n\\t\\t\\t\\t<div class=\\\"elementor-widget-container\\\">\\n\\t\\t\\t\\t\\t\\t\\t\\t\\t<div class=\\\"elementor-button-wrapper\\\">\\n\\t\\t\\t\\t\\t<a class=\\\"elementor-button elementor-button-link elementor-size-sm\\\" href=\\\"#\\\">\\n\\t\\t\\t\\t\\t\\t<span class=\\\"elementor-button-content-wrapper\\\">\\n\\t\\t\\t\\t\\t\\t\\t\\t\\t<span class=\\\"elementor-button-text\\\">Book Now<\\\/span>\\n\\t\\t\\t\\t\\t<\\\/span>\\n\\t\\t\\t\\t\\t<\\\/a>\\n\\t\\t\\t\\t<\\\/div>\\n\\t\\t\\t\\t\\t\\t\\t\\t<\\\/div>\\n\\t\\t\\t\\t<\\\/div>\\n\\t\\t\\t\\t<\\\/div>\\n\\t\\t\\t\\t\\t<\\\/div>\\n\\t\\t\\t\\t<\\\/div>\\n\\t\\t\",\"scripts\":[],\"styles\":[]}}"},"astra-page-options-data":{"elementor_load_fa4_shim":""},"original_content":"<h6>Dive into Ultimate Luxury at<\/h6>\t\t\n\t\t\t<h1>The Caeser Grand<\/h1><p>Lorem ipsum dolor sit amet, consectetur adipiscing elit. Ut elit tellus, <br\/>luctus nec ullamcorper mattis, pulvinar dapibus leo.<\/p>\t\t\n\t\t\t<a href=\"#\">\n\t\t\t\t\t\t\t\t\tMake A Reservation\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<figure><img src=\"https:\/\/websitedemos.net\/luxury-hotel-04\/wp-content\/uploads\/sites\/812\/2021\/04\/carousel-11-.jpg\" alt=\"carousel-11-\" \/><\/figure><figure><img src=\"https:\/\/websitedemos.net\/luxury-hotel-04\/wp-content\/uploads\/sites\/812\/2021\/04\/carousel12-.jpg\" alt=\"carousel12-\" \/><\/figure><figure><img src=\"https:\/\/websitedemos.net\/luxury-hotel-04\/wp-content\/uploads\/sites\/812\/2021\/04\/carousel13-.jpg\" alt=\"carousel13-\" \/><\/figure><figure><img src=\"https:\/\/websitedemos.net\/luxury-hotel-04\/wp-content\/uploads\/sites\/812\/2021\/04\/carousel14-.jpg\" alt=\"carousel14-\" \/><\/figure>\t\t\t\n\t\t\t<h2>An Escape from Reality<\/h2>\t\t\n\t\tQuisque velit nisi, pretium ut lacinia in, elementum id enim. Curabitur non nulla sit amet nisl tempus convallis quis ac lectus. Lorem elit tellus, luctus nec ullamcorper mattis, pulvinar dapibus leo.\t\t\n\t\t\t<a href=\"#\">\n\t\t\t\t\t\t<\/a>\n\t\t\t<h2> Luxurious Services<\/h2>\t\t\n\t\t\t<h5>In-room Dining<\/h5>\t\t\n\t\t\t<h5>Private Pools<\/h5>\t\t\n\t\t\t<h5>Concierge Service<\/h5>\t\t\n\t\t\t<h5>VIP Casino Entries<\/h5>\t\t\n\t\t\t<h3>Every corner with a<br> Luxury Touch<\/h3>\t\t\n\t\tLorem elit tellus, luctus nec ullamcorper mattis, pulvinar dapibus leo.\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img width=\"414\" height=\"670\" src=\"https:\/\/websitedemos.net\/luxury-hotel-04\/wp-content\/uploads\/sites\/812\/2021\/04\/gallery-new-1.jpeg\" alt=\"\" srcset=\"https:\/\/websitedemos.net\/luxury-hotel-04\/wp-content\/uploads\/sites\/812\/2021\/04\/gallery-new-1.jpeg 414w, https:\/\/websitedemos.net\/luxury-hotel-04\/wp-content\/uploads\/sites\/812\/2021\/04\/gallery-new-1-185x300.jpeg 185w, https:\/\/websitedemos.net\/luxury-hotel-04\/wp-content\/uploads\/sites\/812\/2021\/04\/gallery-new-1-400x647.jpeg 400w\" sizes=\"(max-width: 414px) 100vw, 414px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img width=\"414\" height=\"360\" src=\"https:\/\/websitedemos.net\/luxury-hotel-04\/wp-content\/uploads\/sites\/812\/2021\/04\/gallery-new-7.jpeg\" alt=\"\" srcset=\"https:\/\/websitedemos.net\/luxury-hotel-04\/wp-content\/uploads\/sites\/812\/2021\/04\/gallery-new-7.jpeg 414w, https:\/\/websitedemos.net\/luxury-hotel-04\/wp-content\/uploads\/sites\/812\/2021\/04\/gallery-new-7-300x261.jpeg 300w, https:\/\/websitedemos.net\/luxury-hotel-04\/wp-content\/uploads\/sites\/812\/2021\/04\/gallery-new-7-400x348.jpeg 400w\" sizes=\"(max-width: 414px) 100vw, 414px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img width=\"591\" height=\"692\" src=\"https:\/\/websitedemos.net\/luxury-hotel-04\/wp-content\/uploads\/sites\/812\/2021\/04\/gallery-new-4.jpeg\" alt=\"\" srcset=\"https:\/\/websitedemos.net\/luxury-hotel-04\/wp-content\/uploads\/sites\/812\/2021\/04\/gallery-new-4.jpeg 591w, https:\/\/websitedemos.net\/luxury-hotel-04\/wp-content\/uploads\/sites\/812\/2021\/04\/gallery-new-4-256x300.jpeg 256w, https:\/\/websitedemos.net\/luxury-hotel-04\/wp-content\/uploads\/sites\/812\/2021\/04\/gallery-new-4-400x468.jpeg 400w\" sizes=\"(max-width: 591px) 100vw, 591px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img width=\"867\" height=\"1135\" src=\"https:\/\/websitedemos.net\/luxury-hotel-04\/wp-content\/uploads\/sites\/812\/2021\/04\/gallery-15.jpeg\" alt=\"\" srcset=\"https:\/\/websitedemos.net\/luxury-hotel-04\/wp-content\/uploads\/sites\/812\/2021\/04\/gallery-15.jpeg 867w, https:\/\/websitedemos.net\/luxury-hotel-04\/wp-content\/uploads\/sites\/812\/2021\/04\/gallery-15-229x300.jpeg 229w, https:\/\/websitedemos.net\/luxury-hotel-04\/wp-content\/uploads\/sites\/812\/2021\/04\/gallery-15-782x1024.jpeg 782w, https:\/\/websitedemos.net\/luxury-hotel-04\/wp-content\/uploads\/sites\/812\/2021\/04\/gallery-15-768x1005.jpeg 768w, https:\/\/websitedemos.net\/luxury-hotel-04\/wp-content\/uploads\/sites\/812\/2021\/04\/gallery-15-400x524.jpeg 400w\" sizes=\"(max-width: 867px) 100vw, 867px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img width=\"414\" height=\"670\" src=\"https:\/\/websitedemos.net\/luxury-hotel-04\/wp-content\/uploads\/sites\/812\/2021\/04\/gallery-new-5.jpeg\" alt=\"\" srcset=\"https:\/\/websitedemos.net\/luxury-hotel-04\/wp-content\/uploads\/sites\/812\/2021\/04\/gallery-new-5.jpeg 414w, https:\/\/websitedemos.net\/luxury-hotel-04\/wp-content\/uploads\/sites\/812\/2021\/04\/gallery-new-5-185x300.jpeg 185w, https:\/\/websitedemos.net\/luxury-hotel-04\/wp-content\/uploads\/sites\/812\/2021\/04\/gallery-new-5-400x647.jpeg 400w\" sizes=\"(max-width: 414px) 100vw, 414px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img width=\"414\" height=\"360\" src=\"https:\/\/websitedemos.net\/luxury-hotel-04\/wp-content\/uploads\/sites\/812\/2021\/04\/gallery-6.png\" alt=\"\" srcset=\"https:\/\/websitedemos.net\/luxury-hotel-04\/wp-content\/uploads\/sites\/812\/2021\/04\/gallery-6.png 414w, https:\/\/websitedemos.net\/luxury-hotel-04\/wp-content\/uploads\/sites\/812\/2021\/04\/gallery-6-300x261.png 300w, https:\/\/websitedemos.net\/luxury-hotel-04\/wp-content\/uploads\/sites\/812\/2021\/04\/gallery-6-400x348.png 400w\" sizes=\"(max-width: 414px) 100vw, 414px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t<h6>Luxury Privileges<\/h6>\t\t\n\t\t\t<h2>Membership Benefits<\/h2>\t\t\n\t\tLorem ipsum dolor sit amet, consectetur adipiscing elit. Ut elit tellus, luctus nec ullamcorper mattis, pulvinar dapibus leo.\t\t\n\t\t\t<h5>World-class Stay Benefits<\/h5>\t\t\n\t\tLorem ipsum dolor sit amet, consec tetur adipiscing. Ut elit tellus, luctus nec nullam corper, pulvinar dapibus leo.\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img width=\"300\" height=\"300\" src=\"https:\/\/websitedemos.net\/luxury-hotel-04\/wp-content\/uploads\/sites\/812\/2021\/04\/world-class1-300x300.jpg\" alt=\"\" srcset=\"https:\/\/websitedemos.net\/luxury-hotel-04\/wp-content\/uploads\/sites\/812\/2021\/04\/world-class1-300x300.jpg 300w, https:\/\/websitedemos.net\/luxury-hotel-04\/wp-content\/uploads\/sites\/812\/2021\/04\/world-class1-150x150.jpg 150w, https:\/\/websitedemos.net\/luxury-hotel-04\/wp-content\/uploads\/sites\/812\/2021\/04\/world-class1-400x400.jpg 400w, https:\/\/websitedemos.net\/luxury-hotel-04\/wp-content\/uploads\/sites\/812\/2021\/04\/world-class1.jpg 427w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img width=\"300\" height=\"300\" src=\"https:\/\/websitedemos.net\/luxury-hotel-04\/wp-content\/uploads\/sites\/812\/2021\/04\/casino-11-300x300.jpg\" alt=\"\" srcset=\"https:\/\/websitedemos.net\/luxury-hotel-04\/wp-content\/uploads\/sites\/812\/2021\/04\/casino-11-300x300.jpg 300w, https:\/\/websitedemos.net\/luxury-hotel-04\/wp-content\/uploads\/sites\/812\/2021\/04\/casino-11-150x150.jpg 150w, https:\/\/websitedemos.net\/luxury-hotel-04\/wp-content\/uploads\/sites\/812\/2021\/04\/casino-11-400x400.jpg 400w, https:\/\/websitedemos.net\/luxury-hotel-04\/wp-content\/uploads\/sites\/812\/2021\/04\/casino-11.jpg 640w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t<h5>Exclusive Casino Benefits<\/h5>\t\t\n\t\tLorem ipsum dolor sit amet, consec tetur adipiscing. Ut elit tellus, luctus nec nullam corper, pulvinar dapibus leo.\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img width=\"300\" height=\"300\" src=\"https:\/\/websitedemos.net\/luxury-hotel-04\/wp-content\/uploads\/sites\/812\/2021\/04\/350x350-3-300x300.png\" alt=\"\" srcset=\"https:\/\/websitedemos.net\/luxury-hotel-04\/wp-content\/uploads\/sites\/812\/2021\/04\/350x350-3-300x300.png 300w, https:\/\/websitedemos.net\/luxury-hotel-04\/wp-content\/uploads\/sites\/812\/2021\/04\/350x350-3-150x150.png 150w, https:\/\/websitedemos.net\/luxury-hotel-04\/wp-content\/uploads\/sites\/812\/2021\/04\/350x350-3.png 350w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t<h5>Exclusive Lifestyle Voucher<\/h5>\t\t\n\t\tLorem ipsum dolor sit amet, consec tetur adipiscing. Ut elit tellus, luctus nec nullam corper, pulvinar dapibus leo.\t\t\n\t\t\t<h5>Complementary<br> Wine Bottle <\/h5>\t\t\n\t\tLorem ipsum dolor sit amet, consec tetur adipiscing. Ut elit tellus, luctus nec nullam corper, pulvinar dapibus leo.\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img width=\"300\" height=\"300\" src=\"https:\/\/websitedemos.net\/luxury-hotel-04\/wp-content\/uploads\/sites\/812\/2021\/04\/wine-bottle-300x300.jpg\" alt=\"\" srcset=\"https:\/\/websitedemos.net\/luxury-hotel-04\/wp-content\/uploads\/sites\/812\/2021\/04\/wine-bottle-300x300.jpg 300w, https:\/\/websitedemos.net\/luxury-hotel-04\/wp-content\/uploads\/sites\/812\/2021\/04\/wine-bottle-150x150.jpg 150w, https:\/\/websitedemos.net\/luxury-hotel-04\/wp-content\/uploads\/sites\/812\/2021\/04\/wine-bottle-400x400.jpg 400w, https:\/\/websitedemos.net\/luxury-hotel-04\/wp-content\/uploads\/sites\/812\/2021\/04\/wine-bottle.jpg 640w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t<h4> More Benefits<\/h4>\t\t\n\t\tQuisque velit nisi, pretium ut lacinia in, elementum id enim. Curabitur non nulla sit amet nisl tempus convallis quis ac lectus.\t\t\n\t\t\t<a href=\"#\">\n\t\t\t\t\t\t\t\t\tBecome a Member\n\t\t\t\t\t<\/a>\n\t\t\t<h3>Ideal Venue For Any Event<\/h3>\t\t\n\t\tQuisque velit nisi, pretium ut lacinia in, elementum id enim.\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img width=\"452\" height=\"333\" src=\"https:\/\/websitedemos.net\/luxury-hotel-04\/wp-content\/uploads\/sites\/812\/2021\/04\/event-1.png\" alt=\"\" srcset=\"https:\/\/websitedemos.net\/luxury-hotel-04\/wp-content\/uploads\/sites\/812\/2021\/04\/event-1.png 452w, https:\/\/websitedemos.net\/luxury-hotel-04\/wp-content\/uploads\/sites\/812\/2021\/04\/event-1-300x221.png 300w, https:\/\/websitedemos.net\/luxury-hotel-04\/wp-content\/uploads\/sites\/812\/2021\/04\/event-1-400x295.png 400w\" sizes=\"(max-width: 452px) 100vw, 452px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t<h4>Weddings<\/h4><p>Lorem ipsum dolor sit amet, consectetur adipiscing elit. Ut elit tellus, luctus nec ullamcorper mattis, pulvinar dapibus leo.<\/p>\t\t\n\t\t\t<h4>Parties<\/h4><p>Lorem ipsum dolor sit amet, consectetur adipiscing elit. Ut elit tellus, luctus nec ullamcorper mattis, pulvinar dapibus leo.<\/p>\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img width=\"452\" height=\"333\" src=\"https:\/\/websitedemos.net\/luxury-hotel-04\/wp-content\/uploads\/sites\/812\/2021\/04\/event-2.png\" alt=\"\" srcset=\"https:\/\/websitedemos.net\/luxury-hotel-04\/wp-content\/uploads\/sites\/812\/2021\/04\/event-2.png 452w, https:\/\/websitedemos.net\/luxury-hotel-04\/wp-content\/uploads\/sites\/812\/2021\/04\/event-2-300x221.png 300w, https:\/\/websitedemos.net\/luxury-hotel-04\/wp-content\/uploads\/sites\/812\/2021\/04\/event-2-400x295.png 400w\" sizes=\"(max-width: 452px) 100vw, 452px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img width=\"452\" height=\"333\" src=\"https:\/\/websitedemos.net\/luxury-hotel-04\/wp-content\/uploads\/sites\/812\/2021\/04\/conference-1.jpg\" alt=\"\" srcset=\"https:\/\/websitedemos.net\/luxury-hotel-04\/wp-content\/uploads\/sites\/812\/2021\/04\/conference-1.jpg 452w, https:\/\/websitedemos.net\/luxury-hotel-04\/wp-content\/uploads\/sites\/812\/2021\/04\/conference-1-300x221.jpg 300w, https:\/\/websitedemos.net\/luxury-hotel-04\/wp-content\/uploads\/sites\/812\/2021\/04\/conference-1-400x295.jpg 400w\" sizes=\"(max-width: 452px) 100vw, 452px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t<h4>Conference<\/h4><p>Lorem ipsum dolor sit amet, consectetur adipiscing elit. Ut elit tellus, luctus nec ullamcorper mattis, pulvinar dapibus leo.<\/p>\t\t\n\t\t\t<h2>Your search for True Luxury ends here<\/h2>\t\t\n\t\tLorem ipsum dolor sit amet, consectetur adipiscing elit. Ut elit tellus, luctus nec ullamcorper mattis, pulvinar dapibus leo.\t\t\n\t\t\t<a href=\"#\">\n\t\t\t\t\t\t\t\t\tBook Now\n\t\t\t\t\t<\/a>","brizy_media":[],"_links":{"self":[{"href":"https:\/\/websitedemos.net\/luxury-hotel-04\/wp-json\/wp\/v2\/pages\/7","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/websitedemos.net\/luxury-hotel-04\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/websitedemos.net\/luxury-hotel-04\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/websitedemos.net\/luxury-hotel-04\/wp-json\/wp\/v2\/users\/156"}],"replies":[{"embeddable":true,"href":"https:\/\/websitedemos.net\/luxury-hotel-04\/wp-json\/wp\/v2\/comments?post=7"}],"version-history":[{"count":794,"href":"https:\/\/websitedemos.net\/luxury-hotel-04\/wp-json\/wp\/v2\/pages\/7\/revisions"}],"predecessor-version":[{"id":2551,"href":"https:\/\/websitedemos.net\/luxury-hotel-04\/wp-json\/wp\/v2\/pages\/7\/revisions\/2551"}],"wp:attachment":[{"href":"https:\/\/websitedemos.net\/luxury-hotel-04\/wp-json\/wp\/v2\/media?parent=7"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}