{"id":6,"date":"2022-10-31T09:15:37","date_gmt":"2022-10-31T09:15:37","guid":{"rendered":"https:\/\/websitedemos.net\/cake-shop-09\/?page_id=6"},"modified":"2024-08-23T05:10:34","modified_gmt":"2024-08-23T05:10:34","slug":"home","status":"publish","type":"page","link":"https:\/\/websitedemos.net\/cake-shop-07\/","title":{"rendered":"Home"},"content":{"rendered":"\n<div class=\"wp-block-uagb-container uag-blocks-common-selector uagb-block-2c66ecf5 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-container uag-blocks-common-selector uagb-block-b168e446\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-3ba1534c\"><h1 class=\"uagb-heading-text\">Cakes, Pies &amp; Tarts<\/h1><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uag-blocks-common-selector uagb-block-c9b97a85\">      \n\t\t\t<div class=\"uagb-icon-wrapper uagb-block-2a6b046d  wp-block-uagb-icon--has-margin    \"\n\t\t\tstyle=\"\" >\n\t\t\t\t\t\t\t\t<div class='uagb-icon-margin-wrapper'>\n\t\t\t\t\t\t\t\t\t<span class=\"uagb-svg-wrapper\" \n\t\t\t\t\t aria-label=\"quote-left\"\t\t\t\t\ttabindex=\"0\">\t\t\n\t\t\t\t\t\t\t\t\t\t<svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewBox= \"0 0 448 512\" role=\"graphics-symbol\" aria-hidden=\"false\" aria-label=\"\"><path d=\"M96 224C84.72 224 74.05 226.3 64 229.9V224c0-35.3 28.7-64 64-64c17.67 0 32-14.33 32-32S145.7 96 128 96C57.42 96 0 153.4 0 224v96c0 53.02 42.98 96 96 96s96-42.98 96-96S149 224 96 224zM352 224c-11.28 0-21.95 2.305-32 5.879V224c0-35.3 28.7-64 64-64c17.67 0 32-14.33 32-32s-14.33-32-32-32c-70.58 0-128 57.42-128 128v96c0 53.02 42.98 96 96 96s96-42.98 96-96S405 224 352 224z\"><\/path><\/svg>\n\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-43224597\"><p class=\"uagb-heading-text\">Lorem ipsum dolor sit amet, consectetur adipiscing elit. Ut elit tellus, luctus nec ullamcorper mattis, pulvinar dapibus leo.<\/p><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-bb758da2\"><h5 class=\"uagb-heading-text\">Susan Lee<\/h5><\/div>\n\n\n\n<div class=\"wp-block-uagb-image alignright uagb-block-98684736 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-right uag-blocks-common-selector\" style=\"--z-index-desktop:10;;--z-index-tablet:undefined;;--z-index-mobile:undefined;\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" srcset=\"https:\/\/websitedemos.net\/cake-shop-07\/wp-content\/uploads\/sites\/1134\/2022\/10\/signature-free-img.png ,https:\/\/websitedemos.net\/cake-shop-07\/wp-content\/uploads\/sites\/1134\/2022\/10\/signature-free-img-150x150.png 780w, https:\/\/websitedemos.net\/cake-shop-07\/wp-content\/uploads\/sites\/1134\/2022\/10\/signature-free-img.png 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/websitedemos.net\/cake-shop-07\/wp-content\/uploads\/sites\/1134\/2022\/10\/signature-free-img.png\" alt=\"\" class=\"uag-image-54\" width=\"185\" height=\"194\" title=\"\" loading=\"lazy\" role=\"img\"\/><\/figure><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uag-blocks-common-selector uagb-block-b4c87933\">\t\t\t\t\t<div\n\t\t\t\t\t\tclass=\"wp-block-uagb-image-gallery uagb-block-a0cd5a3e     \"\n\t\t\t\t\t\tstyle=\"\"\n\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery spectra-image-gallery__layout--carousel\">\n\t\t\t\t\t\t\t\t<div class=\"uagb-slick-carousel uagb-block-a0cd5a3e\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class='spectra-image-gallery__media-wrapper' data-spectra-gallery-image-id='62'>\n\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media spectra-image-gallery__media--carousel\">\n\t\t\t\t<picture>\n\t\t\t\t\t<source media=\"(min-width: 1024px)\" srcset=\"https:\/\/websitedemos.net\/cake-shop-07\/wp-content\/uploads\/sites\/1134\/2022\/10\/product-01-free-img.png\">\n\t\t\t\t\t<source media=\"(min-width: 768px)\" srcset=\"https:\/\/websitedemos.net\/cake-shop-07\/wp-content\/uploads\/sites\/1134\/2022\/10\/product-01-free-img.png\">\n\t\t\t\t\t<img decoding=\"async\" class=\"spectra-image-gallery__media-thumbnail spectra-image-gallery__media-thumbnail--carousel\" src=\"https:\/\/websitedemos.net\/cake-shop-07\/wp-content\/uploads\/sites\/1134\/2022\/10\/product-01-free-img.png\" alt=\"\" loading=\"lazy\" \/>\n\t\t\t\t<\/picture>\n\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-blurrer\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-caption-wrapper spectra-image-gallery__media-thumbnail-caption-wrapper--overlay\"><\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class='spectra-image-gallery__media-wrapper' data-spectra-gallery-image-id='220'>\n\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media spectra-image-gallery__media--carousel\">\n\t\t\t\t<picture>\n\t\t\t\t\t<source media=\"(min-width: 1024px)\" srcset=\"https:\/\/websitedemos.net\/cake-shop-07\/wp-content\/uploads\/sites\/1134\/2023\/04\/product-02-free-img.png\">\n\t\t\t\t\t<source media=\"(min-width: 768px)\" srcset=\"https:\/\/websitedemos.net\/cake-shop-07\/wp-content\/uploads\/sites\/1134\/2023\/04\/product-02-free-img.png\">\n\t\t\t\t\t<img decoding=\"async\" class=\"spectra-image-gallery__media-thumbnail spectra-image-gallery__media-thumbnail--carousel\" src=\"https:\/\/websitedemos.net\/cake-shop-07\/wp-content\/uploads\/sites\/1134\/2023\/04\/product-02-free-img.png\" alt=\"\" loading=\"lazy\" \/>\n\t\t\t\t<\/picture>\n\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-blurrer\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-caption-wrapper spectra-image-gallery__media-thumbnail-caption-wrapper--overlay\"><\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class='spectra-image-gallery__media-wrapper' data-spectra-gallery-image-id='221'>\n\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media spectra-image-gallery__media--carousel\">\n\t\t\t\t<picture>\n\t\t\t\t\t<source media=\"(min-width: 1024px)\" srcset=\"https:\/\/websitedemos.net\/cake-shop-07\/wp-content\/uploads\/sites\/1134\/2023\/04\/product-03-free-img.png\">\n\t\t\t\t\t<source media=\"(min-width: 768px)\" srcset=\"https:\/\/websitedemos.net\/cake-shop-07\/wp-content\/uploads\/sites\/1134\/2023\/04\/product-03-free-img.png\">\n\t\t\t\t\t<img decoding=\"async\" class=\"spectra-image-gallery__media-thumbnail spectra-image-gallery__media-thumbnail--carousel\" src=\"https:\/\/websitedemos.net\/cake-shop-07\/wp-content\/uploads\/sites\/1134\/2023\/04\/product-03-free-img.png\" alt=\"\" loading=\"lazy\" \/>\n\t\t\t\t<\/picture>\n\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-blurrer\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-caption-wrapper spectra-image-gallery__media-thumbnail-caption-wrapper--overlay\"><\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uag-blocks-common-selector uagb-block-fd9a5843 alignfull uagb-is-root-container\">\n<div class=\"wp-block-uagb-image alignleft uagb-block-5306d181 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-left uag-blocks-common-selector\" style=\"--z-index-desktop:3;;--z-index-tablet:3;;--z-index-mobile:3;\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" srcset=\"https:\/\/websitedemos.net\/cake-shop-07\/wp-content\/uploads\/sites\/1134\/2022\/10\/bg-02-free-img.jpg ,https:\/\/websitedemos.net\/cake-shop-07\/wp-content\/uploads\/sites\/1134\/2022\/10\/bg-02-free-img.jpg 780w, https:\/\/websitedemos.net\/cake-shop-07\/wp-content\/uploads\/sites\/1134\/2022\/10\/bg-02-free-img.jpg 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/websitedemos.net\/cake-shop-07\/wp-content\/uploads\/sites\/1134\/2022\/10\/bg-02-free-img.jpg\" alt=\"\" class=\"uag-image-70\" width=\"850\" height=\"620\" title=\"\" loading=\"lazy\" role=\"img\"\/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uag-blocks-common-selector uagb-block-724d4bb0\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-f7d116b2 uag-blocks-common-selector\" style=\"--z-index-desktop:undefined;;--z-index-tablet:3;;--z-index-mobile:undefined;\"><h2 class=\"uagb-heading-text\">Welcome!<\/h2><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-3e834e65\"><h5 class=\"uagb-heading-text\">Cakes with Love<\/h5><\/div>\n\n\n\n<div class=\"wp-block-uagb-info-box uagb-block-8f60856a uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><h3 class=\"uagb-ifb-title\">Ut enim ad minim veniam, quis nostrud exercitation ullamco.<\/h3><\/div><p class=\"uagb-ifb-desc\">Lorem ipsum dolor sit amet, consectetur adipisicing elit, sed do eiusmod tempor incididunt ut labore et dolore magna aliqua. Ut enim ad minim veniam, quis nostrud exercitation ullamco laboris nisi ut aliquip ex ea commodo consequat. Duis aute irure dolor in reprehenderit in voluptate velit esse cillum dolore eu fugiat nulla pariatur. Excepteur sint occaecat cupidatat non proident, sunt in culpa qui officia deserunt mollit anim id est laborum.<\/p><div class=\"uagb-ifb-button-wrapper wp-block-button\"><a href=\"#\" class=\"uagb-infobox-cta-link wp-block-button__link\" target=\"_self\" rel=\"noopener noreferrer\" onclick=\"return false;\"><span class=\"uagb-inline-editing\">Read More<\/span><\/a><\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-7ff3a404\"><h2 class=\"uagb-heading-text\">Our Cakes<\/h2><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-aace127a\"><h5 class=\"uagb-heading-text\">Cakes with Love<\/h5><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-2727fa58 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-container uag-blocks-common-selector uagb-block-5b0d9f3e\">\n<div class=\"wp-block-uagb-info-box uagb-block-bb367c1b uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-image-content\"><img decoding=\"async\" src=\"https:\/\/websitedemos.net\/cake-shop-07\/wp-content\/uploads\/sites\/1134\/2022\/10\/product-08-free-img-1.jpg\" alt=\"\" width=\"\" height=\"0\" loading=\"lazy\"\/><\/div><div class=\"uagb-ifb-title-wrap\"><h5 class=\"uagb-ifb-title-prefix\">$75<\/h5><h3 class=\"uagb-ifb-title\">Fruit Tart<\/h3><\/div><p class=\"uagb-ifb-desc\">Lorem ipsum dolor sit amet, consectetur adipiscing elit.<\/p><\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-info-box uagb-block-a3cec12e uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-image-content\"><img decoding=\"async\" src=\"https:\/\/websitedemos.net\/cake-shop-07\/wp-content\/uploads\/sites\/1134\/2022\/10\/product-06-free-img-1.jpg\" alt=\"\" width=\"\" height=\"0\" loading=\"lazy\"\/><\/div><div class=\"uagb-ifb-title-wrap\"><h5 class=\"uagb-ifb-title-prefix\">$85<\/h5><h3 class=\"uagb-ifb-title\">Strawberry Tart\u200b<\/h3><\/div><p class=\"uagb-ifb-desc\">Lorem ipsum dolor sit amet, consectetur adipiscing elit.<\/p><\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-info-box uagb-block-861651c6 uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-image-content\"><img decoding=\"async\" src=\"https:\/\/websitedemos.net\/cake-shop-07\/wp-content\/uploads\/sites\/1134\/2022\/10\/product-07-free-img-1.jpg\" alt=\"\" width=\"\" height=\"0\" loading=\"lazy\"\/><\/div><div class=\"uagb-ifb-title-wrap\"><h5 class=\"uagb-ifb-title-prefix\">$90<\/h5><h3 class=\"uagb-ifb-title\">Cherry Tart\u200b<\/h3><\/div><p class=\"uagb-ifb-desc\">Lorem ipsum dolor sit amet, consectetur adipiscing elit.<\/p><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uag-blocks-common-selector uagb-block-2ffcd874\">\n<div class=\"wp-block-uagb-info-box uagb-block-5c24b108 uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-image-content\"><img decoding=\"async\" src=\"https:\/\/websitedemos.net\/cake-shop-07\/wp-content\/uploads\/sites\/1134\/2022\/10\/product-09-free-img.jpg\" alt=\"\" width=\"\" height=\"0\" loading=\"lazy\"\/><\/div><div class=\"uagb-ifb-title-wrap\"><h5 class=\"uagb-ifb-title-prefix\">$75<\/h5><h3 class=\"uagb-ifb-title\">Fruit Tart<\/h3><\/div><p class=\"uagb-ifb-desc\">Lorem ipsum dolor sit amet, consectetur adipiscing elit.<\/p><\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-info-box uagb-block-073479f1 uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-image-content\"><img decoding=\"async\" src=\"https:\/\/websitedemos.net\/cake-shop-07\/wp-content\/uploads\/sites\/1134\/2022\/10\/product-11-free-img.jpg\" alt=\"\" width=\"\" height=\"0\" loading=\"lazy\"\/><\/div><div class=\"uagb-ifb-title-wrap\"><h5 class=\"uagb-ifb-title-prefix\">$80<\/h5><h3 class=\"uagb-ifb-title\">Chocolate Cake\u200b<\/h3><\/div><p class=\"uagb-ifb-desc\">Lorem ipsum dolor sit amet, consectetur adipiscing elit.<\/p><\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-info-box uagb-block-d6915861 uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-image-content\"><img decoding=\"async\" src=\"https:\/\/websitedemos.net\/cake-shop-07\/wp-content\/uploads\/sites\/1134\/2022\/10\/product-12-free-img.jpg\" alt=\"\" width=\"\" height=\"0\" loading=\"lazy\"\/><\/div><div class=\"uagb-ifb-title-wrap\"><h5 class=\"uagb-ifb-title-prefix\">$85<\/h5><h3 class=\"uagb-ifb-title\">Biscuit Cake\u200b<\/h3><\/div><p class=\"uagb-ifb-desc\">Lorem ipsum dolor sit amet, consectetur adipiscing elit.<\/p><\/div><\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-76587460 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-image aligncenter uagb-block-33a302d6 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-center\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" srcset=\"https:\/\/websitedemos.net\/cake-shop-09\/wp-content\/uploads\/sites\/1134\/2022\/10\/testimonial-08-free-img-1.jpg \" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/websitedemos.net\/cake-shop-09\/wp-content\/uploads\/sites\/1134\/2022\/10\/testimonial-08-free-img-1.jpg\" alt=\"\" class=\"uag-image-100\" width=\"100\" height=\"100\" title=\"\" loading=\"lazy\" role=\"img\"\/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-0bf22f7e\"><h5 class=\"uagb-heading-text\">Maria Harris<\/h5><\/div>\n\n\n\n<div class=\"wp-block-uagb-image aligncenter uagb-block-1ee7b860 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-center\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" srcset=\"https:\/\/websitedemos.net\/cake-shop-09\/wp-content\/uploads\/sites\/1134\/2022\/10\/quote-right.png \" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/websitedemos.net\/cake-shop-09\/wp-content\/uploads\/sites\/1134\/2022\/10\/quote-right.png\" alt=\"\" class=\"uag-image-101\" width=\"20\" height=\"20\" title=\"\" loading=\"lazy\" role=\"img\"\/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-60dc4972\"><p class=\"uagb-heading-text\">\u201cI just wanted to say thank you for our lorem it looked and tasted amazing consectetur adipiscing elit.  Ut elit tellus, everyone loved the theme.\u201d<\/p><\/div>\n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Cakes, Pies &amp; Tarts Lorem ipsum dolor sit amet, consectetur adipiscing elit. Ut elit tellus, luctus nec ullamcorper mattis, pulvinar dapibus leo. Susan Lee Welcome! Cakes with Love Our Cakes Cakes with Love Maria Harris \u201cI just wanted to say thank you for our lorem it looked and tasted amazing consectetur adipiscing elit. Ut elit [&hellip;]<\/p>\n","protected":false},"author":156,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"enabled","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-6","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Home - Cake Shop<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/websitedemos.net\/cake-shop-07\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Home - Cake Shop\" \/>\n<meta property=\"og:description\" content=\"Cakes, Pies &amp; Tarts Lorem ipsum dolor sit amet, consectetur adipiscing elit. Ut elit tellus, luctus nec ullamcorper mattis, pulvinar dapibus leo. Susan Lee Welcome! Cakes with Love Our Cakes Cakes with Love Maria Harris \u201cI just wanted to say thank you for our lorem it looked and tasted amazing consectetur adipiscing elit. Ut elit [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/websitedemos.net\/cake-shop-07\/\" \/>\n<meta property=\"og:site_name\" content=\"Cake Shop\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-23T05:10:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/websitedemos.net\/cake-shop-07\/wp-content\/uploads\/sites\/1134\/2022\/10\/signature-free-img.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/websitedemos.net\\\/cake-shop-07\\\/\",\"url\":\"https:\\\/\\\/websitedemos.net\\\/cake-shop-07\\\/\",\"name\":\"Home - Cake Shop\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/websitedemos.net\\\/cake-shop-07\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/websitedemos.net\\\/cake-shop-07\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/websitedemos.net\\\/cake-shop-07\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/websitedemos.net\\\/cake-shop-07\\\/wp-content\\\/uploads\\\/sites\\\/1134\\\/2022\\\/10\\\/signature-free-img.png\",\"datePublished\":\"2022-10-31T09:15:37+00:00\",\"dateModified\":\"2024-08-23T05:10:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/websitedemos.net\\\/cake-shop-07\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/websitedemos.net\\\/cake-shop-07\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/websitedemos.net\\\/cake-shop-07\\\/#primaryimage\",\"url\":\"https:\\\/\\\/websitedemos.net\\\/cake-shop-07\\\/wp-content\\\/uploads\\\/sites\\\/1134\\\/2022\\\/10\\\/signature-free-img.png\",\"contentUrl\":\"https:\\\/\\\/websitedemos.net\\\/cake-shop-07\\\/wp-content\\\/uploads\\\/sites\\\/1134\\\/2022\\\/10\\\/signature-free-img.png\",\"width\":185,\"height\":194},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/websitedemos.net\\\/cake-shop-07\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/websitedemos.net\\\/cake-shop-07\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Home\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/websitedemos.net\\\/cake-shop-07\\\/#website\",\"url\":\"https:\\\/\\\/websitedemos.net\\\/cake-shop-07\\\/\",\"name\":\"Cake Shop\",\"description\":\"Just another Astra Starter Templates site\",\"publisher\":{\"@id\":\"https:\\\/\\\/websitedemos.net\\\/cake-shop-07\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/websitedemos.net\\\/cake-shop-07\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/websitedemos.net\\\/cake-shop-07\\\/#organization\",\"name\":\"Cake Shop\",\"url\":\"https:\\\/\\\/websitedemos.net\\\/cake-shop-07\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/websitedemos.net\\\/cake-shop-07\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/websitedemos.net\\\/cake-shop-07\\\/wp-content\\\/uploads\\\/sites\\\/1134\\\/2022\\\/10\\\/logo-regular-free-img.png\",\"contentUrl\":\"https:\\\/\\\/websitedemos.net\\\/cake-shop-07\\\/wp-content\\\/uploads\\\/sites\\\/1134\\\/2022\\\/10\\\/logo-regular-free-img.png\",\"width\":211,\"height\":93,\"caption\":\"Cake Shop\"},\"image\":{\"@id\":\"https:\\\/\\\/websitedemos.net\\\/cake-shop-07\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Home - Cake Shop","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/websitedemos.net\/cake-shop-07\/","og_locale":"en_US","og_type":"article","og_title":"Home - Cake Shop","og_description":"Cakes, Pies &amp; Tarts Lorem ipsum dolor sit amet, consectetur adipiscing elit. Ut elit tellus, luctus nec ullamcorper mattis, pulvinar dapibus leo. Susan Lee Welcome! Cakes with Love Our Cakes Cakes with Love Maria Harris \u201cI just wanted to say thank you for our lorem it looked and tasted amazing consectetur adipiscing elit. Ut elit [&hellip;]","og_url":"https:\/\/websitedemos.net\/cake-shop-07\/","og_site_name":"Cake Shop","article_modified_time":"2024-08-23T05:10:34+00:00","og_image":[{"url":"https:\/\/websitedemos.net\/cake-shop-07\/wp-content\/uploads\/sites\/1134\/2022\/10\/signature-free-img.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/websitedemos.net\/cake-shop-07\/","url":"https:\/\/websitedemos.net\/cake-shop-07\/","name":"Home - Cake Shop","isPartOf":{"@id":"https:\/\/websitedemos.net\/cake-shop-07\/#website"},"primaryImageOfPage":{"@id":"https:\/\/websitedemos.net\/cake-shop-07\/#primaryimage"},"image":{"@id":"https:\/\/websitedemos.net\/cake-shop-07\/#primaryimage"},"thumbnailUrl":"https:\/\/websitedemos.net\/cake-shop-07\/wp-content\/uploads\/sites\/1134\/2022\/10\/signature-free-img.png","datePublished":"2022-10-31T09:15:37+00:00","dateModified":"2024-08-23T05:10:34+00:00","breadcrumb":{"@id":"https:\/\/websitedemos.net\/cake-shop-07\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/websitedemos.net\/cake-shop-07\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/websitedemos.net\/cake-shop-07\/#primaryimage","url":"https:\/\/websitedemos.net\/cake-shop-07\/wp-content\/uploads\/sites\/1134\/2022\/10\/signature-free-img.png","contentUrl":"https:\/\/websitedemos.net\/cake-shop-07\/wp-content\/uploads\/sites\/1134\/2022\/10\/signature-free-img.png","width":185,"height":194},{"@type":"BreadcrumbList","@id":"https:\/\/websitedemos.net\/cake-shop-07\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/websitedemos.net\/cake-shop-07\/"},{"@type":"ListItem","position":2,"name":"Home"}]},{"@type":"WebSite","@id":"https:\/\/websitedemos.net\/cake-shop-07\/#website","url":"https:\/\/websitedemos.net\/cake-shop-07\/","name":"Cake Shop","description":"Just another Astra Starter Templates site","publisher":{"@id":"https:\/\/websitedemos.net\/cake-shop-07\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/websitedemos.net\/cake-shop-07\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/websitedemos.net\/cake-shop-07\/#organization","name":"Cake Shop","url":"https:\/\/websitedemos.net\/cake-shop-07\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/websitedemos.net\/cake-shop-07\/#\/schema\/logo\/image\/","url":"https:\/\/websitedemos.net\/cake-shop-07\/wp-content\/uploads\/sites\/1134\/2022\/10\/logo-regular-free-img.png","contentUrl":"https:\/\/websitedemos.net\/cake-shop-07\/wp-content\/uploads\/sites\/1134\/2022\/10\/logo-regular-free-img.png","width":211,"height":93,"caption":"Cake Shop"},"image":{"@id":"https:\/\/websitedemos.net\/cake-shop-07\/#\/schema\/logo\/image\/"}}]}},"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"astra-sites-grid-thumbnail":false,"astra-sites-fullpage-grid-thumbnail":false},"uagb_author_info":{"display_name":"ninoslavz","author_link":"https:\/\/websitedemos.net\/cake-shop-07\/author\/ninoslavz\/"},"uagb_comment_info":0,"uagb_excerpt":"Cakes, Pies &amp; Tarts Lorem ipsum dolor sit amet, consectetur adipiscing elit. Ut elit tellus, luctus nec ullamcorper mattis, pulvinar dapibus leo. Susan Lee Welcome! Cakes with Love Our Cakes Cakes with Love Maria Harris \u201cI just wanted to say thank you for our lorem it looked and tasted amazing consectetur adipiscing elit. Ut elit&hellip;","post-meta":{"site-post-title":"disabled","theme-transparent-header-meta":"enabled","adv-header-id-meta":"","stick-header-meta":"","_yoast_wpseo_estimated-reading-time-minutes":"3","_yoast_wpseo_wordproof_timestamp":"","_yoast_wpseo_content_score":"90","_uag_custom_page_level_css":"","ast-site-content-layout":"default","astra-migrate-meta-layouts":"set","footnotes":"","astra-main-page-id":"87075","ast_self_id_87075":"1","skip_page":"","dynamic_page":"","_uag_page_assets":"a:9:{s:3:\"css\";s:174211:\".wp-block-uagb-container{display:flex;position:relative;box-sizing:border-box;transition-property:box-shadow;transition-duration:0.2s;transition-timing-function:ease}.wp-block-uagb-container .spectra-container-link-overlay{bottom:0;left:0;position:absolute;right:0;top:0;z-index:10}.wp-block-uagb-container.uagb-is-root-container{margin-left:auto;margin-right:auto}.wp-block-uagb-container.alignfull.uagb-is-root-container .uagb-container-inner-blocks-wrap{display:flex;position:relative;box-sizing:border-box;margin-left:auto !important;margin-right:auto !important}.wp-block-uagb-container .wp-block-uagb-blockquote,.wp-block-uagb-container .wp-block-spectra-pro-login,.wp-block-uagb-container .wp-block-spectra-pro-register{margin:unset}.wp-block-uagb-container .uagb-container__video-wrap{height:100%;width:100%;top:0;left:0;position:absolute;overflow:hidden;-webkit-transition:opacity 1s;-o-transition:opacity 1s;transition:opacity 1s}.wp-block-uagb-container .uagb-container__video-wrap video{max-width:100%;width:100%;height:100%;margin:0;line-height:1;border:none;display:inline-block;vertical-align:baseline;-o-object-fit:cover;object-fit:cover;background-size:cover}.wp-block-uagb-container.uagb-layout-grid{display:grid;width:100%}.wp-block-uagb-container.uagb-layout-grid>.uagb-container-inner-blocks-wrap{display:inherit;width:inherit}.wp-block-uagb-container.uagb-layout-grid>.uagb-container-inner-blocks-wrap>.wp-block-uagb-container{max-width:unset !important;width:unset !important}.wp-block-uagb-container.uagb-layout-grid>.wp-block-uagb-container{max-width:unset !important;width:unset !important}.wp-block-uagb-container.uagb-layout-grid.uagb-is-root-container{margin-left:auto;margin-right:auto}.wp-block-uagb-container.uagb-layout-grid.uagb-is-root-container>.wp-block-uagb-container{max-width:unset !important;width:unset !important}.wp-block-uagb-container.uagb-layout-grid.alignwide.uagb-is-root-container{margin-left:auto;margin-right:auto}.wp-block-uagb-container.uagb-layout-grid.alignfull.uagb-is-root-container .uagb-container-inner-blocks-wrap{display:inherit;position:relative;box-sizing:border-box;margin-left:auto !important;margin-right:auto !important}body .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>*:not(.wp-block-uagb-container):not(.wp-block-uagb-column):not(.wp-block-uagb-container):not(.wp-block-uagb-section):not(.uagb-container__shape):not(.uagb-container__video-wrap):not(.wp-block-spectra-pro-register):not(.wp-block-spectra-pro-login):not(.uagb-slider-container):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-info-box),body .wp-block-uagb-container>.uagb-container-inner-blocks-wrap,body .wp-block-uagb-container>*:not(.wp-block-uagb-container):not(.wp-block-uagb-column):not(.wp-block-uagb-container):not(.wp-block-uagb-section):not(.uagb-container__shape):not(.uagb-container__video-wrap):not(.wp-block-spectra-pro-register):not(.wp-block-spectra-pro-login):not(.uagb-slider-container):not(.spectra-container-link-overlay):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-lottie):not(.uagb-faq__outer-wrap){min-width:unset !important;width:100%;position:relative}body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>.wp-block-uagb-container>ul,body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>.wp-block-uagb-container ol,body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>ul,body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap ol{max-width:-webkit-fill-available;margin-block-start:0;margin-block-end:0;margin-left:20px}.ast-plain-container .editor-styles-wrapper .block-editor-block-list__layout.is-root-container .uagb-is-root-container.wp-block-uagb-container.alignwide{margin-left:auto;margin-right:auto}.uagb-container__shape{overflow:hidden;position:absolute;left:0;width:100%;line-height:0;direction:ltr}.uagb-container__shape-top{top:-3px}.uagb-container__shape-bottom{bottom:-3px}.uagb-container__shape.uagb-container__invert.uagb-container__shape-bottom,.uagb-container__shape.uagb-container__invert.uagb-container__shape-top{-webkit-transform:rotate(180deg);-ms-transform:rotate(180deg);transform:rotate(180deg)}.uagb-container__shape.uagb-container__shape-flip svg{transform:translateX(-50%) rotateY(180deg)}.uagb-container__shape svg{display:block;width:-webkit-calc(100% + 1.3px);width:calc(100% + 1.3px);position:relative;left:50%;-webkit-transform:translateX(-50%);-ms-transform:translateX(-50%);transform:translateX(-50%)}.uagb-container__shape .uagb-container__shape-fill{-webkit-transform-origin:center;-ms-transform-origin:center;transform-origin:center;-webkit-transform:rotateY(0deg);transform:rotateY(0deg)}.uagb-container__shape.uagb-container__shape-above-content{z-index:9;pointer-events:none}.nv-single-page-wrap .nv-content-wrap.entry-content .wp-block-uagb-container.alignfull{margin-left:calc(50% - 50vw);margin-right:calc(50% - 50vw)}@media only screen and (max-width: 767px){.wp-block-uagb-container .wp-block-uagb-advanced-heading{width:-webkit-fill-available}}.wp-block-uagb-image--align-none{justify-content:center}\n.wp-block-uagb-advanced-heading h1,.wp-block-uagb-advanced-heading h2,.wp-block-uagb-advanced-heading h3,.wp-block-uagb-advanced-heading h4,.wp-block-uagb-advanced-heading h5,.wp-block-uagb-advanced-heading h6,.wp-block-uagb-advanced-heading p,.wp-block-uagb-advanced-heading div{word-break:break-word}.wp-block-uagb-advanced-heading .uagb-heading-text{margin:0}.wp-block-uagb-advanced-heading .uagb-desc-text{margin:0}.wp-block-uagb-advanced-heading .uagb-separator{font-size:0;border-top-style:solid;display:inline-block;margin:0 0 10px 0}.wp-block-uagb-advanced-heading .uagb-highlight{color:#f78a0c;border:0;transition:all 0.3s ease}.uag-highlight-toolbar{border-left:0;border-top:0;border-bottom:0;border-radius:0;border-right-color:#1e1e1e}.uag-highlight-toolbar .components-button{border-radius:0;outline:none}.uag-highlight-toolbar .components-button.is-primary{color:#fff}\n.wp-block-uagb-icon svg{width:30px}.uagb-icon-wrapper .uagb-svg-wrapper{transition:box-shadow 0.2s ease}\n.wp-block-uagb-image{display:flex}.wp-block-uagb-image__figure{position:relative;display:flex;flex-direction:column;max-width:100%;height:auto;margin:0}.wp-block-uagb-image__figure img{height:auto;display:flex;max-width:100%;transition:box-shadow 0.2s ease}.wp-block-uagb-image__figure>a{display:inline-block}.wp-block-uagb-image__figure figcaption{text-align:center;margin-top:0.5em;margin-bottom:1em}.wp-block-uagb-image .components-placeholder.block-editor-media-placeholder .components-placeholder__instructions{align-self:center}.wp-block-uagb-image--align-left{text-align:left}.wp-block-uagb-image--align-right{text-align:right}.wp-block-uagb-image--align-center{text-align:center}.wp-block-uagb-image--align-full .wp-block-uagb-image__figure{margin-left:calc(50% - 50vw);margin-right:calc(50% - 50vw);max-width:100vw;width:100vw;height:auto}.wp-block-uagb-image--align-full .wp-block-uagb-image__figure img{height:auto;width:100% !important}.wp-block-uagb-image--align-wide .wp-block-uagb-image__figure img{height:auto;width:100%}.wp-block-uagb-image--layout-overlay__color-wrapper{position:absolute;left:0;top:0;right:0;bottom:0;opacity:0.2;background:rgba(0,0,0,0.5);transition:opacity 0.35s ease-in-out}.wp-block-uagb-image--layout-overlay-link{position:absolute;left:0;right:0;bottom:0;top:0}.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity:1}.wp-block-uagb-image--layout-overlay__inner{position:absolute;left:15px;right:15px;bottom:15px;top:15px;display:flex;align-items:center;justify-content:center;flex-direction:column;border-color:#fff;transition:0.35s ease-in-out}.wp-block-uagb-image--layout-overlay__inner.top-left,.wp-block-uagb-image--layout-overlay__inner.top-center,.wp-block-uagb-image--layout-overlay__inner.top-right{justify-content:flex-start}.wp-block-uagb-image--layout-overlay__inner.bottom-left,.wp-block-uagb-image--layout-overlay__inner.bottom-center,.wp-block-uagb-image--layout-overlay__inner.bottom-right{justify-content:flex-end}.wp-block-uagb-image--layout-overlay__inner.top-left,.wp-block-uagb-image--layout-overlay__inner.center-left,.wp-block-uagb-image--layout-overlay__inner.bottom-left{align-items:flex-start}.wp-block-uagb-image--layout-overlay__inner.top-right,.wp-block-uagb-image--layout-overlay__inner.center-right,.wp-block-uagb-image--layout-overlay__inner.bottom-right{align-items:flex-end}.wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{color:#fff;transition:transform 0.35s, opacity 0.35s ease-in-out;transform:translate3d(0, 24px, 0);margin:0;line-height:1em}.wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width:30%;border-top-width:2px;border-top-color:#fff;border-top-style:solid;margin-bottom:10px;opacity:0;transition:transform 0.4s, opacity 0.4s ease-in-out;transform:translate3d(0, 30px, 0)}.wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity:0;overflow:visible;color:#fff;transition:transform 0.45s, opacity 0.45s ease-in-out;transform:translate3d(0, 35px, 0)}.wp-block-uagb-image--layout-overlay__inner:hover .uagb-image-heading,.wp-block-uagb-image--layout-overlay__inner:hover .uagb-image-separator,.wp-block-uagb-image--layout-overlay__inner:hover .uagb-image-caption{opacity:1;transform:translate3d(0, 0, 0)}.wp-block-uagb-image--effect-zoomin .wp-block-uagb-image__figure img,.wp-block-uagb-image--effect-zoomin .wp-block-uagb-image__figure .wp-block-uagb-image--layout-overlay__color-wrapper{transform:scale(1);transition:transform 0.35s ease-in-out}.wp-block-uagb-image--effect-zoomin .wp-block-uagb-image__figure:hover img,.wp-block-uagb-image--effect-zoomin .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{transform:scale(1.05)}.wp-block-uagb-image--effect-slide .wp-block-uagb-image__figure img,.wp-block-uagb-image--effect-slide .wp-block-uagb-image__figure .wp-block-uagb-image--layout-overlay__color-wrapper{width:calc(100% + 40px) !important;max-width:none !important;transform:translate3d(-40px, 0, 0);transition:transform 0.35s ease-in-out}.wp-block-uagb-image--effect-slide .wp-block-uagb-image__figure:hover img,.wp-block-uagb-image--effect-slide .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{transform:translate3d(0, 0, 0)}.wp-block-uagb-image--effect-grayscale img{filter:grayscale(0%);transition:0.35s ease-in-out}.wp-block-uagb-image--effect-grayscale:hover img{filter:grayscale(100%)}.wp-block-uagb-image--effect-blur img{filter:blur(0);transition:0.35s ease-in-out}.wp-block-uagb-image--effect-blur:hover img{filter:blur(3px)}\n\ufeff.wp-block-uagb-image-gallery{display:-ms-flex;display:-moz-flex;display:-webkit-flex;display:flex;-webkit-justify-content:center;justify-content:center;flex-direction:column}.spectra-image-gallery *{box-sizing:border-box}.spectra-image-gallery__layout--grid{display:-moz-grid;display:-ms-grid;display:grid;grid-template-columns:repeat(3, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-1{grid-template-columns:repeat(1, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-2{grid-template-columns:repeat(2, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-3{grid-template-columns:repeat(3, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-4{grid-template-columns:repeat(4, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-5{grid-template-columns:repeat(5, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-6{grid-template-columns:repeat(6, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-7{grid-template-columns:repeat(7, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-8{grid-template-columns:repeat(8, minmax(0, 1fr))}.spectra-image-gallery__layout--grid+.spectra-image-gallery__control-wrapper .spectra-image-gallery__control-arrows:hover{transform:scale(1.5);background-color:transparent}.spectra-image-gallery__layout--isogrid-col-1 .spectra-image-gallery__media-wrapper--isotope{width:100%}.spectra-image-gallery__layout--isogrid-col-2 .spectra-image-gallery__media-wrapper--isotope{width:50%}.spectra-image-gallery__layout--isogrid-col-3 .spectra-image-gallery__media-wrapper--isotope{width:33.33%}.spectra-image-gallery__layout--isogrid-col-4 .spectra-image-gallery__media-wrapper--isotope{width:25%}.spectra-image-gallery__layout--isogrid-col-5 .spectra-image-gallery__media-wrapper--isotope{width:20%}.spectra-image-gallery__layout--isogrid-col-6 .spectra-image-gallery__media-wrapper--isotope{width:16.66%}.spectra-image-gallery__layout--isogrid-col-7 .spectra-image-gallery__media-wrapper--isotope{width:14.28%}.spectra-image-gallery__layout--isogrid-col-8 .spectra-image-gallery__media-wrapper--isotope{width:12.5%}.spectra-image-gallery__layout--isogrid+.spectra-image-gallery__control-wrapper .spectra-image-gallery__control-arrows:hover{transform:scale(1.5);background-color:transparent}.spectra-image-gallery__layout--masonry-col-1 .spectra-image-gallery__media-wrapper--isotope{width:100%}.spectra-image-gallery__layout--masonry-col-2 .spectra-image-gallery__media-wrapper--isotope{width:50%}.spectra-image-gallery__layout--masonry-col-3 .spectra-image-gallery__media-wrapper--isotope{width:33.33%}.spectra-image-gallery__layout--masonry-col-4 .spectra-image-gallery__media-wrapper--isotope{width:25%}.spectra-image-gallery__layout--masonry-col-5 .spectra-image-gallery__media-wrapper--isotope{width:20%}.spectra-image-gallery__layout--masonry-col-6 .spectra-image-gallery__media-wrapper--isotope{width:16.66%}.spectra-image-gallery__layout--masonry-col-7 .spectra-image-gallery__media-wrapper--isotope{width:14.28%}.spectra-image-gallery__layout--masonry-col-8 .spectra-image-gallery__media-wrapper--isotope{width:12.5%}.spectra-image-gallery__layout--carousel{width:100%}.spectra-image-gallery__layout--carousel .slick-initialized{visibility:visible}.spectra-image-gallery__layout--carousel .slick-track{display:flex;align-items:center}.spectra-image-gallery__layout--carousel .slick-dots{padding:0;position:relative !important}.spectra-image-gallery__layout--carousel .slick-dots li button{padding:0}.spectra-image-gallery__layout--carousel .uagb-slick-carousel{padding:0}.spectra-image-gallery__layout--tiled{position:relative;display:grid;grid-auto-flow:dense;min-height:0;min-width:0}.spectra-image-gallery__layout--tiled-col-1{grid-template-columns:repeat(1, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-2{grid-template-columns:repeat(2, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-2 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-2 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-2 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-2 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}.spectra-image-gallery__layout--tiled-col-3{grid-template-columns:repeat(3, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-3 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-3 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-3 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-3 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}.spectra-image-gallery__layout--tiled-col-4{grid-template-columns:repeat(4, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-4 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-4 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-4 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-4 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}.spectra-image-gallery__layout--tiled-col-5{grid-template-columns:repeat(5, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-5 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-5 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-5 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-5 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}.spectra-image-gallery__layout--tiled-col-6{grid-template-columns:repeat(6, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-6 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-6 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-6 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-6 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}.spectra-image-gallery__layout--tiled-col-7{grid-template-columns:repeat(7, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-7 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-7 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-7 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-7 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}.spectra-image-gallery__layout--tiled-col-8{grid-template-columns:repeat(8, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-8 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-8 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-8 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-8 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}.spectra-image-gallery__media{position:relative;overflow:hidden;-webkit-transition:box-shadow 0.25s;-moz-transition:box-shadow 0.25s;-o-transition:box-shadow 0.25s;transition:box-shadow 0.25s}.spectra-image-gallery__media--flagged{cursor:not-allowed}.spectra-image-gallery__media--clickable{cursor:pointer}.spectra-image-gallery__media--grid{aspect-ratio:1}.spectra-image-gallery__media--masonry{width:100%}.spectra-image-gallery__media--carousel{width:100%}.spectra-image-gallery__media--tiled{aspect-ratio:1;display:flex;align-items:center;justify-content:center}.spectra-image-gallery__media--tiled-wide,.spectra-image-gallery__media--tiled-tall{aspect-ratio:unset;width:100%;height:100%}.spectra-image-gallery__media--tiled picture{width:100%;height:100%}.spectra-image-gallery__media-sizer{aspect-ratio:1}.spectra-image-gallery__media-wrapper{position:relative}.spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__control-focus{opacity:0.25}.spectra-image-gallery__media-thumbnail{vertical-align:middle;-webkit-transition:filter 0.5s, transform 0.5s;-moz-transition:filter 0.5s, transform 0.5s;-o-transition:filter 0.5s, transform 0.5s;transition:filter 0.5s, transform 0.5s}.spectra-image-gallery__media-thumbnail--grid{width:100% !important;height:100% !important;-o-object-fit:cover;object-fit:cover}.spectra-image-gallery__media-thumbnail--masonry{width:100%}.spectra-image-gallery__media-thumbnail--carousel{width:100%}.spectra-image-gallery__media-thumbnail--tiled{width:100% !important;height:100% !important;-o-object-fit:cover;object-fit:cover}.spectra-image-gallery__media-thumbnail-blurrer{position:absolute;top:0;left:0;width:100% !important;height:100% !important;-webkit-transition:box-shadow 0.25s, -webkit-backdrop-filter 0.5s;-moz-transition:box-shadow 0.25s, backdrop-filter 0.5s;-o-transition:box-shadow 0.25s, backdrop-filter 0.5s;transition:box-shadow 0.25s, backdrop-filter 0.5s}.spectra-image-gallery__media-thumbnail-caption{-webkit-transition-property:color, background-color, border-color;-moz-transition-property:color, background-color, border-color;-o-transition-property:color, background-color, border-color;transition-property:color, background-color, border-color;-webkit-transition-duration:0.25s;-moz-transition-duration:0.25s;-o-transition-duration:0.25s;transition-duration:0.25s}.spectra-image-gallery__media-thumbnail-caption--overlay{display:-ms-flex;display:-moz-flex;display:-webkit-flex;display:flex;width:100%;height:100%;overflow:hidden;padding:1em}.spectra-image-gallery__media-thumbnail-caption--bar-inside{width:100%;overflow:hidden;padding:1em;max-height:90%}.spectra-image-gallery__media-thumbnail-caption--bar-outside{width:100%;overflow:hidden;padding:1em}.spectra-image-gallery__media-thumbnail-caption-wrapper{-webkit-transition:background-color 0.25s;-moz-transition:background-color 0.25s;-o-transition:background-color 0.25s;transition:background-color 0.25s}.spectra-image-gallery__media-thumbnail-caption-wrapper--overlay{position:absolute;top:0;left:0;width:100%;height:100%}.spectra-image-gallery__media-thumbnail-caption-wrapper--bar-inside{position:absolute;top:0;left:0;width:100%;height:100%;display:flex;overflow:hidden}.spectra-image-gallery__media-thumbnail-caption-wrapper--bar-outside{position:relative;width:100%;overflow:hidden}.spectra-image-gallery__control-wrapper{display:-ms-flex;display:-moz-flex;display:-webkit-flex;display:flex;width:100%;justify-content:center}.spectra-image-gallery__control-arrows{display:-ms-flex;display:-moz-flex;display:-webkit-flex;display:flex;align-items:center;background-color:transparent;padding:0;cursor:pointer;-webkit-transition-duration:0.25s;-moz-transition-duration:0.25s;-o-transition-duration:0.25s;transition-duration:0.25s}.spectra-image-gallery__control-arrows:disabled{opacity:0.25;cursor:initial}.spectra-image-gallery__control-arrows:focus{background-color:transparent}.spectra-image-gallery__control-arrows--grid{border:none}.spectra-image-gallery__control-arrows svg{-webkit-transition-duration:0.25s;-moz-transition-duration:0.25s;-o-transition-duration:0.25s;transition-duration:0.25s}.spectra-image-gallery__control-dots{display:-ms-flex;display:-moz-flex;display:-webkit-flex;display:flex;align-items:center;padding:0 !important;margin:0 !important}.spectra-image-gallery__control-dots li{position:relative;display:inline-block;width:20px;height:20px;margin:0;padding:0;cursor:pointer;-webkit-transition-duration:0.25s;-moz-transition-duration:0.25s;-o-transition-duration:0.25s;transition-duration:0.25s}.spectra-image-gallery__control-dots li:hover{transform:scale(1.5);background-color:transparent}.spectra-image-gallery__control-dots li button{font-size:0;line-height:0;display:block;box-sizing:border-box;width:20px;height:20px;padding:5px;cursor:pointer;color:transparent;border:0;outline:none;background:transparent;-webkit-transition-duration:0.25s;-moz-transition-duration:0.25s;-o-transition-duration:0.25s;transition-duration:0.25s}.spectra-image-gallery__control-dots li button::before{font-family:none;font-size:30px;line-height:20px;position:absolute;top:0;left:0;width:20px;height:20px;content:\"\u2022\";text-align:center;opacity:0.25;-webkit-font-smoothing:antialiased;-moz-osx-font-smoothing:grayscale;-webkit-transition-duration:0.25s;-moz-transition-duration:0.25s;-o-transition-duration:0.25s;transition-duration:0.25s}.spectra-image-gallery__control-dots li.spectra-image-gallery__control-dot--active button::before{opacity:0.75}.spectra-image-gallery__control-loader{margin:0 auto;min-height:58px;line-height:58px;width:160px;text-align:center}.spectra-image-gallery__control-loader div{border-radius:100%;display:inline-block;-webkit-animation:sk-bouncedelay 1.4s infinite ease-in-out both;animation:sk-bouncedelay 1.4s infinite ease-in-out both}.spectra-image-gallery__control-loader div.spectra-image-gallery__control-loader--1{-webkit-animation-delay:-0.32s;animation-delay:-0.32s}.spectra-image-gallery__control-loader div.spectra-image-gallery__control-loader--2{-webkit-animation-delay:-0.16s;animation-delay:-0.16s}.spectra-image-gallery__control-button{cursor:pointer;-webkit-transition-duration:0.25s;-moz-transition-duration:0.25s;-o-transition-duration:0.25s;transition-duration:0.25s}.spectra-image-gallery__control-button.disabled{opacity:0.25;pointer-events:none}.spectra-image-gallery__control-focus{cursor:pointer;position:absolute;box-sizing:content-box !important;top:0;right:0;width:1.5em;height:1.5em;padding:0.5em;background-color:transparent;border:none;opacity:0;-webkit-transition-property:opacity;-moz-transition-property:opacity;-o-transition-property:opacity;transition-property:opacity;-webkit-transition-duration:0.25s;-moz-transition-duration:0.25s;-o-transition-duration:0.25s;transition-duration:0.25s}.spectra-image-gallery__control-focus:hover{opacity:1 !important}.spectra-image-gallery__control-focus svg{fill:#fff;filter:drop-shadow(1px 1px 1px rgba(0,0,0,0.5))}.spectra-image-gallery__control-lightbox{position:fixed;top:0;left:0;width:100vw !important;max-width:100vw !important;height:100vh !important;max-height:100vh !important;display:flex;flex-direction:column;opacity:0;-webkit-transition-property:opacity;-moz-transition-property:opacity;-o-transition-property:opacity;transition-property:opacity;z-index:999999999 !important;outline:none;margin-block-start:0;-webkit-transition-duration:0.25s;-moz-transition-duration:0.25s;-o-transition-duration:0.25s;transition-duration:0.25s}.spectra-image-gallery__control-lightbox--main{width:100%;flex:1}.spectra-image-gallery__control-lightbox--main .swiper-slide{height:100%;display:flex;flex-direction:column;align-items:center;justify-content:center}.spectra-image-gallery__control-lightbox--main .swiper-slide img{display:block;max-height:70%;max-width:80%}.spectra-image-gallery__control-lightbox--caption{position:absolute;bottom:0;left:0;width:100%;display:flex;align-items:center;justify-content:center;text-align:center}.spectra-image-gallery__control-lightbox--editor-link{-webkit-transition-property:color;-moz-transition-property:color;-o-transition-property:color;transition-property:color;-webkit-transition-duration:0.25s;-moz-transition-duration:0.25s;-o-transition-duration:0.25s;transition-duration:0.25s}.spectra-image-gallery__control-lightbox--thumbnails{width:75%}.spectra-image-gallery__control-lightbox--thumbnails-wrapper{width:100%}.spectra-image-gallery__control-lightbox--thumbnails .swiper-wrapper{height:150px}.spectra-image-gallery__control-lightbox--thumbnails .swiper-slide{cursor:pointer;height:100%;display:flex;flex-direction:column;align-items:center;justify-content:center;opacity:0.5;transform:scale(75%);-webkit-transition-property:opacity, transform;-moz-transition-property:opacity, transform;-o-transition-property:opacity, transform;transition-property:opacity, transform;-webkit-transition-duration:0.25s;-moz-transition-duration:0.25s;-o-transition-duration:0.25s;transition-duration:0.25s}.spectra-image-gallery__control-lightbox--thumbnails .swiper-slide-active{opacity:1;transform:scale(100%)}.spectra-image-gallery__control-lightbox--thumbnails .swiper-slide img{border-radius:3px}.spectra-image-gallery__control-lightbox--count{position:absolute;z-index:999}.spectra-image-gallery__control-lightbox--close{position:absolute;cursor:pointer;padding:0;background-color:transparent;border:none;outline:0;line-height:0;z-index:999;transition:transform 500ms}.spectra-image-gallery__control-lightbox--close:hover,.spectra-image-gallery__control-lightbox--close:focus,.spectra-image-gallery__control-lightbox--close:focus-visible{background-color:transparent;transform:scale(1.25)}.spectra-image-gallery__iso-ref-wrapper{-ms-overflow-style:none;scrollbar-width:none}.spectra-image-gallery__iso-ref-wrapper::-webkit-scrollbar{display:none}@media (max-width: 976px){.spectra-image-gallery__layout--grid-col-tab-1{grid-template-columns:repeat(1, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-tab-2{grid-template-columns:repeat(2, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-tab-3{grid-template-columns:repeat(3, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-tab-4{grid-template-columns:repeat(4, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-tab-5{grid-template-columns:repeat(5, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-tab-6{grid-template-columns:repeat(6, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-tab-7{grid-template-columns:repeat(7, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-tab-8{grid-template-columns:repeat(8, minmax(0, 1fr))}.spectra-image-gallery__layout--isogrid-col-tab-1 .spectra-image-gallery__media-wrapper--isotope{width:100%}.spectra-image-gallery__layout--isogrid-col-tab-2 .spectra-image-gallery__media-wrapper--isotope{width:50%}.spectra-image-gallery__layout--isogrid-col-tab-3 .spectra-image-gallery__media-wrapper--isotope{width:33.33%}.spectra-image-gallery__layout--isogrid-col-tab-4 .spectra-image-gallery__media-wrapper--isotope{width:25%}.spectra-image-gallery__layout--isogrid-col-tab-5 .spectra-image-gallery__media-wrapper--isotope{width:20%}.spectra-image-gallery__layout--isogrid-col-tab-6 .spectra-image-gallery__media-wrapper--isotope{width:16.66%}.spectra-image-gallery__layout--isogrid-col-tab-7 .spectra-image-gallery__media-wrapper--isotope{width:14.28%}.spectra-image-gallery__layout--isogrid-col-tab-8 .spectra-image-gallery__media-wrapper--isotope{width:12.5%}.spectra-image-gallery__layout--masonry-col-tab-1 .spectra-image-gallery__media-wrapper--isotope{width:100%}.spectra-image-gallery__layout--masonry-col-tab-2 .spectra-image-gallery__media-wrapper--isotope{width:50%}.spectra-image-gallery__layout--masonry-col-tab-3 .spectra-image-gallery__media-wrapper--isotope{width:33.33%}.spectra-image-gallery__layout--masonry-col-tab-4 .spectra-image-gallery__media-wrapper--isotope{width:25%}.spectra-image-gallery__layout--masonry-col-tab-5 .spectra-image-gallery__media-wrapper--isotope{width:20%}.spectra-image-gallery__layout--masonry-col-tab-6 .spectra-image-gallery__media-wrapper--isotope{width:16.66%}.spectra-image-gallery__layout--masonry-col-tab-7 .spectra-image-gallery__media-wrapper--isotope{width:14.28%}.spectra-image-gallery__layout--masonry-col-tab-8 .spectra-image-gallery__media-wrapper--isotope{width:12.5%}.spectra-image-gallery__layout--tiled-col-tab-1{grid-template-columns:repeat(1, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-tab-2{grid-template-columns:repeat(2, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-tab-2 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-tab-2 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-tab-2 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-tab-2 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}.spectra-image-gallery__layout--tiled-col-tab-3{grid-template-columns:repeat(3, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-tab-3 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-tab-3 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-tab-3 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-tab-3 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}.spectra-image-gallery__layout--tiled-col-tab-4{grid-template-columns:repeat(4, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-tab-4 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-tab-4 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-tab-4 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-tab-4 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}.spectra-image-gallery__layout--tiled-col-tab-5{grid-template-columns:repeat(5, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-tab-5 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-tab-5 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-tab-5 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-tab-5 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}.spectra-image-gallery__layout--tiled-col-tab-6{grid-template-columns:repeat(6, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-tab-6 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-tab-6 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-tab-6 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-tab-6 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}.spectra-image-gallery__layout--tiled-col-tab-7{grid-template-columns:repeat(7, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-tab-7 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-tab-7 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-tab-7 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-tab-7 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}.spectra-image-gallery__layout--tiled-col-tab-8{grid-template-columns:repeat(8, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-tab-8 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-tab-8 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-tab-8 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-tab-8 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}}@media (max-width: 767px){.spectra-image-gallery__layout--grid-col-mob-1{grid-template-columns:repeat(1, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-mob-2{grid-template-columns:repeat(2, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-mob-3{grid-template-columns:repeat(3, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-mob-4{grid-template-columns:repeat(4, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-mob-5{grid-template-columns:repeat(5, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-mob-6{grid-template-columns:repeat(6, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-mob-7{grid-template-columns:repeat(7, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-mob-8{grid-template-columns:repeat(8, minmax(0, 1fr))}.spectra-image-gallery__layout--isogrid-col-mob-1 .spectra-image-gallery__media-wrapper--isotope{width:100%}.spectra-image-gallery__layout--isogrid-col-mob-2 .spectra-image-gallery__media-wrapper--isotope{width:50%}.spectra-image-gallery__layout--isogrid-col-mob-3 .spectra-image-gallery__media-wrapper--isotope{width:33.33%}.spectra-image-gallery__layout--isogrid-col-mob-4 .spectra-image-gallery__media-wrapper--isotope{width:25%}.spectra-image-gallery__layout--isogrid-col-mob-5 .spectra-image-gallery__media-wrapper--isotope{width:20%}.spectra-image-gallery__layout--isogrid-col-mob-6 .spectra-image-gallery__media-wrapper--isotope{width:16.66%}.spectra-image-gallery__layout--isogrid-col-mob-7 .spectra-image-gallery__media-wrapper--isotope{width:14.28%}.spectra-image-gallery__layout--isogrid-col-mob-8 .spectra-image-gallery__media-wrapper--isotope{width:12.5%}.spectra-image-gallery__layout--masonry-col-mob-1 .spectra-image-gallery__media-wrapper--isotope{width:100%}.spectra-image-gallery__layout--masonry-col-mob-2 .spectra-image-gallery__media-wrapper--isotope{width:50%}.spectra-image-gallery__layout--masonry-col-mob-3 .spectra-image-gallery__media-wrapper--isotope{width:33.33%}.spectra-image-gallery__layout--masonry-col-mob-4 .spectra-image-gallery__media-wrapper--isotope{width:25%}.spectra-image-gallery__layout--masonry-col-mob-5 .spectra-image-gallery__media-wrapper--isotope{width:20%}.spectra-image-gallery__layout--masonry-col-mob-6 .spectra-image-gallery__media-wrapper--isotope{width:16.66%}.spectra-image-gallery__layout--masonry-col-mob-7 .spectra-image-gallery__media-wrapper--isotope{width:14.28%}.spectra-image-gallery__layout--masonry-col-mob-8 .spectra-image-gallery__media-wrapper--isotope{width:12.5%}.spectra-image-gallery__layout--tiled-col-mob-1{grid-template-columns:repeat(1, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-mob-2{grid-template-columns:repeat(2, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-mob-2 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-mob-2 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-mob-2 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-mob-2 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}.spectra-image-gallery__layout--tiled-col-mob-3{grid-template-columns:repeat(3, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-mob-3 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-mob-3 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-mob-3 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-mob-3 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}.spectra-image-gallery__layout--tiled-col-mob-4{grid-template-columns:repeat(4, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-mob-4 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-mob-4 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-mob-4 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-mob-4 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}.spectra-image-gallery__layout--tiled-col-mob-5{grid-template-columns:repeat(5, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-mob-5 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-mob-5 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-mob-5 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-mob-5 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}.spectra-image-gallery__layout--tiled-col-mob-6{grid-template-columns:repeat(6, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-mob-6 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-mob-6 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-mob-6 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-mob-6 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}.spectra-image-gallery__layout--tiled-col-mob-7{grid-template-columns:repeat(7, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-mob-7 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-mob-7 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-mob-7 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-mob-7 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}.spectra-image-gallery__layout--tiled-col-mob-8{grid-template-columns:repeat(8, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-mob-8 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-mob-8 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-mob-8 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-mob-8 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}}.entry-content .wp-block-uagb-image-gallery .uagb-image-gallery__link{text-decoration:none}body .wp-block-post-content>.wp-block-uagb-image-gallery+.spectra-image-gallery__control-lightbox{margin-block-start:0}@-webkit-keyframes sk-bouncedelay{0%,80%,100%{-webkit-transform:scale(0);transform:scale(0)}40%{-webkit-transform:scale(1);transform:scale(1)}}@keyframes sk-bouncedelay{0%,80%,100%{-webkit-transform:scale(0);transform:scale(0)}40%{-webkit-transform:scale(1);transform:scale(1)}}\n.uagb-ifb-content>svg *{-webkit-transition:all 0.2s;-o-transition:all 0.2s;transition:all 0.2s}.uagb-ifb-content>svg,.uagb-ifb-content{display:inline-block}.uagb-ifb-content>svg{vertical-align:middle;width:inherit;height:inherit;font-style:initial}.uagb-ifb-content .uagb-ifb-icon-wrap svg{box-sizing:content-box;width:inherit;height:inherit}.uagb-ifb-button-wrapper:empty{display:none}div.uagb-ifb-button-wrapper a.uagb-infobox-cta-link,div.uagb-ifb-cta a.uagb-infobox-cta-link,.entry .entry-content a.uagb-infobox-cta-link,a.uagb-infobox-link-wrap,.entry .entry-content a.uagb-infobox-link-wrap{text-decoration:none;align-items:center}.uagb-infobox-icon-left-title.uagb-infobox-image-valign-middle .uagb-ifb-title-wrap,.uagb-infobox-icon-right-title.uagb-infobox-image-valign-middle .uagb-ifb-title-wrap,.uagb-infobox-image-valign-middle .uagb-ifb-icon-wrap,.uagb-infobox-image-valign-middle .uagb-ifb-image-content,.uagb-infobox-icon-left.uagb-infobox-image-valign-middle .uagb-ifb-content,.uagb-infobox-icon-right.uagb-infobox-image-valign-middle .uagb-ifb-content{-ms-flex-item-align:center;-webkit-align-self:center;align-self:center}.uagb-infobox-icon-left-title.uagb-infobox-image-valign-top .uagb-ifb-title-wrap,.uagb-infobox-icon-right-title.uagb-infobox-image-valign-top .uagb-ifb-title-wrap,.uagb-infobox-image-valign-top .uagb-ifb-icon-wrap,.uagb-infobox-image-valign-top .uagb-ifb-image-content,.uagb-infobox-icon-left.uagb-infobox-image-valign-top .uagb-ifb-content,.uagb-infobox-icon-right.uagb-infobox-image-valign-top .uagb-ifb-content{-webkit-align-self:self-start;align-self:self-start}.uagb-infobox-left{justify-content:flex-start;text-align:left;-webkit-box-pack:start;-ms-flex-pack:start;-webkit-justify-content:flex-start;-moz-box-pack:start}.uagb-infobox-center{justify-content:center;text-align:center;-webkit-box-pack:center;-ms-flex-pack:center;-webkit-justify-content:center;-moz-box-pack:center}.uagb-infobox-right{justify-content:flex-end;text-align:right;-webkit-box-pack:end;-ms-flex-pack:end;-webkit-justify-content:flex-end;-moz-box-pack:end}.uagb-infobox-icon-above-title.uagb-infobox__content-wrap,.uagb-infobox-icon-below-title.uagb-infobox__content-wrap{display:block;width:100%}.uagb-infobox-icon-left-title .uagb-ifb-content>svg,.uagb-infobox-icon-left .uagb-ifb-content>svg{margin-right:10px}.uagb-infobox-icon-right-title .uagb-ifb-content>svg,.uagb-infobox-icon-right .uagb-ifb-content>svg{margin-left:10px}.uagb-infobox-icon-left.uagb-infobox__content-wrap,.uagb-infobox-icon-right.uagb-infobox__content-wrap,.uagb-infobox-icon-left-title .uagb-ifb-left-title-image,.uagb-infobox-icon-right-title .uagb-ifb-right-title-image{display:-webkit-box;display:-ms-flexbox;display:-webkit-flex;display:-moz-box;display:flex;-js-display:flex}.uagb-infobox-icon-left-title .uagb-ifb-left-title-image .uagb-ifb-image-content,.uagb-infobox-icon-right-title .uagb-ifb-right-title-image .uagb-ifb-image-content,.uagb-infobox-icon-left .uagb-ifb-image-content,.uagb-infobox-icon-right .uagb-ifb-image-content{flex-shrink:0;line-height:0}.uagb-infobox-icon-left-title .uagb-ifb-left-title-image .uagb-ifb-title-wrap,.uagb-infobox-icon-right-title .uagb-ifb-right-title-image .uagb-ifb-title-wrap,.uagb-infobox-icon-left .uagb-ifb-content,.uagb-infobox-icon-right .uagb-ifb-content{flex-grow:1}.uagb-infobox-icon-right.uagb-infobox__content-wrap,.uagb-infobox-icon-right-title .uagb-ifb-right-title-image{-webkit-box-pack:end;-ms-flex-pack:end;-webkit-justify-content:flex-end;-moz-box-pack:end;justify-content:flex-end}.uagb-ifb-content img{position:relative;display:inline-block;line-height:0;width:auto;height:auto !important;max-width:100%;border-radius:inherit;-webkit-box-sizing:content-box;-moz-box-sizing:content-box;-webkit-border-radius:inherit}.uagb-infobox-module-link{position:absolute;top:0;right:0;bottom:0;left:0;z-index:4;width:100%;height:100%}.uagb-edit-mode .uagb-infobox-module-link{z-index:2}.uagb-infobox-link-icon-after{margin-right:0;margin-left:5px}.uagb-infobox-link-icon-before{margin-right:5px;margin-left:0}.uagb-infobox-link-icon{-webkit-transition:all 200ms linear;transition:all 200ms linear}.uagb-infobox__content-wrap{box-sizing:border-box;position:relative;width:100%;word-break:break-word;z-index:1}.uagb-ifb-separator{display:inline-block;margin:0;border-top-color:#333;border-top-style:solid;border-top-width:2px;line-height:0}.uagb-ifb-button-wrapper{line-height:1}.uagb-ifb-button-wrapper.uagb-ifb-button-type-text .uagb-infobox-cta-link.wp-block-button__link{background-color:unset;border:none}.uagb-ifb-button-wrapper.uagb-ifb-button-type-text .uagb-infobox-cta-link.wp-block-button__link:hover{background-color:unset;border-color:unset}.uagb-ifb-button-wrapper .uagb-infobox-cta-link{cursor:pointer}.uagb-ifb-button-wrapper .uagb-infobox-cta-link.wp-block-button__link{width:auto}.uagb-ifb-button-wrapper .wp-block-button__link svg,.uagb-ifb-button-wrapper .ast-outline-button svg{fill:currentColor}.uagb-infobox__content-wrap a{-webkit-box-shadow:none;box-shadow:none;text-decoration:none}.uagb-ifb-title-wrap{width:100%}.uagb-ifb-title{margin-block-start:0}.uagb-ifb-title-wrap .uagb-ifb-title-prefix{display:block;padding:0;margin:0}.uagb-infobox__content-wrap.uagb-infobox__content-wrap{position:relative}.uagb-ifb-content{width:100%}.uagb-infobox__content-wrap.uagb-infobox,.uagb-ifb-content,.uagb-ifb-title-wrap,.uagb-ifb-title-prefix *,svg.dashicon.dashicons-upload{z-index:1}a.uagb-infobox-link-wrap{color:inherit}.uagb-ifb-content p:empty{display:none}.uagb-infobox__content-wrap .uagb-ifb-content img{display:inline-block;max-width:100%}.uagb-infobox__content-wrap .uagb-ifb-content svg{display:inline-block}.uagb-infobox__content-wrap .uagb-ifb-icon-wrap,.uagb-infobox-icon-left .uagb-ifb-image-content,.uagb-infobox-icon-right .uagb-ifb-image-content{box-sizing:content-box}.uagb-infobox-cta-link>svg{vertical-align:middle;width:15px;height:15px;font-size:15px}.uagb-infobox-cta-link{display:inline-flex}.block-editor-page #wpwrap .uagb-infobox-cta-link svg,.uagb-infobox-cta-link svg{font-style:normal}.uagb-infobox-icon-left-title .uagb-ifb-icon-wrap,.uagb-infobox-icon-left .uagb-ifb-icon-wrap{margin-right:10px;line-height:0}.uagb-infobox-icon-right-title .uagb-ifb-icon-wrap,.uagb-infobox-icon-right .uagb-ifb-icon-wrap{margin-left:10px;line-height:0}html[dir=\"rtl\"] .uagb-infobox-icon-left-title .uagb-ifb-icon-wrap,html[dir=\"rtl\"] .uagb-infobox-icon-left .uagb-ifb-icon-wrap{margin-left:10px;line-height:0}html[dir=\"rtl\"] .uagb-infobox-icon-right-title .uagb-ifb-icon-wrap,html[dir=\"rtl\"] .uagb-infobox-icon-right .uagb-ifb-icon-wrap{margin-right:10px;line-height:0}html[dir=\"rtl\"] .uagb-infobox-left{justify-content:flex-end;text-align:right;-webkit-box-pack:end;-ms-flex-pack:end;-webkit-justify-content:flex-end;-moz-box-pack:end}html[dir=\"rtl\"] .uagb-infobox-right{justify-content:flex-start;text-align:left;-webkit-box-pack:start;-ms-flex-pack:start;-webkit-justify-content:flex-start;-moz-box-pack:start}.uagb-infobox-icon-left .uagb-ifb-left-right-wrap,.uagb-infobox-icon-right .uagb-ifb-left-right-wrap,.uagb-infobox-icon-left-title .uagb-ifb-left-title-image,.uagb-infobox-icon-right-title .uagb-ifb-right-title-image{display:-webkit-box;display:-ms-flexbox;display:flex}.uagb-infobox-icon-right .uagb-ifb-left-right-wrap,.uagb-infobox-icon-right-title .uagb-ifb-right-title-image{-webkit-box-pack:end;-ms-flex-pack:end;-webkit-justify-content:flex-end;-moz-box-pack:end;justify-content:flex-end}a.uagb-infbox__link-to-all{position:absolute;top:0;left:0;z-index:3;width:100%;height:100%;box-shadow:none;text-decoration:none;-webkit-box-shadow:none}@media only screen and (max-width: 976px){.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap .uagb-ifb-image-content{padding:0;margin-bottom:20px}.uagb-infobox-stacked-tablet.uagb-reverse-order-tablet.uagb-infobox__content-wrap{display:-webkit-inline-box;display:-ms-inline-flexbox;display:-webkit-inline-flex;display:-moz-inline-box;display:inline-flex;flex-direction:column-reverse;-js-display:inline-flex;-webkit-box-orient:vertical;-webkit-box-direction:reverse;-ms-flex-direction:column-reverse;-webkit-flex-direction:column-reverse;-moz-box-orient:vertical;-moz-box-direction:reverse}.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap .uagb-ifb-content,.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap .uagb-ifb-icon-wrap,.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap .uagb-ifb-image-content{display:block;width:100%;text-align:center}.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap .uagb-ifb-icon-wrap,.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap .uagb-ifb-image-content{margin-right:0;margin-left:0}.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap{display:inline-block}.uagb-infobox-icon-left-title.uagb-infobox-stacked-tablet .uagb-ifb-image-content,.uagb-infobox-icon-left-title.uagb-infobox-stacked-tablet .uagb-ifb-icon-wrap,.uagb-infobox-icon-left.uagb-infobox-stacked-tablet .uagb-ifb-image-content,.uagb-infobox-icon-left.uagb-infobox-stacked-tablet .uagb-ifb-icon-wrap{margin-right:0}.uagb-infobox-icon-right-title.uagb-infobox-stacked-tablet .uagb-ifb-image-content,.uagb-infobox-icon-right-title.uagb-infobox-stacked-tablet .uagb-ifb-icon-wrap,.uagb-infobox-icon-right.uagb-infobox-stacked-tablet .uagb-ifb-image-content,.uagb-infobox-icon-right.uagb-infobox-stacked-tablet .uagb-ifb-icon-wrap{margin-left:0}.uagb-infobox-icon-left-title .uagb-ifb-separator{margin:10px 0}}@media screen and (max-width: 767px){.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap{display:inline-block}.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap .uagb-ifb-image-content,.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap .uagb-ifb-icon-wrap{padding:0;margin-bottom:20px;margin-right:0;margin-left:0}.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap.uagb-reverse-order-mobile{display:-webkit-inline-box;display:-ms-inline-flexbox;display:-webkit-inline-flex;display:-moz-inline-box;display:inline-flex;flex-direction:column-reverse;-js-display:inline-flex;-webkit-box-orient:vertical;-webkit-box-direction:reverse;-ms-flex-direction:column-reverse;-webkit-flex-direction:column-reverse;-moz-box-orient:vertical;-moz-box-direction:reverse}.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap .uagb-ifb-image-content,.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap .uagb-ifb-icon-wrap,.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap .uagb-ifb-content{display:block;width:100%;text-align:center}.uagb-infobox-icon-left-title.uagb-infobox-stacked-mobile .uagb-ifb-image-content,.uagb-infobox-icon-left-title.uagb-infobox-stacked-mobile .uagb-ifb-icon-wrap,.uagb-infobox-icon-left.uagb-infobox-stacked-mobile .uagb-ifb-image-content,.uagb-infobox-icon-left.uagb-infobox-stacked-mobile .uagb-ifb-icon-wrap{margin-right:0}.uagb-infobox-icon-right-title.uagb-infobox-stacked-mobile .uagb-ifb-image-content,.uagb-infobox-icon-right-title.uagb-infobox-stacked-mobile .uagb-ifb-icon-wrap,.uagb-infobox-icon-right.uagb-infobox-stacked-mobile .uagb-ifb-image-content,.uagb-infobox-icon-right.uagb-infobox-stacked-mobile .uagb-ifb-icon-wrap{margin-left:0}.uagb-infobox-icon-left-title .uagb-ifb-separator{margin:10px 0}}.uagb-ifb-icon svg{width:inherit;height:inherit;vertical-align:middle}.uagb-ifb-button-icon{height:15px;width:15px;font-size:15px;vertical-align:middle}.uagb-ifb-button-icon svg{height:inherit;width:inherit;display:inline-block}.uagb-ifb-button-icon.uagb-ifb-align-icon-after{float:right}.uagb-ifb-cta-button{display:inline-block}.uagb-disable-link{pointer-events:none}@media only screen and (min-width: 977px){.uagb-infobox-margin-wrapper{display:flex}}.uagb-ifb-content .uagb-ifb-desc p:last-child{margin-bottom:0}\n.wp-block-uagb-container.uagb-block-2c66ecf5 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-2c66ecf5 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-2c66ecf5 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-2c66ecf5 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-2c66ecf5 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-2c66ecf5{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-2c66ecf5 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1140px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-2c66ecf5{box-shadow: 0px 0px   #00000070 ;padding-top: 250px;padding-bottom: 0px;padding-left: 40px;padding-right: 40px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;background-color: var(--ast-global-color-4);;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-2c66ecf5.uag-blocks-common-selector{--z-index-desktop: -1;--z-index-tablet: -1;--z-index-mobile: -1;}.wp-block-uagb-container.uagb-block-b168e446 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-b168e446 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-b168e446 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-b168e446 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-b168e446 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-b168e446{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-b168e446 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-b168e446{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-color: inherit;flex-direction: row;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-b168e446.uag-blocks-common-selector{--z-index-desktop: -1;}.wp-block-uagb-advanced-heading.uagb-block-3ba1534c.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-3ba1534c.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-3ba1534c.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-3ba1534c.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-3ba1534c .uagb-heading-text{font-size: 160px;}.wp-block-uagb-container.uagb-block-c9b97a85 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-c9b97a85 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-c9b97a85 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-c9b97a85 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-c9b97a85 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-c9b97a85{max-width: 25%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-c9b97a85 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: flex-end;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-c9b97a85{box-shadow: 0px 0px   #00000070 ;padding-top: 50px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: flex-end;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-c9b97a85.uag-blocks-common-selector{--z-index-desktop: 10;} .uagb-block-2a6b046d.uagb-icon-wrapper{text-align: right;} .uagb-block-2a6b046d.uagb-icon-wrapper .uagb-svg-wrapper a{display: contents;} .uagb-block-2a6b046d.uagb-icon-wrapper svg{width: 75px;height: 75px;transform: rotate(0deg);box-sizing: content-box;fill: var(--ast-global-color-0);filter: drop-shadow( 0px 0px 0px #00000070 );} .uagb-block-2a6b046d.uagb-icon-wrapper .uagb-svg-wrapper{display: inline-flex;padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;border-style: default;box-shadow: 0px 0px 0 #00000070 ;} .uagb-block-2a6b046d.uagb-icon-wrapper .uagb-svg-wrapper:hover{box-shadow: 0px 0px 0 #00000070 ;} .uagb-block-2a6b046d.uagb-icon-wrapper .uagb-svg-wrapper:focus-visible{box-shadow: 0px 0px 0 #00000070 ;} .uagb-block-2a6b046d.uagb-icon-wrapper.wp-block-uagb-icon--has-margin .uagb-icon-margin-wrapper{margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-43224597.wp-block-uagb-advanced-heading {text-align: right;margin-bottom: 20px;padding-left: 50px;}.wp-block-uagb-advanced-heading.uagb-block-43224597.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-43224597.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-43224597.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-43224597.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-bb758da2.wp-block-uagb-advanced-heading {text-align: right;margin-bottom: 20px;padding-top: 8px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-bb758da2.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-bb758da2.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-bb758da2.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-bb758da2.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.uagb-block-98684736.wp-block-uagb-image{margin-top: -85px;margin-right: -100px;margin-bottom: 0px;margin-left: 0px;text-align: right;justify-content: flex-end;align-self: flex-end;}.uagb-block-98684736 .wp-block-uagb-image__figure{align-items: flex-end;}.uagb-block-98684736.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-98684736.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-98684736.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-98684736.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;}.uagb-block-98684736.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-98684736.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-98684736.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-98684736.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-98684736.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-98684736.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-98684736.wp-block-uagb-image .wp-block-uagb-image__figure img{width: 185px;height: auto;}.uagb-block-98684736.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-98684736.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-98684736.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-98684736.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}.wp-block-uagb-container.uagb-block-b4c87933 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-b4c87933 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-b4c87933 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-b4c87933 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-b4c87933 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-b4c87933{max-width: 600px;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-b4c87933 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-b4c87933{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: -130px !important;margin-bottom: 500px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-b4c87933.uag-blocks-common-selector{--z-index-desktop: 3;}.uagb-block-a0cd5a3e.wp-block-uagb-image-gallery{padding: 0px 0px 0px 0px;visibility: hidden;}.uagb-block-a0cd5a3e .spectra-image-gallery__control-arrows svg{fill: #007cba;}.uagb-block-a0cd5a3e .spectra-image-gallery__control-arrows--carousel{border-top-left-radius: 50px;border-top-right-radius: 50px;border-bottom-left-radius: 50px;border-bottom-right-radius: 50px;border-style: none;}.uagb-block-a0cd5a3e .spectra-image-gallery__control-arrows--carousel.slick-prev{left: -24px;}.uagb-block-a0cd5a3e .spectra-image-gallery__control-arrows--carousel.slick-next{right: -24px;}.uagb-block-a0cd5a3e .spectra-image-gallery__layout--carousel ul.slick-dots{top: 8px;}.uagb-block-a0cd5a3e .spectra-image-gallery__layout--carousel ul.slick-dots li button:before{color: #007cba;}.uagb-block-a0cd5a3e .spectra-image-gallery__control-dots li button::before{color: #007cba;}.uagb-block-a0cd5a3e .spectra-image-gallery__control-loader{margin-top: 8px;}.uagb-block-a0cd5a3e .spectra-image-gallery__control-loader div{width: 18px;height: 18px;border-radius: 100%;padding: 0;}.uagb-block-a0cd5a3e .spectra-image-gallery__control-button{margin-top: 8px;padding:    ;font-style: normal;text-decoration: none;}.uagb-block-a0cd5a3e .spectra-image-gallery__layout--grid{grid-gap: 0px;}.uagb-block-a0cd5a3e .spectra-image-gallery__layout--isogrid{margin: 0px;}.uagb-block-a0cd5a3e .spectra-image-gallery__layout--isogrid .spectra-image-gallery__media-wrapper--isotope{padding: 0px;}.uagb-block-a0cd5a3e .spectra-image-gallery__layout--masonry{margin: 0px;}.uagb-block-a0cd5a3e .spectra-image-gallery__layout--masonry .spectra-image-gallery__media-wrapper--isotope{padding: 0px;}.uagb-block-a0cd5a3e .spectra-image-gallery__layout--carousel{margin-bottom: 8px !important;}.uagb-block-a0cd5a3e .spectra-image-gallery__layout--carousel .spectra-image-gallery__media-wrapper{padding: 0px 0px;}.uagb-block-a0cd5a3e .spectra-image-gallery__layout--carousel .slick-list{margin: 0px 0px;}.uagb-block-a0cd5a3e .spectra-image-gallery__layout--tiled{grid-gap: 0px;}.uagb-block-a0cd5a3e .spectra-image-gallery__media{box-shadow: 0px 0px   ;}.uagb-block-a0cd5a3e .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media{box-shadow: 0px 0px   ;}.uagb-block-a0cd5a3e .spectra-image-gallery__media-wrapper:focus-visible .spectra-image-gallery__media{box-shadow: 0px 0px   ;}.uagb-block-a0cd5a3e .spectra-image-gallery__media-thumbnail-blurrer{-webkit-backdrop-filter: none;backdrop-filter: none;box-shadow: 0 0 transparent;}.uagb-block-a0cd5a3e .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media-thumbnail-blurrer{-webkit-backdrop-filter: none;backdrop-filter: none;box-shadow: 0 0 transparent;}.uagb-block-a0cd5a3e .spectra-image-gallery__media-wrapper:focus-visible .spectra-image-gallery__media-thumbnail-blurrer{-webkit-backdrop-filter: none;backdrop-filter: none;box-shadow: 0 0 transparent;}.uagb-block-a0cd5a3e .spectra-image-gallery__media-thumbnail-caption-wrapper--overlay{background-color: rgba(0,0,0,0);}.uagb-block-a0cd5a3e .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media-thumbnail-caption-wrapper--overlay{background-color: rgba(0,0,0,0);}.uagb-block-a0cd5a3e .spectra-image-gallery__media-wrapper:focus-visible .spectra-image-gallery__media-thumbnail-caption-wrapper--overlay{background-color: rgba(0,0,0,0);}.uagb-block-a0cd5a3e .spectra-image-gallery__media-thumbnail-caption-wrapper--bar-inside{-webkit-align-items: center;align-items: center;-webkit-justify-content: center;justify-content: center;}.uagb-block-a0cd5a3e .spectra-image-gallery__media-thumbnail-caption a{color: rgba(0,0,0,0);}.uagb-block-a0cd5a3e .spectra-image-gallery__media-thumbnail-caption{color: rgba(0,0,0,0);text-align: center;font-style: normal;text-decoration: none;padding: 8px 8px 8px 8px;}.uagb-block-a0cd5a3e .spectra-image-gallery__media-thumbnail-caption--overlay{-webkit-align-items: center;align-items: center;-webkit-justify-content: center;justify-content: center;}.uagb-block-a0cd5a3e .spectra-image-gallery__media-thumbnail-caption--bar-inside{background-color: rgba(0,0,0,0);border-color: rgba(0,0,0,0);}.uagb-block-a0cd5a3e .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media-thumbnail-caption--bar-inside{background-color: rgba(0,0,0,0.75);}.uagb-block-a0cd5a3espectra-image-gallery__media-wrapper:focus-visible .spectra-image-gallery__media-thumbnail-caption--bar-inside{background-color: rgba(0,0,0,0.75);}.uagb-block-a0cd5a3e .spectra-image-gallery__media-thumbnail-caption--bar-outside{background-color: rgba(0,0,0,0.75);}.uagb-block-a0cd5a3e .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media-thumbnail-caption--bar-outside{background-color: rgba(0,0,0,0.75);}.uagb-block-a0cd5a3e .spectra-image-gallery__media-wrapper:focus-visible .spectra-image-gallery__media-thumbnail-caption--bar-outside{background-color: rgba(0,0,0,0.75);}.uagb-block-a0cd5a3e .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media-thumbnail-caption{color: rgba(255,255,255,1);}.uagb-block-a0cd5a3e .spectra-image-gallery__media-wrapper:focus-visible .spectra-image-gallery__media-thumbnail-caption{color: rgba(255,255,255,1);}.uagb-block-a0cd5a3e .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media-thumbnail-caption a{color: rgba(255,255,255,1);}.uagb-block-a0cd5a3e .spectra-image-gallery__media-wrapper:focus-visible .spectra-image-gallery__media-thumbnail-caption a{color: rgba(255,255,255,1);}.uagb-block-a0cd5a3e+.spectra-image-gallery__control-lightbox{background-color: rgba(0,0,0,0.75);backdrop-filter: blur( 5px);}.uagb-block-a0cd5a3e+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--caption{color: rgba(255,255,255,1);background: linear-gradient(rgba(0,0,0,0), rgba(0,0,0,1));min-height: 50px;font-style: normal;text-decoration: none;}.uagb-block-a0cd5a3e+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--thumbnails-wrapper{background-color: transparent;}.uagb-block-a0cd5a3e+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--count{top: 10px;left: 10px;color: rgba(255,255,255,1);font-weight: normal;font-size: calc(24px * 3 \/ 4 );line-height: calc(24px * 3 \/ 4 );}.uagb-block-a0cd5a3e+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--close{top: 10px;right: 10px;}.uagb-block-a0cd5a3e+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--close svg{width: 24px;height: 24px;fill: rgba(255,255,255,1);}.uagb-block-a0cd5a3e+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main .swiper-button-prev{left: 10px;color: rgba(255,255,255,1);}.uagb-block-a0cd5a3e+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main .swiper-button-next{right: 10px;color: rgba(255,255,255,1);}.uagb-block-a0cd5a3e+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main.swiper-rtl .swiper-button-prev{right: 10px;left: auto;}.uagb-block-a0cd5a3e+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main.swiper-rtl .swiper-button-next{left: 10px;right: auto;}.uagb-block-a0cd5a3e .spectra-image-gallery__media-thumbnail{-webkit-filter: none;filter: none;}.uagb-block-a0cd5a3e .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media-thumbnail{-webkit-filter: none;filter: none;}.uagb-block-a0cd5a3e .spectra-image-gallery__media-wrapper:focus-visible .spectra-image-gallery__media-thumbnail{-webkit-filter: none;filter: none;}.uagb-block-a0cd5a3e .spectra-image-gallery__layout--carousel .slick-dots{margin-bottom: 30px !important;}.wp-block-uagb-container.uagb-block-fd9a5843 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-fd9a5843 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-fd9a5843 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-fd9a5843 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-fd9a5843 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-fd9a5843{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-block-fd9a5843{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 115px;padding-left: 0px;padding-right: 0px;margin-top: -325px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-color: inherit;background-repeat: no-repeat;background-position: 50% 50%;background-size: cover;background-attachment: scroll;background-image: url(https:\/\/websitedemos.net\/cake-shop-09\/wp-content\/uploads\/sites\/1134\/2022\/10\/bg-03-free-img.jpg);background-clip: padding-box;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-fd9a5843.uag-blocks-common-selector{--z-index-desktop: -1;}.uagb-block-5306d181.wp-block-uagb-image{margin-top: -154px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;text-align: left;justify-content: flex-start;align-self: flex-start;}.uagb-block-5306d181 .wp-block-uagb-image__figure{align-items: flex-start;}.uagb-block-5306d181.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-5306d181.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-5306d181.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-5306d181.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;}.uagb-block-5306d181.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-5306d181.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-5306d181.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-5306d181.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-5306d181.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-5306d181.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-5306d181.wp-block-uagb-image .wp-block-uagb-image__figure img{width: 850px;height: 620px;}.uagb-block-5306d181.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-5306d181.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-5306d181.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-5306d181.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}.wp-block-uagb-container.uagb-block-724d4bb0 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-724d4bb0 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-724d4bb0 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-724d4bb0 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-724d4bb0 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-724d4bb0{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-724d4bb0 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 100%);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 10px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-724d4bb0{box-shadow: 0px 0px   #00000070 ;padding-top: 2%;padding-bottom: 0%;padding-left: 15%;padding-right: 15%;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 10px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-724d4bb0.uag-blocks-common-selector{--z-index-desktop: -100;}.wp-block-uagb-advanced-heading.uagb-block-f7d116b2.wp-block-uagb-advanced-heading {text-align: center;}.wp-block-uagb-advanced-heading.uagb-block-f7d116b2.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-f7d116b2.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-f7d116b2.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-f7d116b2.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-3e834e65.wp-block-uagb-advanced-heading {text-align: center;margin-bottom: 20px;}.wp-block-uagb-advanced-heading.uagb-block-3e834e65.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-3e834e65.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-3e834e65.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-3e834e65.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.uagb-block-8f60856a .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-8f60856a .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-8f60856a .uagb-ifb-icon svg{fill: #333;}.uagb-block-8f60856a.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-8f60856a .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-8f60856a .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-8f60856a.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-8f60856a.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-8f60856a .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-8f60856a .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-8f60856a .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-8f60856a .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-8f60856a.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-8f60856a.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-8f60856a.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-8f60856a.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-8f60856a .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-8f60856a.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 10px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-8f60856a.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 50px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-8f60856a .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-8f60856a .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-8f60856a .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-8f60856a .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-8f60856a.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-8f60856a.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-8f60856a .uagb-infobox__content-wrap{text-align: center;}.uagb-block-8f60856a.uagb-infobox-icon-above-title{text-align: center;}.uagb-block-8f60856a.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-8f60856a.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-8f60856a.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-8f60856a .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-8f60856a.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-8f60856a.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-8f60856a.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-8f60856a.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-8f60856a.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-8f60856a.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-8f60856a.uagb-infobox__content-wrap{text-align: center;}[dir=rtl] .uagb-block-8f60856a.uagb-infobox-icon-above-title{text-align: center;}[dir=rtl] .uagb-block-8f60856a.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-7ff3a404.wp-block-uagb-advanced-heading {text-align: center;padding-top: 65px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-7ff3a404.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-7ff3a404.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-7ff3a404.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-7ff3a404.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-aace127a.wp-block-uagb-advanced-heading {text-align: center;margin-bottom: 20px;padding-bottom: 0%;}.wp-block-uagb-advanced-heading.uagb-block-aace127a.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-aace127a.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-aace127a.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-aace127a.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-container.uagb-block-2727fa58 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-2727fa58 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-2727fa58 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-2727fa58 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-2727fa58 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-2727fa58{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-2727fa58 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 50px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-2727fa58{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 40px;padding-right: 40px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-color: inherit;background-color: var(--ast-global-color-4);;row-gap: 50px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-5b0d9f3e .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-5b0d9f3e .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-5b0d9f3e .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-5b0d9f3e .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-5b0d9f3e .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-5b0d9f3e{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-5b0d9f3e > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: flex-start;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-5b0d9f3e{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 40px;padding-right: 40px;margin-top: -90px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-color: inherit;flex-direction: row;align-items: flex-start;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-5b0d9f3e.uag-blocks-common-selector{--z-index-desktop: 3;}.uagb-block-bb367c1b .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-bb367c1b .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-bb367c1b .uagb-ifb-icon svg{fill: #333;}.uagb-block-bb367c1b.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-bb367c1b .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-bb367c1b .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-bb367c1b.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-bb367c1b.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-bb367c1b .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-bb367c1b .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-bb367c1b .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-bb367c1b .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-bb367c1b.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-bb367c1b.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-bb367c1b.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-bb367c1b.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-bb367c1b .uagb-ifb-title-wrap .uagb-ifb-title-prefix{color: var(--ast-global-color-0);margin-bottom: 10px;margin-top: 35px;margin-left: 0px;margin-right: 0px;}.uagb-block-bb367c1b.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 10px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-bb367c1b.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-bb367c1b .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-bb367c1b .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-bb367c1b .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-bb367c1b .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-bb367c1b.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-bb367c1b.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-bb367c1b .uagb-infobox__content-wrap{text-align: center;}.uagb-block-bb367c1b.uagb-infobox-icon-above-title{text-align: center;}.uagb-block-bb367c1b.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-bb367c1b .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-bb367c1b.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-bb367c1b.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-bb367c1b.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-bb367c1b.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-bb367c1b.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-bb367c1b.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-bb367c1b.uagb-infobox__content-wrap{text-align: center;}[dir=rtl] .uagb-block-bb367c1b.uagb-infobox-icon-above-title{text-align: center;}[dir=rtl] .uagb-block-bb367c1b.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-a3cec12e .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-a3cec12e .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-a3cec12e .uagb-ifb-icon svg{fill: #333;}.uagb-block-a3cec12e.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-a3cec12e .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-a3cec12e .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-a3cec12e.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-a3cec12e.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-a3cec12e .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-a3cec12e .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-a3cec12e .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-a3cec12e .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-a3cec12e.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-a3cec12e.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-a3cec12e.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-a3cec12e.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-a3cec12e .uagb-ifb-title-wrap .uagb-ifb-title-prefix{color: var(--ast-global-color-0);margin-bottom: 10px;margin-top: 35px;margin-left: 0px;margin-right: 0px;}.uagb-block-a3cec12e.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 10px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-a3cec12e.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-a3cec12e .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-a3cec12e .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-a3cec12e .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-a3cec12e .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-a3cec12e.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-a3cec12e.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-a3cec12e .uagb-infobox__content-wrap{text-align: center;}.uagb-block-a3cec12e.uagb-infobox-icon-above-title{text-align: center;}.uagb-block-a3cec12e.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-a3cec12e .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-a3cec12e.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-a3cec12e.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-a3cec12e.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-a3cec12e.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-a3cec12e.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-a3cec12e.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-a3cec12e.uagb-infobox__content-wrap{text-align: center;}[dir=rtl] .uagb-block-a3cec12e.uagb-infobox-icon-above-title{text-align: center;}[dir=rtl] .uagb-block-a3cec12e.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-861651c6 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-861651c6 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-861651c6 .uagb-ifb-icon svg{fill: #333;}.uagb-block-861651c6.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-861651c6 .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-861651c6 .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-861651c6.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-861651c6.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-861651c6 .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-861651c6 .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-861651c6 .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-861651c6 .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-861651c6.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-861651c6.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-861651c6.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-861651c6.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-861651c6 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{color: var(--ast-global-color-0);margin-bottom: 10px;margin-top: 35px;margin-left: 0px;margin-right: 0px;}.uagb-block-861651c6.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 10px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-861651c6.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-861651c6 .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-861651c6 .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-861651c6 .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-861651c6 .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-861651c6.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-861651c6.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-861651c6 .uagb-infobox__content-wrap{text-align: center;}.uagb-block-861651c6.uagb-infobox-icon-above-title{text-align: center;}.uagb-block-861651c6.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-861651c6 .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-861651c6.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-861651c6.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-861651c6.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-861651c6.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-861651c6.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-861651c6.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-861651c6.uagb-infobox__content-wrap{text-align: center;}[dir=rtl] .uagb-block-861651c6.uagb-infobox-icon-above-title{text-align: center;}[dir=rtl] .uagb-block-861651c6.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-block-2ffcd874 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-2ffcd874 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-2ffcd874 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-2ffcd874 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-2ffcd874 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-2ffcd874{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-2ffcd874 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: flex-start;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-2ffcd874{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 40px;padding-right: 40px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-color: inherit;flex-direction: row;align-items: flex-start;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-2ffcd874.uag-blocks-common-selector{--z-index-desktop: 3;}.uagb-block-5c24b108 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-5c24b108 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-5c24b108 .uagb-ifb-icon svg{fill: #333;}.uagb-block-5c24b108.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-5c24b108 .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-5c24b108 .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-5c24b108.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-5c24b108.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-5c24b108 .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-5c24b108 .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-5c24b108 .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-5c24b108 .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-5c24b108.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-5c24b108.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-5c24b108.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-5c24b108.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-5c24b108 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{color: var(--ast-global-color-0);margin-bottom: 10px;margin-top: 35px;margin-left: 0px;margin-right: 0px;}.uagb-block-5c24b108.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 10px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-5c24b108.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-5c24b108 .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-5c24b108 .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-5c24b108 .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-5c24b108 .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-5c24b108.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-5c24b108.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-5c24b108 .uagb-infobox__content-wrap{text-align: center;}.uagb-block-5c24b108.uagb-infobox-icon-above-title{text-align: center;}.uagb-block-5c24b108.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-5c24b108 .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-5c24b108.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-5c24b108.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-5c24b108.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-5c24b108.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-5c24b108.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-5c24b108.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-5c24b108.uagb-infobox__content-wrap{text-align: center;}[dir=rtl] .uagb-block-5c24b108.uagb-infobox-icon-above-title{text-align: center;}[dir=rtl] .uagb-block-5c24b108.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-073479f1 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-073479f1 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-073479f1 .uagb-ifb-icon svg{fill: #333;}.uagb-block-073479f1.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-073479f1 .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-073479f1 .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-073479f1.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-073479f1.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-073479f1 .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-073479f1 .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-073479f1 .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-073479f1 .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-073479f1.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-073479f1.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-073479f1.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-073479f1.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-073479f1 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{color: var(--ast-global-color-0);margin-bottom: 10px;margin-top: 35px;margin-left: 0px;margin-right: 0px;}.uagb-block-073479f1.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 10px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-073479f1.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-073479f1 .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-073479f1 .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-073479f1 .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-073479f1 .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-073479f1.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-073479f1.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-073479f1 .uagb-infobox__content-wrap{text-align: center;}.uagb-block-073479f1.uagb-infobox-icon-above-title{text-align: center;}.uagb-block-073479f1.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-073479f1 .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-073479f1.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-073479f1.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-073479f1.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-073479f1.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-073479f1.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-073479f1.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-073479f1.uagb-infobox__content-wrap{text-align: center;}[dir=rtl] .uagb-block-073479f1.uagb-infobox-icon-above-title{text-align: center;}[dir=rtl] .uagb-block-073479f1.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-d6915861 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-d6915861 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-d6915861 .uagb-ifb-icon svg{fill: #333;}.uagb-block-d6915861.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-d6915861 .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-d6915861 .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-d6915861.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-d6915861.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-d6915861 .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-d6915861 .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-d6915861 .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-d6915861 .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-d6915861.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-d6915861.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-d6915861.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-d6915861.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-d6915861 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{color: var(--ast-global-color-0);margin-bottom: 10px;margin-top: 35px;margin-left: 0px;margin-right: 0px;}.uagb-block-d6915861.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 10px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-d6915861.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-d6915861 .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-d6915861 .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-d6915861 .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-d6915861 .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-d6915861.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-d6915861.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-d6915861 .uagb-infobox__content-wrap{text-align: center;}.uagb-block-d6915861.uagb-infobox-icon-above-title{text-align: center;}.uagb-block-d6915861.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-d6915861 .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-d6915861.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-d6915861.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-d6915861.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-d6915861.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-d6915861.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-d6915861.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-d6915861.uagb-infobox__content-wrap{text-align: center;}[dir=rtl] .uagb-block-d6915861.uagb-infobox-icon-above-title{text-align: center;}[dir=rtl] .uagb-block-d6915861.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-block-76587460 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-76587460 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-76587460 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-76587460 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-76587460 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-76587460{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-76587460 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 600px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 10px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-76587460{box-shadow: 0px 0px   #00000070 ;padding-top: 100px;padding-bottom: 100px;padding-left: 40px;padding-right: 40px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-color: inherit;background-color: var(--ast-global-color-4);;row-gap: 10px;column-gap: 20px;}.uagb-block-33a302d6.wp-block-uagb-image{margin-top: 25px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;text-align: center;justify-content: center;align-self: center;}.uagb-block-33a302d6 .wp-block-uagb-image__figure{align-items: center;}.uagb-block-33a302d6.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;border-top-left-radius: 100px;border-top-right-radius: 100px;border-bottom-left-radius: 100px;border-bottom-right-radius: 100px;}.uagb-block-33a302d6.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-33a302d6.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;border-top-left-radius: 100px;border-top-right-radius: 100px;border-bottom-left-radius: 100px;border-bottom-right-radius: 100px;}.uagb-block-33a302d6.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;border-top-left-radius: 100px;border-top-right-radius: 100px;border-bottom-left-radius: 100px;border-bottom-right-radius: 100px;}.uagb-block-33a302d6.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-33a302d6.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-33a302d6.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-33a302d6.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-33a302d6.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-33a302d6.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-33a302d6.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.uagb-block-33a302d6.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-33a302d6.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-33a302d6.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-33a302d6.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}.wp-block-uagb-advanced-heading.uagb-block-0bf22f7e.wp-block-uagb-advanced-heading {text-align: center;}.wp-block-uagb-advanced-heading.uagb-block-0bf22f7e.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-0bf22f7e.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-0bf22f7e.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-0bf22f7e.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.uagb-block-1ee7b860.wp-block-uagb-image{margin-top: 0px;margin-right: 0px;margin-bottom: 10px;margin-left: 0px;text-align: center;justify-content: center;align-self: center;}.uagb-block-1ee7b860 .wp-block-uagb-image__figure{align-items: center;}.uagb-block-1ee7b860.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-1ee7b860.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-1ee7b860.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-1ee7b860.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;}.uagb-block-1ee7b860.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-1ee7b860.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-1ee7b860.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-1ee7b860.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-1ee7b860.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-1ee7b860.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-1ee7b860.wp-block-uagb-image .wp-block-uagb-image__figure img{width: 20px;height: 20px;}.uagb-block-1ee7b860.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-1ee7b860.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-1ee7b860.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-1ee7b860.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}.wp-block-uagb-advanced-heading.uagb-block-60dc4972.wp-block-uagb-advanced-heading {text-align: center;padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-60dc4972.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-60dc4972.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-60dc4972.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-60dc4972.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}@media only screen and (max-width: 976px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-2c66ecf5{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-2c66ecf5 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-2c66ecf5{padding-top: 190px;padding-bottom: 0px;padding-left: 25px;padding-right: 25px;margin-top:  !important;margin-bottom:  !important;order: initial;background-color: var(--ast-global-color-4);;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-b168e446{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-b168e446 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;align-items: stretch;}.wp-block-uagb-container.uagb-block-b168e446{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 20px !important;margin-left: 0px;margin-right: 0px;order: initial;align-items: stretch;}.wp-block-uagb-advanced-heading.uagb-block-3ba1534c .uagb-heading-text{font-size: 110px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-c9b97a85{max-width: 40%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-c9b97a85 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: flex-end;}.wp-block-uagb-container.uagb-block-c9b97a85{padding-top: 50px;padding-bottom: 0px;padding-left: 0px;padding-right: 50px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;flex-direction: column;align-items: flex-end;}.wp-block-uagb-container.uagb-block-c9b97a85.wp-block-uagb-container > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not( .spectra-container-link-overlay ):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-lottie):not(.uagb-container-inner-blocks-wrap){width: 100%;}.wp-block-uagb-container.uagb-block-c9b97a85.wp-block-uagb-container > .uagb-container-inner-blocks-wrap > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not(.spectra-image-gallery__control-lightbox){width: 100%;} .uagb-block-2a6b046d.uagb-icon-wrapper svg{width: 90px;height: 90px;} .uagb-block-2a6b046d.uagb-icon-wrapper .uagb-svg-wrapper{display: inline-flex;}.wp-block-uagb-advanced-heading.uagb-block-43224597.wp-block-uagb-advanced-heading {padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 25px;}.uagb-block-98684736.wp-block-uagb-image .wp-block-uagb-image__figure img{width: 150px;height: auto;}.uagb-block-98684736.wp-block-uagb-image{margin-top: -85px;margin-right: -70px;margin-bottom: 0px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-b4c87933{max-width: 600px;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-b4c87933 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-b4c87933{padding-top: 0px;padding-bottom: 237px;padding-left: 100px;padding-right: 100px;margin-top: -67px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;}.uagb-block-a0cd5a3e.wp-block-uagb-image-gallery{padding:    ;}.uagb-block-a0cd5a3e .spectra-image-gallery__control-arrows--carousel{border-style: none;}.uagb-block-a0cd5a3e .spectra-image-gallery__control-button{padding:    ;}.uagb-block-a0cd5a3e .spectra-image-gallery__layout--grid{grid-gap: 0px;}.uagb-block-a0cd5a3e .spectra-image-gallery__layout--isogrid{margin: 0px;}.uagb-block-a0cd5a3e .spectra-image-gallery__layout--isogrid .spectra-image-gallery__media-wrapper--isotope{padding: 0px;}.uagb-block-a0cd5a3e .spectra-image-gallery__layout--masonry{margin: 0px;}.uagb-block-a0cd5a3e .spectra-image-gallery__layout--masonry .spectra-image-gallery__media-wrapper--isotope{padding: 0px;}.uagb-block-a0cd5a3e .spectra-image-gallery__layout--carousel .spectra-image-gallery__media-wrapper{padding: 0px 0px;}.uagb-block-a0cd5a3e .spectra-image-gallery__layout--carousel .slick-list{margin: 0px 0px;}.uagb-block-a0cd5a3e .spectra-image-gallery__layout--tiled{grid-gap: 0px;}.uagb-block-a0cd5a3e .spectra-image-gallery__media-thumbnail-caption{padding: 8px 8px 8px 8px;}.uagb-block-a0cd5a3e+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main.swiper-rtl .swiper-button-prev{left: auto;}.uagb-block-a0cd5a3e+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main.swiper-rtl .swiper-button-next{right: auto;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-fd9a5843{width: 100%;}.wp-block-uagb-container.uagb-block-fd9a5843{padding-top: 0px;padding-bottom: 115px;padding-left: 0px;padding-right: 0px;margin-top: -165px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;background-image: url(https:\/\/websitedemos.net\/cake-shop-09\/wp-content\/uploads\/sites\/1134\/2022\/10\/bg-03-free-img.jpg);background-clip: padding-box;}.uagb-block-5306d181.wp-block-uagb-image .wp-block-uagb-image__figure img{width: 384px;height: 280px;}.uagb-block-5306d181.wp-block-uagb-image{margin-top: -10%;margin-right: 0%;margin-bottom: 0%;margin-left: 0%;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-724d4bb0{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-724d4bb0 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-724d4bb0{padding-top: 0px;padding-bottom: 0px;padding-left: 30px;padding-right: 30px;margin-top: -40px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;}.uagb-block-8f60856a.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-8f60856a.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-8f60856a.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-8f60856a .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-8f60856a .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-8f60856a .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-8f60856a .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-8f60856a .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-8f60856a.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-8f60856a.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-aace127a.wp-block-uagb-advanced-heading {margin-bottom: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-2727fa58{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-2727fa58 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;row-gap: 50px;}.wp-block-uagb-container.uagb-block-2727fa58{padding-top: 0px;padding-bottom: 0px;padding-left: 30px;padding-right: 30px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;background-color: var(--ast-global-color-4);;row-gap: 50px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-5b0d9f3e{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-5b0d9f3e > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;align-items: center;column-gap: 14px;}.wp-block-uagb-container.uagb-block-5b0d9f3e{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 10px;margin-right: 10px;order: initial;align-items: center;column-gap: 14px;}.uagb-block-bb367c1b .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 25px;margin-left: 0px;margin-right: 0px;}.uagb-block-bb367c1b.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 10px;}.uagb-block-bb367c1b.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-bb367c1b.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-bb367c1b.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-bb367c1b .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-bb367c1b .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-bb367c1b .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-bb367c1b .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-bb367c1b .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-bb367c1b.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-bb367c1b.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-a3cec12e .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 25px;margin-left: 0px;margin-right: 0px;}.uagb-block-a3cec12e.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 10px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-a3cec12e.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-a3cec12e.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-a3cec12e.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-a3cec12e .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-a3cec12e .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-a3cec12e .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-a3cec12e .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-a3cec12e .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-a3cec12e.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-a3cec12e.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-861651c6 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 25px;margin-left: 0px;margin-right: 0px;}.uagb-block-861651c6.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 10px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-861651c6.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-861651c6.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-861651c6.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-861651c6 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-861651c6 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-861651c6 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-861651c6 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-861651c6 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-861651c6.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-861651c6.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-2ffcd874{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-2ffcd874 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;align-items: stretch;column-gap: 14px;}.wp-block-uagb-container.uagb-block-2ffcd874{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 10px;margin-right: 10px;order: initial;align-items: stretch;column-gap: 14px;}.uagb-block-5c24b108 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 25px;margin-left: 0px;margin-right: 0px;}.uagb-block-5c24b108.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 10px;}.uagb-block-5c24b108.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-5c24b108.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-5c24b108.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-5c24b108 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-5c24b108 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-5c24b108 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-5c24b108 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-5c24b108 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-5c24b108.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-5c24b108.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-073479f1 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 25px;margin-left: 0px;margin-right: 0px;}.uagb-block-073479f1.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 10px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-073479f1.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-073479f1.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-073479f1.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-073479f1 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-073479f1 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-073479f1 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-073479f1 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-073479f1 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-073479f1.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-073479f1.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-d6915861 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 25px;margin-left: 0px;margin-right: 0px;}.uagb-block-d6915861.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 10px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-d6915861.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-d6915861.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-d6915861.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-d6915861 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-d6915861 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-d6915861 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-d6915861 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-d6915861 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-d6915861.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-d6915861.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-76587460{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-76587460 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-76587460{padding-top: 50px;padding-bottom: 150px;padding-left: 25px;padding-right: 25px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;background-color: var(--ast-global-color-4);;}.uagb-block-33a302d6.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.uagb-block-1ee7b860.wp-block-uagb-image .wp-block-uagb-image__figure img{width: 20px;height: auto;}.wp-block-uagb-advanced-heading.uagb-block-60dc4972.wp-block-uagb-advanced-heading {padding-top: 0px;padding-right: 75px;padding-bottom: 0px;padding-left: 75px;}}@media only screen and (max-width: 767px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-2c66ecf5{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-2c66ecf5 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;align-items: flex-start;flex-wrap: wrap;row-gap: 0px;}.wp-block-uagb-container.uagb-block-2c66ecf5{padding-top: 166px;padding-bottom: 20px;padding-left: 30px;padding-right: 30px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;row-gap: 0px;order: initial;background-color: var(--ast-global-color-4);;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-b168e446{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-b168e446 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: center;justify-content: center;flex-wrap: wrap;row-gap: 0px;}.wp-block-uagb-container.uagb-block-b168e446{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 20px !important;margin-left: 0px;margin-right: 0px;row-gap: 0px;order: initial;flex-direction: row;align-items: center;justify-content: center;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-b168e446.wp-block-uagb-container > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not( .spectra-container-link-overlay ):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-lottie):not(.uagb-container-inner-blocks-wrap){width: 100%;}.wp-block-uagb-container.uagb-block-b168e446.wp-block-uagb-container > .uagb-container-inner-blocks-wrap > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not(.spectra-image-gallery__control-lightbox){width: 100%;}.wp-block-uagb-advanced-heading.uagb-block-3ba1534c.wp-block-uagb-advanced-heading {padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-3ba1534c .uagb-heading-text{font-size: 50px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-c9b97a85{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-c9b97a85 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: flex-start;justify-content: flex-start;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-c9b97a85{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;flex-direction: row;align-items: flex-start;justify-content: flex-start;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-c9b97a85.wp-block-uagb-container > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not( .spectra-container-link-overlay ):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-lottie):not(.uagb-container-inner-blocks-wrap){width: 100%;}.wp-block-uagb-container.uagb-block-c9b97a85.wp-block-uagb-container > .uagb-container-inner-blocks-wrap > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not(.spectra-image-gallery__control-lightbox){width: 100%;} .uagb-block-2a6b046d.uagb-icon-wrapper{text-align: left;} .uagb-block-2a6b046d.uagb-icon-wrapper .uagb-svg-wrapper{display: inline-flex;}.wp-block-uagb-advanced-heading.uagb-block-43224597.wp-block-uagb-advanced-heading {text-align: left;padding-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-bb758da2.wp-block-uagb-advanced-heading {text-align: left;}.uagb-block-98684736.wp-block-uagb-image .wp-block-uagb-image__figure img{width: 100px;height: auto;}.uagb-block-98684736.wp-block-uagb-image{margin-top: -40px;margin-right: -50px;margin-bottom: 0px;margin-left: 0px;text-align: left;justify-content: flex-start;align-self: flex-start;}.uagb-block-98684736 .wp-block-uagb-image__figure{align-items: flex-start;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-b4c87933{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-b4c87933 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-b4c87933{padding-top: 20px;padding-bottom: 200px;padding-left: 100px;padding-right: 100px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;flex-wrap: wrap;}.uagb-block-a0cd5a3e.wp-block-uagb-image-gallery{padding:    ;}.uagb-block-a0cd5a3e .spectra-image-gallery__control-arrows--carousel{border-style: none;}.uagb-block-a0cd5a3e .spectra-image-gallery__control-button{padding:    ;}.uagb-block-a0cd5a3e .spectra-image-gallery__layout--grid{grid-gap: 3px;}.uagb-block-a0cd5a3e .spectra-image-gallery__layout--isogrid{margin: -1.5px;}.uagb-block-a0cd5a3e .spectra-image-gallery__layout--isogrid .spectra-image-gallery__media-wrapper--isotope{padding: 1.5px;}.uagb-block-a0cd5a3e .spectra-image-gallery__layout--masonry{margin: -1.5px;}.uagb-block-a0cd5a3e .spectra-image-gallery__layout--masonry .spectra-image-gallery__media-wrapper--isotope{padding: 1.5px;}.uagb-block-a0cd5a3e .spectra-image-gallery__layout--carousel .spectra-image-gallery__media-wrapper{padding: 0px 3px;}.uagb-block-a0cd5a3e .spectra-image-gallery__layout--carousel .slick-list{margin: 0px -3px;}.uagb-block-a0cd5a3e .spectra-image-gallery__layout--tiled .spectra-image-gallery__media-wrapper{grid-gap: 3px;}.uagb-block-a0cd5a3e .spectra-image-gallery__media-thumbnail-caption{padding: 8px 8px 8px 8px;}.uagb-block-a0cd5a3e+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main.swiper-rtl .swiper-button-prev{left: auto;}.uagb-block-a0cd5a3e+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main.swiper-rtl .swiper-button-next{right: auto;}.uagb-block-a0cd5a3e+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main .swiper-button-prev::after{font-size: 24px;}.uagb-block-a0cd5a3e+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main .swiper-button-next::after{font-size: 24px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-fd9a5843{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-block-fd9a5843{padding-top: 0px;padding-bottom: 100px;padding-left: 0px;padding-right: 0px;margin-top: -165px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;row-gap: 0px;order: initial;background-image: url(https:\/\/websitedemos.net\/cake-shop-09\/wp-content\/uploads\/sites\/1134\/2022\/10\/bg-03-free-img.jpg);background-clip: padding-box;flex-wrap: wrap;}.uagb-block-5306d181.wp-block-uagb-image .wp-block-uagb-image__figure img{width: 320px;height: auto;}.uagb-block-5306d181.wp-block-uagb-image{margin-top: -10%;margin-right: 0%;margin-bottom: 0%;margin-left: 0%;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-724d4bb0{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-724d4bb0 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;row-gap: 20px;}.wp-block-uagb-container.uagb-block-724d4bb0{padding-top: 50px;padding-bottom: 0px;padding-left: 30px;padding-right: 30px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;row-gap: 20px;order: initial;flex-wrap: wrap;}.wp-block-uagb-advanced-heading.uagb-block-3e834e65.wp-block-uagb-advanced-heading {padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;}.uagb-block-8f60856a.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 20px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-8f60856a.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-8f60856a.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-8f60856a .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-8f60856a .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-8f60856a.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-8f60856a .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-8f60856a .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-8f60856a .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-8f60856a.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-8f60856a.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-aace127a.wp-block-uagb-advanced-heading {padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-2727fa58{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-2727fa58 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;align-items: flex-start;flex-wrap: wrap;row-gap: 50px;}.wp-block-uagb-container.uagb-block-2727fa58{padding-top: 0px;padding-bottom: 0px;padding-left: 30px;padding-right: 30px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;row-gap: 50px;order: initial;background-color: var(--ast-global-color-4);;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-5b0d9f3e{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-5b0d9f3e > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: wrap;align-content: center;row-gap: 50px;}.wp-block-uagb-container.uagb-block-5b0d9f3e{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;row-gap: 50px;order: initial;flex-direction: column;align-items: center;justify-content: center;flex-wrap: wrap;align-content: center;}.wp-block-uagb-container.uagb-block-5b0d9f3e.wp-block-uagb-container > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not( .spectra-container-link-overlay ):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-lottie):not(.uagb-container-inner-blocks-wrap){width: 100%;}.wp-block-uagb-container.uagb-block-5b0d9f3e.wp-block-uagb-container > .uagb-container-inner-blocks-wrap > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not(.spectra-image-gallery__control-lightbox){width: 100%;}.uagb-block-bb367c1b.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 0px;margin-top: 0px;margin-left: 20px;margin-right: 20px;}.uagb-block-bb367c1b.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-bb367c1b.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-bb367c1b .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-bb367c1b .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-bb367c1b.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-bb367c1b .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-bb367c1b .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-bb367c1b .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-bb367c1b.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-bb367c1b.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-a3cec12e.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 0px;margin-top: 0px;margin-left: 20px;margin-right: 20px;}.uagb-block-a3cec12e.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-a3cec12e.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-a3cec12e .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-a3cec12e .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-a3cec12e.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-a3cec12e .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-a3cec12e .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-a3cec12e .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-a3cec12e.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-a3cec12e.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-861651c6.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 0px;margin-top: 0px;margin-left: 20px;margin-right: 20px;}.uagb-block-861651c6.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-861651c6.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-861651c6 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-861651c6 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-861651c6.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-861651c6 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-861651c6 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-861651c6 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-861651c6.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-861651c6.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-2ffcd874{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-2ffcd874 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: stretch;justify-content: center;flex-wrap: wrap;align-content: center;row-gap: 50px;}.wp-block-uagb-container.uagb-block-2ffcd874{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;row-gap: 50px;order: initial;flex-direction: column;align-items: stretch;justify-content: center;flex-wrap: wrap;align-content: center;}.wp-block-uagb-container.uagb-block-2ffcd874.wp-block-uagb-container > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not( .spectra-container-link-overlay ):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-lottie):not(.uagb-container-inner-blocks-wrap){width: 100%;}.wp-block-uagb-container.uagb-block-2ffcd874.wp-block-uagb-container > .uagb-container-inner-blocks-wrap > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not(.spectra-image-gallery__control-lightbox){width: 100%;}.uagb-block-5c24b108.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 0px;margin-top: 0px;margin-left: 20px;margin-right: 20px;}.uagb-block-5c24b108.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-5c24b108.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-5c24b108 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-5c24b108 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-5c24b108.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-5c24b108 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-5c24b108 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-5c24b108 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-5c24b108.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-5c24b108.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-073479f1.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 0px;margin-top: 0px;margin-left: 20px;margin-right: 20px;}.uagb-block-073479f1.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-073479f1.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-073479f1 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-073479f1 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-073479f1.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-073479f1 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-073479f1 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-073479f1 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-073479f1.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-073479f1.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-d6915861.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 0px;margin-top: 0px;margin-left: 20px;margin-right: 20px;}.uagb-block-d6915861.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-d6915861.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-d6915861 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-d6915861 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-d6915861.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-d6915861 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-d6915861 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-d6915861 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-d6915861.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-d6915861.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-76587460{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-76587460 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-76587460{padding-top: 60px;padding-bottom: 60px;padding-left: 20px;padding-right: 20px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;background-color: var(--ast-global-color-4);;}.uagb-block-33a302d6.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.uagb-block-33a302d6.wp-block-uagb-image{margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;}.uagb-block-1ee7b860.wp-block-uagb-image .wp-block-uagb-image__figure img{width: 20px;height: auto;}.wp-block-uagb-advanced-heading.uagb-block-60dc4972.wp-block-uagb-advanced-heading {padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}}.uag-blocks-common-selector{z-index:var(--z-index-desktop) !important}@media (max-width: 976px){.uag-blocks-common-selector{z-index:var(--z-index-tablet) !important}}@media (max-width: 767px){.uag-blocks-common-selector{z-index:var(--z-index-mobile) !important}}\n.wp-block-uagb-advanced-heading.uagb-block-f8e0d165.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-f8e0d165.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-f8e0d165.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-f8e0d165.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-f7bb4608.wp-block-uagb-advanced-heading {margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-f7bb4608.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-f7bb4608.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-f7bb4608.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-f7bb4608.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-371c34b3.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-371c34b3.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-371c34b3.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-371c34b3.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-8d7523c9.wp-block-uagb-advanced-heading {margin-top: -10px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-8d7523c9.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-8d7523c9.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-8d7523c9.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-8d7523c9.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.uagb-block-ebcc9243.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-ebcc9243.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-ebcc9243.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-ebcc9243.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;}.uagb-block-ebcc9243.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-ebcc9243.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-ebcc9243.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-ebcc9243.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-ebcc9243.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-ebcc9243.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-ebcc9243.wp-block-uagb-image .wp-block-uagb-image__figure img{width: 185px;height: auto;}.uagb-block-ebcc9243.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-ebcc9243.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-ebcc9243.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-ebcc9243.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}@media only screen and (max-width: 976px) {.uagb-block-ebcc9243.wp-block-uagb-image .wp-block-uagb-image__figure img{width: 185px;height: auto;}.uagb-block-ebcc9243.wp-block-uagb-image{text-align: left;justify-content: flex-start;align-self: flex-start;}.uagb-block-ebcc9243 .wp-block-uagb-image__figure{align-items: flex-start;}}@media only screen and (max-width: 767px) {.uagb-block-ebcc9243.wp-block-uagb-image .wp-block-uagb-image__figure img{width: 185px;height: auto;}.uagb-block-ebcc9243.wp-block-uagb-image{text-align: center;justify-content: center;align-self: center;}.uagb-block-ebcc9243 .wp-block-uagb-image__figure{align-items: center;}}.wp-block-uagb-advanced-heading.uagb-block-7b6bbe8d.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-7b6bbe8d.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-7b6bbe8d.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-7b6bbe8d.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-7b6bbe8d .uagb-heading-text{margin-bottom: 10px;}@media only screen and (max-width: 976px) {.wp-block-uagb-advanced-heading.uagb-block-7b6bbe8d.wp-block-uagb-advanced-heading {text-align: left;}.wp-block-uagb-advanced-heading.uagb-block-7b6bbe8d .uagb-heading-text{margin-bottom: 5px;}}@media only screen and (max-width: 767px) {.wp-block-uagb-advanced-heading.uagb-block-7b6bbe8d.wp-block-uagb-advanced-heading {text-align: center;}}\";s:2:\"js\";s:2235:\"document.addEventListener(\"DOMContentLoaded\", function(){ \t\t\t\twindow.addEventListener( 'DOMContentLoaded', () => {\n\t\t\t\t\tconst blockScope = document.querySelector( '.uagb-block-2a6b046d' );\n\t\t\t\t\tif ( ! blockScope ) {\n\t\t\t\t\t\treturn;\n\t\t\t\t\t}\n\n\t\t\t\t\tconst anchorElement = blockScope.querySelector('a');\n\t\t\t\t\tif (!anchorElement) {\n\t\t\t\t\t\treturn;\n\t\t\t\t\t} \n\n\t\t\t\t\t \n\t\t\t\t\tblockScope.addEventListener('keydown', (event) => {\n\t\t\t\t\t\tif ( 13 === event.keyCode || 32 === event.keyCode ) {\n\t\t\t\t\t\t\tevent.preventDefault();\n\t\t\t\t\t\t\t \n\t\t\t\t\t\t\tanchorElement.click();\t\n\t\t\t\t\t\t}\n\t\t\t\t\t} );\n\t\t\t\t} );\n\t\t\tjQuery(document).ready(function () {\n\t\t\t\tlet scope = jQuery(\".wp-block-uagb-image-gallery.uagb-block-a0cd5a3e\");\n\t\t\t\tif ( scope.length ) { \n\t\t\t\t\tscope.css(\"visibility\", \"visible\");\n\t\t\t\t\tlet getSlickCarousel = scope.find(\".uagb-slick-carousel\");\n\t\t\t\t\tif( getSlickCarousel.length ) {\n\t\t\t\t\t\tgetSlickCarousel.slick({\"arrows\":false,\"dots\":false,\"initialSlide\":0,\"infinite\":true,\"autoplay\":true,\"autoplaySpeed\":1500,\"pauseOnHover\":true,\"speed\":500,\"slidesToShow\":1,\"prevArrow\":\"<button type='button' data-role='none' class='spectra-image-gallery__control-arrows spectra-image-gallery__control-arrows--carousel slick-prev slick-arrow' aria-label='Previous' tabindex='0' role='button'><svg xmlns='http:\/\/www.w3.org\/2000\/svg' viewBox='0 0 256 512' width='24' height='24'><path d='M31.7 239l136-136c9.4-9.4 24.6-9.4 33.9 0l22.6 22.6c9.4 9.4 9.4 24.6 0 33.9L127.9 256l96.4 96.4c9.4 9.4 9.4 24.6 0 33.9L201.7 409c-9.4 9.4-24.6 9.4-33.9 0l-136-136c-9.5-9.4-9.5-24.6-.1-34z'><\/path><\/svg><\/button>\",\"nextArrow\":\"<button type='button' data-role='none' class='spectra-image-gallery__control-arrows spectra-image-gallery__control-arrows--carousel slick-next slick-arrow' aria-label='Previous' tabindex='0' role='button'><svg xmlns='http:\/\/www.w3.org\/2000\/svg' viewBox='0 0 256 512' width='24' height='24'><path d='M224.3 273l-136 136c-9.4 9.4-24.6 9.4-33.9 0l-22.6-22.6c-9.4-9.4-9.4-24.6 0-33.9l96.4-96.4-96.4-96.4c-9.4-9.4-9.4-24.6 0-33.9L54.3 103c9.4-9.4 24.6-9.4 33.9 0l136 136c9.5 9.4 9.5 24.6.1 34z'><\/path><\/svg><\/button>\",\"rtl\":false,\"responsive\":[{\"breakpoint\":1024,\"settings\":{\"slidesToShow\":3}},{\"breakpoint\":767,\"settings\":{\"slidesToShow\":1}}]});\n\t\t\t\t\t}\n\t\t\t\t}\n\t\t\t}); });\";s:18:\"current_block_list\";a:13:{i:0;s:14:\"uagb\/container\";i:2;s:21:\"uagb\/advanced-heading\";i:4;s:9:\"uagb\/icon\";i:5;s:10:\"uagb\/image\";i:7;s:18:\"uagb\/image-gallery\";i:8;s:13:\"uagb\/info-box\";i:9;s:11:\"core\/search\";i:10;s:10:\"core\/group\";i:11;s:12:\"core\/heading\";i:12;s:17:\"core\/latest-posts\";i:13;s:20:\"core\/latest-comments\";i:14;s:13:\"core\/archives\";i:15;s:15:\"core\/categories\";}s:8:\"uag_flag\";b:1;s:11:\"uag_version\";s:10:\"1774933245\";s:6:\"gfonts\";a:0:{}s:10:\"gfonts_url\";s:0:\"\";s:12:\"gfonts_files\";a:0:{}s:14:\"uag_faq_layout\";b:0;}","_uag_css_file_name":"uag-css-6.css","_uag_js_file_name":"uag-js-6.js"},"astra-page-options-data":{"elementor_load_fa4_shim":false},"original_content":"<!-- wp:uagb\/container {\"block_id\":\"2c66ecf5\",\"innerContentCustomWidthDesktop\":1140,\"alignItemsMobile\":\"flex-start\",\"backgroundType\":\"color\",\"backgroundSizeTablet\":\"cover\",\"backgroundSizeMobile\":\"cover\",\"backgroundColor\":\"var(\\u002d\\u002dast-global-color-4)\",\"topPaddingDesktop\":250,\"leftPaddingDesktop\":40,\"rightPaddingDesktop\":40,\"topPaddingTablet\":190,\"bottomPaddingTablet\":0,\"leftPaddingTablet\":25,\"rightPaddingTablet\":25,\"topPaddingMobile\":166,\"bottomPaddingMobile\":20,\"leftPaddingMobile\":30,\"rightPaddingMobile\":30,\"paddingLink\":false,\"topMarginMobile\":0,\"bottomMarginMobile\":0,\"leftMarginMobile\":0,\"rightMarginMobile\":0,\"marginLink\":false,\"variationSelected\":true,\"rowGapDesktop\":0,\"rowGapMobile\":0,\"columnGapDesktop\":0,\"isBlockRootParent\":true,\"zIndex\":-1,\"zIndexTablet\":-1,\"zIndexMobile\":-1} -->\n<div class=\"wp-block-uagb-container uag-blocks-common-selector uagb-block-2c66ecf5 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\"><!-- wp:uagb\/container {\"block_id\":\"b168e446\",\"directionDesktop\":\"row\",\"directionMobile\":\"row\",\"alignItemsTablet\":\"stretch\",\"alignItemsMobile\":\"center\",\"justifyContentMobile\":\"center\",\"topMarginDesktop\":0,\"bottomMarginDesktop\":0,\"leftMarginDesktop\":0,\"rightMarginDesktop\":0,\"topMarginTablet\":0,\"bottomMarginTablet\":20,\"leftMarginTablet\":0,\"rightMarginTablet\":0,\"marginLink\":false,\"variationSelected\":true,\"rowGapDesktop\":0,\"rowGapMobile\":0,\"columnGapDesktop\":0,\"zIndex\":-1} -->\n<div class=\"wp-block-uagb-container uag-blocks-common-selector uagb-block-b168e446\"><!-- wp:uagb\/advanced-heading {\"block_id\":\"3ba1534c\",\"classMigrate\":true,\"headingTag\":\"h1\",\"headFontSize\":160,\"headFontSizeTablet\":110,\"headFontSizeMobile\":50,\"blockTopPaddingMobile\":0,\"blockRightPaddingMobile\":0,\"blockLeftPaddingMobile\":0,\"blockBottomPaddingMobile\":0,\"blockTopMarginMobile\":0,\"blockRightMarginMobile\":0,\"blockLeftMarginMobile\":0,\"blockBottomMarginMobile\":0} -->\n<div class=\"wp-block-uagb-advanced-heading uagb-block-3ba1534c\"><h1 class=\"uagb-heading-text\">Cakes, Pies &amp; Tarts<\/h1><\/div>\n<!-- \/wp:uagb\/advanced-heading -->\n\n<!-- wp:uagb\/container {\"block_id\":\"c9b97a85\",\"widthDesktop\":25,\"widthTablet\":40,\"directionTablet\":\"column\",\"directionMobile\":\"row\",\"alignItemsDesktop\":\"flex-end\",\"alignItemsTablet\":\"flex-end\",\"alignItemsMobile\":\"flex-start\",\"justifyContentMobile\":\"flex-start\",\"topPaddingDesktop\":50,\"topPaddingTablet\":50,\"rightPaddingTablet\":50,\"topPaddingMobile\":0,\"bottomPaddingMobile\":0,\"leftPaddingMobile\":0,\"rightPaddingMobile\":0,\"paddingLink\":false,\"topMarginDesktop\":0,\"bottomMarginDesktop\":0,\"leftMarginDesktop\":0,\"rightMarginDesktop\":0,\"marginLink\":false,\"variationSelected\":true,\"rowGapDesktop\":0,\"columnGapDesktop\":0,\"widthSetByUser\":true,\"zIndex\":10} -->\n<div class=\"wp-block-uagb-container uag-blocks-common-selector uagb-block-c9b97a85\"><!-- wp:uagb\/icon {\"icon\":\"quote-left\",\"iconSize\":75,\"iconSizeTablet\":90,\"align\":\"right\",\"alignMobile\":\"left\",\"iconColor\":\"var(\\u002d\\u002dast-global-color-0)\",\"block_id\":\"2a6b046d\",\"iconTopPadding\":0,\"iconRightPadding\":0,\"iconLeftPadding\":0,\"iconBottomPadding\":0,\"iconPaddingLink\":true,\"iconTopMargin\":0,\"iconRightMargin\":0,\"iconLeftMargin\":0,\"iconBottomMargin\":0} \/-->\n\n<!-- wp:uagb\/advanced-heading {\"block_id\":\"43224597\",\"classMigrate\":true,\"headingAlign\":\"right\",\"headingAlignMobile\":\"left\",\"headingTag\":\"p\",\"headSpace\":0,\"headSpaceTablet\":20,\"blockLeftPadding\":50,\"blockTopPaddingTablet\":0,\"blockRightPaddingTablet\":0,\"blockLeftPaddingTablet\":25,\"blockBottomPaddingTablet\":0,\"blockLeftPaddingMobile\":0,\"blockBottomMargin\":20} -->\n<div class=\"wp-block-uagb-advanced-heading uagb-block-43224597\"><p class=\"uagb-heading-text\">Lorem ipsum dolor sit amet, consectetur adipiscing elit. Ut elit tellus, luctus nec ullamcorper mattis, pulvinar dapibus leo.<\/p><\/div>\n<!-- \/wp:uagb\/advanced-heading -->\n\n<!-- wp:uagb\/advanced-heading {\"block_id\":\"bb758da2\",\"classMigrate\":true,\"headingAlign\":\"right\",\"headingAlignMobile\":\"left\",\"headingTag\":\"h5\",\"headSpace\":0,\"headSpaceTablet\":20,\"blockTopPadding\":8,\"blockRightPadding\":0,\"blockLeftPadding\":0,\"blockBottomPadding\":0,\"blockBottomMargin\":20} -->\n<div class=\"wp-block-uagb-advanced-heading uagb-block-bb758da2\"><h5 class=\"uagb-heading-text\">Susan Lee<\/h5><\/div>\n<!-- \/wp:uagb\/advanced-heading -->\n\n<!-- wp:uagb\/image {\"block_id\":\"98684736\",\"url\":\"https:\/\/websitedemos.net\/cake-shop-07\/wp-content\/uploads\/sites\/1134\/2022\/10\/signature-free-img.png\",\"urlTablet\":\"https:\/\/websitedemos.net\/cake-shop-07\/wp-content\/uploads\/sites\/1134\/2022\/10\/signature-free-img-150x150.png\",\"urlMobile\":\"https:\/\/websitedemos.net\/cake-shop-07\/wp-content\/uploads\/sites\/1134\/2022\/10\/signature-free-img.png\",\"align\":\"right\",\"alignMobile\":\"left\",\"id\":54,\"linkDestination\":\"none\",\"width\":185,\"widthTablet\":150,\"widthMobile\":100,\"height\":194,\"heightTablet\":150,\"naturalWidth\":185,\"naturalHeight\":194,\"sizeSlug\":\"full\",\"sizeSlugTablet\":\"thumbnail\",\"sizeSlugMobile\":\"full\",\"imageTopMargin\":-85,\"imageRightMargin\":-100,\"imageLeftMargin\":0,\"imageBottomMargin\":0,\"imageTopMarginTablet\":-85,\"imageRightMarginTablet\":-70,\"imageLeftMarginTablet\":0,\"imageBottomMarginTablet\":0,\"imageTopMarginMobile\":-40,\"imageRightMarginMobile\":-50,\"imageLeftMarginMobile\":0,\"imageBottomMarginMobile\":0,\"imageMarginLink\":false,\"className\":\"alignright\",\"zIndex\":10} -->\n<div class=\"wp-block-uagb-image alignright uagb-block-98684736 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-right uag-blocks-common-selector\" style=\"--z-index-desktop:10;;--z-index-tablet:undefined;;--z-index-mobile:undefined;\"><figure class=\"wp-block-uagb-image__figure\"><img srcset=\"https:\/\/websitedemos.net\/cake-shop-07\/wp-content\/uploads\/sites\/1134\/2022\/10\/signature-free-img.png ,https:\/\/websitedemos.net\/cake-shop-07\/wp-content\/uploads\/sites\/1134\/2022\/10\/signature-free-img-150x150.png 780w, https:\/\/websitedemos.net\/cake-shop-07\/wp-content\/uploads\/sites\/1134\/2022\/10\/signature-free-img.png 360w\" sizes=\"(max-width: 480px) 150px\" src=\"https:\/\/websitedemos.net\/cake-shop-07\/wp-content\/uploads\/sites\/1134\/2022\/10\/signature-free-img.png\" alt=\"\" class=\"uag-image-54\" width=\"185\" height=\"194\" title=\"\" loading=\"lazy\" role=\"img\"\/><\/figure><\/div>\n<!-- \/wp:uagb\/image --><\/div>\n<!-- \/wp:uagb\/container --><\/div>\n<!-- \/wp:uagb\/container -->\n\n<!-- wp:uagb\/container {\"block_id\":\"b4c87933\",\"widthDesktop\":600,\"widthTablet\":600,\"widthType\":\"px\",\"topPaddingTablet\":0,\"bottomPaddingTablet\":237,\"leftPaddingTablet\":100,\"rightPaddingTablet\":100,\"topPaddingMobile\":20,\"bottomPaddingMobile\":200,\"paddingLink\":false,\"topMarginDesktop\":-130,\"bottomMarginDesktop\":500,\"leftMarginDesktop\":0,\"rightMarginDesktop\":0,\"topMarginTablet\":-67,\"bottomMarginTablet\":0,\"leftMarginTablet\":0,\"rightMarginTablet\":0,\"topMarginMobile\":0,\"bottomMarginMobile\":0,\"leftMarginMobile\":0,\"rightMarginMobile\":0,\"marginLink\":false,\"variationSelected\":true,\"rowGapDesktop\":0,\"columnGapDesktop\":0,\"widthSetByUser\":true,\"widthTypeTablet\":\"px\",\"zIndex\":3} -->\n<div class=\"wp-block-uagb-container uag-blocks-common-selector uagb-block-b4c87933\"><!-- wp:uagb\/image-gallery {\"block_id\":\"a0cd5a3e\",\"classMigrate\":true,\"readyToRender\":true,\"mediaGallery\":[{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/websitedemos.net\/cake-shop-07\/wp-content\/uploads\/sites\/1134\/2022\/10\/product-01-free-img-150x150.png\",\"orientation\":\"landscape\"},\"medium\":{\"height\":300,\"width\":291,\"url\":\"https:\/\/websitedemos.net\/cake-shop-07\/wp-content\/uploads\/sites\/1134\/2022\/10\/product-01-free-img-291x300.png\",\"orientation\":\"portrait\"},\"full\":{\"url\":\"https:\/\/websitedemos.net\/cake-shop-07\/wp-content\/uploads\/sites\/1134\/2022\/10\/product-01-free-img.png\",\"height\":858,\"width\":833,\"orientation\":\"portrait\"}},\"mime\":\"image\/png\",\"type\":\"image\",\"subtype\":\"png\",\"id\":62,\"url\":\"https:\/\/websitedemos.net\/cake-shop-07\/wp-content\/uploads\/sites\/1134\/2022\/10\/product-01-free-img.png\",\"alt\":\"\",\"link\":\"https:\/\/websitedemos.net\/cake-shop-07\/home\/product-01-free-img\/\",\"caption\":\"\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/websitedemos.net\/cake-shop-07\/wp-content\/uploads\/sites\/1134\/2023\/04\/product-02-free-img-150x150.png\",\"orientation\":\"landscape\"},\"medium\":{\"height\":300,\"width\":291,\"url\":\"https:\/\/websitedemos.net\/cake-shop-07\/wp-content\/uploads\/sites\/1134\/2023\/04\/product-02-free-img-291x300.png\",\"orientation\":\"portrait\"},\"full\":{\"url\":\"https:\/\/websitedemos.net\/cake-shop-07\/wp-content\/uploads\/sites\/1134\/2023\/04\/product-02-free-img.png\",\"height\":858,\"width\":833,\"orientation\":\"portrait\"}},\"mime\":\"image\/png\",\"type\":\"image\",\"subtype\":\"png\",\"id\":220,\"url\":\"https:\/\/websitedemos.net\/cake-shop-07\/wp-content\/uploads\/sites\/1134\/2023\/04\/product-02-free-img.png\",\"alt\":\"\",\"link\":\"https:\/\/websitedemos.net\/cake-shop-07\/home\/product-02-free-img\/\",\"caption\":\"\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/websitedemos.net\/cake-shop-07\/wp-content\/uploads\/sites\/1134\/2023\/04\/product-03-free-img-150x150.png\",\"orientation\":\"landscape\"},\"medium\":{\"height\":300,\"width\":291,\"url\":\"https:\/\/websitedemos.net\/cake-shop-07\/wp-content\/uploads\/sites\/1134\/2023\/04\/product-03-free-img-291x300.png\",\"orientation\":\"portrait\"},\"full\":{\"url\":\"https:\/\/websitedemos.net\/cake-shop-07\/wp-content\/uploads\/sites\/1134\/2023\/04\/product-03-free-img.png\",\"height\":858,\"width\":833,\"orientation\":\"portrait\"}},\"mime\":\"image\/png\",\"type\":\"image\",\"subtype\":\"png\",\"id\":221,\"url\":\"https:\/\/websitedemos.net\/cake-shop-07\/wp-content\/uploads\/sites\/1134\/2023\/04\/product-03-free-img.png\",\"alt\":\"\",\"link\":\"https:\/\/websitedemos.net\/cake-shop-07\/home\/product-03-free-img\/\",\"caption\":\"\"}],\"mediaIDs\":[62,220,221],\"feedLayout\":\"carousel\",\"imageDisplayCaption\":false,\"galleryImageSizeTablet\":\"full\",\"galleryImageSizeMobile\":\"full\",\"columnsDesk\":1,\"columnsMob\":1,\"gridImageGap\":0,\"gridImageGapMob\":3,\"feedMarginTop\":0,\"feedMarginRight\":0,\"feedMarginBottom\":0,\"feedMarginLeft\":0,\"carouselAutoplaySpeed\":1500,\"paginateUseArrows\":false,\"paginateUseDots\":false,\"imageEnableZoom\":false} \/--><\/div>\n<!-- \/wp:uagb\/container --><\/div><\/div>\n<!-- \/wp:uagb\/container -->\n\n<!-- wp:uagb\/container {\"block_id\":\"fd9a5843\",\"innerContentWidth\":\"alignfull\",\"backgroundType\":\"image\",\"backgroundImageDesktop\":{\"uploading\":false,\"date\":1667212553000,\"filename\":\"bg-03-free-img.jpg\",\"menuOrder\":0,\"uploadedTo\":6,\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":69,\"title\":\"bg-03-free-img\",\"url\":\"https:\/\/websitedemos.net\/cake-shop-09\/wp-content\/uploads\/sites\/1134\/2022\/10\/bg-03-free-img.jpg\",\"link\":\"https:\/\/websitedemos.net\/cake-shop-09\/home\/bg-03-free-img\/\",\"alt\":\"\",\"author\":\"156\",\"description\":\"\",\"caption\":\"\",\"name\":\"bg-03-free-img\",\"status\":\"inherit\",\"modified\":1667212553000,\"mime\":\"image\/jpeg\",\"icon\":\"https:\/\/websitedemos.net\/cake-shop-09\/wp-includes\/images\/media\/default.png\",\"dateFormatted\":\"October 31, 2022\",\"nonces\":{\"update\":\"054d6f6e66\",\"delete\":\"c9e0a391db\",\"edit\":\"9f47690d23\"},\"editLink\":\"https:\/\/websitedemos.net\/cake-shop-09\/wp-admin\/post.php?post=69\\u0026action=edit\",\"meta\":false,\"authorName\":\"ninoslavz\",\"authorLink\":\"https:\/\/websitedemos.net\/cake-shop-09\/wp-admin\/profile.php\",\"uploadedToTitle\":\"Home\",\"uploadedToLink\":\"https:\/\/websitedemos.net\/cake-shop-09\/wp-admin\/post.php?post=6\\u0026action=edit\",\"filesizeInBytes\":66621,\"filesizeHumanReadable\":\"65 KB\",\"context\":\"\",\"height\":1080,\"width\":1920,\"orientation\":\"landscape\",\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/websitedemos.net\/cake-shop-09\/wp-content\/uploads\/sites\/1134\/2022\/10\/bg-03-free-img-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":169,\"width\":300,\"url\":\"https:\/\/websitedemos.net\/cake-shop-09\/wp-content\/uploads\/sites\/1134\/2022\/10\/bg-03-free-img-300x169.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":576,\"width\":1024,\"url\":\"https:\/\/websitedemos.net\/cake-shop-09\/wp-content\/uploads\/sites\/1134\/2022\/10\/bg-03-free-img-1024x576.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/websitedemos.net\/cake-shop-09\/wp-content\/uploads\/sites\/1134\/2022\/10\/bg-03-free-img.jpg\",\"height\":1080,\"width\":1920,\"orientation\":\"landscape\"}},\"compat\":{\"item\":\"\",\"meta\":\"\"}},\"topPaddingDesktop\":0,\"bottomPaddingDesktop\":115,\"leftPaddingDesktop\":0,\"rightPaddingDesktop\":0,\"bottomPaddingMobile\":100,\"leftPaddingMobile\":0,\"rightPaddingMobile\":0,\"paddingLink\":false,\"topMarginDesktop\":-325,\"bottomMarginDesktop\":0,\"leftMarginDesktop\":0,\"rightMarginDesktop\":0,\"topMarginTablet\":-165,\"bottomMarginTablet\":0,\"leftMarginTablet\":0,\"rightMarginTablet\":0,\"bottomMarginMobile\":0,\"marginLink\":false,\"variationSelected\":true,\"rowGapDesktop\":0,\"rowGapMobile\":0,\"columnGapDesktop\":0,\"isBlockRootParent\":true,\"zIndex\":-1} -->\n<div class=\"wp-block-uagb-container uag-blocks-common-selector uagb-block-fd9a5843 alignfull uagb-is-root-container\"><!-- wp:uagb\/image {\"block_id\":\"5306d181\",\"url\":\"https:\/\/websitedemos.net\/cake-shop-07\/wp-content\/uploads\/sites\/1134\/2022\/10\/bg-02-free-img.jpg\",\"urlTablet\":\"https:\/\/websitedemos.net\/cake-shop-07\/wp-content\/uploads\/sites\/1134\/2022\/10\/bg-02-free-img.jpg\",\"urlMobile\":\"https:\/\/websitedemos.net\/cake-shop-07\/wp-content\/uploads\/sites\/1134\/2022\/10\/bg-02-free-img.jpg\",\"align\":\"left\",\"id\":70,\"linkDestination\":\"none\",\"width\":850,\"widthTablet\":384,\"widthMobile\":320,\"height\":620,\"heightTablet\":280,\"naturalWidth\":960,\"naturalHeight\":700,\"sizeSlug\":\"full\",\"sizeSlugTablet\":\"full\",\"sizeSlugMobile\":\"full\",\"imageTopMargin\":-154,\"imageRightMargin\":0,\"imageLeftMargin\":0,\"imageBottomMargin\":0,\"imageTopMarginTablet\":-10,\"imageRightMarginTablet\":0,\"imageLeftMarginTablet\":0,\"imageBottomMarginTablet\":0,\"imageTopMarginMobile\":-10,\"imageRightMarginMobile\":0,\"imageLeftMarginMobile\":0,\"imageBottomMarginMobile\":0,\"imageMarginUnitTablet\":\"%\",\"imageMarginUnitMobile\":\"%\",\"imageMarginLink\":false,\"customHeightSetDesktop\":true,\"customHeightSetTablet\":true,\"className\":\"alignleft\",\"zIndex\":3,\"zIndexTablet\":3,\"zIndexMobile\":3} -->\n<div class=\"wp-block-uagb-image alignleft uagb-block-5306d181 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-left uag-blocks-common-selector\" style=\"--z-index-desktop:3;;--z-index-tablet:3;;--z-index-mobile:3;\"><figure class=\"wp-block-uagb-image__figure\"><img srcset=\"https:\/\/websitedemos.net\/cake-shop-07\/wp-content\/uploads\/sites\/1134\/2022\/10\/bg-02-free-img.jpg ,https:\/\/websitedemos.net\/cake-shop-07\/wp-content\/uploads\/sites\/1134\/2022\/10\/bg-02-free-img.jpg 780w, https:\/\/websitedemos.net\/cake-shop-07\/wp-content\/uploads\/sites\/1134\/2022\/10\/bg-02-free-img.jpg 360w\" sizes=\"(max-width: 480px) 150px\" src=\"https:\/\/websitedemos.net\/cake-shop-07\/wp-content\/uploads\/sites\/1134\/2022\/10\/bg-02-free-img.jpg\" alt=\"\" class=\"uag-image-70\" width=\"850\" height=\"620\" title=\"\" loading=\"lazy\" role=\"img\"\/><\/figure><\/div>\n<!-- \/wp:uagb\/image -->\n\n<!-- wp:uagb\/container {\"block_id\":\"724d4bb0\",\"innerContentCustomWidthDesktop\":100,\"innerContentCustomWidthType\":\"%\",\"topPaddingDesktop\":2,\"bottomPaddingDesktop\":0,\"leftPaddingDesktop\":15,\"rightPaddingDesktop\":15,\"topPaddingTablet\":0,\"leftPaddingTablet\":30,\"rightPaddingTablet\":30,\"topPaddingMobile\":50,\"leftPaddingMobile\":30,\"rightPaddingMobile\":30,\"paddingType\":\"%\",\"paddingLink\":false,\"topMarginDesktop\":0,\"bottomMarginDesktop\":0,\"leftMarginDesktop\":0,\"rightMarginDesktop\":0,\"topMarginTablet\":-40,\"bottomMarginTablet\":0,\"leftMarginTablet\":0,\"rightMarginTablet\":0,\"topMarginMobile\":0,\"bottomMarginMobile\":0,\"leftMarginMobile\":0,\"rightMarginMobile\":0,\"marginLink\":false,\"variationSelected\":true,\"rowGapDesktop\":10,\"rowGapMobile\":20,\"columnGapDesktop\":0,\"zIndex\":-100} -->\n<div class=\"wp-block-uagb-container uag-blocks-common-selector uagb-block-724d4bb0\"><!-- wp:uagb\/advanced-heading {\"block_id\":\"f7d116b2\",\"classMigrate\":true,\"headingAlign\":\"center\",\"headSpace\":0,\"zIndexTablet\":3} -->\n<div class=\"wp-block-uagb-advanced-heading uagb-block-f7d116b2 uag-blocks-common-selector\" style=\"--z-index-desktop:undefined;;--z-index-tablet:3;;--z-index-mobile:undefined;\"><h2 class=\"uagb-heading-text\">Welcome!<\/h2><\/div>\n<!-- \/wp:uagb\/advanced-heading -->\n\n<!-- wp:uagb\/advanced-heading {\"block_id\":\"3e834e65\",\"classMigrate\":true,\"headingAlign\":\"center\",\"headingTag\":\"h5\",\"headSpace\":30,\"headSpaceMobile\":15,\"blockTopPaddingMobile\":0,\"blockRightPaddingMobile\":0,\"blockLeftPaddingMobile\":0,\"blockBottomPaddingMobile\":0,\"blockBottomMargin\":20,\"blockTopMarginMobile\":0,\"blockRightMarginMobile\":0,\"blockLeftMarginMobile\":0,\"blockBottomMarginMobile\":0} -->\n<div class=\"wp-block-uagb-advanced-heading uagb-block-3e834e65\"><h5 class=\"uagb-heading-text\">Cakes with Love<\/h5><\/div>\n<!-- \/wp:uagb\/advanced-heading -->\n\n<!-- wp:uagb\/info-box {\"inheritFromTheme\":true,\"classMigrate\":true,\"headingColor\":\"\",\"subHeadingColor\":\"\",\"subHeadSpace\":50,\"block_id\":\"8f60856a\",\"ctaIcon\":\"\",\"ctaType\":\"button\",\"ctaLink\":\"#\",\"ctaBtnLinkColor\":\"\",\"ctaBgColor\":\"\",\"ctaBorderColor\":\"\",\"ctaBorderStyle\":\"\",\"showIcon\":false,\"headTopMargin\":0,\"headRightMargin\":0,\"headLeftMargin\":0,\"blockTopPadding\":0,\"blockRightPadding\":0,\"blockLeftPadding\":0,\"blockBottomPadding\":0,\"blockPaddingLink\":false,\"subHeadTopMargin\":0,\"subHeadRightMargin\":0,\"subHeadLeftMargin\":0,\"subHeadMarginTopMobile\":0,\"subHeadMarginRightMobile\":0,\"subHeadMobileSpace\":20,\"subHeadMarginLeftMobile\":0,\"btnBorderTopWidth\":1,\"btnBorderLeftWidth\":1,\"btnBorderRightWidth\":1,\"btnBorderBottomWidth\":1,\"btnBorderTopLeftRadius\":0,\"btnBorderTopRightRadius\":0,\"btnBorderBottomLeftRadius\":0,\"btnBorderBottomRightRadius\":0,\"btnBorderStyle\":\"default\",\"btnBorderColor\":\"#333\"} -->\n<div class=\"wp-block-uagb-info-box uagb-block-8f60856a uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><h3 class=\"uagb-ifb-title\">Ut enim ad minim veniam, quis nostrud exercitation ullamco.<\/h3><\/div><p class=\"uagb-ifb-desc\">Lorem ipsum dolor sit amet, consectetur adipisicing elit, sed do eiusmod tempor incididunt ut labore et dolore magna aliqua. Ut enim ad minim veniam, quis nostrud exercitation ullamco laboris nisi ut aliquip ex ea commodo consequat. Duis aute irure dolor in reprehenderit in voluptate velit esse cillum dolore eu fugiat nulla pariatur. Excepteur sint occaecat cupidatat non proident, sunt in culpa qui officia deserunt mollit anim id est laborum.<\/p><div class=\"uagb-ifb-button-wrapper wp-block-button\"><a href=\"#\" class=\"uagb-infobox-cta-link wp-block-button__link\" target=\"_self\" rel=\"noopener noreferrer\" onclick=\"return false;\"><span class=\"uagb-inline-editing\">Read More<\/span><\/a><\/div><\/div><\/div>\n<!-- \/wp:uagb\/info-box -->\n\n<!-- wp:uagb\/advanced-heading {\"block_id\":\"7ff3a404\",\"classMigrate\":true,\"headingAlign\":\"center\",\"headSpace\":0,\"blockTopPadding\":65,\"blockRightPadding\":0,\"blockLeftPadding\":0,\"blockBottomPadding\":0} -->\n<div class=\"wp-block-uagb-advanced-heading uagb-block-7ff3a404\"><h2 class=\"uagb-heading-text\">Our Cakes<\/h2><\/div>\n<!-- \/wp:uagb\/advanced-heading -->\n\n<!-- wp:uagb\/advanced-heading {\"block_id\":\"aace127a\",\"classMigrate\":true,\"headingAlign\":\"center\",\"headingTag\":\"h5\",\"headSpace\":30,\"headSpaceMobile\":15,\"blockBottomPadding\":0,\"blockTopPaddingMobile\":0,\"blockRightPaddingMobile\":0,\"blockLeftPaddingMobile\":0,\"blockBottomPaddingMobile\":0,\"blockPaddingUnit\":\"%\",\"blockBottomMargin\":20,\"blockBottomMarginTablet\":0,\"blockTopMarginMobile\":0,\"blockRightMarginMobile\":0,\"blockLeftMarginMobile\":0,\"blockBottomMarginMobile\":0} -->\n<div class=\"wp-block-uagb-advanced-heading uagb-block-aace127a\"><h5 class=\"uagb-heading-text\">Cakes with Love<\/h5><\/div>\n<!-- \/wp:uagb\/advanced-heading --><\/div>\n<!-- \/wp:uagb\/container --><\/div>\n<!-- \/wp:uagb\/container -->\n\n<!-- wp:uagb\/container {\"block_id\":\"2727fa58\",\"alignItemsMobile\":\"flex-start\",\"backgroundType\":\"color\",\"backgroundColor\":\"var(\\u002d\\u002dast-global-color-4)\",\"leftPaddingDesktop\":40,\"rightPaddingDesktop\":40,\"leftPaddingTablet\":30,\"rightPaddingTablet\":30,\"leftPaddingMobile\":30,\"rightPaddingMobile\":30,\"paddingLink\":false,\"topMarginDesktop\":0,\"bottomMarginDesktop\":0,\"leftMarginDesktop\":0,\"rightMarginDesktop\":0,\"topMarginTablet\":0,\"bottomMarginTablet\":0,\"leftMarginTablet\":0,\"rightMarginTablet\":0,\"topMarginMobile\":0,\"bottomMarginMobile\":0,\"leftMarginMobile\":0,\"rightMarginMobile\":0,\"marginLink\":false,\"variationSelected\":true,\"rowGapDesktop\":50,\"rowGapTablet\":50,\"rowGapMobile\":50,\"isBlockRootParent\":true} -->\n<div class=\"wp-block-uagb-container uagb-block-2727fa58 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\"><!-- wp:uagb\/container {\"block_id\":\"5b0d9f3e\",\"directionDesktop\":\"row\",\"directionMobile\":\"column\",\"alignItemsDesktop\":\"flex-start\",\"alignItemsTablet\":\"center\",\"alignItemsMobile\":\"center\",\"justifyContentMobile\":\"center\",\"alignContentMobile\":\"center\",\"leftPaddingDesktop\":40,\"rightPaddingDesktop\":40,\"topPaddingTablet\":0,\"bottomPaddingTablet\":0,\"leftPaddingTablet\":0,\"rightPaddingTablet\":0,\"topPaddingMobile\":0,\"bottomPaddingMobile\":0,\"leftPaddingMobile\":0,\"rightPaddingMobile\":0,\"paddingLink\":false,\"topMarginDesktop\":-90,\"bottomMarginDesktop\":0,\"leftMarginDesktop\":0,\"rightMarginDesktop\":0,\"topMarginTablet\":0,\"bottomMarginTablet\":0,\"leftMarginTablet\":10,\"rightMarginTablet\":10,\"topMarginMobile\":0,\"bottomMarginMobile\":0,\"leftMarginMobile\":0,\"rightMarginMobile\":0,\"marginLink\":false,\"variationSelected\":true,\"rowGapMobile\":50,\"columnGapTablet\":14,\"zIndex\":3} -->\n<div class=\"wp-block-uagb-container uag-blocks-common-selector uagb-block-5b0d9f3e\"><!-- wp:uagb\/info-box {\"classMigrate\":true,\"headingColor\":\"\",\"subHeadingColor\":\"\",\"prefixColor\":\"var(\\u002d\\u002dast-global-color-0)\",\"prefixHeadingTag\":\"h5\",\"subHeadSpace\":0,\"source_type\":\"image\",\"block_id\":\"bb367c1b\",\"iconImage\":{\"id\":127,\"title\":\"product-08-free-img\",\"filename\":\"product-08-free-img-1.jpg\",\"url\":\"https:\/\/websitedemos.net\/cake-shop-07\/wp-content\/uploads\/sites\/1134\/2022\/10\/product-08-free-img-1.jpg\",\"link\":\"https:\/\/websitedemos.net\/cake-shop-07\/cakes\/product-08-free-img-2\/\",\"alt\":\"\",\"author\":\"156\",\"description\":\"\",\"caption\":\"\",\"name\":\"product-08-free-img-2\",\"status\":\"inherit\",\"uploadedTo\":13,\"date\":\"2022-10-31T12:36:31.000Z\",\"modified\":\"2022-10-31T12:36:31.000Z\",\"menuOrder\":0,\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"icon\":\"https:\/\/websitedemos.net\/cake-shop-07\/wp-includes\/images\/media\/default.png\",\"dateFormatted\":\"October 31, 2022\",\"nonces\":{\"update\":\"d4fb077507\",\"delete\":\"e436dc393c\",\"edit\":\"5b1553bfb7\"},\"editLink\":\"https:\/\/websitedemos.net\/cake-shop-07\/wp-admin\/post.php?post=127\\u0026action=edit\",\"meta\":false,\"authorName\":\"ninoslavz\",\"authorLink\":\"https:\/\/websitedemos.net\/cake-shop-07\/wp-admin\/user-edit.php?user_id=156\",\"uploadedToTitle\":\"Cakes\",\"uploadedToLink\":\"https:\/\/websitedemos.net\/cake-shop-07\/wp-admin\/post.php?post=13\\u0026action=edit\",\"filesizeInBytes\":19785,\"filesizeHumanReadable\":\"19 KB\",\"context\":\"\",\"height\":360,\"width\":380,\"orientation\":\"landscape\",\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/websitedemos.net\/cake-shop-07\/wp-content\/uploads\/sites\/1134\/2022\/10\/product-08-free-img-1-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":284,\"width\":300,\"url\":\"https:\/\/websitedemos.net\/cake-shop-07\/wp-content\/uploads\/sites\/1134\/2022\/10\/product-08-free-img-1-300x284.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/websitedemos.net\/cake-shop-07\/wp-content\/uploads\/sites\/1134\/2022\/10\/product-08-free-img-1.jpg\",\"height\":360,\"width\":380,\"orientation\":\"landscape\"}},\"compat\":{\"item\":\"\",\"meta\":\"\"},\"acf_errors\":false},\"imageSize\":\"full\",\"showPrefix\":true,\"prefixTopMargin\":35,\"prefixRightMargin\":0,\"prefixLeftMargin\":0,\"prefixMarginTopTablet\":25,\"prefixMarginRightTablet\":0,\"prefixTabletSpace\":10,\"prefixMarginLeftTablet\":0,\"headTopMargin\":0,\"headRightMargin\":0,\"headLeftMargin\":0,\"headTabletSpace\":10,\"subHeadTopMargin\":0,\"subHeadRightMargin\":0,\"subHeadLeftMargin\":0,\"subHeadMarginTopMobile\":0,\"subHeadMarginRightMobile\":20,\"subHeadMobileSpace\":0,\"subHeadMarginLeftMobile\":20,\"imgTagWidth\":380,\"btnBorderTopWidth\":1,\"btnBorderLeftWidth\":1,\"btnBorderRightWidth\":1,\"btnBorderBottomWidth\":1,\"btnBorderTopLeftRadius\":0,\"btnBorderTopRightRadius\":0,\"btnBorderBottomLeftRadius\":0,\"btnBorderBottomRightRadius\":0,\"btnBorderStyle\":\"solid\",\"btnBorderColor\":\"#333\"} -->\n<div class=\"wp-block-uagb-info-box uagb-block-bb367c1b uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-image-content\"><img src=\"https:\/\/websitedemos.net\/cake-shop-07\/wp-content\/uploads\/sites\/1134\/2022\/10\/product-08-free-img-1.jpg\" alt=\"\" width=\"\" height=\"0\" loading=\"lazy\"\/><\/div><div class=\"uagb-ifb-title-wrap\"><h5 class=\"uagb-ifb-title-prefix\">$75<\/h5><h3 class=\"uagb-ifb-title\">Fruit Tart<\/h3><\/div><p class=\"uagb-ifb-desc\">Lorem ipsum dolor sit amet, consectetur adipiscing elit.<\/p><\/div><\/div>\n<!-- \/wp:uagb\/info-box -->\n\n<!-- wp:uagb\/info-box {\"classMigrate\":true,\"headingColor\":\"\",\"subHeadingColor\":\"\",\"prefixColor\":\"var(\\u002d\\u002dast-global-color-0)\",\"prefixHeadingTag\":\"h5\",\"subHeadSpace\":0,\"source_type\":\"image\",\"block_id\":\"a3cec12e\",\"iconImage\":{\"id\":125,\"title\":\"product-06-free-img\",\"filename\":\"product-06-free-img-1.jpg\",\"url\":\"https:\/\/websitedemos.net\/cake-shop-07\/wp-content\/uploads\/sites\/1134\/2022\/10\/product-06-free-img-1.jpg\",\"link\":\"https:\/\/websitedemos.net\/cake-shop-07\/cakes\/product-06-free-img-2\/\",\"alt\":\"\",\"author\":\"156\",\"description\":\"\",\"caption\":\"\",\"name\":\"product-06-free-img-2\",\"status\":\"inherit\",\"uploadedTo\":13,\"date\":\"2022-10-31T12:35:03.000Z\",\"modified\":\"2022-10-31T12:35:03.000Z\",\"menuOrder\":0,\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"icon\":\"https:\/\/websitedemos.net\/cake-shop-07\/wp-includes\/images\/media\/default.png\",\"dateFormatted\":\"October 31, 2022\",\"nonces\":{\"update\":\"c38a613905\",\"delete\":\"6eacf2bef2\",\"edit\":\"9ffe13f763\"},\"editLink\":\"https:\/\/websitedemos.net\/cake-shop-07\/wp-admin\/post.php?post=125\\u0026action=edit\",\"meta\":false,\"authorName\":\"ninoslavz\",\"authorLink\":\"https:\/\/websitedemos.net\/cake-shop-07\/wp-admin\/user-edit.php?user_id=156\",\"uploadedToTitle\":\"Cakes\",\"uploadedToLink\":\"https:\/\/websitedemos.net\/cake-shop-07\/wp-admin\/post.php?post=13\\u0026action=edit\",\"filesizeInBytes\":15879,\"filesizeHumanReadable\":\"16 KB\",\"context\":\"\",\"height\":360,\"width\":380,\"orientation\":\"landscape\",\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/websitedemos.net\/cake-shop-07\/wp-content\/uploads\/sites\/1134\/2022\/10\/product-06-free-img-1-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":284,\"width\":300,\"url\":\"https:\/\/websitedemos.net\/cake-shop-07\/wp-content\/uploads\/sites\/1134\/2022\/10\/product-06-free-img-1-300x284.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/websitedemos.net\/cake-shop-07\/wp-content\/uploads\/sites\/1134\/2022\/10\/product-06-free-img-1.jpg\",\"height\":360,\"width\":380,\"orientation\":\"landscape\"}},\"compat\":{\"item\":\"\",\"meta\":\"\"},\"acf_errors\":false},\"imageSize\":\"full\",\"showPrefix\":true,\"prefixTopMargin\":35,\"prefixRightMargin\":0,\"prefixLeftMargin\":0,\"prefixMarginTopTablet\":25,\"prefixMarginRightTablet\":0,\"prefixTabletSpace\":10,\"prefixMarginLeftTablet\":0,\"headTopMargin\":0,\"headRightMargin\":0,\"headLeftMargin\":0,\"headMarginTopTablet\":0,\"headMarginRightTablet\":0,\"headTabletSpace\":10,\"headMarginLeftTablet\":0,\"subHeadTopMargin\":0,\"subHeadRightMargin\":0,\"subHeadLeftMargin\":0,\"subHeadMarginTopMobile\":0,\"subHeadMarginRightMobile\":20,\"subHeadMobileSpace\":0,\"subHeadMarginLeftMobile\":20,\"imgTagWidth\":380,\"btnBorderTopWidth\":1,\"btnBorderLeftWidth\":1,\"btnBorderRightWidth\":1,\"btnBorderBottomWidth\":1,\"btnBorderTopLeftRadius\":0,\"btnBorderTopRightRadius\":0,\"btnBorderBottomLeftRadius\":0,\"btnBorderBottomRightRadius\":0,\"btnBorderStyle\":\"solid\",\"btnBorderColor\":\"#333\"} -->\n<div class=\"wp-block-uagb-info-box uagb-block-a3cec12e uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-image-content\"><img src=\"https:\/\/websitedemos.net\/cake-shop-07\/wp-content\/uploads\/sites\/1134\/2022\/10\/product-06-free-img-1.jpg\" alt=\"\" width=\"\" height=\"0\" loading=\"lazy\"\/><\/div><div class=\"uagb-ifb-title-wrap\"><h5 class=\"uagb-ifb-title-prefix\">$85<\/h5><h3 class=\"uagb-ifb-title\">Strawberry Tart\u200b<\/h3><\/div><p class=\"uagb-ifb-desc\">Lorem ipsum dolor sit amet, consectetur adipiscing elit.<\/p><\/div><\/div>\n<!-- \/wp:uagb\/info-box -->\n\n<!-- wp:uagb\/info-box {\"classMigrate\":true,\"headingColor\":\"\",\"subHeadingColor\":\"\",\"prefixColor\":\"var(\\u002d\\u002dast-global-color-0)\",\"prefixHeadingTag\":\"h5\",\"subHeadSpace\":0,\"source_type\":\"image\",\"block_id\":\"861651c6\",\"iconImage\":{\"id\":128,\"title\":\"product-07-free-img\",\"filename\":\"product-07-free-img-1.jpg\",\"url\":\"https:\/\/websitedemos.net\/cake-shop-07\/wp-content\/uploads\/sites\/1134\/2022\/10\/product-07-free-img-1.jpg\",\"link\":\"https:\/\/websitedemos.net\/cake-shop-07\/cakes\/product-07-free-img-2\/\",\"alt\":\"\",\"author\":\"156\",\"description\":\"\",\"caption\":\"\",\"name\":\"product-07-free-img-2\",\"status\":\"inherit\",\"uploadedTo\":13,\"date\":\"2022-10-31T12:37:07.000Z\",\"modified\":\"2022-10-31T12:37:07.000Z\",\"menuOrder\":0,\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"icon\":\"https:\/\/websitedemos.net\/cake-shop-07\/wp-includes\/images\/media\/default.png\",\"dateFormatted\":\"October 31, 2022\",\"nonces\":{\"update\":\"8bbe6799f7\",\"delete\":\"e380ead26c\",\"edit\":\"78e045f156\"},\"editLink\":\"https:\/\/websitedemos.net\/cake-shop-07\/wp-admin\/post.php?post=128\\u0026action=edit\",\"meta\":false,\"authorName\":\"ninoslavz\",\"authorLink\":\"https:\/\/websitedemos.net\/cake-shop-07\/wp-admin\/user-edit.php?user_id=156\",\"uploadedToTitle\":\"Cakes\",\"uploadedToLink\":\"https:\/\/websitedemos.net\/cake-shop-07\/wp-admin\/post.php?post=13\\u0026action=edit\",\"filesizeInBytes\":21756,\"filesizeHumanReadable\":\"21 KB\",\"context\":\"\",\"height\":360,\"width\":380,\"orientation\":\"landscape\",\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/websitedemos.net\/cake-shop-07\/wp-content\/uploads\/sites\/1134\/2022\/10\/product-07-free-img-1-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":284,\"width\":300,\"url\":\"https:\/\/websitedemos.net\/cake-shop-07\/wp-content\/uploads\/sites\/1134\/2022\/10\/product-07-free-img-1-300x284.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/websitedemos.net\/cake-shop-07\/wp-content\/uploads\/sites\/1134\/2022\/10\/product-07-free-img-1.jpg\",\"height\":360,\"width\":380,\"orientation\":\"landscape\"}},\"compat\":{\"item\":\"\",\"meta\":\"\"},\"acf_errors\":false},\"imageSize\":\"full\",\"showPrefix\":true,\"prefixTopMargin\":35,\"prefixRightMargin\":0,\"prefixLeftMargin\":0,\"prefixMarginTopTablet\":25,\"prefixMarginRightTablet\":0,\"prefixTabletSpace\":10,\"prefixMarginLeftTablet\":0,\"headTopMargin\":0,\"headRightMargin\":0,\"headLeftMargin\":0,\"headMarginTopTablet\":0,\"headMarginRightTablet\":0,\"headTabletSpace\":10,\"headMarginLeftTablet\":0,\"subHeadTopMargin\":0,\"subHeadRightMargin\":0,\"subHeadLeftMargin\":0,\"subHeadMarginTopMobile\":0,\"subHeadMarginRightMobile\":20,\"subHeadMobileSpace\":0,\"subHeadMarginLeftMobile\":20,\"imgTagWidth\":380,\"btnBorderTopWidth\":1,\"btnBorderLeftWidth\":1,\"btnBorderRightWidth\":1,\"btnBorderBottomWidth\":1,\"btnBorderTopLeftRadius\":0,\"btnBorderTopRightRadius\":0,\"btnBorderBottomLeftRadius\":0,\"btnBorderBottomRightRadius\":0,\"btnBorderStyle\":\"solid\",\"btnBorderColor\":\"#333\"} -->\n<div class=\"wp-block-uagb-info-box uagb-block-861651c6 uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-image-content\"><img src=\"https:\/\/websitedemos.net\/cake-shop-07\/wp-content\/uploads\/sites\/1134\/2022\/10\/product-07-free-img-1.jpg\" alt=\"\" width=\"\" height=\"0\" loading=\"lazy\"\/><\/div><div class=\"uagb-ifb-title-wrap\"><h5 class=\"uagb-ifb-title-prefix\">$90<\/h5><h3 class=\"uagb-ifb-title\">Cherry Tart\u200b<\/h3><\/div><p class=\"uagb-ifb-desc\">Lorem ipsum dolor sit amet, consectetur adipiscing elit.<\/p><\/div><\/div>\n<!-- \/wp:uagb\/info-box --><\/div>\n<!-- \/wp:uagb\/container -->\n\n<!-- wp:uagb\/container {\"block_id\":\"2ffcd874\",\"directionDesktop\":\"row\",\"directionMobile\":\"column\",\"alignItemsDesktop\":\"flex-start\",\"alignItemsTablet\":\"stretch\",\"alignItemsMobile\":\"stretch\",\"justifyContentMobile\":\"center\",\"alignContentMobile\":\"center\",\"leftPaddingDesktop\":40,\"rightPaddingDesktop\":40,\"topPaddingTablet\":0,\"bottomPaddingTablet\":0,\"leftPaddingTablet\":0,\"rightPaddingTablet\":0,\"topPaddingMobile\":0,\"bottomPaddingMobile\":0,\"leftPaddingMobile\":0,\"rightPaddingMobile\":0,\"paddingLink\":false,\"topMarginDesktop\":0,\"bottomMarginDesktop\":0,\"leftMarginDesktop\":0,\"rightMarginDesktop\":0,\"topMarginTablet\":0,\"bottomMarginTablet\":0,\"leftMarginTablet\":10,\"rightMarginTablet\":10,\"topMarginMobile\":0,\"bottomMarginMobile\":0,\"leftMarginMobile\":0,\"rightMarginMobile\":0,\"marginLink\":false,\"variationSelected\":true,\"rowGapMobile\":50,\"columnGapTablet\":14,\"zIndex\":3} -->\n<div class=\"wp-block-uagb-container uag-blocks-common-selector uagb-block-2ffcd874\"><!-- wp:uagb\/info-box {\"classMigrate\":true,\"headingColor\":\"\",\"subHeadingColor\":\"\",\"prefixColor\":\"var(\\u002d\\u002dast-global-color-0)\",\"prefixHeadingTag\":\"h5\",\"subHeadSpace\":0,\"source_type\":\"image\",\"block_id\":\"5c24b108\",\"iconImage\":{\"id\":93,\"title\":\"product-09-free-img\",\"filename\":\"product-09-free-img.jpg\",\"url\":\"https:\/\/websitedemos.net\/cake-shop-07\/wp-content\/uploads\/sites\/1134\/2022\/10\/product-09-free-img.jpg\",\"link\":\"https:\/\/websitedemos.net\/cake-shop-07\/home\/product-09-free-img\/\",\"alt\":\"\",\"author\":\"156\",\"description\":\"\",\"caption\":\"\",\"name\":\"product-09-free-img\",\"status\":\"inherit\",\"uploadedTo\":6,\"date\":\"2022-10-31T10:56:17.000Z\",\"modified\":\"2022-10-31T10:56:17.000Z\",\"menuOrder\":0,\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"icon\":\"https:\/\/websitedemos.net\/cake-shop-07\/wp-includes\/images\/media\/default.png\",\"dateFormatted\":\"October 31, 2022\",\"nonces\":{\"update\":\"9297f0ace4\",\"delete\":\"5e18c15ace\",\"edit\":\"d5b0b472c1\"},\"editLink\":\"https:\/\/websitedemos.net\/cake-shop-07\/wp-admin\/post.php?post=93\\u0026action=edit\",\"meta\":false,\"authorName\":\"ninoslavz\",\"authorLink\":\"https:\/\/websitedemos.net\/cake-shop-07\/wp-admin\/user-edit.php?user_id=156\",\"uploadedToTitle\":\"Home\",\"uploadedToLink\":\"https:\/\/websitedemos.net\/cake-shop-07\/wp-admin\/post.php?post=6\\u0026action=edit\",\"filesizeInBytes\":33615,\"filesizeHumanReadable\":\"33 KB\",\"context\":\"\",\"height\":360,\"width\":380,\"orientation\":\"landscape\",\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/websitedemos.net\/cake-shop-07\/wp-content\/uploads\/sites\/1134\/2022\/10\/product-09-free-img-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":284,\"width\":300,\"url\":\"https:\/\/websitedemos.net\/cake-shop-07\/wp-content\/uploads\/sites\/1134\/2022\/10\/product-09-free-img-300x284.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/websitedemos.net\/cake-shop-07\/wp-content\/uploads\/sites\/1134\/2022\/10\/product-09-free-img.jpg\",\"height\":360,\"width\":380,\"orientation\":\"landscape\"}},\"compat\":{\"item\":\"\",\"meta\":\"\"},\"acf_errors\":false},\"imageSize\":\"full\",\"showPrefix\":true,\"prefixTopMargin\":35,\"prefixRightMargin\":0,\"prefixLeftMargin\":0,\"prefixMarginTopTablet\":25,\"prefixMarginRightTablet\":0,\"prefixTabletSpace\":10,\"prefixMarginLeftTablet\":0,\"headTopMargin\":0,\"headRightMargin\":0,\"headLeftMargin\":0,\"headTabletSpace\":10,\"subHeadTopMargin\":0,\"subHeadRightMargin\":0,\"subHeadLeftMargin\":0,\"subHeadMarginTopMobile\":0,\"subHeadMarginRightMobile\":20,\"subHeadMobileSpace\":0,\"subHeadMarginLeftMobile\":20,\"imgTagWidth\":380,\"btnBorderTopWidth\":1,\"btnBorderLeftWidth\":1,\"btnBorderRightWidth\":1,\"btnBorderBottomWidth\":1,\"btnBorderTopLeftRadius\":0,\"btnBorderTopRightRadius\":0,\"btnBorderBottomLeftRadius\":0,\"btnBorderBottomRightRadius\":0,\"btnBorderStyle\":\"solid\",\"btnBorderColor\":\"#333\"} -->\n<div class=\"wp-block-uagb-info-box uagb-block-5c24b108 uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-image-content\"><img src=\"https:\/\/websitedemos.net\/cake-shop-07\/wp-content\/uploads\/sites\/1134\/2022\/10\/product-09-free-img.jpg\" alt=\"\" width=\"\" height=\"0\" loading=\"lazy\"\/><\/div><div class=\"uagb-ifb-title-wrap\"><h5 class=\"uagb-ifb-title-prefix\">$75<\/h5><h3 class=\"uagb-ifb-title\">Fruit Tart<\/h3><\/div><p class=\"uagb-ifb-desc\">Lorem ipsum dolor sit amet, consectetur adipiscing elit.<\/p><\/div><\/div>\n<!-- \/wp:uagb\/info-box -->\n\n<!-- wp:uagb\/info-box {\"classMigrate\":true,\"headingColor\":\"\",\"subHeadingColor\":\"\",\"prefixColor\":\"var(\\u002d\\u002dast-global-color-0)\",\"prefixHeadingTag\":\"h5\",\"subHeadSpace\":0,\"source_type\":\"image\",\"block_id\":\"073479f1\",\"iconImage\":{\"id\":94,\"title\":\"product-11-free-img\",\"filename\":\"product-11-free-img.jpg\",\"url\":\"https:\/\/websitedemos.net\/cake-shop-07\/wp-content\/uploads\/sites\/1134\/2022\/10\/product-11-free-img.jpg\",\"link\":\"https:\/\/websitedemos.net\/cake-shop-07\/home\/product-11-free-img\/\",\"alt\":\"\",\"author\":\"156\",\"description\":\"\",\"caption\":\"\",\"name\":\"product-11-free-img\",\"status\":\"inherit\",\"uploadedTo\":6,\"date\":\"2022-10-31T10:56:26.000Z\",\"modified\":\"2022-10-31T10:56:26.000Z\",\"menuOrder\":0,\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"icon\":\"https:\/\/websitedemos.net\/cake-shop-07\/wp-includes\/images\/media\/default.png\",\"dateFormatted\":\"October 31, 2022\",\"nonces\":{\"update\":\"ff1341ba80\",\"delete\":\"6b702ab389\",\"edit\":\"90ac529bb4\"},\"editLink\":\"https:\/\/websitedemos.net\/cake-shop-07\/wp-admin\/post.php?post=94\\u0026action=edit\",\"meta\":false,\"authorName\":\"ninoslavz\",\"authorLink\":\"https:\/\/websitedemos.net\/cake-shop-07\/wp-admin\/user-edit.php?user_id=156\",\"uploadedToTitle\":\"Home\",\"uploadedToLink\":\"https:\/\/websitedemos.net\/cake-shop-07\/wp-admin\/post.php?post=6\\u0026action=edit\",\"filesizeInBytes\":19798,\"filesizeHumanReadable\":\"19 KB\",\"context\":\"\",\"height\":360,\"width\":380,\"orientation\":\"landscape\",\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/websitedemos.net\/cake-shop-07\/wp-content\/uploads\/sites\/1134\/2022\/10\/product-11-free-img-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":284,\"width\":300,\"url\":\"https:\/\/websitedemos.net\/cake-shop-07\/wp-content\/uploads\/sites\/1134\/2022\/10\/product-11-free-img-300x284.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/websitedemos.net\/cake-shop-07\/wp-content\/uploads\/sites\/1134\/2022\/10\/product-11-free-img.jpg\",\"height\":360,\"width\":380,\"orientation\":\"landscape\"}},\"compat\":{\"item\":\"\",\"meta\":\"\"},\"acf_errors\":false},\"imageSize\":\"full\",\"showPrefix\":true,\"prefixTopMargin\":35,\"prefixRightMargin\":0,\"prefixLeftMargin\":0,\"prefixMarginTopTablet\":25,\"prefixMarginRightTablet\":0,\"prefixTabletSpace\":10,\"prefixMarginLeftTablet\":0,\"headTopMargin\":0,\"headRightMargin\":0,\"headLeftMargin\":0,\"headMarginTopTablet\":0,\"headMarginRightTablet\":0,\"headTabletSpace\":10,\"headMarginLeftTablet\":0,\"subHeadTopMargin\":0,\"subHeadRightMargin\":0,\"subHeadLeftMargin\":0,\"subHeadMarginTopMobile\":0,\"subHeadMarginRightMobile\":20,\"subHeadMobileSpace\":0,\"subHeadMarginLeftMobile\":20,\"imgTagWidth\":380,\"btnBorderTopWidth\":1,\"btnBorderLeftWidth\":1,\"btnBorderRightWidth\":1,\"btnBorderBottomWidth\":1,\"btnBorderTopLeftRadius\":0,\"btnBorderTopRightRadius\":0,\"btnBorderBottomLeftRadius\":0,\"btnBorderBottomRightRadius\":0,\"btnBorderStyle\":\"solid\",\"btnBorderColor\":\"#333\"} -->\n<div class=\"wp-block-uagb-info-box uagb-block-073479f1 uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-image-content\"><img src=\"https:\/\/websitedemos.net\/cake-shop-07\/wp-content\/uploads\/sites\/1134\/2022\/10\/product-11-free-img.jpg\" alt=\"\" width=\"\" height=\"0\" loading=\"lazy\"\/><\/div><div class=\"uagb-ifb-title-wrap\"><h5 class=\"uagb-ifb-title-prefix\">$80<\/h5><h3 class=\"uagb-ifb-title\">Chocolate Cake\u200b<\/h3><\/div><p class=\"uagb-ifb-desc\">Lorem ipsum dolor sit amet, consectetur adipiscing elit.<\/p><\/div><\/div>\n<!-- \/wp:uagb\/info-box -->\n\n<!-- wp:uagb\/info-box {\"classMigrate\":true,\"headingColor\":\"\",\"subHeadingColor\":\"\",\"prefixColor\":\"var(\\u002d\\u002dast-global-color-0)\",\"prefixHeadingTag\":\"h5\",\"subHeadSpace\":0,\"source_type\":\"image\",\"block_id\":\"d6915861\",\"iconImage\":{\"id\":95,\"title\":\"product-12-free-img\",\"filename\":\"product-12-free-img.jpg\",\"url\":\"https:\/\/websitedemos.net\/cake-shop-07\/wp-content\/uploads\/sites\/1134\/2022\/10\/product-12-free-img.jpg\",\"link\":\"https:\/\/websitedemos.net\/cake-shop-07\/home\/product-12-free-img\/\",\"alt\":\"\",\"author\":\"156\",\"description\":\"\",\"caption\":\"\",\"name\":\"product-12-free-img\",\"status\":\"inherit\",\"uploadedTo\":6,\"date\":\"2022-10-31T10:56:36.000Z\",\"modified\":\"2022-10-31T10:56:36.000Z\",\"menuOrder\":0,\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"icon\":\"https:\/\/websitedemos.net\/cake-shop-07\/wp-includes\/images\/media\/default.png\",\"dateFormatted\":\"October 31, 2022\",\"nonces\":{\"update\":\"b61eb1d290\",\"delete\":\"866f3b8500\",\"edit\":\"52964f2e78\"},\"editLink\":\"https:\/\/websitedemos.net\/cake-shop-07\/wp-admin\/post.php?post=95\\u0026action=edit\",\"meta\":false,\"authorName\":\"ninoslavz\",\"authorLink\":\"https:\/\/websitedemos.net\/cake-shop-07\/wp-admin\/user-edit.php?user_id=156\",\"uploadedToTitle\":\"Home\",\"uploadedToLink\":\"https:\/\/websitedemos.net\/cake-shop-07\/wp-admin\/post.php?post=6\\u0026action=edit\",\"filesizeInBytes\":9556,\"filesizeHumanReadable\":\"9 KB\",\"context\":\"\",\"height\":360,\"width\":380,\"orientation\":\"landscape\",\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/websitedemos.net\/cake-shop-07\/wp-content\/uploads\/sites\/1134\/2022\/10\/product-12-free-img-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":284,\"width\":300,\"url\":\"https:\/\/websitedemos.net\/cake-shop-07\/wp-content\/uploads\/sites\/1134\/2022\/10\/product-12-free-img-300x284.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/websitedemos.net\/cake-shop-07\/wp-content\/uploads\/sites\/1134\/2022\/10\/product-12-free-img.jpg\",\"height\":360,\"width\":380,\"orientation\":\"landscape\"}},\"compat\":{\"item\":\"\",\"meta\":\"\"},\"acf_errors\":false},\"imageSize\":\"full\",\"showPrefix\":true,\"prefixTopMargin\":35,\"prefixRightMargin\":0,\"prefixLeftMargin\":0,\"prefixMarginTopTablet\":25,\"prefixMarginRightTablet\":0,\"prefixTabletSpace\":10,\"prefixMarginLeftTablet\":0,\"headTopMargin\":0,\"headRightMargin\":0,\"headLeftMargin\":0,\"headMarginTopTablet\":0,\"headMarginRightTablet\":0,\"headTabletSpace\":10,\"headMarginLeftTablet\":0,\"subHeadTopMargin\":0,\"subHeadRightMargin\":0,\"subHeadLeftMargin\":0,\"subHeadMarginTopMobile\":0,\"subHeadMarginRightMobile\":20,\"subHeadMobileSpace\":0,\"subHeadMarginLeftMobile\":20,\"imgTagWidth\":380,\"btnBorderTopWidth\":1,\"btnBorderLeftWidth\":1,\"btnBorderRightWidth\":1,\"btnBorderBottomWidth\":1,\"btnBorderTopLeftRadius\":0,\"btnBorderTopRightRadius\":0,\"btnBorderBottomLeftRadius\":0,\"btnBorderBottomRightRadius\":0,\"btnBorderStyle\":\"solid\",\"btnBorderColor\":\"#333\"} -->\n<div class=\"wp-block-uagb-info-box uagb-block-d6915861 uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-image-content\"><img src=\"https:\/\/websitedemos.net\/cake-shop-07\/wp-content\/uploads\/sites\/1134\/2022\/10\/product-12-free-img.jpg\" alt=\"\" width=\"\" height=\"0\" loading=\"lazy\"\/><\/div><div class=\"uagb-ifb-title-wrap\"><h5 class=\"uagb-ifb-title-prefix\">$85<\/h5><h3 class=\"uagb-ifb-title\">Biscuit Cake\u200b<\/h3><\/div><p class=\"uagb-ifb-desc\">Lorem ipsum dolor sit amet, consectetur adipiscing elit.<\/p><\/div><\/div>\n<!-- \/wp:uagb\/info-box --><\/div>\n<!-- \/wp:uagb\/container --><\/div><\/div>\n<!-- \/wp:uagb\/container -->\n\n<!-- wp:uagb\/container {\"block_id\":\"76587460\",\"innerContentCustomWidthDesktop\":600,\"backgroundType\":\"color\",\"backgroundColor\":\"var(\\u002d\\u002dast-global-color-4)\",\"topPaddingDesktop\":100,\"bottomPaddingDesktop\":100,\"leftPaddingDesktop\":40,\"rightPaddingDesktop\":40,\"topPaddingTablet\":50,\"bottomPaddingTablet\":150,\"leftPaddingTablet\":25,\"rightPaddingTablet\":25,\"topPaddingMobile\":60,\"bottomPaddingMobile\":60,\"leftPaddingMobile\":20,\"rightPaddingMobile\":20,\"paddingLink\":false,\"topMarginDesktop\":0,\"bottomMarginDesktop\":0,\"leftMarginDesktop\":0,\"rightMarginDesktop\":0,\"marginLink\":false,\"variationSelected\":true,\"rowGapDesktop\":10,\"isBlockRootParent\":true} -->\n<div class=\"wp-block-uagb-container uagb-block-76587460 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\"><!-- wp:uagb\/image {\"block_id\":\"33a302d6\",\"url\":\"https:\/\/websitedemos.net\/cake-shop-09\/wp-content\/uploads\/sites\/1134\/2022\/10\/testimonial-08-free-img-1.jpg\",\"align\":\"center\",\"id\":100,\"linkDestination\":\"none\",\"naturalWidth\":100,\"naturalHeight\":100,\"sizeSlug\":\"full\",\"sizeSlugTablet\":\"full\",\"sizeSlugMobile\":\"full\",\"imageTopMargin\":25,\"imageRightMargin\":0,\"imageLeftMargin\":0,\"imageBottomMargin\":0,\"imageTopMarginMobile\":0,\"imageRightMarginMobile\":0,\"imageLeftMarginMobile\":0,\"imageBottomMarginMobile\":0,\"imageMarginLink\":false,\"imageBorderTopLeftRadius\":100,\"imageBorderTopRightRadius\":100,\"imageBorderBottomLeftRadius\":100,\"imageBorderBottomRightRadius\":100,\"className\":\"aligncenter\"} -->\n<div class=\"wp-block-uagb-image aligncenter uagb-block-33a302d6 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-center\"><figure class=\"wp-block-uagb-image__figure\"><img srcset=\"https:\/\/websitedemos.net\/cake-shop-09\/wp-content\/uploads\/sites\/1134\/2022\/10\/testimonial-08-free-img-1.jpg \" sizes=\"(max-width: 480px) 150px\" src=\"https:\/\/websitedemos.net\/cake-shop-09\/wp-content\/uploads\/sites\/1134\/2022\/10\/testimonial-08-free-img-1.jpg\" alt=\"\" class=\"uag-image-100\" width=\"100\" height=\"100\" title=\"\" loading=\"lazy\" role=\"img\"\/><\/figure><\/div>\n<!-- \/wp:uagb\/image -->\n\n<!-- wp:uagb\/advanced-heading {\"block_id\":\"0bf22f7e\",\"classMigrate\":true,\"headingAlign\":\"center\",\"headingTag\":\"h5\",\"headSpace\":0} -->\n<div class=\"wp-block-uagb-advanced-heading uagb-block-0bf22f7e\"><h5 class=\"uagb-heading-text\">Maria Harris<\/h5><\/div>\n<!-- \/wp:uagb\/advanced-heading -->\n\n<!-- wp:uagb\/image {\"block_id\":\"1ee7b860\",\"url\":\"https:\/\/websitedemos.net\/cake-shop-09\/wp-content\/uploads\/sites\/1134\/2022\/10\/quote-right.png\",\"align\":\"center\",\"id\":101,\"linkDestination\":\"none\",\"width\":20,\"height\":20,\"naturalWidth\":50,\"naturalHeight\":50,\"sizeSlug\":\"full\",\"sizeSlugTablet\":\"full\",\"sizeSlugMobile\":\"full\",\"imageTopMargin\":0,\"imageRightMargin\":0,\"imageLeftMargin\":0,\"imageBottomMargin\":10,\"imageMarginLink\":false,\"customHeightSetDesktop\":true,\"className\":\"aligncenter\"} -->\n<div class=\"wp-block-uagb-image aligncenter uagb-block-1ee7b860 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-center\"><figure class=\"wp-block-uagb-image__figure\"><img srcset=\"https:\/\/websitedemos.net\/cake-shop-09\/wp-content\/uploads\/sites\/1134\/2022\/10\/quote-right.png \" sizes=\"(max-width: 480px) 150px\" src=\"https:\/\/websitedemos.net\/cake-shop-09\/wp-content\/uploads\/sites\/1134\/2022\/10\/quote-right.png\" alt=\"\" class=\"uag-image-101\" width=\"20\" height=\"20\" title=\"\" loading=\"lazy\" role=\"img\"\/><\/figure><\/div>\n<!-- \/wp:uagb\/image -->\n\n<!-- wp:uagb\/advanced-heading {\"block_id\":\"60dc4972\",\"classMigrate\":true,\"headingAlign\":\"center\",\"headingTag\":\"p\",\"headSpace\":0,\"blockTopPadding\":0,\"blockRightPadding\":0,\"blockLeftPadding\":0,\"blockBottomPadding\":0,\"blockTopPaddingTablet\":0,\"blockRightPaddingTablet\":75,\"blockLeftPaddingTablet\":75,\"blockBottomPaddingTablet\":0,\"blockTopPaddingMobile\":0,\"blockRightPaddingMobile\":0,\"blockLeftPaddingMobile\":0,\"blockBottomPaddingMobile\":0} -->\n<div class=\"wp-block-uagb-advanced-heading uagb-block-60dc4972\"><p class=\"uagb-heading-text\">\u201cI just wanted to say thank you for our lorem it looked and tasted amazing consectetur adipiscing elit.  Ut elit tellus, everyone loved the theme.\u201d<\/p><\/div>\n<!-- \/wp:uagb\/advanced-heading --><\/div><\/div>\n<!-- \/wp:uagb\/container -->","brizy_media":[],"_links":{"self":[{"href":"https:\/\/websitedemos.net\/cake-shop-07\/wp-json\/wp\/v2\/pages\/6","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/websitedemos.net\/cake-shop-07\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/websitedemos.net\/cake-shop-07\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/websitedemos.net\/cake-shop-07\/wp-json\/wp\/v2\/users\/156"}],"replies":[{"embeddable":true,"href":"https:\/\/websitedemos.net\/cake-shop-07\/wp-json\/wp\/v2\/comments?post=6"}],"version-history":[{"count":244,"href":"https:\/\/websitedemos.net\/cake-shop-07\/wp-json\/wp\/v2\/pages\/6\/revisions"}],"predecessor-version":[{"id":1100,"href":"https:\/\/websitedemos.net\/cake-shop-07\/wp-json\/wp\/v2\/pages\/6\/revisions\/1100"}],"wp:attachment":[{"href":"https:\/\/websitedemos.net\/cake-shop-07\/wp-json\/wp\/v2\/media?parent=6"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}